{"id":1010543,"date":"2026-05-11T09:15:22","date_gmt":"2026-05-11T09:15:22","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1010543\/"},"modified":"2026-05-11T09:15:22","modified_gmt":"2026-05-11T09:15:22","slug":"debian-macht-ernst-nur-noch-reproduzierbare-pakete-in-testing","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1010543\/","title":{"rendered":"Debian macht ernst: Nur noch reproduzierbare Pakete in \u201etesting\u201c"},"content":{"rendered":"<ol class=\"a-toc__list\">\n<li class=\"a-toc__item&#10;          &#10;            a-toc__item--counter&#10;          &#10;            a-toc__item--current\">\n<p>              Debian macht ernst: Nur noch reproduzierbare Pakete in \u201etesting\u201c<\/p>\n<\/li>\n<\/ol>\n<p>    close notice<\/p>\n<p class=\"notice-banner__text a-u-mb-0\">\n      This article is also available in<br \/>\n        <a href=\"https:\/\/www.heise.de\/en\/news\/Debian-14-Reproducible-builds-become-mandatory-11289352.html\" class=\"notice-banner__link a-u-inline-link\" rel=\"nofollow noopener\" target=\"_blank\">English<\/a>.<\/p>\n<p>      It was translated with technical assistance and editorially reviewed before publication.\n    <\/p>\n<p class=\"notice-banner__link a-u-mb-0\">\n    Don\u2019t show this again.\n<\/p>\n<p>Debian versch\u00e4rft f\u00fcr die kommende Version 14 (\u201eForky\u201c) seine Qualit\u00e4tsanforderungen deutlich: Pakete d\u00fcrfen nur noch dann nach \u201etesting\u201c wandern, wenn sie sich reproduzierbar bauen lassen. Das hat das Debian-Release-Team angek\u00fcndigt. Die entsprechende Migrationslogik ist bereits aktiv. Sie betrifft sowohl neue Pakete, die sich nicht reproduzieren lassen, als auch bestehende Pakete, deren Reproduzierbarkeit sich verschlechtert hat.<\/p>\n<p>        Weiterlesen nach der Anzeige<\/p>\n<p>Was reproduzierbare Builds leisten<\/p>\n<p><a href=\"https:\/\/wiki.debian.org\/ReproducibleBuilds\" rel=\"external noopener nofollow\" target=\"_blank\">Reproduzierbare Pakete<\/a> (\u201ereproducible builds\u201c) erzeugen aus identischem Quellcode und in gleicher Build-Umgebung bit-identische Bin\u00e4rpakete. Damit werden Build-Prozesse nachvollziehbar und manipulationssicher. Unterschiede zwischen zwei Builds lassen sich so eindeutig auf echte \u00c4nderungen oder m\u00f6gliche Manipulationen zur\u00fcckf\u00fchren.<\/p>\n<p>Nicht reproduzierbare Builds entstehen oft durch banale Faktoren: Zeitstempel, zuf\u00e4llige Build-IDs oder eine nichtdeterministische Reihenfolge von Dateien. Zwei Builds desselben Quellcodes k\u00f6nnen dadurch unterschiedliche Bin\u00e4rdateien erzeugen, obwohl sich funktional nichts ge\u00e4ndert hat. Reproducible Builds eliminieren solche Unterschiede systematisch, etwa durch normierte Zeitstempel oder ein deterministisches Packaging.<\/p>\n<p>Vom Qualit\u00e4tsziel zur Release-Voraussetzung<\/p>\n<p>Debian arbeitet bereits seit Jahren mit dem Reproducible-Builds-Projekt an entsprechenden Mechanismen. Neu ist, dass Reproduzierbarkeit nicht mehr nur als Qualit\u00e4tsziel gilt, sondern direkt \u00fcber die Paketmigration nach \u201etesting\u201c entscheidet. Damit macht die Distribution reproduzierbare Builds faktisch zur Voraussetzung f\u00fcr den regul\u00e4ren Release-Prozess. Den aktuellen Reproduzierbarkeitsstatus aller Pakete listet <a href=\"https:\/\/reproduce.debian.net\/\" rel=\"external noopener nofollow\" target=\"_blank\">reproduce.debian.net<\/a> auf.<\/p>\n<p>Parallel baut Debian seine automatisierten Tests aus. Laut Release Team pr\u00fcft die CI-Infrastruktur inzwischen auch sogenannte binNMUs automatisch mit autopkgtests. Dabei handelt es sich um reine Neu\u00fcbersetzungen von Bin\u00e4rpaketen ohne \u00c4nderungen am Quellcode, etwa nach ABI-\u00dcberg\u00e4ngen oder neuen Bibliotheksversionen. Bislang lag der Fokus der Tests vor allem auf klassischen Source-Uploads.<\/p>\n<p>        Weiterlesen nach der Anzeige<\/p>\n<p>L\u00e4ngere Warteschlangen durch loong64<\/p>\n<p>Die neue Architektur loong64 sorgt derzeit vor allem f\u00fcr l\u00e4ngere Warteschlangen in Debians Build- und Testinfrastruktur. Weil viele Pakete auf allen Architekturen neu gebaut werden mussten und Debian nun auch binNMUs per autopkgtest pr\u00fcft, dauert die Migration nach \u201etesting\u201c derzeit l\u00e4nger.<\/p>\n<p>Zugleich <a href=\"https:\/\/lists.debian.org\/debian-devel-announce\/2026\/05\/msg00001.html\" rel=\"external noopener nofollow\" target=\"_blank\">erinnert Debian die Maintainer daran<\/a>, dass sie selbst f\u00fcr die erfolgreiche Migration ihrer Pakete nach \u201etesting\u201c verantwortlich bleiben. Blockieren fehlgeschlagene autopkgtests in Reverse-Dependencies die Migration, sollen die Maintainer entsprechende Release-Critical-Bugs melden.<\/p>\n<p>        Lesen Sie auchMehr anzeigenWeniger anzeigen<\/p>\n<p>(<a class=\"redakteurskuerzel__link\" href=\"https:\/\/www.heise.de\/news\/mailto:fo@heise.de\" title=\"Moritz F\u00f6rster\" rel=\"nofollow noopener\" target=\"_blank\">fo<\/a>)<\/p>\n<p>\n      Dieser Link ist leider nicht mehr g\u00fcltig.\n    <\/p>\n<p>Links zu verschenkten Artikeln werden ung\u00fcltig,<br \/>\n      wenn diese \u00e4lter als 7\u00a0Tage sind oder zu oft aufgerufen wurden.\n    <\/p>\n<p><strong>Sie ben\u00f6tigen ein heise+ Paket, um diesen Artikel zu lesen. Jetzt eine Woche unverbindlich testen \u2013 ohne Verpflichtung!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"Debian macht ernst: Nur noch reproduzierbare Pakete in \u201etesting\u201c close notice This article is also available in English.&hellip;\n","protected":false},"author":2,"featured_media":1010544,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[135],"tags":[38465,29,30,196,24468,24469,190,189,1687,445,194,191,193,192],"class_list":{"0":"post-1010543","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-wissenschaft-technik","8":"tag-debian","9":"tag-deutschland","10":"tag-germany","11":"tag-it","12":"tag-linux-distribution","13":"tag-open-source","14":"tag-science","15":"tag-science-technology","16":"tag-security","17":"tag-softwareentwicklung","18":"tag-technik","19":"tag-technology","20":"tag-wissenschaft","21":"tag-wissenschaft-technik"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116555188161434021","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1010543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1010543"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1010543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1010544"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1010543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1010543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1010543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}