{"id":1012356,"date":"2026-05-12T02:44:18","date_gmt":"2026-05-12T02:44:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1012356\/"},"modified":"2026-05-12T02:44:18","modified_gmt":"2026-05-12T02:44:18","slug":"esc-dieser-musiker-aus-aschersleben-sang-1956-fuer-deutschland","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1012356\/","title":{"rendered":"ESC: Dieser Musiker aus Aschersleben sang 1956 f\u00fcr Deutschland"},"content":{"rendered":"<p class=\"text\">\nAm 24. Mai 1956 hebt sich in Lugano der Vorhang zum ersten Grand Prix Eurovision. Von den Dimensionen heutiger Tage ist <a href=\"https:\/\/www.mdr.de\/meine-schlagerwelt\/sarah-engels-deutscher-esc-vorentscheid-eurovision-song-contest-100.html\" title=\"Offiziell: Sarah Engels ist beim ESC-Vorentscheid dabei\" rel=\"nofollow noopener\" target=\"_blank\">das Festival<\/a> noch weit entfernt. Es handelt sich um ein Experiment, das im kleinen Teatro-Kursaal ausgetragen wird und von dem nur wenige Zuschauer \u00fcberhaupt Notiz nehmen.\n<\/p>\n<p class=\"text\">\nVon Anfang an ist die Bundesrepublik Deutschland mit dabei. Sie wird bei der ersten Ausgabe unter anderem von einem Mann vertreten, der geb\u00fcrtig aus dem Osten des Landes stammt \u2013 und der als Jude nur mit Gl\u00fcck die j\u00fcngste deutsche Vergangenheit \u00fcberlebt hat.\n<\/p>\n<p>Erster Deutscher beim ESC aus <strong>Aschersleben<\/strong><\/p>\n<p class=\"text\">\nWalter Andreas Schwarz, so sein Name, wird 1913 in <a href=\"https:\/\/www.mdr.de\/nachrichten\/sachsen-anhalt\/magdeburg\/salzland\/aschersleben-museum-umzug-depot-kultur-news-100.html\" title=\"Aschersleben: Warum das St\u00e4dtische Museum aus allen N\u00e4hten platzt\" rel=\"nofollow noopener\" target=\"_blank\">Aschersleben<\/a> geboren. Er w\u00e4chst in kleinb\u00fcrgerlichen Verh\u00e4ltnissen auf, als Sohn einer j\u00fcdischen Familie. Fr\u00fch zeigt Schwarz ein musikalisches und schauspielerisches Talent, mit 19 Jahren beginnt er ein Schauspielstudium am renommierten Max-Reinhardt-Seminar in Wien. Anschlie\u00dfend spielt er am Wiener Volkstheater, neben Gr\u00f6\u00dfen wie Atilla H\u00f6rbiger oder Heinrich Schnitzler.\n<\/p>\n<p>Walter Andreas Schwarz \u00fc<a name=\"ueberlebte\">berlebte<\/a> KZ und Holocaust<\/p>\n<p class=\"text\">\nDie Karriere wird j\u00e4h vom Anschluss \u00d6sterreichs an das nationalsozialistische Deutschland beendet. J\u00fcdische K\u00fcnstler haben in Wien nun praktisch keine Auftrittsm\u00f6glichkeiten mehr. Schwarz kehrt <a href=\"https:\/\/www.mdr.de\/nachrichten\/sachsen-anhalt\/magdeburg\/salzland\/aschersleben-jubilaeum-stephaneum-102.html\" title=\"700 Jahre Stephaneum: Diese Promis waren auf einer der \u00e4ltesten Schulen Sachsen-Anhalts\" rel=\"nofollow noopener\" target=\"_blank\">nach Aschersleben<\/a> zur\u00fcck, wo er 1938 die <a href=\"https:\/\/www.mdr.de\/kultur\/ausstellungen\/sachsen-anhalt-ns-zweiter-weltkrieg-gedenkstaetten-102.html\" title=\"Gedenkst\u00e4tten in Sachsen-Anhalt: Wo an Opfer des NS erinnert wird\" rel=\"nofollow noopener\" target=\"_blank\">Pogromnacht<\/a> erlebt.\n<\/p>\n<p class=\"text\">\nKurz darauf werden er und seine gesamte Familie deportiert, Schwarz landet in einem Konzentrationslager (KZ) in Niedersachsen. Er kann nur deshalb bis 1945 \u00fcberleben, weil der Lagerkommandant ein Schulfreund von ihm ist.\n<\/p>\n<p>Karriere nach dem Krieg: <a name=\"Vom\">Vom<\/a> Schauspieler zum S\u00e4nger<\/p>\n<p class=\"text\">\nNach dem Ende des Zweiten Weltkrieges emigriert Schwarz nach London und arbeitet als \u00dcbersetzer f\u00fcr <a href=\"https:\/\/www.mdr.de\/nachrichten\/sachsen-anhalt\/landespolitik\/landtag-enquete-kommission-oeffentlich-rechtlicher-rundfunk-reise-london-bbc-reform-100.html\" title=\"Gespr\u00e4che \u00fcber Reformen: Rundfunk-Kommission reist nach London\" rel=\"nofollow noopener\" target=\"_blank\">die BBC<\/a>. Weil er als Schauspieler an die deutsche Sprache gebunden ist, nimmt er bald auch wieder Engagements in Deutschland an.\n<\/p>\n<p class=\"text\">\nF\u00fcr die Radiowellen der <a href=\"https:\/\/www.mdr.de\/unternehmen\/informationen\/geschichte\/geschichte-rundfunk-mitteldeutschland100.html\" title=\"Kurze Chronik zum Rundfunk in Mitteldeutschland\" rel=\"nofollow noopener\" target=\"_blank\">neugegr\u00fcndeten ARD<\/a> ist er ab 1949 als H\u00f6rspielsprecher t\u00e4tigt, au\u00dferdem tritt er in verschiedenen Kultursendungen als Chansons\u00e4nger auf.\u00a0Er singt Nachdenklich-Poetisches ebenso wie Satirisch-Kabarettistisches, setzt sich kritisch mit der Nachkriegsgesellschaft auseinander. Das breite Publikum erreicht er damit allerdings nicht, er ist kaum mehr als ein Geheimtipp.\n<\/p>\n<p><a name=\"Eurovision\">Eurovision<\/a>-Vorentscheid mit Freddy Quinn gewonnen<\/p>\n<p class=\"text\">\nAnfang 1956 erreicht Walter Andreas Schwarz in London ein Telegramm des Hessischen Rundfunks. Er wird zum nationalen <a href=\"https:\/\/www.mdr.de\/nachrichten\/sachsen-anhalt\/magdeburg\/magdeburg\/laura-nahr-will-zum-esc-100.html\" title=\"ESC 2026: Magdeburgerin tritt bei Vorentscheid an\" rel=\"nofollow noopener\" target=\"_blank\">Vorentscheid<\/a> f\u00fcr einen neuen europ\u00e4ischen Musikwettbewerb eingeladen \u2013 den ersten Grand Prix Eurovision. Schwarz macht sich auf den Weg nach K\u00f6ln, wo der Vorentscheid stattfinden soll. Im Gep\u00e4ck hat er sein Chanson &#8222;Im Wartesaal zum gro\u00dfen Gl\u00fcck&#8220;.\n<\/p>\n<p class=\"text\">\n\u00dcberraschend kann Walter Andreas Schwarz den Vorentscheid in f\u00fcr sich entscheiden \u2013 zusammen mit dem noch unbekannten <a href=\"https:\/\/www.mdr.de\/meine-schlagerwelt\/freddy-quinn-haus-in-hamburg-verkauft-100.html\" title=\"Freddy Quinn hat sein Haus im Hamburg verkauft\" rel=\"nofollow noopener\" target=\"_blank\">Freddy Quinn<\/a>. Damals darf jedes Land zwei Beitr\u00e4ge einreichen, damit bei nur sieben L\u00e4ndern \u00fcberhaupt ein abendf\u00fcllendes Programm zustande kommt.\n<\/p>\n<p><a name=\"Singt\">Singt<\/a> im Eurovision-Finale \u00fcber Nachkriegsdeutschland<\/p>\n<p class=\"text\">\nBeim Finale stechen beide deutschen Beitr\u00e4ge deutlich aus der ansonsten recht gleichf\u00f6rmigen Chanson-Masse hervor. <a href=\"https:\/\/www.mdr.de\/meine-schlagerwelt\/freddy-quinn-frau-rosi-so-halten-sie-ihre-liebe-jung-100.html\" title=\"Freddy Quinn &amp; Frau Rosi: So halten sie ihre Liebe jung\" rel=\"nofollow noopener\" target=\"_blank\">Freddy Quinn<\/a>, weil sein Beitrag der einzige im Rock&#8217;n&#8217;Roll-Stil ist. Walter Andreas Schwarz wegen der eindringlichen Ernsthaftigkeit, mit der er sein zeitkritisches Chanson vortr\u00e4gt.\n<\/p>\n<p class=\"text\">\nDer metaphorische Text handelt von Menschen, die &#8222;seit gestern auf das Gl\u00fcck von morgen&#8220; warten und die dabei die Gegenwart verdr\u00e4ngen. Menschen, die sich &#8222;am Kai der Vergangenheit&#8220; einen Saal mit &#8222;W\u00e4nden aus Tr\u00e4umen&#8220; gebaut haben, gegen die Wirklichkeit \u2013 &#8222;denn die liebte man nicht sehr&#8220;. Sehr wahrscheinlich handelt Schwarz&#8216; Chanson von den <a href=\"https:\/\/www.mdr.de\/geschichte\/ddr\/politik-gesellschaft\/entnazifizierung-nazis-in-der-ddr-100.html\" title=\"Von wegen Entnazifizierung: Nazi-Karrieren in der DDR\" rel=\"nofollow noopener\" target=\"_blank\">Menschen im Nachkriegsdeutschland<\/a>.\n<\/p>\n<blockquote>\n<p class=\"text\">Und man baute am Kai der Vergangenheit \/ einen Saal mit Blick auf das Meer \/ Und mit W\u00e4nden aus Tr\u00e4umen gegen die Wirklichkeit \/ Denn die liebte man nicht sehr<\/p>\n<p>Aus dem Lied &#8222;Im Wartesaal zum gro\u00dfen Gl\u00fcck&#8220; von Walter Andreas Schwarz<\/p>\n<\/blockquote>\n<p class=\"text\">\nIn einer Zeit, in der man in Deutschland die j\u00fcngste Vergangenheit am liebsten vergessen will, wird eben dieses Deutschland mit einem Chanson vertreten, das mindestens implizit vom Umgang mit genau dieser Vergangenheit handelt. Noch dazu von einem Opfer dieser Vergangenheit.\n<\/p>\n<p>Trotz Auftritt beim ESC kein Durchbruch<\/p>\n<p class=\"text\">\nGewinnen kann Schwarz den Grand Prix nicht, die gastgebende Schweiz macht mit dem Titel &#8222;Refrain&#8220; von Weltstar Lys Assia das Rennen. Schwarz\u2019 genaue Platzierung ist nicht bekannt, da damals nur die Siegerin verk\u00fcndet wurde.\n<\/p>\n<p class=\"text\">\nTrotz des Auftritts beim ESC gelingt Walter Andreas Schwarz anschlie\u00dfend der musikalische Durchbruch nicht. Bis Mitte der 80er-Jahre wirkt er an \u00fcber 200 H\u00f6rspielen mit, 1992 stirbt er in Heidelberg. Als S\u00e4nger w\u00e4re er heute vermutlich vergessen \u2013 w\u00e4re er nicht der erste deutsche Vertreter eines Musikwettbewerbs gewesen, der sich mittlerweile zur gr\u00f6\u00dften Fernsehsendung der Welt entwickelt hat.\n<\/p>\n<p class=\"text\">\nRedaktionelle Bearbeitung: vp, sg<\/p>\n","protected":false},"excerpt":{"rendered":"Am 24. Mai 1956 hebt sich in Lugano der Vorhang zum ersten Grand Prix Eurovision. Von den Dimensionen&hellip;\n","protected":false},"author":2,"featured_media":1012357,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[331,3924,332,3922,20893,18088,3364,29,4629,31740,30,20974,13,78839,66,3910,81,9668,14,3923,15,3921,20973,6211,860,12,1909,21435,4412],"class_list":{"0":"post-1012356","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deutschland","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-nachrichten-aus-deutschland","10":"tag-aktuelle-news","11":"tag-aktuelle-news-aus-deutschland","12":"tag-aschersleben","13":"tag-contest","14":"tag-de","15":"tag-deutschland","16":"tag-esc","17":"tag-eurovision","18":"tag-germany","19":"tag-grand","20":"tag-headlines","21":"tag-juedisch","22":"tag-kulturnachrichten","23":"tag-kuenstler","24":"tag-mdr","25":"tag-musiker","26":"tag-nachrichten","27":"tag-nachrichten-aus-deutschland","28":"tag-news","29":"tag-news-aus-deutschland","30":"tag-prix","31":"tag-regionalportal","32":"tag-sachsen-anhalt","33":"tag-schlagzeilen","34":"tag-song","35":"tag-vertreter","36":"tag-wettbewerb"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116559312717277981","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1012356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1012356"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1012356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1012357"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1012356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1012356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1012356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}