{"id":1012418,"date":"2026-05-12T03:16:15","date_gmt":"2026-05-12T03:16:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1012418\/"},"modified":"2026-05-12T03:16:15","modified_gmt":"2026-05-12T03:16:15","slug":"berlin-deutsche-passagiere-muessen-lange-quarantaene-durchstehen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1012418\/","title":{"rendered":"Berlin | Deutsche Passagiere m\u00fcssen lange Quarant\u00e4ne durchstehen"},"content":{"rendered":"<p>Berlin (dpa) &#8211; Zun\u00e4chst zeigt keiner der vier nach Deutschland gebrachten Passagiere des Hantavirus-Schiffes Symptome der Infektion &#8211; wegen der oft langen Zeitspanne zwischen Ansteckung und Erkrankung k\u00f6nnte das aber noch kommen. Ein Hinweis auf eine kritische Entwicklung des Ausbruchs w\u00e4re das aber nicht, wie der Hamburger Virologe Jonas Schmidt-Chanasit betonte. Einzelne weitere F\u00e4lle w\u00e4ren bei meist etwa zwei bis vier Wochen Inkubationszeit nicht \u00fcberraschend, sondern entspr\u00e4chen dem erwartbaren Nachlauf.<\/p>\n<p>Die vier nach Deutschland gebrachten Passagiere stammen aus Berlin, Baden-W\u00fcrttemberg, Bayern und Sachsen. Bei ihnen lie\u00dfe sich auch aus negativen sogenannten PCR-Tests nicht mit absoluter Sicherheit schlie\u00dfen, dass sie virusfrei sind, wie Schmidt-Chanasit vom Bernhard-Nocht-Institut f\u00fcr Tropenmedizin (BNITM) erkl\u00e4rte. \u00abEin negativer PCR-Test zu einem fr\u00fchen Zeitpunkt schlie\u00dft eine sp\u00e4tere Erkrankung nicht sicher aus, wenn sich die Person noch in der Inkubationsphase befindet und das Virus im Blut noch nicht nachweisbar ist.\u00bb<\/p>\n<p>Lange Quarant\u00e4ne steht an<\/p>\n<p>Nach Angaben des Bundesgesundheitsministerium (BMG) d\u00fcrfte vorerst h\u00e4usliche Quarant\u00e4ne f\u00fcr die vier Betroffenen anstehen. \u00abW\u00e4hrend der n\u00e4chsten Wochen werden die Kontaktpersonen kontinuierlich und engmaschig auf Symptome \u00fcberwacht.\u00bb Falls eine Person erkranken sollte, k\u00f6nne sie in speziellen Zentren nach besten medizinischen Standards und sicher behandelt werden.<\/p>\n<p>Von der Weltgesundheitsorganisation wird angenommen, dass die Infektionskette auf der \u00abHondius\u00bb auf ein niederl\u00e4ndisches Ehepaar zur\u00fcckgeht, das am 1. April an Bord ging. Der Mann &#8211; mutma\u00dflich der Erstinfizierte des Infektionsclusters &#8211; hatte am 6. April Fieber, Kopf- und Bauchschmerzen sowie Durchfall entwickelt und war am 11. April gestorben.<\/p>\n<p>Im Zuge dieser Erkrankung sei es nach derzeitiger Annahme zu begrenzten Mensch-zu-Mensch-\u00dcbertragungen auf dem Schiff gekommen, erkl\u00e4rte Schmidt-Chanasit. Da die Symptome denen verschiedener Atemwegserkrankungen \u00e4hneln, war erst verz\u00f6gert auf das Hantavirus getestet worden. Erst dann kamen strengere Isolierungs- und \u00dcberwachungsma\u00dfnahmen in Gang.<\/p>\n<p>Ungl\u00fccklicher Zufall<\/p>\n<p>Die Verz\u00f6gerung sei nicht verwunderlich &#8211; ein Andesvirus-Fall auf einem Kreuzfahrtschiff sei kein sonderlich naheliegendes Szenario, sagte Schmidt-Chanasit. Es handle sich um ein sehr ungew\u00f6hnliches Ereignis, das durch mehrere ungl\u00fcckliche Umst\u00e4nde beg\u00fcnstigt worden sei. Das s\u00fcdamerikanische Andesvirus wird wie alle Hantaviren in der Regel von Nagetieren \u00fcbertragen &#8211; etwa \u00fcber Kotpartikel in aufgewirbeltem Staub.<\/p>\n<p>Inzwischen gelte das Geschehen als gut kontrollierbar: \u00abDie betroffenen Personen werden international nachverfolgt, Hochrisikokontakte werden beobachtet oder quarant\u00e4nisiert, symptomatische Personen werden rasch getestet und isoliert, und die Krankenh\u00e4user wissen nun, worauf sie achten m\u00fcssen\u00bb, so der Virologe. \u00abDamit hat man bisher jeden Andesvirus-Ausbruch unter Kontrolle gebracht.\u00bb<\/p>\n<p>Ausbr\u00fcche lie\u00dfen sich stets gut eind\u00e4mmen<\/p>\n<p>Das Andesvirus ist das einzige Hantavirus, das in seltenen F\u00e4llen bei engem, anhaltenden Kontakt auch von Mensch zu Mensch weitergegeben werden kann. In den vergangenen Jahrzehnten hatte es einige wenige erfasste Ausbr\u00fcche in S\u00fcdamerika gegeben, die alle rasch wieder abebbten. Auch im aktuellen Fall sehen Experten kein Risiko f\u00fcr eine umfassende Ausbreitung des Erregers.<\/p>\n<p>Die \u00abHondius\u00bb hatte am Sonntag den Hafen von Granadilla im S\u00fcden Teneriffas erreicht. Mit Sonderfl\u00fcgen wurden Menschen vom Schiff unter speziellen Sicherheitsvorkehrungen in ihre Heimat gebracht. Am Montagabend wurde die Evakuierungsaktion abgeschlossen. Das Schiff setzte danach seine Fahrt mit einer Restmannschaft Richtung Niederlande fort. Auf dem Kreuzfahrtschiff waren zuletzt insgesamt 140 bis 150 Reiseg\u00e4ste, Besatzungsmitglieder und begleitende Experten aus 23 L\u00e4ndern.<\/p>\n<p>Zur Gesamtzahl der bisherigen Nachweise gab es von der WHO am Montag zun\u00e4chst keine neuen Angaben. Drei Menschen waren Stand Sonntag gestorben: das niederl\u00e4ndische Paar und eine deutsche Passagierin.<\/p>\n","protected":false},"excerpt":{"rendered":"Berlin (dpa) &#8211; Zun\u00e4chst zeigt keiner der vier nach Deutschland gebrachten Passagiere des Hantavirus-Schiffes Symptome der Infektion &#8211;&hellip;\n","protected":false},"author":2,"featured_media":1012419,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[1941,1939,296,1937,29,30,141,2052,984,288,1940,1938,965,5226,4026,1163,193],"class_list":{"0":"post-1012418","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-aktuelle-nachrichten-aus-berlin","9":"tag-aktuelle-news-aus-berlin","10":"tag-berlin","11":"tag-berlin-news","12":"tag-deutschland","13":"tag-germany","14":"tag-gesundheit","15":"tag-hessen","16":"tag-international","17":"tag-krankheit","18":"tag-nachrichten-aus-berlin","19":"tag-news-aus-berlin","20":"tag-niederlande","21":"tag-schifffahrt","22":"tag-spanien","23":"tag-tourismus","24":"tag-wissenschaft"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116559438569138255","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1012418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1012418"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1012418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1012419"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1012418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1012418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1012418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}