{"id":1012644,"date":"2026-05-12T05:24:24","date_gmt":"2026-05-12T05:24:24","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1012644\/"},"modified":"2026-05-12T05:24:24","modified_gmt":"2026-05-12T05:24:24","slug":"eu-einigung-mehr-wichtige-medikamente-in-europa-herstellen-politik","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1012644\/","title":{"rendered":"EU-Einigung: Mehr wichtige Medikamente in Europa herstellen &#8211; Politik"},"content":{"rendered":"<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Im Kampf gegen Engp\u00e4sse bei lebenswichtigen Medikamenten in der EU haben sich Unterh\u00e4ndler in Br\u00fcssel auf Regeln geeinigt, um die Produktion von Arzneimitteln leichter mit \u00f6ffentlichen Geldern unterst\u00fctzen zu k\u00f6nnen. Das teilten die Vertreter des Europ\u00e4ischen Parlaments und der Mitgliedstaaten mit. Europa soll dadurch weniger abh\u00e4ngig von einzelnen Lieferanten und der Herstellung au\u00dferhalb des Kontinents werden.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Menschen in Europa konnten in den vergangenen Jahren manche <a href=\"https:\/\/www.sueddeutsche.de\/thema\/Medikamente\" rel=\"nofollow noopener\" target=\"_blank\">Medikamente<\/a> zeitweise nicht mehr in der Apotheke kaufen. Betroffen waren etwa Schmerzmittel, Antibiotika oder Fiebers\u00e4fte f\u00fcr Kinder. \u201eDie Patienten sollten sich keine Sorgen dar\u00fcber machen m\u00fcssen, ob wichtige Arzneimittel wie Antibiotika in ihrer Apotheke oder ihrem Krankenhaus verf\u00fcgbar sind\u201c, teilte der zyprische Gesundheitsminister Neophytos Charalambides mit. Sein Land hat derzeit die rotierende EU-Ratspr\u00e4sidentschaft inne.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Bevor die Regeln in Kraft treten k\u00f6nnen, m\u00fcssen sie noch vom Europaparlament und den EU-Staaten best\u00e4tigt werden. Normalerweise gilt das als Formsache, wenn sich die Unterh\u00e4ndler der Institutionen zuvor auf einen Kompromiss geeinigt haben.<\/p>\n<p>EU will Anreize f\u00fcr heimische Produktion setzen<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Ein Baustein der neuen Regeln betrifft die Vergabe \u00f6ffentlicher Auftr\u00e4ge. Im Fall von wichtigen Arzneimitteln, bei denen es eine hohe Abh\u00e4ngigkeit von einem oder wenigen L\u00e4ndern gibt, sollen hierbei k\u00fcnftig grunds\u00e4tzlich in Europa hergestellte Medikamente bevorzugt werden. So sollen Anreize f\u00fcr sichere Lieferketten geschaffen werden. Die vorl\u00e4ufige Einigung sieht vor, dass es verschiedene M\u00f6glichkeiten gibt, diese Medikamente zu bevorzugen. \u201eDazu geh\u00f6rt, dass Lieferanten proportional zu dem Anteil der in der EU hergestellten Arzneimittel und deren pharmazeutischer Wirkstoffe verg\u00fctet werden\u201c, teilte das Parlament mit.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Sogenannte strategische Projekte sollen zudem schneller genehmigt werden und schneller Zugang zu F\u00f6rderung bekommen. Mehrere L\u00e4nder k\u00f6nnen sich zudem zusammenschlie\u00dfen und gemeinsam wichtige Medikamente beschaffen. Das betrifft unter anderem Arzneimittel f\u00fcr seltene Erkrankungen, bei denen sonst laut Kommission der Markt versagt.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Mit kritischen Arzneimitteln sind laut EU-Kommission Medikamente gemeint, \u201ebei denen es nur wenige oder gar keine Alternativen gibt und bei denen die Patientinnen und Patienten durch Versorgungsengp\u00e4sse ernsthaft gesch\u00e4digt w\u00fcrden\u201c. Dazu geh\u00f6ren demnach unter anderem Antibiotika und Antithrombotika, Krebstherapeutika und Herz-Kreislauf-Mittel. Sie sind in einer Liste aufgef\u00fchrt.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Die EU-Kommission hatte die Anpassung im M\u00e4rz 2025 vorgeschlagen. Nach Kommissionsangaben gibt es viele Gr\u00fcnde, warum es in der EU in den vergangenen Jahren Versorgungsprobleme gab. Darunter seien etwa Engp\u00e4sse bei Wirkstoffen. Aber auch, dass sich die Produktion in einigen wenigen L\u00e4ndern konzentriere, trage zu den Problemen bei. In der Corona-Pandemie seien Schwachstellen in den Lieferketten deutlich geworden.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Nach Angaben von EU-Gesundheitsministern aus dem vergangenen Jahr stammen etwa 80 bis 90 Prozent der Medikamente in Europa aus Asien, vor allem aus China. Gleichzeitig sind in der EU im Arzneimittelsektor laut Kommission etwa 800 000 Menschen besch\u00e4ftigt.<\/p>\n","protected":false},"excerpt":{"rendered":"Im Kampf gegen Engp\u00e4sse bei lebenswichtigen Medikamenten in der EU haben sich Unterh\u00e4ndler in Br\u00fcssel auf Regeln geeinigt,&hellip;\n","protected":false},"author":2,"featured_media":1012645,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3933],"tags":[331,332,548,663,158,3934,3935,4612,13,148,18115,837,14,15,16,12,149],"class_list":{"0":"post-1012644","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-eu","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-eu","11":"tag-europa","12":"tag-europaeische-union","13":"tag-europe","14":"tag-european-union","15":"tag-gesundheitspolitik","16":"tag-headlines","17":"tag-leserdiskussion","18":"tag-medikamente","19":"tag-medizin","20":"tag-nachrichten","21":"tag-news","22":"tag-politik","23":"tag-schlagzeilen","24":"tag-sueddeutsche-zeitung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116559941988231520","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1012644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1012644"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1012644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1012645"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1012644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1012644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1012644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}