{"id":1012767,"date":"2026-05-12T06:33:23","date_gmt":"2026-05-12T06:33:23","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1012767\/"},"modified":"2026-05-12T06:33:23","modified_gmt":"2026-05-12T06:33:23","slug":"berlin-die-koalition-und-der-lange-schatten-der-villa-borsig-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1012767\/","title":{"rendered":"Berlin | Die Koalition und der lange Schatten der Villa Borsig"},"content":{"rendered":"<p>Berlin (dpa) &#8211; Die Spitzen von Union und SPD kommen am Abend im Koalitionsausschuss zusammen, um \u00fcber Entlastungen angesichts der hohen Energiepreise, \u00fcber den Haushalt und den weiteren Reform-Fahrplan zu beraten. Es ist die erste Sitzung des zentralen Steuerungsgremiums der Koalition seit dem ber\u00fcchtigten Treffen vor einem Monat in der Villa Borsig, das als Kristallisationspunkt der aktuellen Krise des Regierungsb\u00fcndnisses gilt.\u00a0<\/p>\n<p>Damals wollten Bundeskanzler Friedrich Merz (CDU), Vizekanzler Lars Klingbeil (SPD) und Co. endlich ihre gro\u00dfen Sozial- und Steuerreformen in die Spur bringen. Nach zwei Tagen teils lautstarkem Ringen in der Villa Borsig, dem G\u00e4stehaus des Ausw\u00e4rtigen Amts, blieben die Ergebnisse im Vergleich zu den Erwartungen der \u00d6ffentlichkeit aber mau.\u00a0<\/p>\n<p>Aus f\u00fcr Entlastungspr\u00e4mie wahrscheinlich\u00a0<\/p>\n<p>Vor allem wurden zwei Ma\u00dfnahmen beschlossen, um die im Zuge des Iran-Kriegs drastisch gestiegenen Energiepreise abzufedern:<\/p>\n<ul class=\"list-normal\">\n<li>Ein Tankrabatt von 17 Cent, \u00fcber die der Kanzler inzwischen sagt, er funktioniere nur \u00abso leidlich\u00bb.\u00a0<\/li>\n<li>Die M\u00f6glichkeit f\u00fcr Arbeitgeber, bis zu 1.000 Euro steuerfrei als Entlastungspr\u00e4mie an Mitarbeiter auszuzahlen.<\/li>\n<\/ul>\n<p>Die zweite Ma\u00dfnahme steht auf der Kippe, seit der Bundesrat sie am vergangenen Freitag \u00fcberraschend abgelehnt hat. Die Bundesregierung will nun \u00absehr zeitnah\u00bb entscheiden, wie es mit der Pr\u00e4mie weitergeht &#8211; sprich: in der Sitzung des Koalitionsausschusses heute Abend.<\/p>\n<p>Die Regierung hat zwei M\u00f6glichkeiten: Sie kann nach einem Kompromiss mit den L\u00e4ndern suchen und den Vermittlungsausschuss von Bundestag und Bundesrat anrufen. Oder sie l\u00e4sst die Pr\u00e4mie fallen. Die zweite Option gilt als die deutlich wahrscheinlichere. \u00abIch glaube, die ist vom Tisch\u00bb, hat CSU-Chef Markus S\u00f6der bereits am Sonntag in der ARD \u00fcber die Pr\u00e4mie gesagt.\u00a0<\/p>\n<p>Suche nach Alternativen<\/p>\n<p>Es stellt sich dann aber die Frage, ob es einen Ersatz geben wird. Die Bundesregierung hat nach dem Nein des Bundesrats erkl\u00e4rt, dass sie weiter zu Entlastungen bereit sei. Es gibt zwei M\u00f6glichkeiten:<\/p>\n<ul class=\"list-normal\">\n<li>Ma\u00dfnahmen, die kurzfristig wirken wie eine Erh\u00f6hung der Pendlerpauschale, eine Senkung der Stromsteuer f\u00fcr alle oder Direktzahlungen.<\/li>\n<li>Oder man setzt auf die geplante Reform der Einkommensteuer, die eine Entlastung kleiner und mittlerer Einkommen zum Ziel hat. Sie soll zum 1. Januar 2027 in Kraft treten<\/li>\n<\/ul>\n<p>Einkommensteuerreform und Haushalt<\/p>\n<p>Die Einkommensteuerreform wird so oder so Thema des Koalitionsausschusses. Es soll um den weiteren Fahrplan gehen, Entscheidungen in der Sache sind aber nicht zu erwarten. SPD-Generalsekret\u00e4r Tim Kl\u00fcssendorf sagte dem \u00abTagesspiegel\u00bb, die Einkommensteuerreform m\u00fcsse nun \u00abschnellstm\u00f6glich an den Start gehen\u00bb. Ein Vorschlag von Finanzminister Klingbeil sei \u00abin den n\u00e4chsten Wochen, vielleicht auch schon in den n\u00e4chsten Tagen\u00bb zu erwarten.<\/p>\n<p>Weiteres Thema im Kanzleramt: Der Haushalt, in dem noch Milliardenl\u00fccken gestopft werden m\u00fcssen. Die j\u00fcngste Steuersch\u00e4tzung hat f\u00fcr die Jahre 2026 und 2027 jeweils knapp 18 Milliarden Euro weniger Einnahmen als bei der vorangegangenen Sch\u00e4tzung ergeben.<\/p>\n<p>Es geht auch um das gro\u00dfe Ganze<\/p>\n<p>Es d\u00fcrfte in der Sitzung aber auch um das gro\u00dfe Ganze gehen. Seit den f\u00fcr die SPD ganz und f\u00fcr die CDU halb verpatzten Landtagswahlen im M\u00e4rz l\u00e4uft es gar nicht mehr f\u00fcr die Koalition. Die AfD zieht den Regierungsparteien in den Umfragen davon, der Kanzler kommt auf historisch schlechte Beliebtheitswerte und ob er mit seinem Vizekanzler Klingbeil wirklich noch als Achse der Stabilit\u00e4t in der Koalition taugt, wird bezweifelt.\u00a0<\/p>\n<p>Die grunds\u00e4tzliche Herangehensweise an die gro\u00dfen Reformen wird inzwischen in Frage gestellt. Reicht es, wenn die Berliner Regierungskoalition alles alleine macht? Der nordrhein-westf\u00e4lische CDU-Ministerpr\u00e4sident Hendrik W\u00fcst hat j\u00fcngst gefordert: \u00abDeutschland braucht kein Gez\u00e4nk \u2013 es braucht einen Konsens 2030. Ein echtes B\u00fcndnis: Gewerkschaften, Arbeitgeber, Politik.\u00bb<\/p>\n<p>\u00c4hnlich \u00e4u\u00dferte sich unmittelbar vor dem Koalitionsausschuss Niedersachsens SPD-Regierungschef Olaf Lies: \u00abEs braucht eine neue konzertierte Aktion. Wir als Politik aus Bund und L\u00e4ndern sollten die Sozialpartner, Gewerkschaften und Arbeitgeber mit an den Tisch holen\u00bb, sagte er dem \u00abTagesspiegel\u00bb.\u00a0<\/p>\n<p>Reden von Merz und Bas beim DGB setzen den Ton<\/p>\n<p>Merz und SPD-Chefin B\u00e4rbel Bas sind heute bei einem der Sozialpartner zu Gast, beim Deutschen Gewerkschaftsbund. Ihre Reden auf dem DGB-Kongress in Berlin d\u00fcrften die Tonlage f\u00fcr den Koalitionsausschuss am Abend setzen.<\/p>\n","protected":false},"excerpt":{"rendered":"Berlin (dpa) &#8211; Die Spitzen von Union und SPD kommen am Abend im Koalitionsausschuss zusammen, um \u00fcber Entlastungen&hellip;\n","protected":false},"author":2,"featured_media":1012768,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1841],"tags":[1605,1173,3364,29,1721,30,44,1209,2149],"class_list":{"0":"post-1012767","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bielefeld","8":"tag-bielefeld","9":"tag-bundesregierung","10":"tag-de","11":"tag-deutschland","12":"tag-finanzen","13":"tag-germany","14":"tag-koalition","15":"tag-nordrhein-westfalen","16":"tag-steuern"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116560213367943042","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1012767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1012767"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1012767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1012768"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1012767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1012767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1012767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}