{"id":1013367,"date":"2026-05-12T12:14:18","date_gmt":"2026-05-12T12:14:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1013367\/"},"modified":"2026-05-12T12:14:18","modified_gmt":"2026-05-12T12:14:18","slug":"fc-bayern-michael-olise-mit-xxl-anzug-bei-gala-in-frankreich-seltener-auftritt-mit-seinen-eltern-sport","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1013367\/","title":{"rendered":"FC Bayern: Michael Olise mit XXL-Anzug bei Gala in Frankreich \u2013 Seltener Auftritt mit seinen Eltern! | Sport"},"content":{"rendered":"<p><a class=\"skip-content skip-content--link\" href=\"#in-content-skip-link-target-v-0-0\">TTS-Player \u00fcberspringen\u21b5<\/a><a id=\"in-content-skip-link-target-v-0-0\" class=\"skip-content--target-link-hidden skip-content skip-content--target-link\" href=\"#in-content-skip-link-target-v-0-0\">Artikel weiterlesen<\/a><\/p>\n<p>Paris\/M\u00fcnchen \u2013 <b>Was f\u00fcr ein extravagantes Outfit von Michael Olise (24)! Seit Monaten legt der Superstar des <\/b><a href=\"https:\/\/www.bild.de\/sport\/fussball\/bayern-muenchen\/startseite-fc-bayern-muenchen-31074450.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\"><b>FC Bayern<\/b><\/a><b> immer wieder kuriose bis schr\u00e4ge Auftritte in der \u00d6ffentlichkeit hin. Die einen feiern den Franzosen daf\u00fcr, andere sch\u00fctteln immer mal wieder mit dem Kopf. Jetzt der n\u00e4chste Olise-Hingucker \u2013 im schwarzen XXL-Anzug!<\/b><\/p>\n<p>Der Fl\u00fcgel-Star (22 Tore, 30 Vorlagen in 50 Saisonspielen) nutzte seine drei freien Bayern-Tage nach dem 1:0 am Samstag in Wolfsburg, um einen weiteren Titel abzustauben. Olise flog nach Frankreich und ging am Montagabend in Paris zur Gala der franz\u00f6sischen Spieler-Gewerkschaft UNFP. <\/p>\n<p>Olise zum besten Franzosen im Ausland gek\u00fcrt<\/p>\n<p>Dort erhielt er die Troph\u00e4e f\u00fcr den besten franz\u00f6sischen Spieler im Ausland. Damit stach er sogar Kylian Mbapp\u00e9 (27\/41 Saisontore) aus. Der Super-St\u00fcrmer von Real Madrid hatte die Auszeichnung im Vorjahr erhalten, 2024 Antoine Griezmann (35\/Atl\u00e9tico Madrid) und von 2019 bis 2023 Karim Benzema (38\/damals Real, nun Al-Hilal).<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"1178\" alt=\"Weit, weiter, dieser Anzug: Das Outfit von Bayern-Fl\u00fcgel Michael Olise (24) war ein Hingucker auf dem roten Teppich in Paris\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/d1b2033bbefe76ad3c9433bcd88ddbb0,75594f80.jpeg\"   class=\"portrait\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Weit, weiter, dieser Anzug: Das Outfit von Bayern-Fl\u00fcgel Michael Olise (24) war ein Hingucker auf dem roten Teppich in Paris<\/p>\n<p>Foto: UNFP\/FEP\/ICON\/PsnewZ\/Bestimage<\/p>\n<p>Am auff\u00e4lligsten war aber Olises Auftritt auf dem roten Teppich! In seinem l\u00e4ssigen XXL-Anzug posierte der in London geborene und aufgewachsene Star sogar mit seinen Eltern \u2013 ein seltener Auftritt in der \u00d6ffentlichkeit mit seiner Mutter Yamina (franz\u00f6sisch-algerische Herkunft) und seinem Vater Vincent (aus Nigeria).<\/p>\n<p>Immer wieder kuriose Olise-Auftritte<\/p>\n<p>Statt langen Dankesworten sagte Olise im Anschluss bei der Preisverleihung in seiner Heimat trocken: \u201eMein Ziel in dieser Saison war es, mit Frankreich und mit dem FC Bayern alles zu gewinnen. Das ist alles.\u201c <\/p>\n<p>Noch ist mit dem FC Bayern nach dem Aus im Halbfinale der Champions League gegen seine Landsm\u00e4nner von Paris Saint-Germain (4:5, 1:1) das deutsche Double (DFB-Pokalfinale am 23. Mai in Berlin gegen den VfB Stuttgart) und mit der franz\u00f6sischen Nationalmannschaft der WM-Titel in den USA, Kanada und Mexiko (ab 11. Juni, Endspiel am 19. Juli in New York) drin.<\/p>\n","protected":false},"excerpt":{"rendered":"TTS-Player \u00fcberspringen\u21b5Artikel weiterlesen Paris\/M\u00fcnchen \u2013 Was f\u00fcr ein extravagantes Outfit von Michael Olise (24)! Seit Monaten legt der&hellip;\n","protected":false},"author":2,"featured_media":1013368,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3974],"tags":[331,332,51687,123505,468,538,548,663,3934,458,3980,156,347,38029,218133,13,19542,14,55213,15,319,23613,3349,12,803,1470,1261,11404],"class_list":{"0":"post-1013367","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-frankreich","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-atletico-madrid","11":"tag-benzema-karim","12":"tag-champions-league","13":"tag-erste-bundesliga","14":"tag-eu","15":"tag-europa","16":"tag-europe","17":"tag-fc-bayern-muenchen","18":"tag-france","19":"tag-frankreich","20":"tag-fussball","21":"tag-fussball-wm-2026","22":"tag-griezmann-antoine","23":"tag-headlines","24":"tag-kylian-mbappe","25":"tag-nachrichten","26":"tag-nationalmannschaft-frankreich","27":"tag-news","28":"tag-paris","29":"tag-paris-saint-germain","30":"tag-real-madrid","31":"tag-schlagzeilen","32":"tag-spielertransfer","33":"tag-sport-leuchtturm-muenchen","34":"tag-toralarm-top-news","35":"tag-wm"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1013367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1013367"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1013367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1013368"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1013367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1013367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1013367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}