{"id":1014181,"date":"2026-05-12T19:55:15","date_gmt":"2026-05-12T19:55:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1014181\/"},"modified":"2026-05-12T19:55:15","modified_gmt":"2026-05-12T19:55:15","slug":"kunst-welches-kunstwerk-hat-ihr-leben-veraendert","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1014181\/","title":{"rendered":"Kunst: Welches Kunstwerk hat Ihr Leben ver\u00e4ndert?"},"content":{"rendered":"<p class=\"paragraph\">\u00bbOh my gosh\u00ab, sagte Gigi Hadid, <a href=\"https:\/\/www.instagram.com\/reels\/DX8Mh3VxKSR\/\" target=\"_blank\" rel=\"nofollow noopener\">als ihr auf der Met-Gala ein Reporter die Frage stellte, welches Kunstwerk ihr Leben ver\u00e4ndert h\u00e4tte<\/a>. Und fand nicht so recht eine Antwort. Verst\u00e4ndlich! Schlie\u00dflich ist die Welt voller beeindruckender Skulpturen, Gem\u00e4lde, Videos, Fotografien. Wir stellen einige vor, die uns gepr\u00e4gt haben.\n<\/p>\n<p class=\"paragraph\">Ich war ein<br \/>\nTeenager, als mir die erste Videoinstallation von Pipilotti Rist begegnete,<br \/>\noder vielmehr: zu mir sprach, als bek\u00e4me ich eine warme Einladung in einer mir<br \/>\nfremden Sprache. Noch nie hatte ich Kunst gesehen, die auf derma\u00dfen<br \/>\nunbehagliche Weise intim und komisch ist wie etwa ihr Video Ever Is Over All von 1997. Darin schreitet eine Frau in Sommerkleid und roten Schuhen durch eine<br \/>\nFu\u00dfg\u00e4ngerzone, heiter wie eine Anarchoversion von Dorothy aus Der Zauberer von<br \/>\nOz, und zerdeppert Autoscheiben mit einem Zepter in Lilienform. Sie lacht, eine<br \/>\npatrouillierende Polizistin gr\u00fc\u00dft, und ich bin wie hypnotisiert, so wundersch\u00f6n<br \/>\nungem\u00fctlich ist dieser Schwebezustand zwischen Anmut und Aggression.<br \/>Julia<br \/>\nLorenz\n<\/p>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"\u00bbOh my gosh\u00ab, sagte Gigi Hadid, als ihr auf der Met-Gala ein Reporter die Frage stellte, welches Kunstwerk&hellip;\n","protected":false},"author":2,"featured_media":1014182,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1775],"tags":[1793,2076,13682,29,214,13217,30,115656,2075,1794,14117,944,215],"class_list":{"0":"post-1014181","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kunst-und-design","8":"tag-art-and-design","9":"tag-ausstellung","10":"tag-claude-monet","11":"tag-deutschland","12":"tag-entertainment","13":"tag-feuilleton","14":"tag-germany","15":"tag-kaethe-kollwitz","16":"tag-kunst","17":"tag-kunst-und-design","18":"tag-kunstwerk","19":"tag-new-york","20":"tag-unterhaltung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116563366685596255","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1014181"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1014182"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1014181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1014181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1014181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}