{"id":1014216,"date":"2026-05-12T20:15:15","date_gmt":"2026-05-12T20:15:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1014216\/"},"modified":"2026-05-12T20:15:15","modified_gmt":"2026-05-12T20:15:15","slug":"bei-wiesbaden-blindgaenger-bei-kaserne-gefunden-bahnstrecke-und-a66-dicht","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1014216\/","title":{"rendered":"Bei Wiesbaden: Blindg\u00e4nger bei Kaserne gefunden \u2013 Bahnstrecke und A66 dicht"},"content":{"rendered":"<p>            Kopiere den aktuellen Link<\/p>\n<p>          Zur Merkliste hinzuf\u00fcgen<\/p>\n<p>Am Mittwoch soll eine Fliegerbombe bei Wiesbaden entsch\u00e4rft werden. Bahnstrecke und A66 sind ab dem Morgen gesperrt. Wer von den Evakuierungen betroffen ist.<\/p>\n<p class=\"typo-body-sc-md is-initial\">Ein 500-Kilo-Blindg\u00e4nger aus dem Zweiten Weltkrieg soll am Mittwoch bei <a class=\"taxonomy-entity place\" data-target-type=\"article\" href=\"https:\/\/www.stern.de\/politik\/deutschland\/themen\/wiesbaden-4155460.html\" rel=\"nofollow noopener\" target=\"_blank\">Wiesbaden<\/a> unsch\u00e4dlich gemacht werden. Die Bombe sei am Dienstagnachmittag bei Sondierungsarbeiten an der Zufahrt der Bundesstra\u00dfe 455 zur Lucius D. Clay Kaserne in Erbenheim gefunden worden, wie die Stadt mitteilte.\u00a0<\/p>\n<p class=\"typo-body-sc-md\">Rund 50 Einwohner rund um den Fundort m\u00fcssten deswegen am Mittwochmorgen ihre H\u00e4user verlassen. Die Entsch\u00e4rfung oder kontrollierte Sprengung sei f\u00fcr 11.00 Uhr geplant. Die amerikanische Fliegerbombe sei gesichert worden und werde bis zur Entsch\u00e4rfung bewacht.\u00a0<\/p>\n<p class=\"typo-body-sc-md\">Auch die Stra\u00dfen und <a class=\"taxonomy-entity keyword\" data-target-type=\"article\" href=\"https:\/\/www.stern.de\/panorama\/themen\/bahnstrecke-4119114.html\" rel=\"nofollow noopener\" target=\"_blank\">Bahnstrecken<\/a> in einem Radius von 700 Metern um den Fundort w\u00fcrden gesperrt. Betroffen seien somit auch die Bahntrasse Wiesbaden-K\u00f6ln und die A66 zwischen Erbenheim und Nordenstadt. Die Autobahn werde in dem Bereich ab 10.30 Uhr gesperrt.<\/p>\n<p>\n    dpa\n  <\/p>\n","protected":false},"excerpt":{"rendered":"Kopiere den aktuellen Link Zur Merkliste hinzuf\u00fcgen Am Mittwoch soll eine Fliegerbombe bei Wiesbaden entsch\u00e4rft werden. Bahnstrecke und&hellip;\n","protected":false},"author":2,"featured_media":1014217,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1847],"tags":[3364,29,548,663,3934,30,13,2052,14,15,12,4544],"class_list":{"0":"post-1014216","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-wiesbaden","8":"tag-de","9":"tag-deutschland","10":"tag-eu","11":"tag-europa","12":"tag-europe","13":"tag-germany","14":"tag-headlines","15":"tag-hessen","16":"tag-nachrichten","17":"tag-news","18":"tag-schlagzeilen","19":"tag-wiesbaden"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116563445519233014","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1014216"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1014217"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1014216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1014216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1014216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}