{"id":1014345,"date":"2026-05-12T21:25:25","date_gmt":"2026-05-12T21:25:25","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1014345\/"},"modified":"2026-05-12T21:25:25","modified_gmt":"2026-05-12T21:25:25","slug":"iran-krieg-aktuell-bericht-bringt-vermittler-pakistan-in-erklaerungsnot","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1014345\/","title":{"rendered":"Iran-Krieg aktuell: Bericht bringt Vermittler Pakistan in Erkl\u00e4rungsnot"},"content":{"rendered":"<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Zuvor hatte der US-Sender CBS News unter Berufung auf namentlich nicht genannte US-Regierungsvertreter berichtet, der Iran habe Flugzeuge nach Pakistan und <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" data-tracking=\"{&quot;action&quot;:&quot;click&quot;,&quot;category&quot;:&quot;intextLink&quot;,&quot;label&quot;:&quot;\/themen\/afghanistan\/&quot;}\" href=\"https:\/\/www.t-online.de\/themen\/afghanistan\/\" data-sctrack=\"BodyAnchor\" rel=\"nofollow noopener\" target=\"_blank\">Afghanistan<\/a> verbracht. Teheran habe kurz nach Trumps Verk\u00fcndung der Waffenruhe im April mehrere Milit\u00e4rflugzeuge auf eine Milit\u00e4rbasis in der N\u00e4he von Islamabad geflogen. Das pakistanische Au\u00dfenministerium wies den CBS-Bericht in einer Stellungnahme als &#8222;irref\u00fchrend und rei\u00dferisch&#8220; zur\u00fcck. Einige Flugzeuge des Iran und der USA seien nach Verk\u00fcndung der Waffenruhe in Pakistan angekommen, um die Logistik im Rahmen der Friedensverhandlungen der beiden L\u00e4nder in Islamabad zu unterst\u00fctzen. Einige Flugzeuge und Personal seien anschlie\u00dfend in Erwartung weiterer Gespr\u00e4che im Land verblieben.<\/p>\n<p>Teheran: USA wollen vollst\u00e4ndige Kapitulation Irans<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Mit Blick auf die Ungewissheit \u00fcber die Zukunft des Iran-Kriegs kritisiert Teheran die Verhandlungsstrategie der Vereinigten Staaten. Die USA strebten keine echten Verhandlungen an, sondern die vollst\u00e4ndige Kapitulation Irans, zitierte die iranische Nachrichtenagentur Isna Au\u00dfenamtssprecher Ismail Baghai. In einem Interview mit dem indischen Magazin &#8222;India Today Global&#8220; sagte der Sprecher demnach, statt einer Geben- und Nehmen-Diplomatie verfolgten die USA mit ihren Forderungen die Unterordnung seines Landes.<\/p>\n<p><a href=\"#focus-1\" class=\"transition-colors duration-200 block text-current relative\" data-sctrack=\"FocusGalleryImage.Reference\"><img   loading=\"lazy\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/ismail-baghai-sprecher-des-iranischen-aussenministeriums.jpg\" alt=\"urn:newsml:dpa.com:20090101:260421-935-1294005\" title=\"urn:newsml:dpa.com:20090101:260421-935-1294005\" width=\"1386\" height=\"780\" class=\"h-full w-full max-w-full rounded-8\" decoding=\"async\"\/><img loading=\"lazy\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/zoom-in.f7dae02f.svg\" alt=\"Vergr\u00f6\u00dfern des Bildes\" title=\"Vergr\u00f6\u00dfern des Bildes\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none absolute bottom-8 right-8 rounded-4 bg-snow p-8\" style=\"--width:32;--height:32\" decoding=\"async\"\/>Ismail Baghai, Sprecher des iranischen Au\u00dfenministeriums. (Quelle: Shadati)<\/a><\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Den USA gehe es nicht um eine friedliche L\u00f6sung, sondern um ein Kapitulationsdokument, schrieb auch der iranische Vizeau\u00dfenminister Kasem Gharibabadi auf X. Der Standpunkt Irans sei eindeutig: Man wolle eine Beendigung der Kampfhandlungen, keine Wiederaufnahme des Konflikts, Entsch\u00e4digungen, ein Ende der Blockade, Aufhebung von Sanktionen sowie die Achtung internationaler Rechte des Iran.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">US-Pr\u00e4sident Donald Trump hatte am Montag die seit fast f\u00fcnf Wochen dauernde Waffenruhe \u00f6ffentlich infrage gestellt. Grund daf\u00fcr sei der &#8222;d\u00e4mliche Vorschlag&#8220; aus Teheran zur Beendigung des Krieges. Er nahm dabei Bezug auf ein Verhandlungsdokument, das die iranische Seite \u00fcbermittelt hatte. Aus Parlamentskreisen in Teheran hie\u00df es am Dienstag, dass die iranische Regierung ein Wiederaufflammen der Kampfhandlungen f\u00fcr wahrscheinlich halte. Eine gut informierte Quelle sagte, es gebe keine Entwicklungen mit Blick auf die Verhandlungen zwischen Teheran und Washington.<\/p>\n<p>Pentagon: Iran-Krieg kostete &#8222;eher&#8220; 29 Milliarden Dollar<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Die Kosten des Iran-Krieges f\u00fcr die Vereinigten Staaten sind nach Sch\u00e4tzungen eines hochrangigen Pentagon-Mitarbeiters deutlich gestiegen. Die Ausgaben l\u00e4gen mittlerweile &#8222;eher&#8220; bei 29 Milliarden <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" data-tracking=\"{&quot;action&quot;:&quot;click&quot;,&quot;category&quot;:&quot;intextLink&quot;,&quot;label&quot;:&quot;\/finanzen\/boerse\/waehrung\/eur-usd\/eu0009652759\/&quot;}\" href=\"https:\/\/www.t-online.de\/finanzen\/boerse\/waehrung\/eur-usd\/eu0009652759\/\" data-sctrack=\"BodyAnchor\" rel=\"nofollow noopener\" target=\"_blank\">US-Dollar<\/a> (gut 24,6 Milliarden Euro), sagte Jules W. Hurst III bei einer Anh\u00f6rung des Repr\u00e4sentantenhauses. Grund daf\u00fcr seien Reparatur- und Ersatzbeschaffungen sowie &#8222;allgemeine Betriebskosten&#8220;.<\/p>\n<p>Loading&#8230;<\/p>\n<p>Loading&#8230;<\/p>\n<p>Loading&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"Zuvor hatte der US-Sender CBS News unter Berufung auf namentlich nicht genannte US-Regierungsvertreter berichtet, der Iran habe Flugzeuge&hellip;\n","protected":false},"author":2,"featured_media":1014346,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1217,326,848,7451,12315,45578,227,68302,106,13,345,186871,79885,218297,411,213106,4045,32794,409,451,14,15,3129,10670,1614,649,1555,12,29839,9976,44827,10,8,9,11,64,831,28955,320,103,104,10257],"class_list":{"0":"post-1014345","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-welt","8":"tag-1217","9":"tag-326","10":"tag-aa","11":"tag-afghanistan","12":"tag-aussenministerium-der-vereinigten-staaten","13":"tag-cbs-news","14":"tag-china","15":"tag-dan-caine","16":"tag-donald-trump","17":"tag-headlines","18":"tag-iran","19":"tag-iran-krieg","20":"tag-islamabad","21":"tag-ismail-baghai","22":"tag-israel","23":"tag-jules-w","24":"tag-konflikt","25":"tag-lindsey-graham","26":"tag-marco-rubio","27":"tag-militaer","28":"tag-nachrichten","29":"tag-news","30":"tag-newsblog","31":"tag-pakistan","32":"tag-peking","33":"tag-pete-hegseth","34":"tag-republikaner","35":"tag-schlagzeilen","36":"tag-strasse-von-hormus","37":"tag-teheran","38":"tag-tommy-pigott","39":"tag-top-news","40":"tag-top-meldungen","41":"tag-topmeldungen","42":"tag-topnews","43":"tag-usa","44":"tag-vereinigte-arabische-emirate","45":"tag-wang-yi","46":"tag-washington","47":"tag-welt","48":"tag-world","49":"tag-xi-jinping"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1014345"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1014346"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1014345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1014345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1014345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}