{"id":1014412,"date":"2026-05-12T22:01:23","date_gmt":"2026-05-12T22:01:23","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1014412\/"},"modified":"2026-05-12T22:01:23","modified_gmt":"2026-05-12T22:01:23","slug":"msv-news-kw-20-duisburg-trainiert-nur-noch-oeffentlich","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1014412\/","title":{"rendered":"MSV-News KW 20: Duisburg trainiert nur noch \u00f6ffentlich"},"content":{"rendered":"<p>Im w\u00f6chentlichen \u00dcberblick bringt euch FuPa Niederrhein die aktuellen News rund um den MSV Duisburg direkt auf euer mobiles Endger\u00e4t. In KW20 gibt es im Zebrastall einen Aufstieg zu feiern. Die Frauen sind souver\u00e4n Meister in der Niederrheinliga geworden. Auch die Amateure k\u00f6nnen auf ein siegreiches Wochenende zur\u00fcckblicken. F\u00fcr die Profis geht es am letzten Spieltag in der 3. Liga um den Aufstieg. Gegen Viktoria K\u00f6ln muss ein Sieg her.<\/p>\n<p> 12. Mai, 15.30 Uhr: Zebras trainieren \u00f6ffentlich <\/p>\n<p>Der Trainingsplan der Zebras hat sich noch einmal ver\u00e4ndert. Die zun\u00e4chst als nicht-\u00f6ffentlich geplante Einheit am Donnerstag findet nun doch mit Zuschauern statt. Damit k\u00f6nnen interessierte Fans an jedem Tag an der Westender Stra\u00dfe vorbeischauen und beobachten, wie sich das Team auf den Showdown am letzten Spieltag vorbereitet. Mit dem Ball ge\u00fcbt wird am Dienstag, Mittwoch und Donnerstag jeweils um 11 Uhr, das Abschlusstraining am Freitag steigt um 14 Uhr.<\/p>\n<p> 11. Mai, 11 Uhr: Frauen steigen souver\u00e4n auf So., 10.05.2026, 17:00 Uhr  <\/p>\n<p>Es war eine beeindruckende Saison, die die Frauen des MSV Duisburg gespielt haben. Nun haben sie vorzeitig den Aufstieg in die Regionalliga West einget\u00fctet und damit im ersten Jahr nach dem Neustart gleich das erste Zwischenziel erreicht. Durch den 1:0-Erfolg beim TSV Urdenbach steht der Aufstieg drei Spieltage vor dem Ende der Saison fest, Verfolger Rhenania Bottrop kann den R\u00fcckstand nicht mehr aufholen. In bislang 21 Begegnungen in der Niederrheinliga gingen die Zebra-Frauen 20 Mal als Sieger vom Feld, nur ein einziges Mal mussten sie sich geschlagen geben. 66 erzielte und nur sieben Kassierte Tore sprechen auf der Statistik-Seite eine eindeutige Sprache.<\/p>\n<p>Ein Doppelpack von Jan Niklas Kempf sicherte den MSV-Amateuren drei Punkte gegen Blau-Wei\u00df Neuenkamp. In der Schlussphase der ersten H\u00e4lfte lie\u00df Kempf die Zuschauer zum ersten Mal jubeln (36.), doch die G\u00e4ste schlugen unmittelbar darauf zur\u00fcck. Hanson Acheampong Iddrisu glich nur drei Zeigerumdrehungen sp\u00e4ter aus. Auch im zweiten Durchgang stand vor allem die Schlussphase im Fokus. Zun\u00e4chst gab es die Ampelkarte f\u00fcr Adriano Lenz, wodurch Neuenkamp nur noch mit zehn Spielern auf dem Feld stand. Kempf nutzte das wenig sp\u00e4ter und erzielte den 2:1-Endstand (81.). In der Nachspielzeit gab es dann noch glatt Rot f\u00fcr BWN-Kicker Juanito Vincenzo Mettbach. Bei noch zwei ausstehenden Partien belegen die Zebras mit 47 Punkten den f\u00fcnften Tabellenplatz. Weiter geht es erst am 31. Mai, dann gastiert Gr\u00fcn-Wei\u00df Roland Meiderich im Stadtteilduell an der Westender Stra\u00dfe.<\/p>\n<p> 11. Mai, 8 Uhr: So trainieren die Zebras <\/p>\n<p>Es geht in den Endspurt in der 3. Liga. Nur noch ein Spiel steht f\u00fcr den MSV Duisburg im Terminkalender, in dem entscheidet sich auch, ob es im kommenden Jahr in der 2. Bundesliga oder der 3. Liga weitergeht. Auch der Gang in die Relegation ist noch eine Option. Um auf den Opponent am Samstag, Viktoria K\u00f6ln, perfekt vorbereitet zu sein, bittet Cheftrainer Dietmar Hirsch nach zwei freien Tagen am Dienstag zum ersten Training in dieser Woche. P\u00fcnktlich um 11 Uhr stehen seine Mannen dann auf dem Trainingsplatz, wie auch am Mittwoch. Die Einheit am Donnerstag findet nicht-\u00f6ffentlich statt. Das Abschlusstraining am Freitag beginnt um 14 Uhr.<\/p>\n<p>  ____ <\/p>\n<p>\ud83d\udcf0 Alle aktuellen Nachrichten: <a href=\"https:\/\/www.fupa.net\/region\/niederrhein\/news\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.fupa.net\/region\/niederrhein\/news<\/a><\/p>\n<p>\ud83d\udcdd Alle aktuellen Transfers: <a href=\"https:\/\/www.fupa.net\/region\/niederrhein\/transfer\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.fupa.net\/region\/niederrhein\/transfer<\/a><\/p>\n<p>\u26bd Die Spiele des Tages: <a href=\"https:\/\/www.fupa.net\/region\/niederrhein\/matches\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.fupa.net\/region\/niederrhein\/matches<\/a><\/p>\n<p> ____ <\/p>\n<p>Dein Kontakt zur FuPa-Redaktion:<\/p>\n","protected":false},"excerpt":{"rendered":"Im w\u00f6chentlichen \u00dcberblick bringt euch FuPa Niederrhein die aktuellen News rund um den MSV Duisburg direkt auf euer&hellip;\n","protected":false},"author":2,"featured_media":1010614,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1838],"tags":[995,217649,3364,29,3715,30275,104135,30,17794,45562,3721,1209,29819,6921],"class_list":{"0":"post-1014412","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-duisburg","8":"tag-3-liga","9":"tag-blau-weiss-neuenkamp","10":"tag-de","11":"tag-deutschland","12":"tag-duisburg","13":"tag-duisburg-muelheim-dinslaken","14":"tag-frauen-niederrheinliga","15":"tag-germany","16":"tag-gruppe-2","17":"tag-kreisliga-c","18":"tag-msv-duisburg","19":"tag-nordrhein-westfalen","20":"tag-tsv-urdenbach","21":"tag-viktoria-koeln"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116563862595485399","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1014412"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1010614"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1014412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1014412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1014412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}