{"id":1014788,"date":"2026-05-13T01:32:19","date_gmt":"2026-05-13T01:32:19","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1014788\/"},"modified":"2026-05-13T01:32:19","modified_gmt":"2026-05-13T01:32:19","slug":"real-madrid-ploetzlich-not-pressekonferenz-heute-abend-sport","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1014788\/","title":{"rendered":"Real Madrid: Pl\u00f6tzlich Not-Pressekonferenz heute Abend! | Sport"},"content":{"rendered":"<p><a class=\"skip-content skip-content--link\" href=\"#in-content-skip-link-target-v-0-0\">TTS-Player \u00fcberspringen\u21b5<\/a><a id=\"in-content-skip-link-target-v-0-0\" class=\"skip-content--target-link-hidden skip-content skip-content--target-link\" href=\"#in-content-skip-link-target-v-0-0\">Artikel weiterlesen<\/a><\/p>\n<p><b>Was ist denn da los? Bei Real Madrid herrscht aktuell Chaos vor. Am sp\u00e4ten Nachmittag k\u00fcndigen die K\u00f6niglichen in den sozialen Medien pl\u00f6tzlich eine Not-Pressekonferenz an. Diese soll um 18 Uhr stattfinden. Vermeldet von Real um 16.10 Uhr auf X, also gerade einmal mit 1 Stunde und 50 Minuten Vorlauf!<\/b><\/p>\n<p>In der Mitteilung dazu hei\u00dft es: \u201eReal Madrid gibt bekannt, dass heute Nachmittag um 18 Uhr Pr\u00e4sident Florentino P\u00e9rez nach der Sitzung des Vorstands im Presseraum von Real Madrid auftreten und sich in einer Pressekonferenz an die Medien wenden wird.\u201c<\/p>\n<p> An dieser Stelle findest du Inhalte aus Twitter <\/p>\n<p> Um mit Inhalten aus Twitter und anderen sozialen Netzwerken zu interagieren oder diese darzustellen, brauchen wir deine Zustimmung. <\/p>\n<p> soziale Netzwerke aktivieren  Um eingebettete Inhalte anzuzeigen, ist Ihre jederzeit widerrufliche Einwilligung (\u00fcber den Schalter oder \u00fcber &#8220; <a class=\"embed-placeholder__text-link\" href=\"#\" rel=\"noopener noreferrer\" title=\"Tracking widerrufen\"> Widerruf Tracking und Cookies<\/a> &#8220; am Seitenende) zur Verarbeitung personenbezogener Daten n\u00f6tig.  Dabei k\u00f6nnen Daten in Drittl\u00e4nder wie die USA \u00fcbermittelt werden (Art. 49 Abs. 1 lit. a DSGVO). Mit dem Aktivieren des Inhalts stimmen Sie zu. Weitere Infos finden Sie <a class=\"embed-placeholder__text-link\" href=\"#\" rel=\"noopener noreferrer\" title=\"Zu den Privatsph\u00e4re Einstellungen\"> hier<\/a>. Drei Szenarien in den spanischen Medien<\/p>\n<p>Aktuell ist noch v\u00f6llig unklar, worum es gehen k\u00f6nnte. In der spanischen Presse und bei den Real-Fans wird schon wild spekuliert. Dabei werden drei m\u00f6gliche Szenarien genannt.<\/p>\n<p>1. P\u00e9rez k\u00f6nnte im Anschluss an die Vorstandssitzung mit seinen eigenen Stars abrechnen. Diese hatten in der laufenden Saison auf ganzer Linie entt\u00e4uscht. Die Horror-Bilanz von <a href=\"https:\/\/www.bild.de\/sport\/fussball\/real-madrid\/real-madrid-alle-infos-79564306.bild.html\" target=\"_blank\" rel=\"nofollow noopener\" class=\"text-link\">Real<\/a>: In der Liga abgeschlagen nur Platz 2 (drei Spieltage vor Schluss 14 Punkte R\u00fcckstand auf Bar\u00e7a), in der <a href=\"https:\/\/www.bild.de\/sport\/fussball\/champions-league\/home-15770784.bild.html\" target=\"_blank\" rel=\"nofollow noopener\" class=\"text-link\">Champions League<\/a> im Viertelfinale an den Bayern gescheitert (1:2\/3:4) und im Pokal blamabel im Achtelfinale beim Zweitligisten Albacete (2:3) raus.<\/p>\n<p>2. Es k\u00f6nnte eine Entscheidung geben, was die Trainerfrage betrifft. Klar ist bereits, dass es mit Alvaro Arbeloa (43) nicht \u00fcber die aktuelle Saison hinaus weitergehen wird. Der Spanier hatte das Amt erst im Januar vom gefeuerten Xabi Alonso (44\/zuvor 2024 Double-Sieger mit Leverkusen) \u00fcbernommen. Als Top-Favorit auf die Arbeloa-Nachfolge gilt <a href=\"https:\/\/www.bild.de\/sport\/fussball\/trainer-knall-bei-real-madrid-um-jose-mourinho-6a031202453b15e1190761b0\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Jos\u00e9 Mourinho<\/a> (63\/aktuell Benfica-Coach), der Real schon von 2010 bis 2013 trainiert hatte. Der Transfer-Journalist Sacha Tavolieri berichtet auf X (\u00fcber 200.000 Follower) sogar schon von einem abgeschlossenen Deal. Nach BILD-Informationen gibt es aber noch keinen Vollzug bei Mourinho und Real.<\/p>\n<p>Mehr zum Thema<\/p>\n<p>3. Vereinzelt halten es Fans sogar f\u00fcr m\u00f6glich, dass P\u00e9rez selbst seinen Hut nehmen k\u00f6nnte. Das w\u00e4re allerdings eine extrem gro\u00dfe \u00dcberraschung. Der Spanier ist seit 2009 ununterbrochen Pr\u00e4sident von Real Madrid. <\/p>\n<p>Zuletzt schon Chaos bei Real um Valverde<\/p>\n<p>Kurz vor der Cl\u00e1sico-Pleite (0:2), durch welche die Meisterschaft des gro\u00dfen Rivalen Bar\u00e7a in der spanischen La Liga besiegelt wurde, gab es schon gro\u00dfen \u00c4rger bei Real. Kapit\u00e4n <a href=\"https:\/\/www.bild.de\/sport\/fussball\/real-madrid-fede-valverede-aurelien-tchouameni-star-aeussert-sich-zum-kabinen-zoff-69fd7b0d30e98e4ac324e128\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Fede Valverde<\/a> (27) musste nach einer Auseinandersetzung mit seinem Teamkollegen Aur\u00e9lien Tchouam\u00e9ni (26) ins Krankenhaus eingeliefert werden. Valverde stellte dazu klar: \u201eW\u00e4hrend des Streits stie\u00df ich mir versehentlich den Kopf an einem Tisch und zog mir dabei eine kleine Schnittwunde an der Stirn zu, die einen Routinebesuch im Krankenhaus erforderlich machte.\u201c<\/p>\n<p>M\u00f6glicherweise versinkt Real jetzt noch tiefer im Chaos &#8230;<\/p>\n<p>Verschw\u00f6rung, Kampagne &amp; Real-Pr\u00fcgelei: Die bizarre Perez-Show im Video<a class=\"anchor video-teaser__anchor\" href=\"https:\/\/www.bild.de\/sport\/fussball\/verschwoerung-kampagne-real-pruegelei-die-bizarre-perez-show-im-video-6a037d2d9e875c402d54ede7\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" width=\"992\" height=\"558\" alt=\"\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/a64cd71f8044815152fa2f88377de5fa-landscape,913f299b.jpeg\"   class=\"landscape teaser__image\" loading=\"lazy\"\/><\/a><\/p>\n<p>Quelle: Reuters, BILD12.05.2026<\/p>\n","protected":false},"excerpt":{"rendered":"TTS-Player \u00fcberspringen\u21b5Artikel weiterlesen Was ist denn da los? Bei Real Madrid herrscht aktuell Chaos vor. Am sp\u00e4ten Nachmittag&hellip;\n","protected":false},"author":2,"featured_media":1014789,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[218376,1263,8834,13,14,15,25275,3349,12,10,8,9,11,10057],"class_list":{"0":"post-1014788","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nachrichten","8":"tag-arbeloa","9":"tag-aufmacher-bereich","10":"tag-fc-barcelona","11":"tag-headlines","12":"tag-nachrichten","13":"tag-news","14":"tag-primera-division-la-liga","15":"tag-real-madrid","16":"tag-schlagzeilen","17":"tag-top-news","18":"tag-top-meldungen","19":"tag-topmeldungen","20":"tag-topnews","21":"tag-xabi-alonso"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116564692109332922","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1014788"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1014789"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1014788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1014788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1014788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}