{"id":1014932,"date":"2026-05-13T02:56:25","date_gmt":"2026-05-13T02:56:25","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1014932\/"},"modified":"2026-05-13T02:56:25","modified_gmt":"2026-05-13T02:56:25","slug":"usa-schicken-gesandten-nach-groenland-kann-trump-daenemarks-regierungschaos-fuer-sich-nutzen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1014932\/","title":{"rendered":"USA schicken Gesandten nach Gr\u00f6nland: Kann Trump D\u00e4nemarks Regierungschaos f\u00fcr sich nutzen?"},"content":{"rendered":"<p class=\"tspA5jq tspA5jr\">Immer wieder heimst Mette Frederiksen Rekorde ein. Vor fast genau sieben Jahren wurde die damals 41 Jahre alte Sozialdemokratin im Juni 2019 zur j\u00fcngsten Regierungschefin D\u00e4nemarks gew\u00e4hlt. Bei ihrer Wiederwahl drei Jahre sp\u00e4ter vergingen volle 44 Tage, ehe Frederiksen eine neue Regierung bilden konnte. Auch das war d\u00e4nischer Rekord. <\/p>\n<p class=\"tspA5jq\">Bei den <a href=\"https:\/\/www.tagesspiegel.de\/internationales\/danemarks-mette-frederiksen-eine-wahlgewinnerin-die-keine-ist-15396449.html?icid=in-text-link_15588210\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" rel=\"nofollow noopener\" target=\"_blank\">Parlamentswahlen Ende M\u00e4rz dieses Jahres wurden die Genossinnen und Genossen um die Regierungschefin zwar st\u00e4rkste Kraft<\/a>, fuhren aber das schlechteste Ergebnis seit mehr als 120 Jahren ein. Ein Rekord, auf den die 48 Jahre alte Frederiksen sicher gern verzichtet h\u00e4tte. <\/p>\n<p class=\"tspA5jq\">Seitdem sind am Dienstag bereits 50 Tage vergangen \u2013 und das skandinavische K\u00f6nigreich hat noch immer keine funktionierende Regierung. Eine H\u00f6chstmarke, die wom\u00f6glich nicht mehr Frederiksen angerechnet werden kann. Denn der <a href=\"https:\/\/www.tagesspiegel.de\/internationales\/verhandlungen-nach-wahl-rechtsliberaler-will-regierung-in-danemark-bilden-15576729.html?icid=in-text-link_15588210\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" rel=\"nofollow noopener\" target=\"_blank\">Auftrag zur Bildung einer neuen Regierung wurde ihr vom K\u00f6nig am Wochenende offiziell entzogen<\/a>. Die Wahlgewinnerin, die eigentlich nie eine war, schaut nur noch von der Seitenlinie zu \u2013 und D\u00e4nemark steht inmitten einer der schwersten au\u00dfenpolitischen Krisen seit nunmehr sieben Wochen ohne stabile Regierung da. <\/p>\n<p> Zersplittertes Parteiensystem  <\/p>\n<p class=\"tspA5jq\">Der amtierende Au\u00dfenminister und Frederiksens Koalitionspartner von der zentristischen Moderaterne, Lars L\u00f8kke Rasmussen, hat am Freitag \u00fcberraschend die Gespr\u00e4che mit der Sozialdemokratin abgebrochen. Dabei hatte es das Duo in den vergangenen Monaten international zu einiger Bekanntheit gebracht: <a href=\"https:\/\/www.tagesspiegel.de\/internationales\/der-kampf-um-gronland-wir-haben-weiterhin-grundlegende-meinungsverschiedenheiten-15138151.html?icid=in-text-link_15588210\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" rel=\"nofollow noopener\" target=\"_blank\">als erfolgreiche Widerst\u00e4ndler gegen die imperialistischen Einverleibungsfantasien des US-Pr\u00e4sidenten Donald Trump und damit als Besch\u00fctzer der zu D\u00e4nemark geh\u00f6renden Insel Gr\u00f6nland<\/a>.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/denmark-politics-vote.jpeg\"   alt=\"Acting Danish Prime Minister Mette Frederiksen arrives for a meeting with appointed royal investigator Troels Lund Poulsen on negotiations to form a government, in Copenhagen, Denmark, on May 11, 2026. (Photo by Mads Claus Rasmussen \/ Ritzau Scanpix \/ AFP) \/ Denmark OUT\" aria-labelledby=\"caption-15588980\" width=\"440\" height=\"330\" loading=\"lazy\" class=\"tspALhn\"\/> Schrieb zuletzt innenpolitisch zwar einige Rekorde, aber nur wenige Erfolgsmeldungen: D\u00e4nemarks amtierende Regierungschefin Mette Frederiksen.  <\/p>\n<p class=\"tspXft\"> \u00a9 AFP\/Mads Claus Rasmussen <\/p>\n<p class=\"tspA5jq\">An Lars L\u00f8kke Rasmussen f\u00fchrt zumindest eine stabile Regierung nicht vorbei. Sowohl der linke als auch der rechte Parteienblock ben\u00f6tigen seine Zustimmung f\u00fcr die absolute Mehrheit. Dessen Ziel ist eine Neuauflage der Mitte-Koalition von Sozialdemokraten, Moderaten und Liberalen, unterst\u00fctzt von kleineren Juniorpartnern \u2013 und unter F\u00fchrung Mette Frederiksens als Vorsitzende der st\u00e4rksten Partei. Mit dem Abbruch der Gespr\u00e4che versuche L\u00f8kke, \u201emaximalen Druck auf die anderen Parteien auszu\u00fcben\u201c, sagt Rune Stubager dem Tagesspiegel. An der Universit\u00e4t Aarhus forscht der Politikwissenschaftler unter anderem zum Parteiensystem in D\u00e4nemark. <\/p>\n<p class=\"tspA5jq\">Neu mit der Regierungsbildung beauftragt ist nun der Parteichef der liberalen Venstre-Partei und amtierende Verteidigungsminister Troels Lund Poulsen. Er soll es nun in Kopenhagen richten \u2013 oder zumindest die Chancen f\u00fcr seine Wunschkoalition rechts der Mitte ausloten. Lund Poulsens rechtsliberale Partei Venstre kam Ende M\u00e4rz nur auf die drittmeisten Stimmen und fuhr zugleich das schlechteste Ergebnis seit 1987 ein, ein vielversprechenderer Kandidat im rechten Parteienblock l\u00e4sst sich in Kopenhagen momentan aber kaum finden.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/rune-stubager-foto-taget-af-ashraf-rachid.jpeg\"   alt=\"Ashraf Rachid Name: Rune Stubager Info: Rune Stubager forscht als Politikwissenschaftler an der Universit\u00e4t Aarhus unter anderem zum Parteiensystem in D\u00e4nemark.\" width=\"80\" height=\"80\" loading=\"lazy\" class=\"tspALhn\"\/><\/p>\n<p class=\"tspCQqc\"><strong>Rune Stubager<\/strong> forscht als Politikwissenschaftler an der Universit\u00e4t Aarhus unter anderem zum Parteiensystem in D\u00e4nemark.<\/p>\n<p class=\"tspA5jq\">Das ist der Zersplitterung des d\u00e4nischen Parteiensystems geschuldet, dass nun nach Frederiksen ausgerechnet der n\u00e4chste gro\u00dfe Wahlverlierer eine stabile Regierung bilden soll. Es gibt zw\u00f6lf Parteien im Parlament, nur drei von ihnen haben mehr als zehn Prozent der Stimmen.<\/p>\n<p class=\"tspA5jq\">Dabei muss der Chef der Liberalen auch auf die vor Selbstbewusstsein strotzenden Rechten der D\u00e4nischen Volkspartei setzen. Die Nationalisten konnten ihr Ergebnis mehr als verdreifachen, fordern von einer zuk\u00fcnftigen Regierung ausdr\u00fccklich, \u201e<a href=\"https:\/\/www.kongehuset.dk\/nyheder\/ny-forhandlingsleder-udpeget\" target=\"_blank\" rel=\"noopener nofollow\" class=\"link link--external\" data-gtm-class=\"article-text-link\" data-gtm-val=\"external\" aria-describedby=\"message-target-blank\">Ma\u00dfnahmen einzuf\u00fchren, die zu einer Nettoauswanderung von Muslimen aus D\u00e4nemark f\u00fchren<\/a>\u201c \u2013 und keine Beteiligung von Sozialdemokraten oder Moderaten.<\/p>\n<p class=\"tspA5jq\">F\u00fcr eine Mehrheit im Folketing, dem Parlament, ben\u00f6tigt allerdings auch der rechte Block wenigstens die Moderaten um den amtierenden Au\u00dfenminister \u2013 und K\u00f6nigsmacher \u2013 Lars L\u00f8kke Rasmussen. <\/p>\n<p> Gr\u00f6nlands Regierungschef w\u00fcnscht sich \u201ebald\u201c neue Regierung <\/p>\n<p class=\"tspA5jq\">Am Ende k\u00f6nnte es nach wochenlangen Verhandlungen und Gespr\u00e4chen fast zu einer Neuauflage der alten Regierung und Mette Frederiksens dritter Amtszeit kommen, das w\u00e4re ihr n\u00e4chster Rekord.<\/p>\n<p class=\"tspA5jq\">Wie realistisch das ist, lasse sich aktuell \u201eziemlich schwierig einsch\u00e4tzen\u201c, sagt Politologe Rune Stubager. Insbesondere zwischen Sozialdemokraten und Liberalen herrsche nach vier Jahren gemeinsamer Regierungszeit tiefes Misstrauen. Au\u00dferdem seien die Liberalen der Meinung, dass die Sozialdemokraten sie im Wahlkampf unfair behandelt h\u00e4tten: \u201eAlles in allem kein guter Ausgangspunkt f\u00fcr eine neue Zusammenarbeit.\u201c<\/p>\n<p><a href=\"https:\/\/www.tagesspiegel.de\/internationales\/niels-brimnes-interview-15216675.html?icid=single-topic_15588210___\" data-gtm-class=\"article-mzt-link\" class=\"tspDBry\" rel=\"nofollow noopener\" target=\"_blank\">D\u00e4nemarks dunkle Geschichte \u201eGr\u00f6nland wurde wie ein Entwicklungsland behandelt\u201c <\/a><\/p>\n<p class=\"tspA5jq\">Im mehr als 3.500 Kilometer entfernten Nuuk blickt die Autonomieregierung auf das politische Tauziehen in Kopenhagen mit immer gr\u00f6\u00dferer Sorge. Gr\u00f6nlands Regierungschef Jens-Frederik Nielsen sagte <a href=\"https:\/\/www.sermitsiaq.ag\/samfund\/jens-frederik-nielsen-ved-endnu-ikke-om-han-skal-modes-med-jeff-landry\/2382641\" target=\"_blank\" rel=\"noopener nofollow\" class=\"link link--external\" data-gtm-class=\"article-text-link\" data-gtm-val=\"external\" aria-describedby=\"message-target-blank\">der Tageszeitung \u201eSermitsiaq\u201c zufolge am Dienstag<\/a>, dass er sich \u201ebald eine d\u00e4nische Regierung\u201c w\u00fcnsche. \u201eDas w\u00e4re gro\u00dfartig f\u00fcr uns in Gr\u00f6nland. Denn wenn wir \u00fcber Au\u00dfenpolitik, Verteidigung und so weiter sprechen, geht es um das K\u00f6nigreich D\u00e4nemark, also um Gr\u00f6nland und D\u00e4nemark gemeinsam.\u201c<\/p>\n<p>Streit um Gr\u00f6nland<\/p>\n<p class=\"tspA5jq\">US-Pr\u00e4sident Donald Trump beharrt darauf, dass die USA Gr\u00f6nland aus Gr\u00fcnden der \u201enationalen Sicherheit\u201c annektieren m\u00fcssten. Auch den Einsatz milit\u00e4rischer Gewalt haben Mitglieder der Trump-Regierung nicht ausgeschlossen.<\/p>\n<p class=\"tspA5jq\">Als gr\u00f6\u00dfte Insel der Welt liegt Gr\u00f6nland im Nordatlantik zwischen Europa und Nordamerika. \u00dcber 80 Prozent der mehr als zwei Millionen Quadratkilometer Fl\u00e4che sind von Eis \u00fcberzogen. Die Insel ist etwa sechsmal so gro\u00df wie Deutschland. Aufgrund der Klimakrise \u00f6ffnen sich durch das Abschmelzen des Eises neue Schifffahrtsrouten.<\/p>\n<p class=\"tspA5jq\"><strong>Bev\u00f6lkerung<\/strong>: Knapp 57.000 Menschen leben auf Gr\u00f6nland, ein Gro\u00dfteil davon sind indigene Kalaallit. Die Insel ist fast ausschlie\u00dflich an den eisfreien K\u00fcsten bewohnbar.<\/p>\n<p class=\"tspA5jq\"><strong>Geschichte<\/strong>: Erstmals besiedelt worden ist Gr\u00f6nland vor mehr als 4400 Jahren von Inuit aus Nordamerika. Von 1721 bis 1953 wurde Gr\u00f6nland durch D\u00e4nemark kolonisiert, seit 1979 besitzt es innenpolitische Autonomie. Seit 2009 ist die Insel selbstverwalteter Teil des K\u00f6nigreichs D\u00e4nemark. Au\u00dfen- und Verteidigungspolitik bleiben in d\u00e4nischer Hand.<\/p>\n<p class=\"tspA5jq\"><strong>Bodensch\u00e4tze<\/strong>: Unter dem riesigen Inlandseis werden massive Rohstoffe vermutet, darunter seltene Erden, Gold, Eisen und Kupfer, dazu \u00d6l und Gas an den K\u00fcsten. Die Geological Survey of Denmark and Greenland sch\u00e4tzt, dass 25 der 34 kritischen Rohstoffe der EU auf Gr\u00f6nland zu finden sind.<\/p>\n<p class=\"tspA5jq\"><strong>Milit\u00e4r<\/strong>: Wegen der Besetzung D\u00e4nemarks durch Nazideutschland im Zweiten Weltkrieg sind die USA seit 1941 auf der Insel pr\u00e4sent. Es sollte verhindert werden, dass die Wehrmacht Gr\u00f6nland als Sprungbrett Richtung Nordamerika nutzen kann. Seit 1951 gibt es zwischen D\u00e4nemark und den USA einen bilateralen Vertrag, der Washington den Aufbau milit\u00e4rischer St\u00fctzpunkte gew\u00e4hrt. Heute ist die Pituffik Space Base im Nordwesten der einzige US\u2011St\u00fctzpunkt. Er dient haupts\u00e4chlich der Raketen\u00fcberwachung. (mb)<\/p>\n<p class=\"tspA5jq\">Kommende Woche findet auf der weltweit gr\u00f6\u00dften Insel die Konferenz \u201eFuture Greenland\u201c statt \u2013 auch Jeff Landry, der umstrittene Sondergesandte des US-Pr\u00e4sidenten, soll daran teilnehmen. Anders als hohe Vertreter und Vertreterinnen der d\u00e4nischen Regierung, <a href=\"https:\/\/futuregreenland.gl\/en\/future-greenland\/future-greenland-2026\/participant-list\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"link link--external\" data-gtm-class=\"article-text-link\" data-gtm-val=\"external\" aria-describedby=\"message-target-blank\">die in Nuuk der offiziellen Teilnahmeliste zufolge fehlen werden<\/a>. <\/p>\n<p><a href=\"https:\/\/www.tagesspiegel.de\/internationales\/dane-protestiert-mit-wortspielen-gegen-trump-es-begann-als-witz-und-wurde-zur-bewegung-15244312.html?icid=single-topic_15588210___\" data-gtm-class=\"article-mzt-link\" class=\"tspDBry\" rel=\"nofollow noopener\" target=\"_blank\">D\u00e4ne protestiert mit Wortspielen gegen Trump \u201eEs begann als Witz und wurde zur Bewegung\u201c <\/a><\/p>\n<p class=\"tspA5jq\">Die Beziehungen zwischen D\u00e4nemark, den USA und Gr\u00f6nland sind so schlecht wie seit dem Zweiten Weltkrieg nicht mehr. Trump droht der Arktisinsel immer unverhohlener mit milit\u00e4rischer \u00dcbernahme. <a href=\"https:\/\/www.tagesspiegel.de\/internationales\/das-ist-ein-bedeutender-wandel-danemark-stuft-die-usa-als-bedrohung-ein--wie-russland-und-china-15039124.html?icid=in-text-link_15588210\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" rel=\"nofollow noopener\" target=\"_blank\">Mitte Dezember stufte der milit\u00e4rische Nachrichtendienst D\u00e4nemarks den langj\u00e4hrigen Partner und Nato-Verb\u00fcndeten deshalb erstmals als Bedrohung f\u00fcr die Sicherheit des K\u00f6nigreichs ein<\/a>\u00a0\u2013 neben Russland und China. <\/p>\n<blockquote class=\"tspC2rd\">\n<p>Zwischen den Parteien herrscht weitgehende Einigkeit \u00fcber die au\u00dfenpolitische Linie.<\/p>\n<\/blockquote>\n<p class=\"tspC2re\"><strong>Rune Stubager<\/strong>, Politikwissenschaftler Universit\u00e4t Aarhus<\/p>\n<p class=\"tspA5jq\">Kurz <a href=\"https:\/\/www.tagesspiegel.de\/internationales\/gronland-macht-und-misstrauen-trump-verscharft-den-konflikt-mit-danemark-15064096.html?icid=in-text-link_15588210\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" rel=\"nofollow noopener\" target=\"_blank\">vor dem Jahreswechsel 2025\/2026 ernannte Trump den 79 Jahre alten Republikaner Landry, eigentlich Gouverneur von Louisiana, zum gr\u00f6nl\u00e4ndischen Sondergesandten<\/a>. Der bedankte sich damals auf dem sozialen Medium X und schrieb, es sei ihm eine \u201eEhre\u201c, dazu beitragen zu d\u00fcrfen, \u201eGr\u00f6nland zu einem Teil der USA zu machen\u201c.<\/p>\n<p>Mehr \u00fcber Nordeuropa bei Tagesspiegel Plus<a href=\"https:\/\/www.tagesspiegel.de\/internationales\/regierungskrise-in-gronland-ist-trumps-lieblingsinsel-jetzt-anfalliger-fur-angriffe-von-aussen-15408177.html?icid=topic-list_15588210___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:true},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/internationales\/regierungskrise-in-gronland-ist-trumps-lieblingsinsel-jetzt-anfalliger-fur-angriffe-von-aussen-15408177.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;Regierungskrise in Gr\u00f6nland&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;Ist Trumps Lieblingsinsel jetzt anf\u00e4lliger f\u00fcr Angriffe von au\u00dfen?&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15408177&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspDBry tspC9rv\" rel=\"nofollow noopener\" target=\"_blank\">Regierungskrise in Gr\u00f6nland Ist Trumps Lieblingsinsel jetzt anf\u00e4lliger f\u00fcr Angriffe von au\u00dfen? <\/a><a href=\"https:\/\/www.tagesspiegel.de\/internationales\/danemarks-nachstes-problem-im-nordatlantik-die-faroer-sind-ein-einfallstor-fur-china-und-russland-15320680.html?icid=topic-list_15588210___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:true},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/internationales\/danemarks-nachstes-problem-im-nordatlantik-die-faroer-sind-ein-einfallstor-fur-china-und-russland-15320680.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;D\u00e4nemarks n\u00e4chstes Problem im Nordatlantik?&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;\u201eDie F\u00e4r\u00f6er sind ein Einfallstor f\u00fcr China und Russland\u201c&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15320680&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspDBry tspC9rv\" rel=\"nofollow noopener\" target=\"_blank\">D\u00e4nemarks n\u00e4chstes Problem im Nordatlantik? \u201eDie F\u00e4r\u00f6er sind ein Einfallstor f\u00fcr China und Russland\u201c <\/a><a href=\"https:\/\/www.tagesspiegel.de\/internationales\/konnen-absprachen-zwischen-putin-und-trump-nicht-ausschliessen-der-streit-um-gronland-bedroht-auch-spitzbergen-15173760.html?icid=topic-list_15588210___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:true},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/internationales\/konnen-absprachen-zwischen-putin-und-trump-nicht-ausschliessen-der-streit-um-gronland-bedroht-auch-spitzbergen-15173760.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;\u201eK\u00f6nnen Absprachen zwischen Putin und Trump nicht ausschlie\u00dfen\u201c&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;Der Streit um Gr\u00f6nland bedroht auch Spitzbergen&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15173760&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspDBry tspC9rv\" rel=\"nofollow noopener\" target=\"_blank\">\u201eK\u00f6nnen Absprachen zwischen Putin und Trump nicht ausschlie\u00dfen\u201c Der Streit um Gr\u00f6nland bedroht auch Spitzbergen <\/a><\/p>\n<p class=\"tspA5jq\">Der d\u00e4nische Politikwissenschaftler Stubager sieht in den langwierigen Verhandlungen in Kopenhagen fast zwei Monate nach der Wahl dennoch keine akute Gefahr f\u00fcr die Sicherheit der Nordatlantikinsel. Aktuell <a href=\"https:\/\/www.tagesspiegel.de\/internationales\/trump-will-arktisinsel-kaufen--oder-annektieren-gronlands-woche-der-entscheidung-15126178.html?icid=in-text-link_15588210\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" rel=\"nofollow noopener\" target=\"_blank\">gebe es keinen unmittelbaren Druck wie im Januar und Februar<\/a>, deshalb \u201esind wir wahrscheinlich nicht besonders verwundbar\u201c.<\/p>\n<p class=\"tspA5jq\">Sollte sich das \u00e4ndern, noch ehe eine neue Regierung vereidigt worden ist, w\u00fcrde die Situation ihm zufolge \u201ereibungslos bew\u00e4ltigt\u201c werden k\u00f6nnen: \u201eZwischen den Parteien herrscht weitgehende Einigkeit \u00fcber die au\u00dfenpolitische Linie.\u201c <\/p>\n","protected":false},"excerpt":{"rendered":"Immer wieder heimst Mette Frederiksen Rekorde ein. Vor fast genau sieben Jahren wurde die damals 41 Jahre alte&hellip;\n","protected":false},"author":2,"featured_media":1014933,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1160,106,452,13,3295,14,15,12,184,10,8,9,11,64,103,104,103983],"class_list":{"0":"post-1014932","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-welt","8":"tag-daenemark","9":"tag-donald-trump","10":"tag-groenland","11":"tag-headlines","12":"tag-hochschulen","13":"tag-nachrichten","14":"tag-news","15":"tag-schlagzeilen","16":"tag-spd","17":"tag-top-news","18":"tag-top-meldungen","19":"tag-topmeldungen","20":"tag-topnews","21":"tag-usa","22":"tag-welt","23":"tag-world","24":"tag-zweiter-weltkrieg-und-kriegsende"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116565023769373839","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1014932"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1014932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1014933"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1014932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1014932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1014932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}