{"id":1015026,"date":"2026-05-13T03:54:18","date_gmt":"2026-05-13T03:54:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1015026\/"},"modified":"2026-05-13T03:54:18","modified_gmt":"2026-05-13T03:54:18","slug":"spielzeit-2026-27-faust-wird-von-der-ki-verfuehrt-das-plant-das-schauspiel-stuttgart","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1015026\/","title":{"rendered":"Spielzeit 2026\/27: Faust wird von der KI verf\u00fchrt \u2013 Das plant das Schauspiel Stuttgart"},"content":{"rendered":"<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t      \t\t            \t\t             \t\t\t\t   \t\t\t\t\t   <img decoding=\"async\" id=\"article-image\" fetchpriority=\"high\" alt=\"Spielzeit 2026\/27: Faust wird von der KI verf\u00fchrt \u2013 Das plant das Schauspiel Stuttgart\" title=\"Spielzeit 2026\/27: Faust wird von der KI verf\u00fchrt \u2013 Das plant das Schauspiel Stuttgart\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/media.media.9996b017-a348-4701-a9f0-9fb925b5fce0.16x9_700.jpg\" data-linkto=\"https:\/\/www.stuttgarter-nachrichten.de\/javascript:void(0);\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tIntendant Burkhard C. Kosminski\u00a0Foto: Lichtgut\/Leif Piechowski\t\t\t<\/p>\n<p>Von wegen Krise: Das Schauspiel Stuttgart muss zwar sparen, will die aktuellen Erfolge aber auch durch Kooperationen fortsetzen.<\/p>\n<p>D<a href=\"https:\/\/www.stuttgarter-zeitung.de\/inhalt.interview-mit-schauspielchef-an-kultur-und-bildung-darf-nicht-gespart-werden.0f5e8f20-6478-437d-93f1-f384009e066d.html\" target=\"_blank\" rel=\"nofollow noopener\">en Kopf steckt Burkhard C. Kosminski sicher nicht in den Sand<\/a>. Auch wenn das <a href=\"https:\/\/www.stuttgarter-nachrichten.de\/thema\/Schauspiel_Stuttgart\" title=\"Schauspiel Stuttgart\" class=\"art_thema\" rel=\"nofollow noopener\" target=\"_blank\">Schauspiel Stuttgart<\/a> sparen muss, geht der Intendant die neue Saison positiv an, \u201edenn wir haben auch Chancen\u201c. So kommt im Oktober \u201eTanzende Idioten\u201c von Thorsten Lensing nach Stuttgart. Die prominent besetzte Inszenierung, die im Mai beim Wiener Theatertreffen gezeigt wird, ist eine Koproduktion, mit der sich Kosten sparen lassen, ohne das Programm eindampfen zu m\u00fcssen. Deshalb wird auch \u201eSacred Monster\u201c von Nino Haratischwili nach der Urauff\u00fchrung in Stuttgart an die Hamburger Elbphilharmonie wandern. Der Abend mit Orchester und Chor dreht sich um Medea und Frauen, die zu T\u00e4terinnen werden. <\/p>\n<p>Er\u00f6ffnet wird die Saison mit einer \u201etheatralen Erkundung zu Hannah Arendt\u201c, die der Intendant inszeniert. Auf der B\u00fchne wird auch Daniel Cohn-Bendit stehen, einst prominenter Vertreter der Studentenbewegung. Aber auch die \u201eKlassikerpflege\u201c ist Kosminski wichtig \u2013 mit Schillers \u201eKabale und Liebe\u201c und Shakespeares \u201eK\u00f6nig Richard III.\u201c, der von Andreas Kriegenburg inszeniert und von Max Simonischek gespielt werden wird. <\/p>\n<p>Auf Erfolgskurs  <\/p>\n<p>Das Schauspiel Stuttgart ist derzeit auf Erfolgskurs, davon zeugen die Einladungen zum Berliner Theatertreffen und zum Heidelberger St\u00fcckemarkt, aber auch Gastspielanfragen sogar aus Schanghai. F\u00fcr Kosminski ist das ein Beleg, dass es sich ausgezahlt hat, das Team zu verj\u00fcngen, zumal mehrere Abschiede anstehen. Michael Stiller geht in den Ruhestand und f\u00fcr Gabriele Hintermaier und Boris Burgstaller ist 2026\/27 die letzte Spielzeit. Sie haben sich zum Abschied Hans Falladas \u201eKleiner Mann \u2013 was nun?\u201c gew\u00fcnscht. Sie werden die Geschichte eines strauchelnden Paares w\u00e4hrend der Weltwirtschaftskrise im Kammertheater spielen. <\/p>\n<p>Neue digitale Welten erobern  <\/p>\n<p>Das Kammertheater habe sich ansonsten sehr erfolgreich als Ort f\u00fcr zeitgen\u00f6ssische Texte etabliert, so Kosminski. F\u00fcr die neue Saison haben Alina Sarnatska, Maryna Smilianets und Luda Tymoshenko drei Minidramen geschrieben \u00fcber eine Erfahrung, die sie auch selbst machen mussten: \u201eFl\u00fcchtige Welten\u201c handelt von Ukrainerinnen, die nach Deutschland geflohen sind. Zwischen Kunst und Theater bewegen sich zwei weitere Urauff\u00fchrungen: In \u201eDie J\u00e4ger im Schnee\u201c von Clemens Setz geht es um virtuelle Museumsbesuche f\u00fcr kranke Menschen. Der K\u00fcnstlerautor Stephan Kaluza wird dagegen eine Faust-Variante schreiben, bei der die <a href=\"https:\/\/www.stuttgarter-nachrichten.de\/thema\/KI\" title=\"KI\" class=\"art_thema\" rel=\"nofollow noopener\" target=\"_blank\">KI<\/a> teuflisch am Werk ist. Kosminski wird inszenieren und hofft, auch visuell neue digitale Welten erobern zu k\u00f6nnen. <\/p>\n<p>Cornelia Funkes \u201eHerr der Diebe\u201c f\u00fcr Familien <\/p>\n<p>Mit der B\u00fchnenfassung des Romans \u201eZierfische in H\u00e4nden von Idioten\u201c von Manuel Butt will man nun auch explizit eine Produktion f\u00fcr Jugendliche anbieten, was ein Wunsch der Schulen war, mit denen das Schauspiel Stuttgart zusammenarbeitet. Derzeit sind es knapp 140 Partnerschulen, die am Schauspiel Workshops, Proben und Fortbildungen besuchen k\u00f6nnen. W\u00e4hrend das Europa Festival wegen der K\u00fcrzungen auf wackligen Beinen steht, wird das Stuttgarter Schultheaterfestival im Sommer 2027 wieder stattfinden. Au\u00dferdem kommt f\u00fcr Familien im Schauspielhaus am 29. November Cornelia Funkes \u201eHerr der Diebe\u201c heraus.<\/p>\n<p>Info <\/p>\n<p class=\"infobox\"> <strong>Tickets<\/strong><br \/>\u00a0Karten f\u00fcr alle bereits ver\u00f6ffentlichten Termine der Spielzeit sowie f\u00fcr das gesamte Programm von Oper, Ballett und Schauspiel im September und Oktober gibt es vom 13. Juli (10 Uhr) an online, telefonisch und an der Theaterkasse.<\/p>\n<p class=\"infobox\"> <strong>Abo<\/strong><br \/>\u00a0Die Staatstheater Stuttgart bieten eine Vielzahl von Abonnements an. Alle sind buchbar vom 26. Mai an. Platz- und Serienwechsel k\u00f6nnen vom 18. Mai bis zum 12. Juni vorgenommen werden. Der Blick in die Abo-Angebote lohnt sich auf jeden Fall. Angeboten wird zum Beispiel auch ein Abo jung f\u00fcr junge Menschen zwischen 14 und 25 Jahren f\u00fcr 42 Euro mit einem Preisvorteil von 75 Prozent. <\/p>\n<p class=\"infobox\"> <strong>Gutscheine<\/strong><br \/>\u00a0 Tickets f\u00fcr Staatstheater-Vorstellungen verschenken? Das geht mit Gutscheinen, die es im Online-Shop auch zum Selbstausdruck gibt. Die Gutscheine sind drei Jahre g\u00fcltig. <\/p>\n","protected":false},"excerpt":{"rendered":"Intendant Burkhard C. Kosminski\u00a0Foto: Lichtgut\/Leif Piechowski Von wegen Krise: Das Schauspiel Stuttgart muss zwar sparen, will die aktuellen&hellip;\n","protected":false},"author":2,"featured_media":1015027,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1830],"tags":[94559,1634,218418,133816,3364,29,30,671,80,9387,21860,966,1441],"class_list":{"0":"post-1015026","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-stuttgart","8":"tag-andreas-kriegenburg","9":"tag-baden-wuerttemberg","10":"tag-burkhard-c-kosminiski","11":"tag-daniel-cohn-bendit","12":"tag-de","13":"tag-deutschland","14":"tag-germany","15":"tag-ki","16":"tag-kultur","17":"tag-saison","18":"tag-schauspiel-stuttgart","19":"tag-schule","20":"tag-stuttgart"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116565250489581208","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1015026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1015026"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1015026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1015027"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1015026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1015026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1015026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}