{"id":1015073,"date":"2026-05-13T04:20:19","date_gmt":"2026-05-13T04:20:19","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1015073\/"},"modified":"2026-05-13T04:20:19","modified_gmt":"2026-05-13T04:20:19","slug":"bergretter-schimpfen-auf-junge-und-ueberforderte-wanderer-auf-zugspitze","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1015073\/","title":{"rendered":"Bergretter schimpfen auf junge und \u00fcberforderte Wanderer auf Zugspitze"},"content":{"rendered":"<ol class=\"id-DonaldBreadcrumb lp_west_breadcrumb id-DonaldBreadcrumb--default\" data-k5a-pos=\"west_breadcrumb\">\n<li class=\"id-Breadcrumb-item\"><a href=\"https:\/\/www.merkur.de\/\" class=\"id-Breadcrumb-link\" data-id-ec=\"{\" shn=\"\" textlink=\"\" data-k5a-pos=\"1_startseite\" rel=\"nofollow noopener\" target=\"_blank\">Startseite<\/a><\/li>\n<li class=\"id-Breadcrumb-item\"><a href=\"https:\/\/www.merkur.de\/welt\/\" class=\"id-Breadcrumb-link\" data-id-ec=\"{\" shn=\"\" textlink=\"\" data-k5a-pos=\"2_welt\" rel=\"nofollow noopener\" target=\"_blank\">Welt<\/a><\/li>\n<\/ol>\n<p class=\"id-Story-timestamp id-Story-timestamp--default\">Stand: 13.05.2026, 04:47 Uhr<\/p>\n<p class=\"id-Story-authors id-Story-authors--default\">Von: <a class=\"id-Story-authors-link lp_west_author\" href=\"https:\/\/www.merkur.de\/autor\/marcus-giebel-4v5olio58.html\" title=\"Zur Autorenseite von Marcus Giebel\" data-id-ec=\"{\" shn=\"\" author-link=\"\" giebel=\"\" data-k5a-pos=\"west_author\" rel=\"nofollow noopener\" target=\"_blank\">Marcus Giebel<\/a><\/p>\n<p class=\"id-Story-interactionBar id-Story-interactionBar--default\">DruckenTeilen<\/p>\n<p><a href=\"https:\/\/profile.google.com\/cp\/CgsvZy8xODdjY3p3choA\" class=\"id-Story-googleFollowButton id-Story-googleFollowButton--default\" target=\"_blank\" data-id-ec=\"{\" shn=\"\" google-follow=\"\" auf=\"\" google=\"\" folgen=\"\" rel=\"nofollow noopener\">Uns auf Google folgen<\/a><\/p>\n<p class=\"id-StoryElement-leadText\">Die Zugspitze ragt fast 3000 Meter \u00fcber Deutschland auf. Dennoch scheinen viele junge Menschen den Berg ohne gro\u00dfe Vorbereitung bezwingen zu wollen.<\/p>\n<p class=\"id-StoryElement-paragraph\">Ehrwald \u2013 In Zeiten von Sozialen Medien wollen immer mehr Menschen hoch hinaus. Manche sogar wortw\u00f6rtlich. Sehr zum Leidwesen der Bergretter. Denn die m\u00fcssen umso h\u00e4ufiger ausr\u00fccken, um in Not geratene Hobby-Kletterer in Sicherheit zu bringen. Besonders beliebt scheint f\u00fcr die unge\u00fcbten Alpinisten die <a href=\"https:\/\/www.merkur.de\/lokales\/garmisch-partenkirchen\/zugspitze-webcam-seilbahn-wandern-hoehe-bahn-ticket-wanderung-zahnradbahn-or-91107471.html\" class=\"id-import-Link\" data-id-ec=\"{&quot;sht&quot;:&quot;Container&quot;,&quot;shn&quot;:&quot;Story&quot;,&quot;p&quot;:{&quot;containerType&quot;:&quot;Paragraph&quot;,&quot;displayType&quot;:&quot;Paragraph InlineLink&quot;,&quot;type&quot;:&quot;INLINE_LINK&quot;,&quot;value&quot;:&quot;Zugspitze&quot;,&quot;variant&quot;:&quot;standardLink&quot;,&quot;sponsored&quot;:false,&quot;linkHref&quot;:&quot;https:\/\/www.merkur.de\/lokales\/garmisch-partenkirchen\/zugspitze-webcam-seilbahn-wandern-hoehe-bahn-ticket-wanderung-zahnradbahn-or-91107471.html&quot;,&quot;storyElementPosition&quot;:8,&quot;storyElementCount&quot;:31}}\" rel=\"nofollow noopener\" target=\"_blank\">Zugspitze<\/a> zu sein, mit 2962 Metern h\u00f6chster Berg Deutschlands und auch von \u00d6sterreich aus zu erklimmen.<\/p>\n<p><img decoding=\"async\" class=\"id-RatioPlaceholder-element wv_story_el_image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/42548175-kletterer-am-gipfelkreuz-der-zugspitze-2vrVuEemxABG.jpg\" loading=\"lazy\"   height=\"619\" width=\"1100\" alt=\"Kletterer am Gipfelkreuz der Zugspitze\"\/>Sie haben es ganz nach oben geschafft: W\u00e4hrend viele Wanderer das Gipfelkreuz auf der Zugspitze aus n\u00e4chster N\u00e4he bewundern k\u00f6nnen, \u00fcbernehmen sich auch immer wieder Hobby-Kletterer beim Aufstieg. \u00a9\u00a0picture alliance\/dpa | Peter Kneffel<\/p>\n<p class=\"id-StoryElement-paragraph\">Wie die Kronen-Zeitung berichtet, brachte das Team der Bergrettung Ehrwald allein am ersten Mai-Sonntag drei feststeckende Bergsteiger ins Tal. Diese h\u00e4tten sogar eine deutlich erkennbare Steigsperre ignoriert. Ob allein f\u00fcr den Kick oder um die eigenen Follower mit besonders spektakul\u00e4ren Aufnahmen zu f\u00fcttern, ist letztlich unerheblich. \u201eJe extremer eine Tour zu sein scheint, desto lieber haben sie es\u201c, wird Robin Lutnig, Chef der Bergrettung Ehrwald, in dem Artikel zitiert.<\/p>\n<p>Bergretter an der Zugspitze: Jungen Wanderern \u201efehlt Erfahrung und Gesp\u00fcr f\u00fcr die Berge\u201c<\/p>\n<p class=\"id-StoryElement-paragraph\">Die unerfahrenen Alpinisten w\u00fcrden nicht nur aus Deutschland oder Italien kommen, sondern auch aus den USA, aus Tunesien oder aus Indien anreisen. \u201eSie sind \u00fcber die sozialen Medien auf Touren gesto\u00dfen und sehen die Berge als Spielplatz\u201c, kritisiert Lutnig. Oftmals w\u00fcrden sie die Touren mit dem Gedanken starten, dass \u201eda eh nichts dabei sei\u201c.<\/p>\n<p class=\"id-StoryElement-paragraph\">Wobei sie nicht unbedingt v\u00f6llig unvorbereitet loslegen. \u201eDie jungen Leute haben zwar <a href=\"https:\/\/www.merkur.de\/lokales\/garmisch-partenkirchen\/ist-von-touren-abzuraten-klettersteig-vereist-bergrettung-muss-fuenf-bergsteiger-von-der-zugspitze-holen-bis-auf-weiteres-93976639.html\" class=\"id-import-Link\" data-id-ec=\"{&quot;sht&quot;:&quot;Container&quot;,&quot;shn&quot;:&quot;Story&quot;,&quot;p&quot;:{&quot;containerType&quot;:&quot;Paragraph&quot;,&quot;displayType&quot;:&quot;Paragraph InlineLink&quot;,&quot;type&quot;:&quot;INLINE_LINK&quot;,&quot;value&quot;:&quot;oft eine gute Ausr&#xFC;stung dabei&quot;,&quot;variant&quot;:&quot;standardLink&quot;,&quot;sponsored&quot;:false,&quot;linkHref&quot;:&quot;https:\/\/www.merkur.de\/lokales\/garmisch-partenkirchen\/ist-von-touren-abzuraten-klettersteig-vereist-bergrettung-muss-fuenf-bergsteiger-von-der-zugspitze-holen-bis-auf-weiteres-93976639.html&quot;,&quot;storyElementPosition&quot;:15,&quot;storyElementCount&quot;:31}}\" rel=\"nofollow noopener\" target=\"_blank\">oft eine gute Ausr\u00fcstung dabei<\/a>, wissen aber nicht, wie man damit umgeht\u201c, nennt der Berg-Experte ein Problem. In der Regel handele es sich um junge M\u00e4nner und Frauen unter 20 Jahren, die konditionell auf der H\u00f6he seien, \u201ees fehlt ihnen aber jede Erfahrung und <a href=\"https:\/\/www.24vita.de\/bewegung\/haben-koennen-warum-kleine-fehler-in-den-bergen-grosse-folgen-93980404.html\" class=\"id-import-Link id-pageApi-Link--externalDomain\" data-id-ec=\"{&quot;sht&quot;:&quot;Container&quot;,&quot;shn&quot;:&quot;Story&quot;,&quot;p&quot;:{&quot;containerType&quot;:&quot;Paragraph&quot;,&quot;displayType&quot;:&quot;Paragraph InlineLink&quot;,&quot;type&quot;:&quot;INLINE_LINK&quot;,&quot;value&quot;:&quot;jedes Gesp&#xFC;r f&#xFC;r die Berge&quot;,&quot;variant&quot;:&quot;standardLink&quot;,&quot;sponsored&quot;:false,&quot;linkHref&quot;:&quot;https:\/\/www.24vita.de\/bewegung\/haben-koennen-warum-kleine-fehler-in-den-bergen-grosse-folgen-93980404.html&quot;,&quot;storyElementPosition&quot;:15,&quot;storyElementCount&quot;:31}}\" rel=\"nofollow noopener\" target=\"_blank\">jedes Gesp\u00fcr f\u00fcr die Berge<\/a>\u201c.<\/p>\n<p>25 der sch\u00f6nsten Ausflugsziele in Deutschland: Alle liegen im S\u00fcden<img decoding=\"async\" class=\"id-RatioPlaceholder-element wv_story_el_interstitialImage\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/42069347-der-deutsche-sueden-zaehlt-zu-den-schoensten-reisezielen-des-landes-3Ffe.jpg\" loading=\"lazy\"   height=\"1350\" width=\"2400\" alt=\"Der deutsche S&#xFC;den z&#xE4;hlt zu den sch&#xF6;nsten Reisezielen des Landes.\"\/><a href=\"https:\/\/www.merkur.de\/deutschland\/deutschland-alle-liegen-im-sueden-25-der-schoensten-ausflugsziele-in-zr-94243538.html\" class=\"id-StoryElement-intestitialLink-link\" data-id-ec=\"{\" shn=\"\" ansehen=\"\" data-k5a-pos=\"west_story_16_photoGalleryLink\" title=\"Zur Fotostrecke: 25 der sch&#xF6;nsten Ausflugsziele in Deutschland: Alle liegen im S&#xFC;den\" rel=\"nofollow noopener\" target=\"_blank\">Fotostrecke ansehen<\/a><\/p>\n<p class=\"id-StoryElement-paragraph\">Zu Wort kommt auch Lutnigs Stellvertreterin Regina Poberschnigg, die eine weitere Gefahr nennt: \u201eDiese jungen Leute gehen h\u00e4ufig stundenlang im Schnee, ohne zu bedenken, dass sie auch noch zur\u00fcck oder die letzte Talfahrt der Zugspitzbahn erwischen m\u00fcssen. Umdrehen gibt es f\u00fcr sie nicht.\u201c Die Folge: <a href=\"https:\/\/www.mannheim24.de\/region\/rettung-von-der-zugspitze-kletterer-aus-mannheim-wartet-stundenlang-am-berg-93777430.html\" class=\"id-import-Link id-pageApi-Link--externalDomain\" data-id-ec=\"{&quot;sht&quot;:&quot;Container&quot;,&quot;shn&quot;:&quot;Story&quot;,&quot;p&quot;:{&quot;containerType&quot;:&quot;Paragraph&quot;,&quot;displayType&quot;:&quot;Paragraph InlineLink&quot;,&quot;type&quot;:&quot;INLINE_LINK&quot;,&quot;value&quot;:&quot;Ihnen fehle die Kraft f&#xFC;r den R&#xFC;ckweg&quot;,&quot;variant&quot;:&quot;standardLink&quot;,&quot;sponsored&quot;:false,&quot;linkHref&quot;:&quot;https:\/\/www.mannheim24.de\/region\/rettung-von-der-zugspitze-kletterer-aus-mannheim-wartet-stundenlang-am-berg-93777430.html&quot;,&quot;storyElementPosition&quot;:18,&quot;storyElementCount&quot;:31}}\" rel=\"nofollow noopener\" target=\"_blank\">Ihnen fehle die Kraft f\u00fcr den R\u00fcckweg<\/a>, geraten sie in Dunkelheit, komme Panik auf. \u201eDann weinen sie Rotz und Wasser und schlagen Alarm\u201c, erg\u00e4nzt sie.<\/p>\n<p>Bergrettung warnt vor Tour auf Zugspitze: \u201eInfos nicht bei TikTok oder Instagram einholen\u201c<\/p>\n<p class=\"id-StoryElement-paragraph\">In der noch jungen Wandersaison h\u00e4tten allein die Tiroler Bergretter aus Ehrwald schon rund 30 solcher F\u00e4lle erlebt. Zum Gl\u00fcck seien die unbedarften Hobby-Alpinisten allesamt praktisch unverletzt geblieben.<\/p>\n<p class=\"id-StoryElement-paragraph\">Auf ihren Social-Media-Accounts warnte die Bergrettung Ehrwald bereits am 11. April vor derartigen Ausfl\u00fcgen. Binnen einer Woche wurden demnach vier Eins\u00e4tze mit acht geretteten Personen gez\u00e4hlt, \u201ewelche aufgrund der Schneeverh\u00e4ltnisse und mangelhafter Planung oder fehlender Ausr\u00fcstung blockiert waren und gerettet werden mussten\u201c. Damit lag die Zahl der \u201ein diesem Jahr im Winter\u201c geretteten Bergsteiger bereits zu jenem Zeitpunkt bei 21.<\/p>\n<p><img decoding=\"async\" class=\"id-RatioPlaceholder-element wv_story_el_image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/42548410-kletterer-am-verschneiten-berg-polizeihubschrauber-steht-im-schnee-RDMX8vKROBG.jpg\" loading=\"lazy\"   height=\"619\" width=\"1100\" alt=\"Kletterer am verschneiten Berg, Polizeihubschrauber steht im Schnee\"\/>Szenen am Berg: Rettungseins\u00e4tze wegen \u00fcberforderter Wanderer werden auf der Zugspitze zunehmend zur Normalit\u00e4t. \u00a9\u00a0Facebook Bergrettung Ehrwald<\/p>\n<p class=\"id-StoryElement-paragraph\">\u201eUm solche Eins\u00e4tze zu vermeiden, appellieren wir stark an den Hausverstand und an das umfangreiche Informieren \u00fcber solche Touren\u201c, schreibt das Team auf Instagram und Facebook und gibt den wichtigen Ratschlag: \u201eInfos z.B. bei lokalen Alpinschulen einholen, nicht aus <a href=\"https:\/\/www.ingame.de\/news\/streaming\/tiktok-social-network-altersbeschraenkung-taenze-challenges-celebs-geschichte-91234155.html\" class=\"id-import-Link id-pageApi-Link--externalDomain\" data-id-ec=\"{&quot;sht&quot;:&quot;Container&quot;,&quot;shn&quot;:&quot;Story&quot;,&quot;p&quot;:{&quot;containerType&quot;:&quot;Paragraph&quot;,&quot;displayType&quot;:&quot;Paragraph InlineLink&quot;,&quot;type&quot;:&quot;INLINE_LINK&quot;,&quot;value&quot;:&quot;TikTok&quot;,&quot;variant&quot;:&quot;standardLink&quot;,&quot;sponsored&quot;:false,&quot;linkHref&quot;:&quot;https:\/\/www.ingame.de\/news\/streaming\/tiktok-social-network-altersbeschraenkung-taenze-challenges-celebs-geschichte-91234155.html&quot;,&quot;storyElementPosition&quot;:25,&quot;storyElementCount&quot;:31}}\" rel=\"nofollow noopener\" target=\"_blank\">TikTok<\/a> oder Instagram\u201c.<\/p>\n<p>Zugspitze erklimmen: Nicht jeder vermeintliche Kletterer ist zu Fu\u00df hochgekommen<\/p>\n<p class=\"id-StoryElement-paragraph\">Bereits am ersten Wochenende des Jahres hatte der ORF berichtet, dass die Bergrettung Ehrwald zwei- bis dreimal pro Woche ausr\u00fccken m\u00fcsse. Auch damals wurde thematisiert, dass junge Wanderer von <a href=\"https:\/\/www.tz.de\/muenchen\/stadt\/professor-aus-muenchen-ueber-gefaehrlichen-einfluss-von-social-media-trends-94299743.html\" class=\"id-import-Link id-pageApi-Link--externalDomain\" data-id-ec=\"{&quot;sht&quot;:&quot;Container&quot;,&quot;shn&quot;:&quot;Story&quot;,&quot;p&quot;:{&quot;containerType&quot;:&quot;Paragraph&quot;,&quot;displayType&quot;:&quot;Paragraph InlineLink&quot;,&quot;type&quot;:&quot;INLINE_LINK&quot;,&quot;value&quot;:&quot;Social-Media-Posts &#xFC;ber vermeintlich gute Verh&#xE4;ltnisse angelockt&quot;,&quot;variant&quot;:&quot;standardLink&quot;,&quot;sponsored&quot;:false,&quot;linkHref&quot;:&quot;https:\/\/www.tz.de\/muenchen\/stadt\/professor-aus-muenchen-ueber-gefaehrlichen-einfluss-von-social-media-trends-94299743.html&quot;,&quot;storyElementPosition&quot;:28,&quot;storyElementCount&quot;:31}}\" rel=\"nofollow noopener\" target=\"_blank\">Social-Media-Posts \u00fcber vermeintlich gute Verh\u00e4ltnisse angelockt<\/a> w\u00fcrden und dann nahezu unvorbereitet in gef\u00e4hrliche Situationen gerieten.<\/p>\n<p class=\"id-StoryElement-paragraph\">Barbara Stehr, Marketing-Leitung der Tiroler Zugspitzbahn, gab zu bedenken, dass manche vermeintlichen Kletterer posten w\u00fcrden, sie seien hinaufgestiegen, obwohl sie in Wahrheit die Bahn genutzt haben. Mit der kann der H\u00f6henunterschied von 1725 Metern in zehn Minuten \u00fcberwunden werden.<\/p>\n<p class=\"id-StoryElement-paragraph\">Mit Blog-Artikeln, Social-Media-Posts und Hinweisen zu sicheren Routen sollte dem Trend entgegengewirkt werden. Zudem sollten den alpinen Risiken mit aktiven Informationen begegnet werden. (Quellen: Kronen-Zeitung, Bergrettung Ehrwald, ORF) (mg)<\/p>\n","protected":false},"excerpt":{"rendered":"Startseite Welt Stand: 13.05.2026, 04:47 Uhr Von: Marcus Giebel DruckenTeilen Uns auf Google folgen Die Zugspitze ragt fast&hellip;\n","protected":false},"author":2,"featured_media":1015074,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[13,14,15,12,10,8,9,11,103,104],"class_list":{"0":"post-1015073","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-welt","8":"tag-headlines","9":"tag-nachrichten","10":"tag-news","11":"tag-schlagzeilen","12":"tag-top-news","13":"tag-top-meldungen","14":"tag-topmeldungen","15":"tag-topnews","16":"tag-welt","17":"tag-world"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116565352855535120","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1015073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1015073"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1015073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1015074"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1015073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1015073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1015073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}