{"id":1015361,"date":"2026-05-13T07:04:17","date_gmt":"2026-05-13T07:04:17","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1015361\/"},"modified":"2026-05-13T07:04:17","modified_gmt":"2026-05-13T07:04:17","slug":"trump-spricht-von-verrat-iran-soll-noch-70-prozent-seiner-raketen-besitzen-warnung-vor-lage-an-strasse-von-hormus","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1015361\/","title":{"rendered":"Trump spricht von \u201eVerrat\u201c: Iran soll noch 70 Prozent seiner Raketen besitzen \u2013 Warnung vor Lage an Stra\u00dfe von Hormus"},"content":{"rendered":"<p class=\"tspA5jq tspA5jr\">Tausende Angriffe des amerikanischen und israelischen Milit\u00e4rs gab es seit Beginn des Kriegs im Nahen Osten \u2013 ein wirkliches Ende der Kampfhandlungen ist aber nicht in Sicht. Aktuell herrscht im Iran-Krieg eine br\u00fcchige Waffenruhe, Verhandlungen sind ins Stocken geraten.<\/p>\n<p class=\"tspA5jq\">Und der Iran agiert offenbar aus einer Position der St\u00e4rke: US-Medienberichten zufolge verf\u00fcgen die Mullahs noch immer \u00fcber den Gro\u00dfteil ihrer Best\u00e4nde an mobilen Abschussrampen und Raketen. Die <a href=\"https:\/\/www.nytimes.com\/2026\/05\/12\/us\/politics\/iran-missiles-us-intelligence.html\" target=\"_blank\" rel=\"noopener nofollow\" class=\"link link--external\" data-gtm-class=\"article-text-link\" data-gtm-val=\"external\" aria-describedby=\"message-target-blank\">\u201eNew York Times\u201c<\/a> berichtet \u00fcber Erkenntnisse von US-Geheimdiensten, wonach <a href=\"https:\/\/www.tagesspiegel.de\/internationales\/knie-rucken-schnittwunde-iran-nennt-erstmals-details-zu-verletzungen-von-fuhrer-modschtaba-chamenei-15579654.html?icid=in-text-link_15590719\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" rel=\"nofollow noopener\" target=\"_blank\">das Regime im Iran<\/a> noch etwa 70 Prozent seiner mobilen Abschussrampen sowie rund 70 Prozent des Raketenarsenals habe, das es vor dem Krieg hatte.<\/p>\n<p class=\"tspA5jq\">Dieser Bestand umfasse sowohl ballistische Raketen, die andere Staaten in der Region ins Visier nehmen k\u00f6nnen, als auch einen kleineren Vorrat an Marschflugk\u00f6rpern, die gegen Ziele mit k\u00fcrzerer Reichweite an Land oder auf See eingesetzt werden k\u00f6nnen.<\/p>\n<p class=\"tspA5jq\">Die Zeitung beruft sich dabei auf Personen, die mit den Geheimdiensterkenntnissen von Anfang dieses Monats vertraut sind. Demnach habe der Iran auch wieder Zugang zu ungef\u00e4hr 90 Prozent seiner unterirdischen Raketenlager- und Startanlagen erlangt, die nun als \u201eteilweise oder vollst\u00e4ndig einsatzf\u00e4hig\u201c eingestuft werden.<\/p>\n<blockquote class=\"tspC2rd\">\n<p>Wenn die Fake News behaupten, dass der iranische Feind milit\u00e4risch gut gegen uns abschneidet, ist das praktisch VERRAT.<\/p>\n<\/blockquote>\n<p class=\"tspC2re\"><strong>Donald Trump<\/strong>, US-Pr\u00e4sident<\/p>\n<p class=\"tspA5jq\">Am alarmierendsten sind demnach f\u00fcr einige hochrangige Beamte Hinweise darauf, dass Iran den operativen Zugang zu 30 der 33 Raketenstellungen wiederhergestellt hat, die es entlang der Stra\u00dfe von Hormus unterh\u00e4lt, was amerikanische Kriegsschiffe und \u00d6ltanker bedrohen k\u00f6nnte, die diese enge Wasserstra\u00dfe passieren.<\/p>\n<p class=\"tspA5jq\">Die Zeitung weist darauf hin, dass Trump am 9. M\u00e4rz, zehn Tage nach Beginn des Kriegs, gegen\u00fcber CBS News gesagt hatte, Irans \u201eRaketen seien auf ein paar verstreute Reste reduziert\u201c und das Land habe \u201emilit\u00e4risch gesehen nichts mehr \u00fcbrig\u201c.<\/p>\n<p class=\"tspA5jq\">Verteidigungsminister Pete Hegseth erkl\u00e4rte auf einer Pressekonferenz im Pentagon am 8. April, dass Operation Epic Fury \u2013 die gemeinsame US-israelische Kampagne, die am 28. Februar gestartet wurde \u2013 \u201eIrans Milit\u00e4r dezimiert und es f\u00fcr Jahre als kampfunf\u00e4hig gemacht\u201c habe.<\/p>\n<p class=\"tspA5jq\">Die Einsch\u00e4tzung der US-Geheimdienste nach Angaben der \u201eNew York Times\u201c: <\/p>\n<ul data-qa-hook=\"story-list-ul\" class=\"tspCZq3\">\n<li class=\"tspCZhp tspCZhp\"><strong>90 Prozent der unterirdischen Raketenlager und Startanlagen<\/strong> im Iran sollen wieder teilweise oder vollst\u00e4ndig einsatzf\u00e4hig sein<\/li>\n<li class=\"tspCZhp tspCZhp\"><strong>70 Prozent der mobilen Abschussrampen und etwa 70 Prozent des Raketenbestands<\/strong> aus der Zeit vor dem Krieg sollen dem Regime in Teheran zur Verf\u00fcgung stehen<\/li>\n<li class=\"tspCZhp tspCZhp\"><strong>30 von 33 Raketenstandorten in der Stra\u00dfe von Hormus<\/strong> k\u00f6nnten von Irans Milit\u00e4r wieder genutzt werden<\/li>\n<\/ul>\n<p class=\"tspA5jq\">Die <a href=\"https:\/\/www.washingtonpost.com\/national-security\/2026\/05\/07\/cia-intelligence-iran-trump-blockade-missiles\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"link link--external\" data-gtm-class=\"article-text-link\" data-gtm-val=\"external\" aria-describedby=\"message-target-blank\">\u201eWashington Post\u201c<\/a> hatte bereits vergangene Woche \u00fcber eine US-Geheimdienstanalyse berichtet und \u00e4hnliche Zahlen genannt. Der Iran verf\u00fcge noch \u00fcber etwa 75 Prozent seiner Vorkriegsbest\u00e4nde an mobilen Abschussrampen sowie etwa 70 Prozent seiner Raketen, zitierte die Zeitung einen US\u2011Beamten. <\/p>\n<p class=\"tspA5jq\">Dieser verwies demnach auch auf Hinweise, dass die iranische F\u00fchrung in der Lage gewesen sei, fast alle ihrer unterirdischen Lagerst\u00e4tten wieder in Betrieb zu nehmen, einige besch\u00e4digte Raketen zu reparieren sowie einige neue Raketen fertigzustellen.<\/p>\n<p> Trump kritisiert Berichterstattung <\/p>\n<p class=\"tspA5jq\">Trump kritisierte am Dienstag auf seiner Plattform Truth Social wieder einmal die mediale Berichterstattung \u00fcber den Iran-Krieg. \u201eWenn die Fake News behaupten, dass der iranische Feind milit\u00e4risch gut gegen uns abschneidet, ist das praktisch VERRAT, insofern als es sich um eine derart falsche und sogar absurde Behauptung handelt.\u201c Sie unterst\u00fctzten den Feind, z\u00fcrnte der US-Pr\u00e4sident.<\/p>\n<p class=\"tspA5jq\">Die Berichte der \u201eNew York Times\u201c und \u201eWashington Post\u201c stehen in starkem Kontrast zur Darstellung der US-Regierung, wonach der Iran durch den von Israel und den USA Ende Februar begonnenen Krieg milit\u00e4risch weitestgehend geschlagen sei. Sie fallen zudem in eine Zeit, in der die direkten und indirekten Kosten des Kriegs in den USA immer wieder Thema sind.\u00a0<\/p>\n<p> Sorge um Munitions- und Raketenverbrauch\u00a0 <\/p>\n<p class=\"tspA5jq\"><a href=\"https:\/\/www.tagesspiegel.de\/internationales\/nach-kritik-an-trump-und-iran-krieg-us-verteidigungsminister-hegseth-droht-senator-kelly-wegen-angeblichem-geheimnisverrat-15583359.html?icid=in-text-link_15590719\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" rel=\"nofollow noopener\" target=\"_blank\">US-Senator Mark Kelly<\/a> etwa sagte der Agentur dpa zufolge j\u00fcngst, die Munitions- und Raketenvorr\u00e4te des US-Milit\u00e4rs seien stark aufgezehrt. Als Mitglied des Streitkr\u00e4fte-Ausschusses hatte das Pentagon den Demokraten \u00fcber bestimmte Munitionsarten informiert \u2013 nach Kellys Aussage geh\u00f6rten dazu etwa Angaben zu Raketen der Typen Tomahawk, ATACMS, SM-3 oder jene f\u00fcr die Flugabwehrsysteme vom Typ Patriot.\u00a0<\/p>\n<p class=\"tspA5jq\">Die \u201eNew York Times\u201c hatte zuvor bereits berichtet, dass die USA in dem Krieg bisher ungef\u00e4hr 1100 weitreichende Marschflugk\u00f6rper einsetzten \u2013 nahezu so viel wie der gesamte Vorrat, der noch vorhanden sei. Das Milit\u00e4r feuerte demnach au\u00dferdem mehr als 1000 Tomahawk-Raketen ab \u2013 ungef\u00e4hr das Zehnfache der Menge, die das Pentagon in einem Jahr beschafft. Und es setzte mehr als 1300 Patriot-Abfangraketen ein, was mehr als zwei Jahren Produktion bei den Raten von 2025 entspreche.<\/p>\n<p>Mehr zum Thema<a href=\"https:\/\/www.tagesspiegel.de\/internationales\/vollig-inakzeptabel-trump-lehnt-iranischen-gegenvorschlag-zum-us-friedensplan-ab-15581332.html?icid=topic-list_15590719___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:null},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/internationales\/vollig-inakzeptabel-trump-lehnt-iranischen-gegenvorschlag-zum-us-friedensplan-ab-15581332.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;\u201eV\u00f6llig inakzeptabel\u201c&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;Trump lehnt iranischen Gegenvorschlag zum US-Friedensplan ab&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15581332&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspDBry tspC9rv\" rel=\"nofollow noopener\" target=\"_blank\">\u201eV\u00f6llig inakzeptabel\u201c Trump lehnt iranischen Gegenvorschlag zum US-Friedensplan ab <\/a><a href=\"https:\/\/www.tagesspiegel.de\/internationales\/iran-will-sich-den-usa-nicht-beugen-der-krieg-im-nahen-osten-wird-zu-trumps-waterloo-15581252.html?icid=topic-list_15590719___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:true},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/internationales\/iran-will-sich-den-usa-nicht-beugen-der-krieg-im-nahen-osten-wird-zu-trumps-waterloo-15581252.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;Iran will sich den USA nicht beugen&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;Der Krieg im Nahen Osten wird zu Trumps Waterloo&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15581252&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspDBry tspC9rv\" rel=\"nofollow noopener\" target=\"_blank\">Iran will sich den USA nicht beugen Der Krieg im Nahen Osten wird zu Trumps Waterloo <\/a><a href=\"https:\/\/www.tagesspiegel.de\/internationales\/irans-wegwerfagenten-in-europa-neue-terrorgruppe-beunruhigt-deutsche-behorden-15583132.html?icid=topic-list_15590719___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:null},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/internationales\/irans-wegwerfagenten-in-europa-neue-terrorgruppe-beunruhigt-deutsche-behorden-15583132.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;Irans \u201eWegwerfagenten\u201c in Europa&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;Neue Terrorgruppe beunruhigt deutsche Beh\u00f6rden&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15583132&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspDBry tspC9rv\" rel=\"nofollow noopener\" target=\"_blank\">Irans \u201eWegwerfagenten\u201c in Europa Neue Terrorgruppe beunruhigt deutsche Beh\u00f6rden <\/a><\/p>\n<p class=\"tspA5jq\">Generalstabschef Dan Caine betonte, dass ihm die Regionalkommandos des US-Milit\u00e4rs ausreichende Munitionsvorr\u00e4te f\u00fcr die derzeitigen Missionen meldeten. Skeptiker sorgen sich jedoch weniger um aktuelle Eins\u00e4tze, sondern mehr um die Frage, ob die Munitionsvorr\u00e4te des US-Milit\u00e4rs auch f\u00fcr einen weiteren m\u00f6glichen Gro\u00dfkonflikt, etwa um Taiwan, reichen w\u00fcrden.<\/p>\n","protected":false},"excerpt":{"rendered":"Tausende Angriffe des amerikanischen und israelischen Milit\u00e4rs gab es seit Beginn des Kriegs im Nahen Osten \u2013 ein&hellip;\n","protected":false},"author":2,"featured_media":1015362,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[106,13,345,14,15,12,10,8,9,11,64,103,104],"class_list":{"0":"post-1015361","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-welt","8":"tag-donald-trump","9":"tag-headlines","10":"tag-iran","11":"tag-nachrichten","12":"tag-news","13":"tag-schlagzeilen","14":"tag-top-news","15":"tag-top-meldungen","16":"tag-topmeldungen","17":"tag-topnews","18":"tag-usa","19":"tag-welt","20":"tag-world"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116565997733037208","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1015361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1015361"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1015361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1015362"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1015361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1015361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1015361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}