{"id":1015817,"date":"2026-05-13T11:26:14","date_gmt":"2026-05-13T11:26:14","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1015817\/"},"modified":"2026-05-13T11:26:14","modified_gmt":"2026-05-13T11:26:14","slug":"bpol-nrw-oeffentlichkeitsfahndung-der-bundespolizei-wer-kennt-diesen-mann","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1015817\/","title":{"rendered":"BPOL NRW: \u00d6ffentlichkeitsfahndung der Bundespolizei Wer kennt diesen Mann?"},"content":{"rendered":"<p class=\"date\">13.05.2026 \u2013 10:52<\/p>\n<p class=\"customer\">\n                        <a class=\"story-customer\" title=\"weiter zum newsroom von Bundespolizeidirektion Sankt Augustin\" href=\"https:\/\/www.presseportal.de\/blaulicht\/nr\/70116\" rel=\"nofollow noopener\" target=\"_blank\">Bundespolizeidirektion Sankt Augustin<\/a>\n                    <\/p>\n<p><a data-category=\"citylink-story-view\" data-action=\"click\" data-label=\"Citylink in Meldungsansicht\" class=\"story-city event-trigger\" href=\"https:\/\/www.presseportal.de\/regional\/Rheine%252FH%F6rstel\" title=\"News aus Rheine\/H\u00f6rstel \" rel=\"nofollow noopener\" target=\"_blank\">Rheine\/H\u00f6rstel<\/a> (ots)<\/p>\n<p>Mit Beschluss hat das Amtsgericht M\u00fcnster die \u00d6ffentlichkeitsfahndung nach einem bislang unbekannten T\u00e4ter angeordnet.<\/p>\n<p>Der unbekannte T\u00e4ter wird beschuldigt, am 17. Dezember 2025 im Bahnhof Rheine einen 44-j\u00e4hrigen Mann geschlagen und verletzt zu haben.<\/p>\n<p>Aufgrund von mehreren defekten Zugt\u00fcren kam es beim Einstieg in die Regionalbahn 61 an einer ge\u00f6ffneten T\u00fcr zu einem Gedr\u00e4nge, bei dem der 44-J\u00e4hrige mehrmals vom Unbekannten geschubst wurde. Nach der Aufforderung dies zu unterlassen, schlug der unbekannte T\u00e4ter dem Reisenden unvermittelt dreimal mit der Faust ans Kinn. Der Angegriffene erlitt hierbei Verletzungen im Mundbereich. Nach Ankunft des Zuges im Bahnhof H\u00f6rstel verlie\u00df der Angreifer den Zug.<\/p>\n<p>Laut Beschluss des Amtsgerichtes M\u00fcnster werden die gesicherten Bilder des Unbekannten aus der Video\u00fcberwachungsanlage des Zuges f\u00fcr die \u00d6ffentlichkeitsfahndung unter folgendem Link zur Verf\u00fcgung gestellt:<\/p>\n<p><a target=\"_blank\" class=\"uri-ext outbound\" rel=\"noopener nofollow\" href=\"https:\/\/t1p.de\/vgu2u\">https:\/\/t1p.de\/vgu2u<\/a><\/p>\n<p>Die Bundespolizeiinspektion M\u00fcnster ermittelt wegen K\u00f6rperverletzung und fragt in diesem Zusammenhang:<\/p>\n<p>Wer kennt diesen Mann? Wer kann Hinweise zum Aufenthaltsort des Tatverd\u00e4chtigen geben?<\/p>\n<p>Hinweise nimmt die Bundespolizei unter der kostenfreien Servicenummer 0800 6 888 000 oder jeder anderen Polizeidienststelle entgegen.<\/p>\n<p class=\"contact-headline\">R\u00fcckfragen bitte an:<\/p>\n<p class=\"contact-text\">Bundespolizeidirektion Sankt Augustin<br \/>Bundespolizeiinspektion M\u00fcnster<br \/>Pressestelle<br \/>Roger Schl\u00e4chter<br \/>Telefon: 0251 97437 -1011 (oder -0)<br \/>E-Mail: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/70116\/mailto: presse.ms@polizei.bund.de\" class=\"uri-mailto\" rel=\"nofollow noopener\" target=\"_blank\"> presse.ms@polizei.bund.de<\/a><br \/>X (Twitter): @BPOL NRW<\/p>\n<p>Internet: <a target=\"_blank\" class=\"uri-ext outbound\" rel=\"noopener nofollow\" href=\"https:\/\/www.bundespolizei.de\">www.bundespolizei.de<\/a><\/p>\n<p>Bahnhofstr. 1<br \/>48143 M\u00fcnster<\/p>\n<p>Weitere Informationen erhalten Sie unter <a target=\"_blank\" class=\"uri-ext outbound\" rel=\"noopener nofollow\" href=\"https:\/\/www.bundespolizei.de\">www.bundespolizei.de<\/a> oder <br \/>unter oben genannter Kontaktadresse.<\/p>\n<p class=\"originator\">Original-Content von: Bundespolizeidirektion Sankt Augustin, \u00fcbermittelt durch news aktuell<\/p>\n","protected":false},"excerpt":{"rendered":"13.05.2026 \u2013 10:52 Bundespolizeidirektion Sankt Augustin Rheine\/H\u00f6rstel (ots) Mit Beschluss hat das Amtsgericht M\u00fcnster die \u00d6ffentlichkeitsfahndung nach einem&hellip;\n","protected":false},"author":2,"featured_media":386213,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1843],"tags":[3364,29,30,177,8970,1209,176,121,178,180,179,181],"class_list":{"0":"post-1015817","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-muenster","8":"tag-de","9":"tag-deutschland","10":"tag-germany","11":"tag-kriminalitt","12":"tag-muenster","13":"tag-nordrhein-westfalen","14":"tag-nrw","15":"tag-polizei","16":"tag-presse","17":"tag-pressemeldung","18":"tag-pressemitteilung","19":"tag-pressemitteilungen"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1015817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1015817"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1015817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/386213"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1015817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1015817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1015817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}