{"id":1015936,"date":"2026-05-13T12:32:16","date_gmt":"2026-05-13T12:32:16","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1015936\/"},"modified":"2026-05-13T12:32:16","modified_gmt":"2026-05-13T12:32:16","slug":"von-china-seit-2020-sanktioniert-sprach-kniff-pekings-macht-einreise-von-us-aussenminister-rubio-moeglich","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1015936\/","title":{"rendered":"Von China seit 2020 sanktioniert: Sprach-Kniff Pekings macht Einreise von US-Au\u00dfenminister Rubio m\u00f6glich"},"content":{"rendered":"<p>Von China seit 2020 sanktioniertSprach-Kniff Pekings macht Einreise von US-Au\u00dfenminister Rubio m\u00f6glich<\/p>\n<p>13.05.2026, 11:08 Uhr <\/p>\n<p>Artikel anh\u00f6ren(04:25 min)<\/p>\n<p><img decoding=\"async\" class=\"Image_img__fQCi0 Image_Img_16_9__4BLfH widget-picture-inline_maximizable__t_E7h\" loading=\"eager\" fetchpriority=\"high\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/May-12-2026-Washington-District-Of-Columbia-United-States-U-S-Secretary-of-State-MARCO-RUBIO-leaves-.webp\" alt=\"May-12-2026-Washington-District-Of-Columbia-United-States-U-S-Secretary-of-State-MARCO-RUBIO-leaves-the-White-House-with-President-DONALD-TRUMP-as-they-depart-for-China\"\/>US-Au\u00dfenminister Rubio kurz vor seiner Abreise Richtung S\u00fcdkorea und China. (Foto: picture alliance \/ ZUMAPRESS.com)TeilenFolgen auf:<a href=\"https:\/\/www.whatsapp.com\/channel\/0029Va5cdVJD8SDp5YZgYF01\" title=\"Auf WhatsApp folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/whatsapp.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><a href=\"https:\/\/www.google.com\/preferences\/source?q=n-tv.de\" title=\"ntv als bevorzugte Quelle auf Google hinzuf\u00fcgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/google.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><\/p>\n<p class=\"Typography_text-m__XI0da Typography_weight-bold__uT6mq storyline_lead_text_leadtext__q_wg8\">US-Pr\u00e4sident Trump besucht China. Damit auch sein Au\u00dfenminister einreisen kann, bedient sich Peking offenbar eines sprachlichen Kniffs. Denn eigentlich ist Marco Rubio mit Sanktionen belegt &#8211; und die w\u00fcrden auch eine Einreise unm\u00f6glich machen.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">US-Vertreter sind nach Asien gereist, zun\u00e4chst nach S\u00fcdkorea, an diesem Mittwoch soll es nach Peking weitergehen. Hintergrund der Reise ist der Handel zwischen beiden Staaten, erkl\u00e4rte Pr\u00e4sident Donald Trump vor der Abreise. Zur Delegation geh\u00f6ren neben ihm Finanzminister Scott Bessent und Au\u00dfenminister Marco Rubio. Letzterer ist jedoch mit Sanktionen Pekings belegt und d\u00fcrfte eigentlich nicht einreisen. <\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Als Sohn kubanischer Exilanten trat der in Florida geborene Rubio stets als harter Antikommunist auf. Er kritisierte China in der Vergangenheit immer wieder scharf f\u00fcr dessen Menschenrechtsverletzungen. Im Kongress war er einer der Verfasser eines Gesetzentwurfs, der weitreichende Sanktionen gegen China aufgrund der Unterdr\u00fcckung der muslimischen Minderheit der Uiguren forderte. Immer wieder sprach er sich f\u00fcr ein hartes Vorgehen gegen Chinas F\u00fchrung aus. Er kritisierte zudem das Vorgehen Pekings in Hongkong und unterst\u00fctzte die dortige Demokratiebewegung. <\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Das lie\u00df sich Peking nicht gefallen. 2020 belegte die chinesische Regierung Rubio, der seinerzeit einen der Senatorensitze Floridas innehatte, und weitere US-Politiker mit Sanktionen. Dazu geh\u00f6rte laut &#8222;S\u00fcddeutscher Zeitung&#8220; auch ein Einreiseverbot. Dass die Strafma\u00dfnahmen gegen ihn beendet oder ausgesetzt wurden, ist nicht bekannt. Nun, sechs Jahre sp\u00e4ter, ist Rubio jedoch nicht mehr Senator, sondern US-Au\u00dfenminister. Seine Reise nach China m\u00fcsste nun eigentlich an den bestehenden Sanktionen scheitern. <\/p>\n<p>Das Gl\u00fcck mit den unterschiedlichen Transkriptionen<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Laut dem britischen &#8222;Guardian&#8220; pausiert Peking nicht etwa die Sanktionen oder bedient sich einer besonderen Erkl\u00e4rung, warum Rubios erster Besuch doch m\u00f6glich ist. Stattdessen tut China einfach so, als handle es sich beim US-Au\u00dfenminister nicht um jenen Marco Rubio, der 2020 mit einem Einreiseverbot belegt wurde. Dazu wird einfach eine abweichende Transkription des Namens im Chinesischen verwendet. <\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Bereits kurz vor seiner Ernennung zum US-Au\u00dfenminister im Januar 2025 begannen sowohl die chinesische Regierung als auch chinesische Medien laut &#8222;Guardian&#8220;, ein anderes chinesisches Schriftzeichen f\u00fcr &#8222;lu&#8220; zu verwenden, um die erste Silbe seines Nachnamens darzustellen. <\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Zwei Diplomaten erkl\u00e4rten gegen\u00fcber der Nachrichtenagentur AFP, sie gingen davon aus, dass China diese \u00c4nderung vorgenommen habe, weil Rubio unter der alten Schreibweise seines Namens Sanktionen unterlag, zu denen auch besagtes Einreiseverbot geh\u00f6rte. &#8222;Die Sanktionen richten sich gegen die \u00c4u\u00dferungen und Handlungen von Herrn Rubio w\u00e4hrend seiner Amtszeit als US-Senator in Bezug auf China&#8220;, argumentierte der Sprecher der chinesischen Botschaft, Liu Pengyu, laut &#8222;Guardian&#8220; \u00e4hnlich. Auf die Frage nach dieser sprachlichen \u00c4nderung erkl\u00e4rte die Sprecherin des chinesischen Au\u00dfenministeriums, Mao Ning, laut chinesischen Staatsmedien, sie habe &#8222;dies nicht bemerkt, werde sich aber damit befassen&#8220;. Mao sagte, Rubios englischer Name sei wichtiger.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Wie die britische Zeitung weiter berichtet, sind unterschiedliche Transkriptionen westlicher Namen im Chinesischen nicht ungew\u00f6hnlich. F\u00fcr US-Pr\u00e4sident Trump w\u00fcrden ebenfalls zwei Namen existieren. Die chinesische Regierung und die staatlichen Medien nennen ihn &#8222;Telangpu&#8220;, doch oft wird er auch als &#8222;Chuanpu&#8220; bezeichnet, eine leicht abweichende Transkription. Dass sie genutzt werden, um etwa ein aktives Einreiseverbot gegen jemanden zu kaschieren, ist dann aber doch eher ungew\u00f6hnlich. Und so k\u00f6nnte Rubio am Ende eben doch ohne Sorge in China einreisen. <\/p>\n<p class=\"Typography_text-s__wu_cm Typography_weight-normal__pqUbH Typography_color-darkgrey__sZEnP article-detail-footer_source__KslPc\">Quelle: ntv.de, als<\/p>\n","protected":false},"excerpt":{"rendered":"Von China seit 2020 sanktioniertSprach-Kniff Pekings macht Einreise von US-Au\u00dfenminister Rubio m\u00f6glich 13.05.2026, 11:08 Uhr Artikel anh\u00f6ren(04:25 min)&hellip;\n","protected":false},"author":2,"featured_media":1015937,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[227,106,13,409,14,15,16,1155,12,10,8,9,11,103,104],"class_list":{"0":"post-1015936","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-welt","8":"tag-china","9":"tag-donald-trump","10":"tag-headlines","11":"tag-marco-rubio","12":"tag-nachrichten","13":"tag-news","14":"tag-politik","15":"tag-sanktionen","16":"tag-schlagzeilen","17":"tag-top-news","18":"tag-top-meldungen","19":"tag-topmeldungen","20":"tag-topnews","21":"tag-welt","22":"tag-world"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116567288787310693","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1015936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1015936"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1015936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1015937"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1015936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1015936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1015936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}