{"id":1016294,"date":"2026-05-13T15:48:15","date_gmt":"2026-05-13T15:48:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1016294\/"},"modified":"2026-05-13T15:48:15","modified_gmt":"2026-05-13T15:48:15","slug":"klinik-in-duisburg-erster-kabelloser-herzschrittmacher-eingesetzt","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1016294\/","title":{"rendered":"Klinik in Duisburg: Erster kabelloser Herzschrittmacher eingesetzt"},"content":{"rendered":"<p class=\"text_ohne_einzug richtext text-em-55 !leading-serif mx-6 desktop:mx-0\">Im Herzzentrum <a href=\"https:\/\/rp-online.de\/thema\/duisburg\/\" rel=\"nofollow noopener\" target=\"_blank\">Duisburg<\/a> ist erstmals erfolgreich ein kabelloser Herzschrittmacher implantiert worden. Den Eingriff f\u00fchrte Dr. Hamdi Elfarra, Leitender Oberarzt der Klinik f\u00fcr Herzchirurgie und Kinderherzchirurgie sowie Leiter des Bereichs Rhythmuschirurgie unter Chefarzt Prof. Dr. Jochen B\u00f6rgermann, mit seinem Team durch. Das teilte das Herzzentrum nun mit, die Einrichtung geh\u00f6rt zum Evangelischen Klinikum Niederrhein.<\/p>\n<p class=\"richtext text-em-55 !leading-serif mx-6 desktop:mx-0\">Die Patientin hatte bereits vor zwei Jahren einen Herzschrittmacher erhalten, nachdem ihr Herz nicht mehr im richtigen Rhythmus geschlagen hat. Sp\u00e4ter traten jedoch Komplikationen auf. Im Bereich des Implantats entwickelte sich etwa eine Infektion. Au\u00dferdem war eine Vene unter dem Schl\u00fcsselbein verschlossen, \u00fcber die normalerweise neue Elektroden zum Herz geschoben werden. Eine OP mit einem klassischen Schrittmachersystem war deshalb bei der Patientin nur eingeschr\u00e4nkt m\u00f6glich.<\/p>\n<p>Schrittmacher wird \u00fcber die Leiste eingesetzt      <\/p>\n<p class=\"richtext text-em-55 !leading-serif mx-6 desktop:mx-0\">Das Behandlungsteam aus der Duisburger Klinik entschied sich daher f\u00fcr ein kabelloses System. Im Unterschied zu herk\u00f6mmlichen Herzschrittmachern braucht das weder Elektroden noch ein Aggregat unter der Haut. Statt \u00fcber den Brustbereich wird das kleine System minimalinvasiv \u00fcber die Leiste direkt im Herzen eingesetzt.<\/p>\n<p class=\"richtext text-em-55 !leading-serif mx-6 desktop:mx-0\">\u201eMit dieser Technologie k\u00f6nnen wir gerade in komplexen F\u00e4llen eine schonende Alternative anbieten\u201c, sagt Dr. Elfarra. \u201eInsbesondere wenn klassische Zugangswege nicht mehr zur Verf\u00fcgung stehen, er\u00f6ffnet sie neue M\u00f6glichkeiten in der Behandlung.\u201c<\/p>\n<p>Ger\u00e4te sind deutlich kleiner als herk\u00f6mmliche Modelle      <\/p>\n<p class=\"richtext text-em-55 !leading-serif mx-6 desktop:mx-0\">Herzschrittmacher werden generell eingesetzt, wenn das Herz zu langsam oder zu unregelm\u00e4\u00dfig schl\u00e4gt. Die kleinen Ger\u00e4te senden elektrische Impulse aus und sorgen so daf\u00fcr, dass das Herz im richtigen Rhythmus arbeitet. Kabellose Herzschrittmacher gelten als vergleichsweise neue Technologie. Sie sind deutlich kleiner als herk\u00f6mmliche Systeme und werden ohne Elektroden direkt im Herzen platziert.<\/p>\n<p class=\"richtext text-em-55 !leading-serif mx-6 desktop:mx-0\">Mit dem Eingriff erweitert das Herzzentrum Duisburg sein Behandlungsspektrum nach eigenen Angaben um eine Option f\u00fcr Patienten, bei denen herk\u00f6mmliche Verfahren nicht mehr infrage kommen.<\/p>\n","protected":false},"excerpt":{"rendered":"Im Herzzentrum Duisburg ist erstmals erfolgreich ein kabelloser Herzschrittmacher implantiert worden. Den Eingriff f\u00fchrte Dr. Hamdi Elfarra, Leitender&hellip;\n","protected":false},"author":2,"featured_media":1016295,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1838],"tags":[3364,29,3715,29360,30,3914,218608,65154,218603,31506,218607,218604,218606,16179,52251,1209,36160,218609,218605,17622],"class_list":{"0":"post-1016294","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-duisburg","8":"tag-de","9":"tag-deutschland","10":"tag-duisburg","11":"tag-erstmals","12":"tag-germany","13":"tag-herz","14":"tag-herzchirurgie","15":"tag-herzen","16":"tag-herzschrittmacher","17":"tag-herzzentrum","18":"tag-kabellose","19":"tag-kabelloser","20":"tag-kinderherzchirurgie","21":"tag-komplikationen","22":"tag-leiste","23":"tag-nordrhein-westfalen","24":"tag-patientin","25":"tag-schrittmacher","26":"tag-schrittmachersystem","27":"tag-system"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116568058236706096","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1016294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1016294"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1016294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1016295"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1016294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1016294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1016294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}