{"id":1016425,"date":"2026-05-13T17:01:15","date_gmt":"2026-05-13T17:01:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1016425\/"},"modified":"2026-05-13T17:01:15","modified_gmt":"2026-05-13T17:01:15","slug":"africa-forward-paris-sucht-in-nairobi-nach-neuen-impulsen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1016425\/","title":{"rendered":"&#8222;Africa Forward&#8220;: Paris sucht in Nairobi nach neuen Impulsen"},"content":{"rendered":"<p>Der Afrika-<a class=\"internal-link\" href=\"https:\/\/www.dw.com\/de\/frankreich\/t-17518447\" rel=\"nofollow noopener\" target=\"_blank\">Frankreich<\/a>-Gipfel hat \u00fcber die Jahre so manche Metamorphose durchlaufen: Vom Auftakt 1973 in der <a class=\"internal-link\" href=\"https:\/\/www.dw.com\/de\/zentralafrikanische-republik\/t-17532999\" rel=\"nofollow noopener\" target=\"_blank\">Zentralafrikanischen Republik<\/a>, auf Initiative des ersten nigrischen Staatspr\u00e4sidenten Hamani Diori, \u00fcber den Gipfel 1990 im franz\u00f6sischen\u00a0La Baule, wo\u00a0Pr\u00e4sident Fran\u00e7ois Mitterrand Entwicklungshilfen st\u00e4rker an Fortschritte bei Demokratisierung, Menschenrechten und Rechtsstaatlichkeit in den afrikanischen Partnerl\u00e4ndern kn\u00fcpfte, bis heute &#8211; immer wieder haben\u00a0sich Format und Inhalte grundlegend gewandelt.<\/p>\n<p>Auch\u00a0<a class=\"internal-link\" href=\"https:\/\/www.dw.com\/de\/emmanuel-macron\/t-38664576\" rel=\"nofollow noopener\" target=\"_blank\">Pr\u00e4sident Emmanuel Macron<\/a>\u00a0hat bereits mit einer Tradition gebrochen: 2021 in Montpellier blieben die Staatschefs zugunsten der Zivilgesellschaft gleich ganz zu Hause. Jetzt, weitere f\u00fcnf Jahre sp\u00e4ter, fiel die Wahl auf ein Land, das durchaus Gipfel-erfahren &#8211; und doch in diesem Kontext eine kleine Sensation ist: Denn mit <a class=\"internal-link\" href=\"https:\/\/www.dw.com\/de\/kenia\/t-17534427\" rel=\"nofollow noopener\" target=\"_blank\">Kenia<\/a>\u00a0verlegte Macron die Begegnung <a class=\"internal-link\" href=\"https:\/\/www.dw.com\/de\/afrika-gipfel-in-kenia-frankreich-sucht-neue-partner\/a-77091271\" rel=\"nofollow noopener\" target=\"_blank\">erstmals in die Anglophonie<\/a>.<\/p>\n<p>Frankreich orientiert sich zum englischsprachigen Afrika<\/p>\n<p>F\u00fcr viele Beobachter spiegelt die Wahl Kenias den Willen Frankreichs wider, sich dem englischsprachigen Afrika zuzuwenden, das als wirtschaftlich dynamischer gilt.<\/p>\n<p><img data-format=\"MASTER_LANDSCAPE\" data-id=\"77115544\" data-url=\"https:\/\/static.dw.com\/image\/77115544_${formatId}.jpg\" data-aspect-ratio=\"16\/9\" alt=\"Africa Forward Summit 2026 | Macron, Ruto &amp; weitere Teilnehmer\" style=\"padding-bottom: 56.25%; height: 0; max-height: 0;\"\/>Der Gipfel &#8222;Africa Forward&#8220; fand am\u00a011. Mai 2026 in der Taifa Hall der Universit\u00e4t Nairobi in Kenia stattBild: Monicah Mwangi\/REUTERS<\/p>\n<p>Es geht aber nicht nur um die Wirtschaft, sondern auch um die grunds\u00e4tzliche Ausrichtung der franz\u00f6sischen Politik: Die Beziehungen zwischen <a class=\"internal-link\" href=\"https:\/\/www.dw.com\/de\/afrikanisches-jahr-1960-wo-stehen-frankreichs-ex-kolonien\/a-73730903\" rel=\"nofollow noopener\" target=\"_blank\">Paris und mehreren frankophonen Partnern<\/a> haben sich <a class=\"internal-link\" href=\"https:\/\/www.dw.com\/de\/frankreichs-einfluss-in-afrika-schwindet\/a-71246564\" rel=\"nofollow noopener\" target=\"_blank\">in den letzten Jahren stark verschlechtert<\/a>. Der Ausrichtungsort Nairobi wird daher als Symbol gelesen. Der Afrika-Experte Antoine Glaser etwa sieht darin eine politische Botschaft an die ehemaligen Hauptst\u00e4dte des frankophonen Einflussbereichs:<\/p>\n<p>&#8222;Es hei\u00dft\u00a0immer, auf diesem Gipfel w\u00fcrde nur \u00fcber Wirtschaft, Sport und Kultur gesprochen &#8211;\u00a0aber ich habe selten einen so politischen Gipfel gesehen&#8220;, findet der franz\u00f6sische Journalist. &#8222;Es ist eine Botschaft an die Staatschefs des frankophonen Afrikas: Ihr habt Frankreich weggeschickt\u2026 <a class=\"internal-link\" href=\"https:\/\/www.dw.com\/de\/hat-macron-das-undankbare-afrika-endg\u00fcltig-verprellt\/a-71267530\" rel=\"nofollow noopener\" target=\"_blank\">Glaubt ihr immer noch, dass wir euch brauchen?<\/a> Wir gehen jetzt ins englischsprachige Afrika und werden unsere Gesch\u00e4fte dort machen.&#8220;<\/p>\n<p>Ostafrika: eine Region mit starkem Wachstum<\/p>\n<p>Die Zahlen scheinen diese Entwicklung zu best\u00e4tigen. Zwischen 2004 und 2015 verzeichneten die \u00fcberwiegend englischsprachigen <a rel=\"noopener follow nofollow\" target=\"_blank\" class=\"external-link\" href=\"https:\/\/www.comesa.int\/\" title=\"Externer Link \u2014 COMESA\">COMESA<\/a>-L\u00e4nder (eine 1994 gegr\u00fcndete Wirtschaftsgemeinschaft aus\u00a021 Mitgliedsstaaten im \u00f6stlichen und s\u00fcdlichen Afrika mit Sitz in Lusaka, Sambia) ein Wachstum von \u00fcber 6 Prozent &#8211;\u00a0fast doppelt so viel, wie das in einigen\u00a0franz\u00f6sischsprachigen L\u00e4ndern der Fall ist.<\/p>\n<p>Kenia, die zweitgr\u00f6\u00dfte Volkswirtschaft Ostafrikas, d\u00fcrfte laut UNO im Jahr 2026 ein Wachstum von 5,1 Prozent verzeichnen. Nairobi pr\u00e4sentiert sich heute als stabile und attraktive regionale Plattform f\u00fcr ausl\u00e4ndische Investitionen.<\/p>\n<p><img data-format=\"MASTER_LANDSCAPE\" data-id=\"77093921\" data-url=\"https:\/\/static.dw.com\/image\/77093921_${formatId}.jpg\" data-aspect-ratio=\"16\/9\" alt=\"Kenia Nairobi 2026 | Motorradfahrer vor Plakat zum Kenya-France Africa Forward Summit\" style=\"padding-bottom: 56.25%; height: 0; max-height: 0;\"\/>Die Gastgeber Ruto und Macron auf einem Werbeplakat f\u00fcr den Gipfel &#8222;Africa Forward&#8220; in NairobiBild: Simon Maina\/AFP<\/p>\n<p>F\u00fcr Frank Baasner, emeritierter Professor an der Universit\u00e4t Mannheim, erm\u00f6glicht diese Strategie Frankreich zudem, seinen Einfluss gegen\u00fcber <a class=\"internal-link\" href=\"https:\/\/www.dw.com\/de\/wie-china-und-die-usa-um-afrikas-rohstoffe-buhlen\/a-74716920\" rel=\"nofollow noopener\" target=\"_blank\">China auf dem afrikanischen Kontinent<\/a> zu wahren &#8211;\u00a0im Gegensatz zu Deutschland: &#8222;Es gibt\u00a0keine deutschen Ambitionen in Afrika, wenn man das mit Frankreich vergleicht. Das ist nat\u00fcrlich eine Tradition.&#8220;<\/p>\n<p>Der ehemalige Direktor des Deutsch-Franz\u00f6sischen Instituts pr\u00e4zisiert: &#8222;Jetzt weitet sich das aus und wird eher zu einer Investitionsstrategie, um diesen gro\u00dfen, jungen und dynamischen Kontinent nicht China zu \u00fcberlassen. Es stimmt, dass es zweifellos eine kluge Entscheidung ist, dort zu investieren, wo die Chinesen bereits investiert haben. Und die Deutschen lassen\u00a0diesen Zug meiner Meinung nach vorbeifahren, anstatt aufzuspringen.&#8220;<\/p>\n<p>Am Dienstag (12.05.2026) k\u00fcndigte Frankreichs Pr\u00e4sident Macron Investitionen in H\u00f6he von 23\u00a0Milliarden Euro in verschiedenen Sektoren in Afrika an, darunter Energie, k\u00fcnstliche Intelligenz und Landwirtschaft.<\/p>\n<p>Milit\u00e4rische Zusammenarbeit von Nairobi und Paris<\/p>\n<p>Auch die sicherheitspolitische Dimension hat eine zentrale Bedeutung: Nachdem die franz\u00f6sischen Streitkr\u00e4fte zuletzt <a class=\"internal-link\" href=\"https:\/\/www.dw.com\/de\/elfenbeink\u00fcste-k\u00fcndigt-abzug-franz\u00f6sischer-truppen-an\/a-71195400\" rel=\"nofollow noopener\" target=\"_blank\">aus mehreren westafrikanischen L\u00e4ndern nacheinander abgezogen<\/a> wurden, waren kurz vor dem Gipfel 800 franz\u00f6sische Soldaten in Kenia eingetroffen.<\/p>\n<p>Ein bereits im Oktober 2025 unterzeichnetes Abkommen \u00fcber die milit\u00e4rische Zusammenarbeit zwischen Nairobi und Paris, das im vergangenen April vom kenianischen Parlament ratifiziert wurde, besiegelte diese neue strategische Partnerschaft zwischen Frankreich und Ostafrika.<\/p>\n<p><img data-format=\"MASTER_LANDSCAPE\" data-id=\"77115627\" data-url=\"https:\/\/static.dw.com\/image\/77115627_${formatId}.jpg\" data-aspect-ratio=\"16\/9\" alt=\"Africa Forward Summit 2026 | Teilnehmer in der Taifa Hall der Universit\u00e4t Nairobi\" style=\"padding-bottom: 56.25%; height: 0; max-height: 0;\"\/>Einige Zuschauer in der Taifa Hall der Universit\u00e4t Nairobi waren Pr\u00e4sident Macron offenkundig zu lautBild: Thomas Mukoya\/REUTERS<\/p>\n<p>Zwischenfall bei Podiumsdiskussion<\/p>\n<p>Ger\u00e4uschlos war Emmanuel Macrons Auftritt in Nairobi indes nicht: Sichtlich genervt vom L\u00e4rm im Saal hatte er w\u00e4hrend einer Podiumsdiskussion von K\u00fcnstlern und jungen Unternehmern die B\u00fchne gest\u00fcrmt und vom Publikum Ruhe verlangt. Der L\u00e4rm\u00a0sei ein &#8222;v\u00f6lliger Mangel an Respekt&#8220;. Videos von Macrons hitziger Intervention verbreiteten sich in den sozialen Medien und l\u00f6sten eine Mischung aus Spott, Lob und Kritik aus.<\/p>\n<p>Mit dem Gipfel will Frankreich den Wandel von der ehemaligen Kolonialmacht, die als dominant wahrgenommen wurde, hin zu dem, was Paris als Partnerschaft auf Augenh\u00f6he beschreibt, demonstrieren. F\u00fcr manche Beobachter passte Macrons Aktion da nicht wirklich ins Bild:<\/p>\n<p>&#8222;Stellen Sie sich nur vor, was passieren w\u00fcrde, wenn ein afrikanischer Staatschef dasselbe in Amerika oder Europa tun w\u00fcrde&#8220;, sagte Thierno Mbaye, Geschichtsstudent an einer Universit\u00e4t in Senegals Hauptstadt Dakar, gegen\u00fcber AP. &#8222;Er hat sich wie ein Lehrer verhalten, der Kinder zurechtweist.&#8220; Auch aus Frankreich gab es Kritik: &#8222;Es liegt nicht in seiner Macht: Sobald er den afrikanischen Kontinent betritt, kann er nicht anders, als sich wie ein Kolonialherr zu verhalten&#8220;, schrieb Dani\u00e8le Obono, Abgeordnete der radikal linken Partei La France insoumise, auf X.<\/p>\n<p><img data-format=\"MASTER_LANDSCAPE\" data-id=\"77115371\" data-url=\"https:\/\/static.dw.com\/image\/77115371_${formatId}.jpg\" data-aspect-ratio=\"16\/9\" alt=\"Africa Forward Summit 2026 | Emmanuel Macron bei Pressekonferenz in Nairobi\" style=\"padding-bottom: 56.25%; height: 0; max-height: 0;\"\/>Emmanuel Macron bei der Pressekonferenz im Vorfeld des Gipfels in Nairobi: &#8222;Wir sind die wahren Panafrikanisten&#8220;Bild: Thomas Mukoya\/REUTERS<\/p>\n<p>Macron, der Panafrikanist?<\/p>\n<p>Bereits im Vorfeld des Gipfels hatte Macron heftige Kritik auf sich gezogen, weil er auf einer Pressekonferenz an der Seite des kenianischen Pr\u00e4sidenten William Ruto behauptet hatte: &#8222;Wir sind die wahren Panafrikanisten.&#8220;<\/p>\n<p>Panafrikanismus bezeichnet eine Ideologie, die die Einheit der Afrikaner und die Beseitigung des Kolonialismus anstrebt. Angesichts der kolonialen Vergangenheit Frankreichs hatte Macrons \u00c4u\u00dferung deutliche Gegenreaktionen ausgel\u00f6st: &#8222;Panafrikanismus ist keine Marke, Herr Macron, und auch keine diplomatische Haltung&#8220;, erkl\u00e4rte Farida Nabourema, eine togolesische Menschenrechtsaktivistin, in einem offenen Brief. &#8222;Es ist eine politische Philosophie, die Nein zu allem sagt, wozu Frankreich drei Jahrhunderte lang Ja gesagt hat: Sklaverei, Kolonialismus und Neokolonialismus.&#8220;<\/p>\n<p>Macron, der als erster franz\u00f6sischer Pr\u00e4sident nach der Kolonialzeit geboren wurde, habe durch einen informelleren diplomatischen Stil, der auf den Wiederaufbau von Vertrauen abziele, eine Abkehr vom kolonialen Erbe eingeleitet, sagte Alioune Tine, Gr\u00fcnder des Thinktanks Afrikajom Center.<\/p>\n<p>Laut einer Ipsos-Umfrage, die im Auftrag des franz\u00f6sischen Au\u00dfenministeriums im Vorfeld des Gipfels in neun afrikanischen L\u00e4ndern durchgef\u00fchrt wurde, gaben 74 Prozent der Befragten an, ein positives Bild von Frankreich zu haben. Am h\u00f6chsten war die Zustimmung in englischsprachigen L\u00e4ndern und unter den Befragten unter 35 Jahren.<\/p>\n<p>Adaptiert aus dem Franz\u00f6sischen von Nikolas Fischer<\/p>\n","protected":false},"excerpt":{"rendered":"Der Afrika-Frankreich-Gipfel hat \u00fcber die Jahre so manche Metamorphose durchlaufen: Vom Auftakt 1973 in der Zentralafrikanischen Republik, auf&hellip;\n","protected":false},"author":2,"featured_media":1016426,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3974],"tags":[331,332,548,663,3934,3980,156,13,14,15,12],"class_list":{"0":"post-1016425","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-frankreich","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-eu","11":"tag-europa","12":"tag-europe","13":"tag-france","14":"tag-frankreich","15":"tag-headlines","16":"tag-nachrichten","17":"tag-news","18":"tag-schlagzeilen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116568345561077227","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1016425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1016425"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1016425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1016426"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1016425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1016425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1016425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}