{"id":1016451,"date":"2026-05-13T17:16:16","date_gmt":"2026-05-13T17:16:16","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1016451\/"},"modified":"2026-05-13T17:16:16","modified_gmt":"2026-05-13T17:16:16","slug":"ehefrau-ueberfaehrt-ehemann-wegen-vermoegen-lebenslange-haft-in-dresden","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1016451\/","title":{"rendered":"Ehefrau \u00fcberf\u00e4hrt Ehemann wegen Verm\u00f6gen: Lebenslange Haft in Dresden"},"content":{"rendered":"<p>Lebenslang! Ehefrau und G\u00e4rtner ermorden Anwalt f\u00fcr sein Erbe<img alt=\"Die Hauptangeklagte (M) sitzt vor Beginn des Prozesses gegen eine 52 Jahre alte Frau und einen 76 Jahre alten Mann wegen Mordes und Beihilfe in einem Verhandlungssaal im Landgericht, daneben stehen ihre Rechtsanw\u00e4lte. Die Angeklagte soll ihren Ehemann im September vergangenen Jahres absichtlich angefahren haben. Der 76-J\u00e4hrige wurde schwer verletzt und starb. Der Mitangeklagte soll den Plan der Frau, ihren Mann zu t\u00f6ten, gekannt und ihr das Auto daf\u00fcr besorgt haben. Ihm wird Beihilfe vorgeworfen. +++ dpa-Bildfunk +++\" fetchpriority=\"high\" width=\"940\" height=\"529\" decoding=\"async\" data-nimg=\"1\" class=\"Image_image__SdgLQ Picture_image__vGN9W\" style=\"color:transparent\"   src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/die-hauptangeklagte-m-sitzt-vor-beginn-des-prozesses-gegen-eine-52-jahre-alte-frau-und-einen-76-jahr.webp\"\/><\/p>\n<p>Die 53-J\u00e4hrige wurde wegen Mordes zu lebenslanger Haft verurteilt. <\/p>\n<p>picture alliance\/dpa \/ Robert Michael<\/p>\n<p>13. Mai 2026 um 18:56 Uhr<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Die Geschichte klingt nach einem Film Noir, ist aber Realit\u00e4t: Eine Frau t\u00f6tet ihren wohlhabenden Mann, um an sein Erbe zu kommen. Mit dabei im Mordkomplott &#8211; der G\u00e4rtner der Familie. Beide m\u00fcssen nun lebenslang in Haft.<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Weil sie ihren joggenden Ehemann mit einem Auto \u00fcberfuhr und t\u00f6tete, hat das Landgericht Dresden eine 53-J\u00e4hrige wegen Mordes zu lebenslanger Haft verurteilt. Nach 44 Verhandlungstagen sah es das Gericht in der s\u00e4chsischen Landeshauptstadt als erwiesen an, dass die Angeklagte ihren deutlich \u00e4lteren Ehemann ermordet hatte, um an sein Verm\u00f6gen zu kommen, wie ein Gerichtssprecher mitteilte. Ein mitangeklagter 76-J\u00e4hriger wurde ebenfalls zu lebenslanger Haft verurteilt.<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Laut den Urteilsfeststellungen hatte die Angeklagte im September 2024 im s\u00e4chsischen Klipphausen mit einem Gel\u00e4ndewagen von hinten ihren joggenden Ehemann angefahren. Anschlie\u00dfend \u00fcberrollte sie ihn mit dem Auto. Der 76 Jahre alte Mann starb noch am Tatort.<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Die Angeklagte habe ihren Mann heimt\u00fcckisch und aus Habgier ermordet, um an sein Erbe zu gelangen. Dabei habe sie die Arg- und Wehrlosigkeit ihres Ehemanns bewusst ausgenutzt. Das Gericht stellte die besondere Schwere der Schuld fest, womit eine vorzeitige Haftentlassung nach 15 Jahren quasi ausgeschlossen ist. Der Mann war einem Bericht der \u201eDresdner Neueste Nachrichten\u201c ein wohlhabender Anwalt und ehemaliger Insolvenzverwalter.<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Der 76-j\u00e4hrige Mitangeklagte, ein ehemaliger Hausmeister und G\u00e4rtner der Eheleute, wurde ebenfalls wegen Mordes verurteilt, auch er muss lebenslang ins Gef\u00e4ngnis. Er soll der 53-J\u00e4hrigen das Auto besorgt und vor der Tat \u00fcbergeben haben. Auch habe er den Transport des besch\u00e4digten Autos zu einem bereits zuvor vereinbartem Reparaturtermin in einer Dresdner Autowerkstatt \u00fcbernommen. Das Gericht ging davon aus, dass er weitgehend in den Tatplan der Angeklagten eingeweiht war und diesen billigte.<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Das Urteil gegen die 53-J\u00e4hrige entsprach der Forderung der Staatsanwaltschaft. Die Verteidigung hatte hingegen auf Freispruch pl\u00e4diert. Der 76-J\u00e4hrige war urspr\u00fcnglich wegen Beihilfe zum Mord angeklagt. Sowohl die Staatsanwaltschaft als auch die Verteidigung pl\u00e4dierten auf Freispruch. Das Urteil ist nicht rechtskr\u00e4ftig.<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Verwendete Quellen: uzh\/AFP<\/p>\n","protected":false},"excerpt":{"rendered":"Lebenslang! Ehefrau und G\u00e4rtner ermorden Anwalt f\u00fcr sein Erbe Die 53-J\u00e4hrige wurde wegen Mordes zu lebenslanger Haft verurteilt.&hellip;\n","protected":false},"author":2,"featured_media":1016452,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1835],"tags":[331,338,332,339,3364,29,2386,344,342,343,30,335,329,336,334,341,330,337,333,328,327,859,12,340],"class_list":{"0":"post-1016451","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dresden","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-nachrichten-auf-einen-blick","10":"tag-aktuelle-news","11":"tag-aktuelle-themen-in-der-welt","12":"tag-de","13":"tag-deutschland","14":"tag-dresden","15":"tag-ems_-news","16":"tag-ems_news_newsausland","17":"tag-ems_news_newsinland","18":"tag-germany","19":"tag-nachrichten-aus-aller-welt","20":"tag-nachrichten-deutschland","21":"tag-nachrichten-heute","22":"tag-nachrichten-international","23":"tag-nachrichten-usa","24":"tag-news-deutschland","25":"tag-news-heute","26":"tag-news-international","27":"tag-rtl-nachrichten","28":"tag-rtl-news","29":"tag-sachsen","30":"tag-schlagzeilen","31":"tag-usa-news"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116568404163744723","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1016451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1016451"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1016451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1016452"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1016451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1016451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1016451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}