{"id":109656,"date":"2025-05-14T10:14:09","date_gmt":"2025-05-14T10:14:09","guid":{"rendered":"https:\/\/www.europesays.com\/de\/109656\/"},"modified":"2025-05-14T10:14:09","modified_gmt":"2025-05-14T10:14:09","slug":"schauspieler-robert-de-niro-teilt-bei-filmfestspielen-in-cannes-gegen-trump-aus","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/109656\/","title":{"rendered":"Schauspieler Robert De Niro teilt bei Filmfestspielen in Cannes gegen Trump aus"},"content":{"rendered":"<p class=\"tspAUhl tspAUhm\"><strong>Robert De Niro<\/strong> hat die <a href=\"https:\/\/www.tagesspiegel.de\/kultur\/eroffnung-des-filmfestivals-cannes-positive-handelsbilanzen-im-weltkino-13672618.html?icid=in-text-link_13687420\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" target=\"_blank\" rel=\"noopener\">Filmfestspiele in Cannes<\/a> mit deutlicher <strong>Kritik an Donald Trump <\/strong>eingel\u00e4utet. Der 81-J\u00e4hrige sendet damit ein Signal an Hollywood, das sich zuletzt mit politischen Statements auffallend zur\u00fcckhielt. Auf der B\u00fchne des Festivalpalastes <strong>kritisierte er die Ank\u00fcndigung des US-Pr\u00e4sidenten, Z\u00f6lle auf im Ausland produzierte Filme erheben zu wollen<\/strong>.\u00a0<\/p>\n<p class=\"tspAUhl\">De Niro erhielt in Cannes die Goldene Ehrenpalme f\u00fcr sein Lebenswerk und wurde mit Standing Ovations begr\u00fc\u00dft. Obwohl er als Trump-Gegner bekannt ist, sind seine Worte bemerkenswert. Denn seit der zweiten Amtseinf\u00fchrung Trumps haben insbesondere US-Filmstars vermieden, \u00f6ffentlich politische Kritik zu \u00fcben. Einzig Trumps F\u00fcrsprecher in der Filmwelt &#8211; allen voran Oscar-Preistr\u00e4ger Jon Voight &#8211; wurden laut.<\/p>\n<p><a href=\"https:\/\/abo.tagesspiegel.de\/tagesspiegel-app?icid=single-topic_13687420___\" data-gtm-class=\"article-mzt-link\" class=\"tspCCmu\" target=\"_blank\" rel=\"noopener\">Die Tagesspiegel-App Aktuelle Nachrichten, Hintergr\u00fcnde und Analysen direkt auf Ihr Smartphone. Dazu die digitale Zeitung. Hier gratis herunterladen.  <\/a><\/p>\n<p class=\"tspAUhl\"><a href=\"https:\/\/www.tagesspiegel.de\/wirtschaft\/deutsche-unternehmen-halten-usa-fur-unberechenbar-mit-trumps-amtsantritt-ist-das-land-wenig-attraktiv-fur-spitzenkrafte-geworden-13677175.html?icid=in-text-link_13687420\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" target=\"_blank\" rel=\"noopener\">Trumps Zoll-Androhung<\/a> h\u00e4ngt zu Beginn der 78. Filmfestspiele wie eine dunkle Wolke \u00fcber Cannes. \u201eIch wei\u00df nicht, was ich dazu sagen soll\u201c, sagte Jury-Pr\u00e4sidentin Juliette Binoche auf Trump angesprochen. \u201eWir k\u00f6nnen sehen, dass er k\u00e4mpft und auf viele, viele verschiedene Arten versucht, Amerika zu retten und seinen Arsch zu retten.\u201c<\/p>\n<p class=\"tspTef\">Empfohlener redaktioneller Inhalt<\/p>\n<p> An dieser Stelle finden Sie einen von unseren Redakteuren ausgew\u00e4hlten, externen Inhalt, der den Artikel f\u00fcr Sie mit zus\u00e4tzlichen Informationen anreichert. Sie k\u00f6nnen sich hier den externen Inhalt mit einem Klick anzeigen lassen oder wieder ausblenden. <\/p>\n<p> Externen Inhalt anzeigen <\/p>\n<p class=\"tspTel\"> Ich bin damit einverstanden, dass mir der externe Inhalt angezeigt wird. Damit k\u00f6nnen personenbezogene Daten an Drittplattformen \u00fcbermittelt werden.  Mehr Informationen dazu erhalten Sie in den Datenschutz-Einstellungen. Diese finden Sie ganz unten auf unserer Seite im Footer, sodass Sie Ihre Einstellungen jederzeit verwalten oder widerrufen k\u00f6nnen. <\/p>\n<p> De Niro ruft zu gewaltfreiem Handeln auf <\/p>\n<p class=\"tspAUhl\">De Niro bezeichnete den US-Pr\u00e4sidenten in seiner Dankesrede als Banausen und rief das Publikum dazu auf, politisch wehrhaft sein. \u201eIn meinem Land k\u00e4mpfen wir mit aller Macht um die Demokratie, die wir einst f\u00fcr selbstverst\u00e4ndlich hielten\u201c, sagte der zweifache Oscar-Preistr\u00e4ger.\u00a0<\/p>\n<p class=\"tspTef\">Empfohlener redaktioneller Inhalt<\/p>\n<p> An dieser Stelle finden Sie einen von unseren Redakteuren ausgew\u00e4hlten, externen Inhalt, der den Artikel f\u00fcr Sie mit zus\u00e4tzlichen Informationen anreichert. Sie k\u00f6nnen sich hier den externen Inhalt mit einem Klick anzeigen lassen oder wieder ausblenden. <\/p>\n<p> Externen Inhalt anzeigen <\/p>\n<p class=\"tspTel\"> Ich bin damit einverstanden, dass mir der externe Inhalt angezeigt wird. Damit k\u00f6nnen personenbezogene Daten an Drittplattformen \u00fcbermittelt werden.  Mehr Informationen dazu erhalten Sie in den Datenschutz-Einstellungen. Diese finden Sie ganz unten auf unserer Seite im Footer, sodass Sie Ihre Einstellungen jederzeit verwalten oder widerrufen k\u00f6nnen. <\/p>\n<p class=\"tspAUhl\">Er fuhr fort: \u201eKunst umarmt die Vielfalt. Und deshalb ist die Kunst eine Bedrohung. Deshalb sind wir eine Bedrohung f\u00fcr Autokraten und Faschisten. Amerikas philisterhafter Pr\u00e4sident hat sich selbst zum Leiter einer unserer wichtigsten Kultureinrichtungen ernannt. Er hat die Mittel und die Unterst\u00fctzung f\u00fcr die K\u00fcnste, die Geisteswissenschaften und die Bildung gek\u00fcrzt. Und jetzt hat er einen 100-prozentigen Zoll auf au\u00dferhalb der USA produzierte Filme angek\u00fcndigt. Lassen Sie das einen Moment auf sich wirken. Man kann Kreativit\u00e4t nicht mit einem Preis belegen, aber anscheinend kann man sie mit einem Zoll belegen. Das ist nat\u00fcrlich inakzeptabel.\u201c<\/p>\n<p class=\"tspAUhl\">De Niro fuhr fort: \u201eWir k\u00f6nnen uns nicht einfach wie bei einer Filmvorf\u00fchrung zur\u00fccklehnen und einfach zuschauen. Wir m\u00fcssen handeln. Und wir m\u00fcssen jetzt handeln \u2013 ohne Gewalt, aber mit gro\u00dfer Leidenschaft und Entschlossenheit. F\u00fcr alle, die sich um unsere Freiheit sorgen, ist es jetzt an der Zeit sich zu organisieren, zu protestieren und zu w\u00e4hlen, wenn es Wahlen gibt.\u201c <\/p>\n<p class=\"tspAUhl\">Der Schauspieler schloss seine Rede mit den Worten \u201eLibert\u00e9, \u00c9galit\u00e9, Fraternit\u00e9\u201c (zu Deutsch: \u201eFreiheit, Gleichheit, Br\u00fcderlichkeit\u201c), die als zentraler Slogan der Franz\u00f6sischen Revolution im Jahr 1789 verwendet wurden und nach wie vor die Ideale der Revolution verk\u00f6rpern.<\/p>\n<p> Leonardo DiCaprio bezeichnet De Niro als Vorbild <\/p>\n<p class=\"tspAUhl\">Die Laudatio auf De Niro hatte zuvor Leonardo DiCaprio gehalten, der seinen Schauspielkollegen als \u201edas Vorbild\u201c bezeichnete, \u201ezu dem wir aufgeschaut haben\u201c. Der 50-J\u00e4hrige beschrieb De Niro so: \u201eEr sagt nicht viel, aber wenn er es tut, ist es wichtig. Ob es um seine Freunde, seine Familie, den Kampf f\u00fcr unsere Demokratie oder die Unterst\u00fctzung der Filmkunst geht, er ist immer dabei.\u201c<\/p>\n<blockquote class=\"tspBKj5\">\n<p>Es ist jetzt an der Zeit, sich zu organisieren und zu protestieren.<\/p>\n<\/blockquote>\n<p class=\"tspBKj6\">Robert de Niro<\/p>\n<p class=\"tspAUhl\">Trumps <a href=\"https:\/\/www.tagesspiegel.de\/potsdam\/brandenburg\/nach-hollywood-schock-beim-filmstudio-babelsberg-sind-viele-fragen-zu-us-zollplanen-offen-13643725.html?icid=in-text-link_13687420\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" target=\"_blank\" rel=\"noopener\">unkonkrete Pl\u00e4ne f\u00fcr die US-Filmwirtschaft<\/a> werden das Festival wohl weiter besch\u00e4ftigen. Festivaldirektor Thierry Fr\u00e9maux hatte vor der Zeremonie gesagt, er habe Schwierigkeiten, zu etwas Stellung zu beziehen, das \u201eauf den Erkl\u00e4rungen des amerikanischen Pr\u00e4sidenten beruht, der uns in den letzten drei Monaten daran gew\u00f6hnt hat, eine Sache zu sagen und sie dann zu erg\u00e4nzen, zu erl\u00e4utern, zu widerlegen und so weiter\u201c.<\/p>\n<p> US-Kino in Cannes stark vertreten <\/p>\n<p class=\"tspAUhl\">Wenn er direkt mit Trump sprechen k\u00f6nnte, w\u00fcrde er ihm sagen, dass ausl\u00e4ndische Filme die amerikanische Fantasie und Kultur bereicherten, so Fr\u00e9maux. \u201eAber ich glaube nicht, dass er wirklich daran interessiert ist\u201c, fuhr er fort und f\u00fcgte hinzu: Cannes werde \u201eniemanden zulassen, der das amerikanische Kino schw\u00e4cht. Und auch in diesem Jahr ist das amerikanische Kino wieder sehr stark, sehr erfinderisch und sehr kreativ.\u201c<\/p>\n<p class=\"tspAUhl\">Die Filmfestspiele dauern bis zum 24. Mai. Mit Regisseuren wie Spike Lee, Richard Linklater, Wes Anderson und Stars wie Tom Cruise, Joaquin Phoenix, Emma Stone, Kristen Stewart, Scarlett Johansson oder Denzel Washington ist das US-Kino tats\u00e4chlich stark vertreten.\u00a0<\/p>\n<p> Lesen Sie auch: <a href=\"https:\/\/www.tagesspiegel.de\/internationales\/grossartige-geste-trump-will-kunftig-geschenkten-luxusjet-aus-katar-als-prasidentenmaschine-nutzen-13680400.html?icid=topic-list_13687420___\" data-gtm-class=\"article-mzt-link\" class=\"tspCCmu\" target=\"_blank\" rel=\"noopener\">\u201eGro\u00dfartige Geste\u201c Trump will k\u00fcnftig geschenkten Luxusjet aus Katar als Pr\u00e4sidentenmaschine nutzen <\/a><a href=\"https:\/\/www.tagesspiegel.de\/politik\/als-geheim-eingestuft-cicero-veroffentlicht-gesamtes-afd-gutachten-13687645.html?icid=topic-list_13687420___\" data-gtm-class=\"article-mzt-link\" class=\"tspCCmu\" target=\"_blank\" rel=\"noopener\">Als geheim eingestuft \u201eCicero\u201c ver\u00f6ffentlicht gesamtes AfD-Gutachten <\/a><a href=\"https:\/\/www.tagesspiegel.de\/politik\/ich-werde-mit-ihm-da-hinfahren-merz-will-mit-trump-winzerort-in-der-pfalz-besuchen-13687255.html?icid=topic-list_13687420___\" data-gtm-class=\"article-mzt-link\" class=\"tspCCmu\" target=\"_blank\" rel=\"noopener\">\u201eIch werde mit ihm da hinfahren\u201c Merz will mit Trump Winzerort in der Pfalz besuchen <\/a><\/p>\n<p class=\"tspAUhl\">22 Filme konkurrieren um die Goldene Palme. Ins Rennen geht auch die Berlinerin Mascha Schilinski mit ihrem Film \u201eIn die Sonne schauen\u201c. Das Drama l\u00e4utet am Mittwoch als erste Premiere den Wettbewerb ein. Abends ist die Weltpremiere von \u201eMission: Impossible \u2013 The Final Reckoning\u201c mit Tom Cruise geplant.\u00a0<\/p>\n<p class=\"tspAUhl\">Cruise ist in Cannes weder auf einer Pressekonferenz noch bei einer anderen f\u00fcr die Presse zug\u00e4nglichen Veranstaltung zugegen &#8211; was bei einer Premiere dieses Kalibers ungew\u00f6hnlich ist. Bei einem Presseevent in London, so schreibt der \u201eHollywood Reporter\u201c, sei Cruise einer Frage zu Trumps Zoll-Pl\u00e4nen unl\u00e4ngst ausgewichen und habe gesagt, er wolle lieber \u00fcber seinen neuen Film sprechen. (dpa, mira)<\/p>\n","protected":false},"excerpt":{"rendered":"Robert De Niro hat die Filmfestspiele in Cannes mit deutlicher Kritik an Donald Trump eingel\u00e4utet. Der 81-J\u00e4hrige sendet&hellip;\n","protected":false},"author":2,"featured_media":109657,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[331,332,3364,29,106,42879,30,13,95,42922,42921,14,15,12,64],"class_list":{"0":"post-109656","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nachrichten","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-de","11":"tag-deutschland","12":"tag-donald-trump","13":"tag-filmfestspiele-cannes","14":"tag-germany","15":"tag-headlines","16":"tag-kino","17":"tag-kulturpreise","18":"tag-leonardo-dicaprio","19":"tag-nachrichten","20":"tag-news","21":"tag-schlagzeilen","22":"tag-usa"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/114505663611842154","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/109656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=109656"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/109656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/109657"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=109656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=109656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=109656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}