{"id":1115236,"date":"2026-06-23T07:31:13","date_gmt":"2026-06-23T07:31:13","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1115236\/"},"modified":"2026-06-23T07:31:13","modified_gmt":"2026-06-23T07:31:13","slug":"anklage-erhoben-polizist-soll-anzeigen-fuer-nacktbilder-gefaelscht-haben-regional","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1115236\/","title":{"rendered":"Anklage erhoben: Polizist soll Anzeigen f\u00fcr Nacktbilder gef\u00e4lscht haben | Regional"},"content":{"rendered":"<p><a class=\"skip-content skip-content--link\" href=\"#in-content-skip-link-target-v-0-0\">TTS-Player \u00fcberspringen\u21b5<\/a><a id=\"in-content-skip-link-target-v-0-0\" class=\"skip-content--target-link-hidden skip-content skip-content--target-link\" href=\"#in-content-skip-link-target-v-0-0\">Artikel weiterlesen<\/a><\/p>\n<p data-780e759e=\"0-578\">Berlin \u2013 <b>Ein Polizist aus Berlin soll amtliche Dokumente gegen Bilder mit sexuellem Inhalt getauscht haben. Die Staatsanwaltschaft wirft dem 41-J\u00e4hrigen vor, f\u00fcr einen Bekannten gef\u00e4lschte Ordnungswidrigkeitsanzeigen erstellt zu haben. Als Gegenleistung soll er die Bilder verlangt haben.<\/b>  <\/p>\n<p data-780e759e=\"0-578\">Der Mann, um den es geht, ist 25 Jahre alt. Laut Staatsanwaltschaft Berlin soll er den Polizisten in den Jahren 2024 und 2025 mehrfach um Hilfe gebeten haben.<\/p>\n<p>Polizist soll gef\u00e4lschte Anzeige erstellt haben<\/p>\n<p data-780e759e=\"0-578\">Am 6. Oktober 2024 soll der Beamte dem 25-J\u00e4hrigen eine ausgef\u00fcllte Ordnungswidrigkeitsanzeige geschickt haben. Der Grund: Der junge Mann wollte seinen Gl\u00e4ubigern vorgaukeln, die Polizei habe 700 Euro von ihm beschlagnahmt. In Wahrheit hatte er das Geld in einem <a href=\"https:\/\/www.bild.de\/regional\/berlin\/berlin-regional\/home-15823246.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Berliner<\/a> Nachtclub ausgegeben. F\u00fcr die gef\u00e4lschte Anzeige soll der Polizist Bilder mit sexuellem Inhalt verlangt haben.<\/p>\n<p>Zweiter Vorwurf gegen Berliner Polizisten<\/p>\n<p data-780e759e=\"579-1157\">Laut Staatsanwaltschaft kam es Monate sp\u00e4ter zu einem weiteren Fall. Am 8. Februar 2025 soll der Beamte dem 25-J\u00e4hrigen eine Abfrage im polizeilichen System versprochen haben. Au\u00dferdem soll er erneut zwei <a href=\"https:\/\/www.bild.de\/themen\/ereignisse\/ordnungswidrigkeit\/news-fotos-videos-17027146.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Ordnungswidrigkeitenanzeigen<\/a> erstellt haben \u2013 erneut im Tausch gegen Bilder mit sexualisiertem Inhalt.<\/p>\n<p data-780e759e=\"1158-1754\">Aufgeflogen ist der Beamte nur durch Zufall: Bei einem Verfahren wegen Bet\u00e4ubungsmittelhandels stellten Ermittler ein Mobiltelefon sicher und werteten es aus. Dabei stie\u00dfen sie auf die brisanten Chats.<\/p>\n<p>Polizist schweigt zu den Vorw\u00fcrfen<\/p>\n<p data-780e759e=\"1158-1754\">Der 41-J\u00e4hrige schweigt laut Staatsanwaltschaft zu den Vorw\u00fcrfen. Nach Bekanntwerden der Anschuldigungen sprach die <a href=\"https:\/\/www.bild.de\/regional\/aktuelles\/polizei\/polizeieinsatz-alle-infos-76681760.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Polizei<\/a> ihm ein Verbot der Dienstaus\u00fcbung aus. Nun muss das Amtsgericht Tiergarten entscheiden, ob die Anklage zur Hauptverhandlung zugelassen wird.<\/p>\n","protected":false},"excerpt":{"rendered":"TTS-Player \u00fcberspringen\u21b5Artikel weiterlesen Berlin \u2013 Ein Polizist aus Berlin soll amtliche Dokumente gegen Bilder mit sexuellem Inhalt getauscht&hellip;\n","protected":false},"author":2,"featured_media":1115237,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1825],"tags":[296,9315,29,30,324,121,1997,138370],"class_list":["post-1115236","post","type-post","status-publish","format-standard","has-post-thumbnail","category-berlin","tag-berlin","tag-chat","tag-deutschland","tag-germany","tag-korruption","tag-polizei","tag-staatsanwaltschaft","tag-team-first"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116798258400086591","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1115236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1115236"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1115236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1115237"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1115236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1115236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1115236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}