{"id":1159495,"date":"2026-07-11T16:34:22","date_gmt":"2026-07-11T16:34:22","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1159495\/"},"modified":"2026-07-11T16:34:22","modified_gmt":"2026-07-11T16:34:22","slug":"testspiele-dynamo-dresden-siegt-lok-muss-sich-hertha-geschlagen-geben","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1159495\/","title":{"rendered":"Testspiele: Dynamo Dresden siegt &#8211; Lok muss sich Hertha geschlagen geben"},"content":{"rendered":"<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/07\/lok-leipzig-hertha-bsc-132.webp\" alt=\"Torjubel bei Hertha BSC nach einem Treffer beim 1. FC Lok Leipzig\" title=\"Torjubel bei Hertha BSC nach einem Treffer beim 1. FC Lok Leipzig |  IMAGO \/ Beautiful Sports\" class=\"responsive\"\/><\/p>\n<p>AUDIO: Fu\u00dfball: Lok Leipzig unterliegt Hertha &#8211; Dynamo gewinnt (1 Min)<\/p>\n<p class=\"topline\">Fu\u00dfball | Testspiele<\/p>\n<p>\n                Stand: 11.07.2026 18:17 Uhr<\/p>\n<p class=\"preface\">Zweitligist Dynamo Dresden zeigt sich gegen Hessen Kassel gut aufgelegt. Lok Leipzig bot gegen Hertha BSC eine ansprechende Leistung. Siege feierten auch Erzgebirge Aue, FSV Zwickau und Chemnitzer FC.<\/p>\n<p>    Dynamo Dresden l\u00e4sst Kassel keine Chance<\/p>\n<p class=\"\">Bei hochsommerlichen Temperaturen hat Dynamo Dresden das Testspiel in Gro\u00dfenhain gegen die KSV Hessen Kassel mit 4:0 (1:0) gewonnen. Zur Pause f\u00fchrte Schwarz-Gelb dank des Treffers von U21-Akteur Nico K\u00fcnzel (38.) mit 1:0. Zum zweiten Durchgang wechselte Trainer Thomas Stamm einmal durch und brachte unter anderem Jonas Oehmichen, der in der 74. Spielminute das 2:0 erzielte. Ein Doppelschlag durch Kaan Inanoglu (87.) und Niklas Remus (88.) sorgte kurz vor Schluss f\u00fcr den 4:0-Sieg. Am Donnerstag reist Dynamo ins Trainingslager ins \u00f6sterreichische Windischgarsten. Dort findet auch das n\u00e4chste Testspiel gegen Erstligist Grazer AK am 18. Juli statt.<\/p>\n<p>    Lok Leipzig h\u00e4lt gegen Hertha mit &#8211; Abschied von Jochen Seitz<\/p>\n<p>                    <a href=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/07\/jochen-seitz-232.webp\" class=\"zoomimage\" title=\"Bild vergr\u00f6\u00dfern\"><\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/07\/jochen-seitz-232.webp\" alt=\"Der fr\u00fcher Lok-Trainer Jochen Seitz (2. v.l.) wird verabschiedet.\" title=\"Der fr\u00fcher Lok-Trainer Jochen Seitz (2. v.l.) wird verabschiedet. |  IMAGO \/ Beautiful Sports\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>                    <\/a><\/p>\n<p>                    Der fr\u00fcher Lok-Trainer Jochen Seitz (2. v.l.) wird verabschiedet.<\/p>\n<p class=\"\">Vor 3.784 Zuschauern im Bruno-Plache-Stadion hat Lok Leipzig das Testspiel gegen Zweitligist Hertha BSC mit 1:3 (1:2) verloren. Gegen gut aufgelegte Leipziger erzielte Sebastian Gr\u00f6nning die F\u00fchrung (32.) f\u00fcr die Berliner. Ayodele Adetula (35.) gelang mit der ersten guten M\u00f6glichkeit der Ausgleich, der Knipser versenkte den Ball im langen unteren Eck. Soufian Gouram sorgte zwei Minuten sp\u00e4ter mit einem 20-Meter-Knaller f\u00fcr die erneute Hertha-F\u00fchrung. Kurz nach Wiederanpfiff stellte Marten Winkler den Endstand her. Vor der Partie wurde Jochen Seitz offiziell verabschiedet. Der 48-J\u00e4hrige war nach dem erneut verpassten Aufstieg von seinem Traineramt zur\u00fcckgetreten. Seitz hatte die Leipziger zweimal in Folge zum Staffelsieg in der Regionalliga Nordost gef\u00fchrt.<\/p>\n<p>    N\u00e4chster Testspielsieg f\u00fcr Aue<\/p>\n<p class=\"\">Im sechsten Testspiel haben die Veilchen den sechsten Sieg eingefahren. Gegen den tschechischen Zweitligisten SK Kladno siegte Aue mit 2:0 (1:0). Nach Vorlage von Keeper Martin M\u00e4nnel traf Linus Quei\u00dfer nach 20 Minuten zur F\u00fchrung. Kurz vor Schluss erzielte Willi Kamm per Strafsto\u00df das 2:0 zum Endstand. &#8222;Nach der Trainingswoche war das ein sehr guter Test f\u00fcr uns. Nat\u00fcrlich hat noch nicht alles funktioniert, aber ich denke, wir sind auf einem guten Weg&#8220;, erkl\u00e4rte Abwehrspieler Patrick Kapp.<\/p>\n<p>    FSV Zwickau feiert Torfestival<\/p>\n<p class=\"\">Vor 480 Zuschauern hat der FSV Zwickau ein Torespektakel pr\u00e4sentiert und den tschechischen Zweiligisten FK Usti nad Labem mit 6:3 (3:2) besiegt. Ein Doppelpack von Cemal Sezer (7., 12.\/FE) sorgte f\u00fcr die F\u00fchrung, die Usti egalisierte (32., 44.), aber Lennert M\u00f6bius sorgte vom Punkt (45.) f\u00fcr die Pausenf\u00fchrung der Schw\u00e4ne. In der zweiten H\u00e4lfte erh\u00f6hten Fynn Seidel (46.) und Veron Dobruna (65.) auf 5:2. Auf den dritten Treffer von Labem folgte das Tor von Philipp Harant (83.) zum 6:3-Endstand.<\/p>\n<p>    Rot-Wei\u00df Erfurt mit erster Testspielniederlage<\/p>\n<p class=\"\">Die Mannschaft von Fabian Gerber hat nach dem 0:0 am Vorabend nun die erste Testspielniederlage hinnehmen m\u00fcssen. Gegen die Zweitvertretung von Mainz 05 unterlagen die Erfurter mit 0:3.<\/p>\n<p>    Chemnitz \u00fcberzeugt gegen Schweinfurt<\/p>\n<p>                    <a href=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/07\/chemnitzer-fc-schweinfurt-100.webp\" class=\"zoomimage\" title=\"Bild vergr\u00f6\u00dfern\"><\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/07\/chemnitzer-fc-schweinfurt-100.webp\" alt=\"Der Chemnitzer Amadeus Zamora Gonzalez (li.) im Duell mit Nicolas Pfarr\" title=\"Der Chemnitzer Amadeus Zamora Gonzalez (li.) im Duell mit Nicolas Pfarr |  IMAGO \/ Max Kilian\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>                    <\/a><\/p>\n<p>                    Der Chemnitzer Amadeus Zamora Gonzalez (li.) im Duell mit Nicolas Pfarr<\/p>\n<p class=\"\">Nach dem starken Auftritt gegen Union Berlin (1:1) unter der Woche haben sich die Himmelblauen zwei Wochen vor Saisonstart erneut in guter Form gezeigt und den Drittligaabsteiger aus Schweinfurt mit 4:0 (2:0) besiegt. Johannes Pistol (6.) und Jonas Marx (16.) sorgten f\u00fcr eine 2:0-Pausenf\u00fchrung. Im zweiten Durchgang erh\u00f6hten Maximilian Fesser (56.) und Neuzugang Jan L\u00f6hmannsr\u00f6ben (77.) und sorgten so f\u00fcr einen komfortablen Sieg.<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/07\/google-handy-100.webp\" alt=\"Ein Handy liegt auf einer Laptoptastatur. Das Display zeigt das Google Logo\" title=\"Ein Handy liegt auf einer Laptoptastatur. Das Display zeigt das Google Logo |  IMAGO \/ SOPA Images\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>Nachrichten personalisieren<\/p>\n<p>Die Nachrichtenlage ist un\u00fcbersichtlich und Sie wollen aktuelle Informationen aus Ihrer Region, die f\u00fcr Sie relevant sind? Dann legen Sie MDR.de als bevorzugte Quelle in der Google-Suche fest. So funktioniert&#8217;s.<\/p>\n","protected":false},"excerpt":{"rendered":"AUDIO: Fu\u00dfball: Lok Leipzig unterliegt Hertha &#8211; Dynamo gewinnt (1 Min) Fu\u00dfball | Testspiele Stand: 11.07.2026 18:17 Uhr&hellip;\n","protected":false},"author":2,"featured_media":1159496,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1835],"tags":[621,6178,3364,29,2386,3766,6044,12444,10149,347,30,12435,3457,859,3499,265,3498,11460],"class_list":["post-1159495","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dresden","tag-2-bundesliga","tag-chemnitzer-fc","tag-de","tag-deutschland","tag-dresden","tag-dynamo-dresden","tag-erzgebirge-aue","tag-fc-rot-weiss-erfurt","tag-fsv-zwickau","tag-fussball","tag-germany","tag-hallescher-fc","tag-lok-leipzig","tag-sachsen","tag-spio","tag-sport","tag-sport-im-osten","tag-testspiel"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116902315733964465","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1159495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1159495"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1159495\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1159496"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1159495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1159495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1159495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}