{"id":11655,"date":"2025-04-06T23:42:27","date_gmt":"2025-04-06T23:42:27","guid":{"rendered":"https:\/\/www.europesays.com\/de\/11655\/"},"modified":"2025-04-06T23:42:27","modified_gmt":"2025-04-06T23:42:27","slug":"krieg-in-der-ukraine-ein-toter-und-verletzte-bei-raketenangriff-auf-kiew-3","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/11655\/","title":{"rendered":"Krieg in der Ukraine: Ein Toter und Verletzte bei Raketenangriff auf Kiew"},"content":{"rendered":"<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t      \t\t            \t\t             \t\t\t\t   \t\t\t\t\t   <img decoding=\"async\" id=\"article-image\" fetchpriority=\"high\" alt=\"Krieg in der Ukraine: Ein Toter und Verletzte bei Raketenangriff auf Kiew\" onclick=\"var pA=document.createElement('a');pA.setAttribute('href','https:\/\/www.stuttgarter-nachrichten.de\/gallery.krieg-in-der-ukraine-russland-greift-kiew-mit-raketen-an.0990c535-a39e-42ec-bf8f-0d4010888df8.html'),pA.click();\" title=\"Krieg in der Ukraine: Ein Toter und Verletzte bei Raketenangriff auf Kiew\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/04\/media.media.f2066a5b-f94b-4253-a843-5303ef4432f9.16x9_700.jpg\" data-linkto=\"https:\/\/www.stuttgarter-nachrichten.de\/gallery.krieg-in-der-ukraine-russland-greift-kiew-mit-raketen-an.0990c535-a39e-42ec-bf8f-0d4010888df8.html\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tIn der Nacht ist Kiew erneut unter Beschuss gekommen.\u00a0Foto: Andreas Stroh\/ZUMA Press Wire\/dpa\t\t\t<\/p>\n<p>Russlands Milit\u00e4r attackiert die Ukraine einmal mehr mit Drohnenschw\u00e4rmen und Raketen. In der Hauptstadt Kiew kommt es zu Explosionen. B\u00fcrgermeister Klitschko spricht von mehreren Opfern.<\/p>\n<p>Kiew &#8211; Das russische Milit\u00e4r hat die <a href=\"https:\/\/www.stuttgarter-nachrichten.de\/thema\/Ukraine\" title=\"Ukraine\" class=\"art_thema\" rel=\"nofollow noopener\" target=\"_blank\">Ukraine<\/a> in der Nacht erneut mit Raketen angegriffen und auch die Hauptstadt Kiew ins Visier genommen. Das Nachrichtenportal &#8222;Kyiv Independent&#8220; berichtete am Morgen unter Berufung auf B\u00fcrgermeister Vitali Klitschko von mehreren Explosionen, drei Verletzten und einem teilweise zerst\u00f6rten B\u00fcrogeb\u00e4ude.\u00a0<\/p>\n<p>In mehreren Bezirken der Millionenstadt seien Br\u00e4nde ausgebrochen, hie\u00df es. Rettungskr\u00e4fte seien im Einsatz. Sp\u00e4ter teilte Klitschko mit, ein Mann sei tot auf einer Stra\u00dfe gefunden worden, die von dem Angriff getroffen worden sei. Auch in anderen Landesteilen herrschte dem Bericht zufolge Raketenalarm.<\/p>\n<p>Flugabwehr machtlos gegen Iskander-Raketen <\/p>\n<p>In einer Bilanz berichtete die ukrainische Luftwaffe vormittags von einem kombinierten russischen Angriff mit 23 Raketen und Marschflugk\u00f6rpern sowie mit 109 Drohnen. 13 Raketen und Marschflugk\u00f6rper seien abgefangen worden. Weitgehend machtlos war die Flugabwehr indes gegen ballistische Raketen vom Typ Iskander-M.\u00a0<\/p>\n<p>Auch 40 Kampfdrohnen iranischer Bauart seien abgeschossen worden. Zudem wurden 53 sogenannter K\u00f6derdrohnen ohne Sprengstoff ausgeschaltet, die zur Ablenkung der Flugabwehr eingesetzt werden. Sch\u00e4den gab es den Milit\u00e4rangaben zufolge in den Gebieten Kiew, Sumy, Charkiw, Chmelnyzkyj, Tscherkassy und Mykolajiw.<\/p>\n","protected":false},"excerpt":{"rendered":"In der Nacht ist Kiew erneut unter Beschuss gekommen.\u00a0Foto: Andreas Stroh\/ZUMA Press Wire\/dpa Russlands Milit\u00e4r attackiert die Ukraine&hellip;\n","protected":false},"author":2,"featured_media":11437,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4013],"tags":[331,332,13,8221,4046,14,15,4043,4044,850,307,12,317],"class_list":{"0":"post-11655","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-russland","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-headlines","11":"tag-konflikte","12":"tag-krieg","13":"tag-nachrichten","14":"tag-news","15":"tag-russia","16":"tag-russian-federation","17":"tag-russische-foederation","18":"tag-russland","19":"tag-schlagzeilen","20":"tag-ukraine"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/114293672725406529","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/11655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=11655"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/11655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/11437"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=11655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=11655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=11655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}