{"id":1214299,"date":"2026-08-04T08:00:18","date_gmt":"2026-08-04T08:00:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1214299\/"},"modified":"2026-08-04T08:00:18","modified_gmt":"2026-08-04T08:00:18","slug":"erpressung-nach-chat-sextortion","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1214299\/","title":{"rendered":"Erpressung nach Chat &#8211; Sextortion"},"content":{"rendered":"<p>Die 13-J\u00e4hrige wurde aufgefordert, sich nackt zu zeigen, was sie auch tat. <\/p>\n<p><strong>Polizeipr\u00e4sidium Rheinpfalz (ots). <\/strong>Eine 13-J\u00e4hrige lernte in den vergangenen Wochen \u00fcber TikTok ein angeblich anderes M\u00e4dchen kennen. Beide chatteten regelm\u00e4\u00dfig miteinander. Im weiteren Verlauf wurde die 13-J\u00e4hrige aufgefordert, sich nackt zu zeigen, was diese auch tat. Unter Androhung die Nacktaufnahmen zu verbreiten, wurden weitere Bilder und Videos gefordert. Die 13-J\u00e4hrige ging nicht auf die Forderung ein und erstattete Anzeige bei der Polizei.<\/p>\n<p>Beachten Sie die Tipps Ihrer Polizei, um sich vor &#8222;sexueller Erpressung&#8220; zu sch\u00fctzen:<\/p>\n<ul class=\"list-normal\">\n<li>Nehmen Sie keine Freundschaftsanfragen von fremden Personen an.<\/li>\n<li>Pr\u00fcfen Sie regelm\u00e4\u00dfig Ihre Account- und   Privatsph\u00e4reneinstellungen.<\/li>\n<li>Seien Sie zur\u00fcckhaltend mit der Ver\u00f6ffentlichung pers\u00f6nlicher Daten wie Anschrift, Geburtsdatum oder Arbeitgeber.<\/li>\n<li>Stimmen Sie nicht vorschnell einem Videochat zu.<\/li>\n<li>Im Zweifel: kleben Sie die Chatkamera zun\u00e4chst ab, um lediglich   verbal zu kommunizieren und das Geschehen zu beobachten.<\/li>\n<li>Stimmen Sie keinen Entbl\u00f6\u00dfungen oder intimen Handlungen in   Videochats zu, wenn Sie die Person erst seit kurzem kennen.<\/li>\n<li>Halten Sie Betriebs- sowie Virenschutzsysteme auf Ihren online-genutzten Endger\u00e4ten wie Smartphone, Laptop, Tablet oder   Computer immer auf dem aktuellen Stand, um sich vor   Schadsoftware, sogenannter Malware, zu sch\u00fctzen. Es gibt Malware, die Ihre Webcam problemlos aktiviert und Sie damit jederzeit filmen kann.<\/li>\n<\/ul>\n<p><strong>Falls Sie bereits erpresst werden:<\/strong><\/p>\n<ul class=\"list-normal\">\n<li>\u00dcberweisen Sie kein Geld. Die Erpressung h\u00f6rt nach der Zahlung   meist nicht auf.<\/li>\n<li>Erstatten Sie Anzeige bei der Polizei.<\/li>\n<li>Kontaktieren Sie den Betreiber der Seite und veranlassen Sie,   dass das Bildmaterial gel\u00f6scht wird. Nicht angemessene Inhalte   kann man dem Seitenbetreiber \u00fcber eigens hierf\u00fcr eingerichtete   \u00a0Buttons melden.<\/li>\n<li>Brechen Sie den Kontakt zu der anonymen Person sofort ab,   reagieren Sie nicht auf Nachrichten.<\/li>\n<li>Sichern Sie die Chatverl\u00e4ufe und Nachrichten mittels   Screenshots.<\/li>\n<\/ul>\n<p>Weitere Informationen zu dem Thema erhalten Sie unter:<\/p>\n<p><a href=\"https:\/\/www.polizei-beratung.de\/aktuelles\/detailansicht\/sextortion-erpressung-mit-nacktbildern\/\" target=\"_blank\" class=\"uri-ext outbound\" rel=\"noreferrer noopener nofollow\">https:\/\/www.polizei-beratung.de\/aktuelles\/detailansicht\/sextortion-erpressung-mit-nacktbildern\/<\/a><\/p>\n<p>Text und Logo: Polizeipr\u00e4sidium Rheinpfalz<\/p>\n","protected":false},"excerpt":{"rendered":"Die 13-J\u00e4hrige wurde aufgefordert, sich nackt zu zeigen, was sie auch tat. Polizeipr\u00e4sidium Rheinpfalz (ots). Eine 13-J\u00e4hrige lernte&hellip;\n","protected":false},"author":2,"featured_media":952582,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1845],"tags":[16222,17310,1634,17312,17302,17311,3364,29,17317,17309,548,663,3934,17313,30,13,17306,14835,7011,17304,2096,14,15,16935,17314,17316,17305,12,17315,17308,17303,17300,17301,17307,571,1986],"class_list":["post-1214299","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mannheim","tag-dom","tag-altpoertel","tag-baden-wuerttemberg","tag-bistum-speyer","tag-brezelfest","tag-brezelkracher","tag-de","tag-deutschland","tag-dudenhofen","tag-eger","tag-eu","tag-europa","tag-europe","tag-evangelische-kirche-der-pfalz","tag-germany","tag-headlines","tag-historisches-museum","tag-hockenheim","tag-kirchen","tag-kurpfalz","tag-mannheim","tag-nachrichten","tag-news","tag-pfalz","tag-protestantische-landeskirche","tag-roemerberg","tag-salier","tag-schlagzeilen","tag-schwetzingen","tag-sealife","tag-speyer","tag-speyer-kurier","tag-tageszeitung","tag-technik-museum","tag-wochenzeitung","tag-zeitung"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/117036189495015138","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1214299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1214299"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1214299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/952582"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1214299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1214299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1214299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}