{"id":1250766,"date":"2026-08-21T06:52:29","date_gmt":"2026-08-21T06:52:29","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1250766\/"},"modified":"2026-08-21T06:52:29","modified_gmt":"2026-08-21T06:52:29","slug":"depressionen-im-alter-mit-geringerem-volumen-in-teilen-des-hippocampus-verbunden","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1250766\/","title":{"rendered":"Depressionen im Alter mit geringerem Volumen in Teilen des Hippocampus verbunden"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Eine Studie mit mehr als 2.000 kognitiv gesunden \u00e4lteren Erwachsenen ergab, dass Depressionen mit strukturellen Unterschieden in einem bestimmten Bereich des Hippocampus einhergingen \u2013 unabh\u00e4ngig von wesentlichen Risikofaktoren f\u00fcr die Alzheimer-Krankheit.<\/strong><\/p>\n<p class=\"wp-block-paragraph\">Forschende des USC Mark and Mary Stevens Neuroimaging and Informatics Institute (Stevens INI) an der Keck School of Medicine der USC haben festgestellt, dass Depressionen mit einem geringeren Volumen in einem bestimmten Teil des Hippocampus einhergehen.<\/p>\n<p class=\"wp-block-paragraph\">Die in der Fachzeitschrift \u201eTranslational Psychiatry\u201c <a href=\"https:\/\/doi.org\/10.1038\/s41398-026-04223-y\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">ver\u00f6ffentlichte<\/a> Studie untersuchte hochaufl\u00f6sende Gehirnscans von 2.009 kognitiv gesunden Erwachsenen im Alter von 50 bis 90 Jahren. Dabei zeigte sich, dass Teilnehmende mit Depressionen ein geringeres Volumen in einem Hippocampus-Bereich aufwiesen, der die Regionen CA2, CA3 und den Gyrus dentatus umfasst \u2013 zusammenfassend als CA23DG bezeichnet. Dieser Zusammenhang bestand auch dann noch, als Faktoren wie der Body-Mass-Index, die k\u00f6rperliche Aktivit\u00e4t sowie wichtige biologische Indikatoren f\u00fcr das Alzheimer-Risiko (darunter Amyloid- und Tau-Proteine \u200b\u200bsowie die genetische Variante APOE \u03b54) ber\u00fccksichtigt wurden.<\/p>\n<p class=\"wp-block-paragraph\">\u201eDepressionen werden schon lange mit einem erh\u00f6hten Risiko f\u00fcr die Entwicklung von Alzheimer in Verbindung gebracht, doch der biologische Zusammenhang zwischen beiden ist noch nicht vollst\u00e4ndig gekl\u00e4rt\u201c, erkl\u00e4rt Danielle Luu, Erstautorin der Studie und Doktorandin im Neurowissenschafts-Programm der USC. \u201eDurch die genaue Betrachtung der einzelnen Teile des Hippocampus konnten wir einen spezifischen Bereich identifizieren, der bei \u00e4lteren Erwachsenen m\u00f6glicherweise besonders anf\u00e4llig f\u00fcr die Auswirkungen von Depressionen ist.\u201c<\/p>\n<p>Ein genauerer Blick auf das Ged\u00e4chtniszentrum des Gehirns<\/p>\n<p class=\"wp-block-paragraph\">Der Hippocampus spielt eine zentrale Rolle bei der Bildung und dem Abruf von Erinnerungen. Obwohl er oft als eine einzige Hirnregion betrachtet wird, setzt er sich aus mehreren kleineren Abschnitten \u2013 sogenannten Teilfeldern \u2013 zusammen. Diese erf\u00fcllen unterschiedliche Funktionen und reagieren m\u00f6glicherweise verschieden auf Alterungsprozesse, Depressionen und neurologische Erkrankungen. Eine Untersuchung des Hippocampus als Ganzes kann Ver\u00e4nderungen verschleiern, die sich auf nur eines dieser Teilfelder konzentrieren. <\/p>\n<p class=\"wp-block-paragraph\">F\u00fcr die neue Studie nutzten die Forschenden hochaufl\u00f6sende MRT-Aufnahmen, um drei Bereiche zu vermessen: CA1, das Subiculum und CA23DG (eine kombinierte Region aus CA2, CA3 und dem Gyrus dentatus). Jeder dieser Bereiche tr\u00e4gt auf unterschiedliche Weise zu Lern- und Ged\u00e4chtnisprozessen bei. CA1 unterst\u00fctzt das Gehirn dabei, neue Informationen zu erkennen und mit bereits vorhandenem Wissen zu verkn\u00fcpfen. CA23DG spielt eine besonders wichtige Rolle beim Abruf von Erinnerungen, bei der Unterscheidung \u00e4hnlicher Erlebnisse sowie bei der Rekonstruktion vollst\u00e4ndigerer Erinnerungen aus Teilinformationen. Das Subiculum fungiert als wesentliche Verbindungsstrecke, \u00fcber die Informationen vom Hippocampus in andere Hirnregionen geleitet werden. <\/p>\n<p class=\"wp-block-paragraph\">Von den 2.009 Teilnehmenden wurden 630 aufgrund ihrer aktuellen Symptome oder einer fr\u00fcheren Diagnose durch medizinisches Fachpersonal als an Depressionen leidend eingestuft. Die \u00fcbrigen 1.379 Teilnehmenden wiesen keine Depressionen auf. Da alle Teilnehmenden kognitiv unbeeintr\u00e4chtigt waren, konnten die Forschenden Unterschiede im Gehirn untersuchen, die m\u00f6glicherweise bereits vor Ged\u00e4chtnisverlust oder anderen Symptomen eines kognitiven Abbaus auftreten.<\/p>\n<p class=\"wp-block-paragraph\">Die Forschenden stellten fest, dass Depressionen mit einem geringeren Volumen der Region CA23DG einhergingen, jedoch nicht mit signifikanten Unterschieden im Bereich CA1 oder im Subiculum. \u201eDiese Studie verdeutlicht, warum es wichtig ist, \u00fcber die Gesamtgr\u00f6\u00dfe des Hippocampus hinauszublicken\u201c, erkl\u00e4rt Studienleiterin Dr. Meredith N. Braskie. \u201eDepressionen waren nicht mit einem verringerten Volumen der gesamten Region verbunden. Der Zusammenhang beschr\u00e4nkte sich auf bestimmte Unterregionen, was uns ein pr\u00e4ziseres Bild davon vermittelt, wie Depressionen im Alter mit der Gehirngesundheit zusammenh\u00e4ngen k\u00f6nnten.\u201c<\/p>\n<p>Unabh\u00e4ngig von wichtigen Alzheimer-Risikofaktoren<\/p>\n<p class=\"wp-block-paragraph\">Da Depressionen mit einer h\u00f6heren Wahrscheinlichkeit f\u00fcr die Entwicklung von Alzheimer einhergehen, untersuchten die Forschenden zudem, ob die beobachteten Unterschiede im Gehirn durch etablierte Alzheimer-Risikofaktoren erkl\u00e4rt werden k\u00f6nnten. Sie nutzten PET-Scans (Positronen-Emissions-Tomografie), um Amyloid und Tau zu messen \u2013 zwei Proteine, die sich im Gehirn von Alzheimer-Patienten abnormal anreichern. Au\u00dferdem pr\u00fcften sie, ob die Teilnehmer die Genvariante APOE \u03b54 trugen, die mit einem erh\u00f6hten Alzheimer-Risiko verbunden ist.<\/p>\n<p class=\"wp-block-paragraph\">Amyloid, Tau und APOE \u03b54 ver\u00e4nderten den Zusammenhang zwischen Depression und dem Volumen der Regionen CA1 sowie CA23DG nicht wesentlich. Die Ergebnisse deuten darauf hin, dass Depressionen die Struktur des Hippocampus m\u00f6glicherweise \u00fcber Mechanismen beeinflussen, die sich zumindest teilweise von diesen bekannten Merkmalen der Alzheimer-Krankheit unterscheiden.<\/p>\n<p class=\"wp-block-paragraph\">\u201eDiese Ergebnisse unterstreichen, wie wichtig es ist, die psychische Gesundheit als Teil des Gesamtbildes eines gesunden Alterns des Gehirns zu betrachten\u201c, so Co-Autor Dr. Arthur Toga, PhD. \u201eDas Verst\u00e4ndnis des Zusammenhangs zwischen Depressionen und spezifischen Ged\u00e4chtnissystemen k\u00f6nnte Forschern helfen, gef\u00e4hrdete Personen zu identifizieren, die Verbindungen zwischen Depression und Demenz zu kl\u00e4ren und letztlich personalisiertere Ans\u00e4tze zum Schutz der Gehirngesundheit zu entwickeln.\u201c<\/p>\n<p>Ergebnisse zu Antidepressiva erfordern weitere Untersuchungen<\/p>\n<p class=\"wp-block-paragraph\">Innerhalb der Gruppe der Depressiven wiesen Teilnehmende, die angaben, Antidepressiva einzunehmen, ein geringeres Volumen in den Bereichen CA1 und CA23DG auf als diejenigen, die keine solchen Medikamente nahmen. Die Forschenden wiesen jedoch darauf hin, dass dieses Ergebnis nicht zwangsl\u00e4ufig belege, dass die Antidepressiva die Unterschiede verursacht h\u00e4tten.<\/p>\n<p class=\"wp-block-paragraph\">Es lagen keine Informationen dar\u00fcber vor, wie lange die Teilnehmer bereits unter Depressionen litten, wie schwer die Symptome vor Beginn der Behandlung waren oder wie lange sie die Medikamente bereits einnahmen. Personen, denen Antidepressiva verschrieben wurden, litten m\u00f6glicherweise unter schwereren oder l\u00e4nger anhaltenden Depressionen, was wiederum mit dem Hippocampus-Volumen zusammenh\u00e4ngen k\u00f6nnte.<\/p>\n<p class=\"wp-block-paragraph\">\u201eIn dieser Studie k\u00f6nnen wir m\u00f6gliche Auswirkungen der Medikamente nicht von den Auswirkungen der schwereren Depressionen trennen, zu deren Behandlung diese Medikamente verschrieben werden\u201c, berichtet Luu. \u201eLangzeitstudien, die Menschen vor und nach der Behandlung begleiten, sind entscheidend, um diese Zusammenh\u00e4nge zu verstehen. Unsere Ergebnisse sollten keinesfalls als Anlass genommen werden, verschriebene Medikamente eigenm\u00e4chtig zu \u00e4ndern oder abzusetzen.\u201c<\/p>\n<p class=\"wp-block-paragraph\">Zudem basierten die Depressionsdiagnosen und die Angaben zur Medikation in der Studie auf den Aussagen der Teilnehmenden und nicht auf medizinischen Unterlagen. Zuk\u00fcnftige Forschungsarbeiten werden die Teilnehmenden \u00fcber einen l\u00e4ngeren Zeitraum begleiten und dabei die Vorgeschichte von Depressionen, den Schweregrad der Symptome sowie Art, Dosierung und Dauer der medikament\u00f6sen Behandlung untersuchen.<\/p>\n<p>Weitere Studien sind erforderlich<\/p>\n<p class=\"wp-block-paragraph\">Die Ergebnisse belegen nicht, dass Depressionen eine Schrumpfung des Hippocampus verursachen oder dass die beobachteten Unterschiede zwangsl\u00e4ufig zu Alzheimer f\u00fchren. Vielmehr identifizieren sie eine spezifische Hirnregion f\u00fcr weitere Untersuchungen und unterstreichen, wie wichtig es ist, die psychische Gesundheit in die Forschung zu Altern und Demenz einzubeziehen.<\/p>\n<p class=\"wp-block-paragraph\">(lj\/BIERMANN)<\/p>\n<p class=\"wp-block-paragraph\"><strong>Mehr zu dem Thema:<\/strong><\/p>\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/biermann-medizin.de\/forschende-finden-hinweise-auf-zusammenhang-zwischen-depressionen-und-demenz\/\" rel=\"nofollow noopener\" target=\"_blank\">Forschende finden Hinweise auf Zusammenhang zwischen Depressionen und Demenz<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Eine Studie mit mehr als 2.000 kognitiv gesunden \u00e4lteren Erwachsenen ergab, dass Depressionen mit strukturellen Unterschieden in einem&hellip;\n","protected":false},"author":2,"featured_media":1250767,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[137],"tags":[1049,880,29,30,141,232],"class_list":["post-1250766","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gesundheit","tag-alzheimer","tag-depression","tag-deutschland","tag-germany","tag-gesundheit","tag-health"],"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1250766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1250766"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1250766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1250767"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1250766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1250766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1250766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}