{"id":1251792,"date":"2026-08-21T18:44:18","date_gmt":"2026-08-21T18:44:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1251792\/"},"modified":"2026-08-21T18:44:18","modified_gmt":"2026-08-21T18:44:18","slug":"harrison-ford-wird-erneut-zu-indiana-jones","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1251792\/","title":{"rendered":"Harrison Ford wird erneut zu Indiana Jones"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Harrison Ford schl\u00fcpft erneut in seine wohl ber\u00fchmteste Abenteuerrolle: Der 84-j\u00e4hrige Schauspieler wird wieder als Indiana Jones zu sehen sein \u2013 allerdings nicht in einem neuen Kinofilm. Disney holt den Arch\u00e4ologen und Abenteurer f\u00fcr eine neue Attraktion in Walt Disney World zur\u00fcck.<\/p>\n<p class=\"wp-block-paragraph\">Der Jude Ford wird Teil der neuen Indiana-Jones-Attraktion im Freizeitpark Animal Kingdom sein. Das Fahrgesch\u00e4ft mit dem Titel \u00bbIndiana Jones and the Myth of the Jade Serpent\u00ab entsteht derzeit auf dem Gel\u00e4nde der fr\u00fcheren \u00bbDinoland, U.S.A.\u00ab-Zone.<\/p>\n<p class=\"wp-block-paragraph\">Ford selbst best\u00e4tigte seine Beteiligung in einer vorab aufgezeichneten Videobotschaft. Mit Blick auf die neue Attraktion sagte er: \u00bbIch bin das tats\u00e4chliche Vorbild.\u00ab Anschlie\u00dfend k\u00fcndigte er an: \u00bbIch komme bald nach Walt Disney World.\u00ab<\/p>\n<p>Geschichte aus dem Indiana-Jones-Universum<\/p>\n<p class=\"wp-block-paragraph\">Die neue Fahrt war bereits 2024 auf dem Walt-Disney-Fan-Event D23 angek\u00fcndigt worden. Disney plant dabei einen grundlegenden Umbau der fr\u00fcheren Dinosaurier-Attraktion. Die bisherige Gestaltung, die sich unter anderem am Film \u00bbDinosaur\u00ab aus dem Jahr 2000 orientierte, wird verschwinden. Stattdessen soll eine Geschichte aus dem Indiana-Jones-Universum entstehen.<\/p>\n<p class=\"u-teaser-list__headline\">Lesen Sie auch<\/p>\n<p class=\"wp-block-paragraph\">Die urspr\u00fcngliche Attraktion er\u00f6ffnete 1998 unter dem Namen \u00bbCountdown to Extinction\u00ab gemeinsam mit dem Animal Kingdom. Besucher wurden damals in speziellen Fahrzeugen auf eine Reise durch die Welt der Dinosaurier geschickt. Die technische Grundlage der Fahrzeuge erinnerte bereits an das System der \u00bbIndiana Jones Adventure\u00ab-Attraktion, die 1995 im kalifornischen Disneyland er\u00f6ffnet worden war, und zugleich an \u00bbJurassic Park\u00ab.<\/p>\n<p class=\"wp-block-paragraph\">Mit Fords R\u00fcckkehr wird zugleich ein deutlich gr\u00f6\u00dferes Disney-Projekt vorangetrieben. Die Er\u00f6ffnung des neuen Bereichs ist f\u00fcr 2027 vorgesehen.<\/p>\n<p>Umfassende Erweiterung<\/p>\n<p class=\"wp-block-paragraph\">F\u00fcr Ford ist es die R\u00fcckkehr zu einer Figur, die er seit mehr als vier Jahrzehnten verk\u00f6rpert. Erstmals spielte er Indiana Jones 1981 in \u00bbJ\u00e4ger des verlorenen Schatzes\u00ab. Zuletzt war er 2023 im f\u00fcnften Kinofilm \u00bbIndiana Jones und das Rad des Schicksals\u00ab als legend\u00e4rer Arch\u00e4ologe auf der Leinwand zu sehen.<\/p>\n<p class=\"wp-block-paragraph\">Die neue Indiana-Jones-Fahrt ist Teil einer umfassenden Erweiterung der Disney-Parks. Auch im Magic Kingdom stehen gro\u00dfe Ver\u00e4nderungen bevor. Dort sind unter anderem der neue Bereich \u00bbPiston Peak\u00ab aus dem \u00bbCars\u00ab-Universum sowie \u00bbVillains Land\u00ab geplant, das vollst\u00e4ndig den Disney-B\u00f6sewichten gewidmet sein soll. im<\/p>\n","protected":false},"excerpt":{"rendered":"Harrison Ford schl\u00fcpft erneut in seine wohl ber\u00fchmteste Abenteuerrolle: Der 84-j\u00e4hrige Schauspieler wird wieder als Indiana Jones zu&hellip;\n","protected":false},"author":2,"featured_media":1251793,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1771],"tags":[573,574,1778,29,214,30,411,570,576,95,572,80,1777,14,16,575,215,571],"class_list":["post-1251792","post","type-post","status-publish","format-standard","has-post-thumbnail","category-kino","tag-berichte","tag-blogs","tag-cinema","tag-deutschland","tag-entertainment","tag-germany","tag-israel","tag-juedische-allgemeine","tag-juedisches-leben","tag-kino","tag-kommentare","tag-kultur","tag-movie","tag-nachrichten","tag-politik","tag-religion","tag-unterhaltung","tag-wochenzeitung"],"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1251792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1251792"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1251792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1251793"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1251792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1251792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1251792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}