{"id":1273223,"date":"2026-09-01T05:18:19","date_gmt":"2026-09-01T05:18:19","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1273223\/"},"modified":"2026-09-01T05:18:19","modified_gmt":"2026-09-01T05:18:19","slug":"marsinneres-ist-im-sueden-heisser-als-im-norden","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1273223\/","title":{"rendered":"Marsinneres ist im S\u00fcden hei\u00dfer als im Norden"},"content":{"rendered":"<p>Obwohl der Mars unser Nachbarplanet ist, gibt er noch einige R\u00e4tsel auf. Dazu geh\u00f6ren Details <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"text-[#036147] underline hover:text-[#024C3B]\" href=\"https:\/\/wissenschaft.de\/artikel\/mars-koennte-doch-einen-festen-innenkern-besitzen\">seines inneren Aufbaus<\/a> und seiner vergangenen Geschichte, aber auch die auff\u00e4lligen Unterschiede zwischen dem zerkl\u00fcfteten Hochlandterrain im S\u00fcden des Planeten und den mehrere Kilometer tiefergelegenen Tiefebenen des Nordens.<\/p>\n<p>Der Ursprung dieser Hemisph\u00e4ren-Unterschiede ist strittig: \u201eEinige Studien legen nahe, dass ein gewaltiger Einschlag den urspr\u00fcnglichen Mantel des Mars ver\u00e4nderte\u201c, erkl\u00e4ren Alexander Berne von der University of Arizona in Tucson und seine Kollegen. Dieser Einschlag k\u00f6nnte dann auch die Kruste auf der S\u00fcdhalbkugel verdickt oder im Norden ausged\u00fcnnt haben. Diskutiert wird aber auch, ob es unter der Kruste der Mars-S\u00fcdhalbkugel vielleicht eine st\u00e4rkere Aufstr\u00f6mung gibt, die aufsteigendes <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"text-[#036147] underline hover:text-[#024C3B]\" href=\"https:\/\/wissenschaft.de\/artikel\/seismischer-blick-in-den-marsmantel\">Mantelmaterial <\/a>an die Krustenunterseite anlagert.<\/p>\n<p>Was saisonale Gezeiteneffekte \u00fcber den Marsmantel verraten<\/p>\n<p>Und noch etwas ist unklar: Setzt sich diese Asymmetrie der Marsh\u00e4lften bis in den Marsmantel hinab fort? Um dies zu kl\u00e4ren, haben Berne und sein Team eine spezielle Form der Gravitationsmessung durchgef\u00fchrt: Sie analysierten, wie sich das Schwerefeld der Marshemisph\u00e4ren durch die wechselnden Gezeitenkr\u00e4fte der Sonne ver\u00e4ndert. Denn durch die elliptische Umlaufbahn des Mars um die Sonne variiert ihre Anziehung je nach Jahreszeit leicht.<\/p>\n<p>Ist ein Planet kugelsymmetrisch, verursachen diese Gezeiteneffekte nur bestimmte, klar definierte Deformationen im Schwerefeld des Planeten. Gibt es jedoch tiefliegende Abweichungen in der Zusammensetzung, Temperatur oder Masse einer Planetenh\u00e4lfte, erzeugt dies auch Ver\u00e4nderungen h\u00f6herer Ordnung im Schwerefeld \u2013 quasi in den Obert\u00f6nen der komplexen Messwerte. Mithilfe von Daten der drei Mars-Orbitersonden Mars Global Surveyor, Mars Odyssey und Mars Reconnaissance Orbiter haben Berne und seine Kollegen nach solchen Effekten dritten Grades gesucht.<\/p>\n<p>Daf\u00fcr werteten die Forschenden 16 Jahre des Funkverkehrs dieser Sonden mit der Erde aus. Subtile Ver\u00e4nderungen in Flugh\u00f6he und Position der Raumsonden erzeugen in diesen Radiodaten Signale, die die Reaktion des Mars-Schwerefelds auf die saisonal schwankenden Gezeitenkr\u00e4fte der Sonne widerspiegeln.<\/p>\n<p><img src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/09\/.webp\" alt=\"Topografie und Schermodul\" loading=\"lazy\" decoding=\"async\"\/><\/p>\n<p class=\"article-body-image-caption\" style=\"font-size:var(--text-c-xs);color:var(--color-text-tertiary);margin-top:calc(var(--space-16) * -1);margin-bottom:var(--space-32);line-height:1.5\">Topografische Karte des Mars und dar\u00fcber halbtransparent das \u00fcber die saisonalen Gezeiteneffekte ermittelte Schermodul des Marsmantels. Demnach ist das Mantelgestein im Norden des Planeten fester. \u2014 \u00a9 Berne et al.\/ Nature, <a href=\"http:\/\/creativecommons.org\/licenses\/by\/4.0\" target=\"_blank\" rel=\"nofollow noopener\">CC-by 4.0<\/a><\/p>\n<p>Marsmantel ist im S\u00fcden 200 bis 400 Gad hei\u00dfer<\/p>\n<p>Tats\u00e4chlich wurden Berne und sein Team f\u00fcndig: \u201eDie Komponenten dritten Grades im Schwerefeld des Mars unterscheiden sich um bis zu 300 Prozent von den Vorhersagen eines kugelsymmetrischen Planeten\u201c, berichten sie. \u201eDas deutet auf eine heterogene interne Struktur des Marsmantels hin.\u201c Das Schermodul des Mantelgesteins, das die Elastizit\u00e4t angibt, unterscheidet sich zwischen beiden Hemisph\u00e4ren demnach um mehr als 20 Prozent.<\/p>\n<p>Konkret bedeutet dies: Der Marsmantel in der S\u00fcdh\u00e4lfte des Mars ist weicher und w\u00e4rmer als im Norden. Der Temperaturunterschied beider Mantelh\u00e4lften muss bei 200 bis 400 Grad liegen, wie Berne und sein Team mithilfe eines geophysikalischen Modells ermittelten. Der Mars ist demnach nicht nur in Bezug auf die Landschaften seiner Oberfl\u00e4che ziemlich asymmetrisch \u2013 seine Dichotomie setzt sich bis in die Tiefen des Mantelgesteins fort.<\/p>\n<p><img src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/09\/1788239899_992_.webp\" alt=\"Marsmantel\" loading=\"lazy\" decoding=\"async\"\/><\/p>\n<p class=\"article-body-image-caption\" style=\"font-size:var(--text-c-xs);color:var(--color-text-tertiary);margin-top:calc(var(--space-16) * -1);margin-bottom:var(--space-32);line-height:1.5\">Die S\u00fcdh\u00e4lfte des Marsmantels ist hei\u00dfer und weicher als die Nordh\u00e4lfte. Vielleicht steigt dort sogar noch glutfl\u00fcssiges Magma bis an die Marskruste auf. \u2014 \u00a9 Berne et al.\/ Nature, <a href=\"http:\/\/creativecommons.org\/licenses\/by\/4.0\" target=\"_blank\" rel=\"nofollow noopener\">CC-by 4.0<\/a><\/p>\n<p>Drei Kandidaten f\u00fcr die \u201eMantelheizung\u201c<\/p>\n<p>Doch was ist die Ursache? \u201eDaf\u00fcr kommen theoretisch drei Kandidaten in Frage: ein gewaltiger Einschlag, spontane Aufstr\u00f6mungen im Marsmantel, die bis heute anhalten, und eine verst\u00e4rkte Aufheizung des s\u00fcdlichen Mantels durch radioaktive Zerf\u00e4lle im Gestein und eine dickere, st\u00e4rker isolierende Kruste\u201c, erkl\u00e4ren die Forschenden. Allerdings passen nicht alle Erkl\u00e4rungsans\u00e4tze zu den geologischen Merkmalen des Mars.<\/p>\n<p>So k\u00f6nnte der Einschlag eines riesigen Asteroiden in der Fr\u00fchzeit des Mars zwar erkl\u00e4ren, warum die Nordhalbkugel eine deutlich d\u00fcnnere Kruste besitzt. Aber die durch den Impakt erzeugte Hitze m\u00fcsste bis heute l\u00e4ngst verschwunden sein. Bei einer bis heute anhaltenden st\u00e4rkeren Mantelkonvektion der Mars-S\u00fcdhalbkugel m\u00fcsste das hei\u00dfe Magma die dortige Marskruste mit Eisen anreichern. Das k\u00f6nnte m\u00f6glicherweise erkl\u00e4ren, warum die Kruste des s\u00fcdlichen Hochlands st\u00e4rker magnetisiert ist als die im Norden, so Berne und sein Team.<\/p>\n<p>Denkbar w\u00e4re aber auch das dritte Szenario, nach dem die dickere Kruste des marsianischen Hochlands wie eine Isolierdecke wirkt und den Marsmantel dadurch l\u00e4nger warm gehalten hat. Nach Ansicht der Forschenden w\u00e4re aber auch eine Kombination dieser Isolierwirkung mit st\u00e4rkeren Aufstr\u00f6mungen im S\u00fcd-Marsmantel m\u00f6glich.<\/p>\n<p>Antwort bleibt offen &#8211; vorerst<\/p>\n<p>Noch ist unklar, welches dieser Szenarien zutrifft. Vorerst bleibt der Rote Planet auch in dieser Hinsicht eine Antwort schuldig. \u201eAber diese Daten liefern uns wertvolle Informationen, um k\u00fcnftige Marsmissionen und die Erkundung dieser Ph\u00e4nomene zu planen\u201c, sagt Berne. \u201eUnd wenn wir die innere Struktur des Mars verstehen, dann hilft uns das wiederum, die Prozesse zu entschl\u00fcsseln, die seine Bildung und Entwicklung pr\u00e4gten.\u201c<\/p>\n<p>Quelle: Alexander Berne (University of Arizona, Tucson) et al., Nature, 2026; <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"text-[#036147] underline hover:text-[#024C3B]\" href=\"https:\/\/www.nature.com\/articles\/s41586-026-10893-x\">doi: 10.1038\/s41586-026-10893-x<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Obwohl der Mars unser Nachbarplanet ist, gibt er noch einige R\u00e4tsel auf. Dazu geh\u00f6ren Details seines inneren Aufbaus&hellip;\n","protected":false},"author":2,"featured_media":1273224,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[135],"tags":[29,30,190,189,194,191,193,192],"class_list":["post-1273223","post","type-post","status-publish","format-standard","has-post-thumbnail","category-wissenschaft-technik","tag-deutschland","tag-germany","tag-science","tag-science-technology","tag-technik","tag-technology","tag-wissenschaft","tag-wissenschaft-technik"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/117194098906523357","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1273223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1273223"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1273223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1273224"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1273223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1273223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1273223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}