{"id":1273785,"date":"2026-09-01T12:59:18","date_gmt":"2026-09-01T12:59:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1273785\/"},"modified":"2026-09-01T12:59:18","modified_gmt":"2026-09-01T12:59:18","slug":"berlin-bundesregierung-gruendet-ki-sicherheitsinstitut-aisi","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1273785\/","title":{"rendered":"Berlin: Bundesregierung gr\u00fcndet KI-Sicherheitsinstitut AISI"},"content":{"rendered":"<p>Am 31. August hat die Bundesregierung das neue AI Security and Safety Institute (AISI) in Berlin gegr\u00fcndet. Damit wird ein Beschluss des Nationalen Sicherheitsrats von Juni umgesetzt, haben das Bundesministerium f\u00fcr Digitales und Staatsmodernisierung und das Bundesinnenministerium<a href=\"https:\/\/bmds.bund.de\/aktuelles\/pressemitteilungen\/detail\/aisi-deutschland-gegruendet?utm_source=chatgpt.com\" target=\"_blank\" class=\"link-external\" title=\"Gemeinsame Pressemeldung des BMDS und des BMI\" rel=\"noreferrer nofollow noopener\"> in einer gemeinsamen Presseerkl\u00e4rung mitgeteilt<\/a>. Ziel des Instituts sei es, &#8222;die Chancen und Risiken, die sich durch fortschrittliche KI-Modelle f\u00fcr Deutschland ergeben, zu evaluieren und die Resilienz im Bereich k\u00fcnstlicher Intelligenz nachhaltig zu st\u00e4rken&#8220;.<\/p>\n<p>Digitalminister Karsten Wildberger (CDU) hebt in der Stellungnahme die Bedeutung der neuen Einrichtung f\u00fcr das Ziel hervor, mit der enormen technologischen Entwicklungsgeschwindigkeit Schritt zu halten: &#8222;Wir m\u00fcssen Risiken und Leistungsf\u00e4higkeit moderner KI-Systeme technisch fundiert und schnell bewerten k\u00f6nnen.&#8220; Innenminister Alexander Dobrindt (CSU) f\u00fcgt hinzu, dass KI enorme Chancen f\u00fcr B\u00fcrgerinnen und B\u00fcrger, Wirtschaft und Staat biete, sie jedoch kontrollierbar bleiben m\u00fcsse: &#8222;Wir m\u00fcssen an ihrer rapiden Entwicklung teilhaben.&#8220;<\/p>\n<p>BSI und Bundesnetzagentur teilen sich die Verantwortung im AISI<\/p>\n<p>Der Aufbau des AISI erfolgt laut Pressemeldung in mehreren Phasen. Zun\u00e4chst bildeten das Bundesamt f\u00fcr Sicherheit in der Informationstechnik (BSI) und die Bundesnetzagentur (BNetzA) den &#8222;virtuellen Nukleus&#8220; des Instituts. Dabei liege der Schwerpunkt auf der Analyse und Bewertung f\u00fchrender KI-Modelle &#8222;vor allem hinsichtlich ihrer F\u00e4higkeiten und Risiken f\u00fcr die Cybersicherheit&#8220;. Wie die Deutsche Presse-Agentur (dpa) berichtet, sei das BSI f\u00fcr Fragen von Cybersicherheit (Security) verantwortlich, also daf\u00fcr, wie ein KI-System und seine Daten vor Angriffen und Missbrauch gesch\u00fctzt werden k\u00f6nnen. Die Bundesnetzagentur solle die Verantwortung f\u00fcr den sogenannten Safety-Aspekt tragen: Hier gehe es um technische Fehler, etwa wenn ein autonomes Fahrzeug ein Hindernis zu sp\u00e4t erkennt oder eine Medizin-KI einen Tumor auf dem R\u00f6ntgenbild \u00fcbersieht.<\/p>\n<p>Im zweiten Schritt werde das AISI thematisch sowie in seiner Kapazit\u00e4t ausgebaut, teilen die Ministerien mit. Neben einem strukturierten Wissenstransfer sicherheitsrelevanter Erkenntnisse zu K\u00fcnstlicher Intelligenz solle es die Bundesregierung in Fragen der technischen Evaluierung, zu Entwicklungsszenarien sowie zu strategischen Handlungsbedarfen beraten.<\/p>\n<p>Ein weiterer wichtiger Aspekt des neuen Instituts ist der Presseerkl\u00e4rung zufolge die Vernetzung mit internationalen Partnern \u2013 sowohl im europ\u00e4ischen als auch im transatlantischen Raum. Ein Austausch finde unter anderem bereits mit Frankreich, dem Vereinigten K\u00f6nigreich und dem EU AI Office statt. Ziel der Kooperationen sind demnach der Wissensaustausch, die Erarbeitung gemeinsamer Positionen der beteiligten Staaten sowie einheitlicher Standards.<\/p>\n<p>Unterschiedliche Standorte hatten sich beworben<\/p>\n<p>Wie die Nachrichtenplattform heise online am 1. September berichtet, musste sich die Hauptstadt gegen einige Mitbewerber um den Standort des KI-Sicherheitsinstituts durchsetzen. Demnach h\u00e4tten KI-Zentren oder Informatik-Fakult\u00e4ten in anderen Landesteilen durchaus Vorteile gehabt, beispielsweise die Anbindung an bereits etablierte Forschungseinrichtungen.<\/p>\n<p>Nach \u00fcbereinstimmenden Medienberichten waren zuletzt neben Berlin noch M\u00fcnchen und Saarbr\u00fccken im Rennen um die Ansiedlung des AISI. Wie die Augsburger Allgemeine am 21. August berichtete, bewarb Bayerns Digitalminister Fabian Mehring (Freie W\u00e4hler) die Landeshauptstadt mit dem &#8222;leistungsf\u00e4higen Technologie- und Sicherheits\u00f6kosystem&#8220;, in das das neue Institut eingebettet werden k\u00f6nne. Saarlands Ministerpr\u00e4sidentin Anke Rehlinger (SPD) hatte sich dem Saarl\u00e4ndischen Rundfunk (SR) zufolge f\u00fcr eine Anbindung des AISI an bestehende Einrichtungen an der Universit\u00e4t des Saarlandes eingesetzt und eine finanzielle Beteiligung des Landes in der Aufbauphase angeboten.<\/p>\n<p>Der Tagesspiegel berichtete indes, dass Berlin als Standort vor allem attraktiv sei, wenn es um die Anwerbung internationaler Talente \u2013 beispielsweise aus den USA \u2013 gehe. Auch die r\u00e4umliche N\u00e4he zur Politik galt demnach als entscheidendes Kriterium.<\/p>\n","protected":false},"excerpt":{"rendered":"Am 31. August hat die Bundesregierung das neue AI Security and Safety Institute (AISI) in Berlin gegr\u00fcndet. Damit&hellip;\n","protected":false},"author":2,"featured_media":1273786,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1825],"tags":[263006,263007,20,106999,772,296,14776,29,138500,30,37464,671,161425,1256,1268,4180,406],"class_list":["post-1273785","post","type-post","status-publish","format-standard","has-post-thumbnail","category-berlin","tag-ai-security-and-safety-institute","tag-aisi","tag-alexander-dobrindt","tag-anke-rehlinger","tag-bayern","tag-berlin","tag-cybersicherheit","tag-deutschland","tag-fabian-mehring","tag-germany","tag-karsten-wildberger","tag-ki","tag-ki-sicherheit","tag-kuenstliche-intelligenz","tag-muenchen","tag-saarbruecken","tag-saarland"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/117195909548036902","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1273785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1273785"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1273785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1273786"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1273785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1273785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1273785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}