{"id":333595,"date":"2025-08-10T10:23:19","date_gmt":"2025-08-10T10:23:19","guid":{"rendered":"https:\/\/www.europesays.com\/de\/333595\/"},"modified":"2025-08-10T10:23:19","modified_gmt":"2025-08-10T10:23:19","slug":"10-restaurants-die-lange-geoeffnet-haben","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/333595\/","title":{"rendered":"10 Restaurants, die lange ge\u00f6ffnet haben"},"content":{"rendered":"<p> <img fetchpriority=\"high\" decoding=\"async\" alt=\"Auch in Z\u00fcrich gibt es Restaurants, die bis sp\u00e4tabends Essen servieren.\" data-nzz-tid=\"article-image\" width=\"4024\" height=\"6036\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/08\/c4d7903e-20be-4160-b100-7515a515b38e.jpg\" loading=\"eager\"  class=\"image-placeholder__image\" style=\"cursor:pointer;transform:scale(1);\"\/>         <\/p>\n<p class=\"headline__lead\">Bereits um 18 oder 19 Uhr essen gehen? Inspiriert von unsren s\u00fcdlichen Nachbarn, schiebt sich die Zeit des Abendessens im Sommer gerne etwas nach hinten. Doch nur wenige Schweizer Restaurants erlauben die Speisenbestellung nach 21 Uhr 30. Verhungern muss in Z\u00fcrich allerdings niemand so schnell \u2013 10 Tipps.<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1i0tfv0n70\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">In Spanien geht alles etwas anders zu als anderswo. Wer in Sevilla oder <a target=\"_blank\" href=\"https:\/\/bellevue.nzz.ch\/kochen-geniessen\/gastrokritik-aus-valencia-ld.1323521\" rel=\"nofollow noopener\">Valencia<\/a> erst um 21 Uhr 30 oder um 22 Uhr zum Essen erscheint, wird nicht schief angesehen. Viele Restaurants bieten auch noch um 23 Uhr und sp\u00e4ter Essbares an, wenngleich es nicht unbedingt das grosse Menu sein sollte.<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22ce6vs1\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">In der Schweiz ist das anders. Je gehobener das Restaurant, desto limitierter die Zeiten. Nicht selten wird die Ankunfts- oder Bestellzeit auf 20 Uhr 15 oder 20 Uhr 30 limitiert, und in vielen einfacheren Beizen sieht es speisetechnisch nach 21 Uhr 30 d\u00fcster aus.<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfr80\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Gehe nicht anders, sagen die Restaurantbetreiber. Die Kosten f\u00fcr noch sp\u00e4teren Verzehr seien zu hoch, auch K\u00f6che wollten einmal Feierabend haben, Personal bleibe knapp. Und das, obwohl die <a target=\"_blank\" href=\"https:\/\/bellevue.nzz.ch\/kochen-geniessen\/gastronomie\/essen-um-mitternacht-im-late-night-dinner-steckt-potenzial-ld.1846797\" rel=\"nofollow noopener\">Nachfrage nach dem Late-Night-Dinner<\/a> durchaus vorhanden zu sein scheint. Selbst Betriebe, die f\u00fcr langes Offensein pr\u00e4destiniert w\u00e4ren, wie die \u00ab<a target=\"_blank\" href=\"https:\/\/bellevue.nzz.ch\/kochen-geniessen\/gastronomie\/brasserie-sued-hauptbahnhof-zuerich-food-aus-nenad-mlinarevic-hand-ld.1768901\" rel=\"nofollow noopener\">Brasserie S\u00fcd<\/a>\u00bb im Z\u00fcrcher Hauptbahnhof, machen wohl oder \u00fcbel um 21 Uhr zu.<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cgfgl1\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Bleibt oft nur noch, ausser Fast Food, die Einkehr in Cocktailadressen wie die <a target=\"_blank\" href=\"https:\/\/bellevue.nzz.ch\/kochen-geniessen\/gastronomie\/die-besten-bars-bar-am-wasser-und-widder-bar-in-zuerich-ld.1706644\" rel=\"nofollow noopener\">\u00abWidder-Bar\u00bb<\/a>, wo es Kleinigkeiten \u00e0 la Currywurst und Burger gibt. Oft bis 23 Uhr, manchmal noch sp\u00e4ter. Oder man besucht diese Z\u00fcrcher Restaurants: In denen bekommt man zumindest manchmal noch sp\u00e4t etwas zu essen.<\/p>\n<p>\u00abOsso\u00bb: am Wochenende sp\u00e4t<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfrd0\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Man kann <a target=\"_blank\" href=\"https:\/\/ossozuerich.ch\/\" rel=\"nofollow noopener\">im \u00abOsso\u00bb<\/a> montags bis donnerstags immerhin bis sp\u00e4testens 21 Uhr 45 bestellen, freitags und samstags sogar bis sp\u00e4testens 22 Uhr 45. Das ist aussergew\u00f6hnlich. Doch Vorsicht: Falls das Restaurant zu sp\u00e4terer Stunde nicht mehr gut ausgelastet ist und keine Bestellungen mehr get\u00e4tigt werden, beh\u00e4lt es sich vor, die K\u00fcche schon eher zu schliessen. Was schade w\u00e4re, denn Grilled-Kimchi-Club-Sandwich oder Pulled-Lamm mit Safranemulsion gibt es anderswo in Z\u00fcrich kaum oder gar nicht.<\/p>\n<p><img decoding=\"async\" alt=\"Bei schlechtem Wetter sitzt man im Raum drinnen, bei sch\u00f6nem auf der grossz\u00fcgigen Terrasse draussen.\" data-nzz-tid=\"article-image\" width=\"4724\" height=\"3149\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" loading=\"lazy\"  class=\"image-placeholder__image\" style=\"cursor:pointer;transform:scale(1);\"\/>    Bei schlechtem Wetter sitzt man im Raum drinnen, bei sch\u00f6nem auf der grossz\u00fcgigen Terrasse draussen. <\/p>\n<p>PD<\/p>\n<p data-team-footnote=\"\" id=\"id-doc-1j22cdfre0\" content=\"\" pagetype=\"Article\" componenttype=\"footnote\" is-new-line-child=\"true\" class=\"articlecomponent footnote nzzinteraction\">Osso, Zollstrasse 121, 8005 Z\u00fcrich<\/p>\n<p>\u00abAura\u00bb: place to grill<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfrh0\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Steak vom 800-Grad-Grill? Solcherart zubereitetes Fleisch ist zwar keine absolute Neuerung mehr, aber immer noch nicht selbstverst\u00e4ndlich in der Schweiz. Bis Mitternacht hat das <a target=\"_blank\" href=\"https:\/\/www.aura-zurich.ch\/grill\/\" rel=\"nofollow noopener\">Grill-Restaurant<\/a> ge\u00f6ffnet, und donnerstags, freitags und samstags k\u00f6nnen bis um 22 Uhr 15 Grilladen bestellt werden.<\/p>\n<p><img decoding=\"async\" alt=\"Der Smoky Korean Tofu wird um diese Zeit \u00fcbrigens auch noch serviert.\" data-nzz-tid=\"article-image\" width=\"4975\" height=\"3317\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" loading=\"lazy\"  class=\"image-placeholder__image\" style=\"cursor:pointer;transform:scale(1);\"\/>    Der Smoky Korean Tofu wird um diese Zeit \u00fcbrigens auch noch serviert. <\/p>\n<p>PD<\/p>\n<p data-team-footnote=\"\" id=\"id-doc-1j22cdfri0\" content=\"\" pagetype=\"Article\" componenttype=\"footnote\" is-new-line-child=\"true\" class=\"articlecomponent footnote nzzinteraction\">Aura, Bleicherweg 5, 8001 Z\u00fcrich<\/p>\n<p>\u00abKronenhalle\u00bb: fast wie fr\u00fcher<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfrk0\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Die \u00abgute alte Zeit\u00bb ist <a target=\"_blank\" href=\"https:\/\/www.kronenhalle.com\/\" rel=\"nofollow noopener\">hier<\/a> noch lebendig \u2013 also jene Epoche, in der die ber\u00fchmtesten Schriftsteller der Schweiz gern an diesem Ort und beim einen oder anderen Wein versackt sind. Heutzutage hat die gastronomische Legende immer noch bis Mitternacht ge\u00f6ffnet, die K\u00fcche steht den Kunden t\u00e4glich von 12 bis 22 Uhr 30 zur Verf\u00fcgung. Was ich schon deshalb gut finde, weil man anderswo ja an Montagen kaum sp\u00e4t etwas zu essen bekommt \u2013 und schon gar kein Wiener Schnitzel und kein Chateaubriand mit B\u00e9arnaise und R\u00f6sti.<\/p>\n<p data-team-footnote=\"\" id=\"id-doc-1j22cdfrl0\" content=\"\" pagetype=\"Article\" componenttype=\"footnote\" is-new-line-child=\"true\" class=\"articlecomponent footnote nzzinteraction\">Kronenhalle, R\u00e4mistrasse 4, 8001 Z\u00fcrich<\/p>\n<p>\u00abTao\u2019s\u00bb: Steak mit Pfeffer<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfrm1\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Das Reservierungssystem erlaubt es den G\u00e4sten, an Samstagen noch f\u00fcr 22 Uhr einen Tisch zu buchen. Dann muss man sich beeilen, um noch etwas zu bekommen. Die K\u00fcchenzeiten enden im <a target=\"_blank\" href=\"https:\/\/www.taos-zurich.ch\/\" rel=\"nofollow noopener\">\u00abTao\u2019s\u00bb<\/a> zwischen Donnerstag und Samstag um 22 Uhr 15, an den anderen Tagen eine halbe Stunde eher. F\u00fcr Ceviche oder ein kurz gebratenes Black-Pepper-Beef d\u00fcrfte dies aber allemal reichen.<\/p>\n<p><img decoding=\"async\" alt=\"Die Crispy-Chicken-Tacos z\u00e4hlen \u00fcbrigens zu den Lieblingen der Stadt.\" data-nzz-tid=\"article-image\" width=\"2400\" height=\"1600\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" loading=\"lazy\"  class=\"image-placeholder__image\" style=\"cursor:pointer;transform:scale(1);\"\/>    Die Crispy-Chicken-Tacos z\u00e4hlen \u00fcbrigens zu den Lieblingen der Stadt. <\/p>\n<p>PD<\/p>\n<p data-team-footnote=\"\" id=\"id-doc-1j22cdfrn0\" content=\"\" pagetype=\"Article\" componenttype=\"footnote\" is-new-line-child=\"true\" class=\"articlecomponent footnote nzzinteraction\">Tao\u2019s, St.-Peter-Strasse 1, Augustinerhof\/Augustinergasse 3, 8001 Z\u00fcrich<\/p>\n<p>\u00abTamarind Garden\u00bb: sp\u00e4te Lust auf Tikka Masala<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfro1\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Um 22 Uhr einen Tisch reservieren? Das ist m\u00f6glich in <a target=\"_blank\" href=\"https:\/\/tamarindgarden.ch\/\" rel=\"nofollow noopener\">diesem indischen Restaurant<\/a>. Dass die K\u00fcche sich dann noch an siebeng\u00e4ngige Menus wagt, bezweifle ich, aber f\u00fcr Kartoffel-Zwiebel-Krapfen oder Naan mit Lammhackfleisch und Ingwer d\u00fcrfte es allemal reichen, von den Poulet-Klassikern der indischen K\u00fcche gar nicht zu reden. Auch Gulab Jamun, die s\u00fcssen Teigb\u00e4llchen, d\u00fcrften mit einiger Wahrscheinlichkeit noch vorr\u00e4tig sein.<\/p>\n<p data-team-footnote=\"\" id=\"id-doc-1j22cdfrp0\" content=\"\" pagetype=\"Article\" componenttype=\"footnote\" is-new-line-child=\"true\" class=\"articlecomponent footnote nzzinteraction\">Tamarind Garden, Birmensdorferstrasse 427, 8055 Z\u00fcrich<\/p>\n<p>\u00abLoft Five\u00bb: Hungerstillen an der Europaallee<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfrq0\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Bis 24 Uhr ist das <a target=\"_blank\" href=\"https:\/\/www.loftfive.ch\/\" rel=\"nofollow noopener\">\u00abLoft Five\u00bb<\/a> auf, an Freitagen und Samstagen sogar bis 2 Uhr in der Nacht. Was bedeutet, dass die K\u00fcche des Restaurants prinzipiell bis 23 Uhr ge\u00f6ffnet hat. Dass man sich eine Menge Gedanken macht um das, was auf die Teller gelangt, ist ohnehin klar: Avocadotatar f\u00fcr den Sommer, BBQ-Rindsfederst\u00fcck f\u00fcr die etwas k\u00fchleren Tage, gute Weine sowieso. Und zum Schluss Cocktails und Late-Night-Bites an der integrierten Bar.<\/p>\n<p data-team-footnote=\"\" id=\"id-doc-1j22cdfrr0\" content=\"\" pagetype=\"Article\" componenttype=\"footnote\" is-new-line-child=\"true\" class=\"articlecomponent footnote nzzinteraction\">Loft Five, Europaallee 15, 8004 Z\u00fcrich<\/p>\n<p>\u00abKrone Unterstrass\u00bb: der etwas andere Italiener<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfrs0\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Kein schlechtes <a target=\"_blank\" href=\"https:\/\/www.hotel-krone.ch\/\" rel=\"nofollow noopener\">Konzept<\/a>, welches dieses Hotel mit dem Restaurant Differente auf die Beine gestellt hat. Bis 21 Uhr 30 serviert die Crew die gesamte Karte, also beispielsweise das etwas andere Vitello tonnato (mit Thunfischtatar) oder die klassische Tagliata, aber auch das nicht wirklich mediterrane Rindstatar auf sechs verschiedene W\u00fcrzarten, danach wird noch eine halbe Stunde lang eine verk\u00fcrzte Karte gereicht.<\/p>\n<p><img decoding=\"async\" alt=\"Bis sp\u00e4t essen kann man auch im Restaurant Differente des Hotels Krone Unterstrass.\" data-nzz-tid=\"article-image\" width=\"3586\" height=\"2391\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" loading=\"lazy\"  class=\"image-placeholder__image\" style=\"cursor:pointer;transform:scale(1);\"\/>    Bis sp\u00e4t essen kann man auch im Restaurant Differente des Hotels Krone Unterstrass. <\/p>\n<p>PD<\/p>\n<p data-team-footnote=\"\" id=\"id-doc-1j22cdfrt0\" content=\"\" pagetype=\"Article\" componenttype=\"footnote\" is-new-line-child=\"true\" class=\"articlecomponent footnote nzzinteraction\">Krone Unterstrass \/ Restaurant Differente, Schaffhauserstrasse 1, 8006 Zurich<\/p>\n<p>\u00abSanta Lucia Corso\u00bb: Pizza bis in die Puppen<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfrv0\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Eine <a target=\"_blank\" href=\"https:\/\/www.bindella.ch\/gastronomie\/santa-lucia-corso\" rel=\"nofollow noopener\">Rarit\u00e4t<\/a> in Z\u00fcrich: Pizza in zahlreichen Varianten und andere Spezialit\u00e4ten der italienischen K\u00fcche werden hier sp\u00e4t, sehr sp\u00e4t serviert. Freitags und samstags hat die K\u00fcche sogar bis 1 Uhr am Morgen ge\u00f6ffnet; eine Pizzaorder kann man noch bis 1 Uhr 30 aufgeben. Eine halbe Stunde danach ist dann aber Schluss mit der Bewirtung. Dass man nicht reservieren kann, wird angesichts der vielen Pl\u00e4tze zur Nebensache.<\/p>\n<p data-team-footnote=\"\" id=\"id-doc-1j22cdfs00\" content=\"\" pagetype=\"Article\" componenttype=\"footnote\" is-new-line-child=\"true\" class=\"articlecomponent footnote nzzinteraction\">Santa Lucia Corso, Theaterstrasse 10, 8001 Z\u00fcrich<\/p>\n<p>\u00abSternen-Grill\u00bb: Wurst bis fast um Mitternacht<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfs10\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Okay, <a target=\"_blank\" href=\"https:\/\/www.sternengrill.ch\/\" rel=\"nofollow noopener\">das<\/a> ist kein Restaurant im strengen Sinne, aber der Take-away am Bellevue ist immerhin eine gute M\u00f6glichkeit, sich auch noch nach Schliessung der allermeisten Restaurantk\u00fcchen der Stadt deftig und beissend (der Senf!) zu verpflegen. Von Dienstag bis Samstag wird die letzte Wurst um 23 Uhr 45 vom Grill genommen; an Sonntagen und Montagen rechnet man wohl nicht mit Late-Night-Hungrigen und verlegt die Schlusszeit um eine Stunde auf 22 Uhr 45.<\/p>\n<p data-team-footnote=\"\" id=\"id-doc-1j22cdfs20\" content=\"\" pagetype=\"Article\" componenttype=\"footnote\" is-new-line-child=\"true\" class=\"articlecomponent footnote nzzinteraction\">Sternen-Grill, Theaterstrasse 22, 8001 Z\u00fcrich<\/p>\n<p>\u00abBarf\u00fcsser\u00bb: Late-Night-Event<\/p>\n<p data-team-paragraph=\"\" id=\"id-doc-1j22cdfs40\" content=\"\" pagetype=\"Article\" componenttype=\"p\" is-new-line-child=\"true\" class=\"articlecomponent text nzzinteraction\">Normalerweise hat die K\u00fcche <a target=\"_blank\" href=\"https:\/\/www.barfuesser.ch\/de\/zuerich\" rel=\"nofollow noopener\">des \u00abBarf\u00fcssers\u00bb<\/a> nur bis 21 Uhr 30 ge\u00f6ffnet, aber es gibt Ausnahmen. Vielleicht ein Modell f\u00fcr andere Restaurants? Anl\u00e4sslich der sogenannten mediterranen N\u00e4chte werden die Schlusszeiten n\u00e4mlich um 90 Minuten verl\u00e4ngert. In diesem Jahr sind noch zwei dieser Events eingeplant: am 15. und am 16.\u00a0August. Bleiben k\u00f6nnen die G\u00e4ste dann bis 2 Uhr am Morgen.<\/p>\n<p data-team-footnote=\"\" id=\"id-doc-1j22cdfs41\" content=\"\" pagetype=\"Article\" componenttype=\"footnote\" is-new-line-child=\"true\" class=\"articlecomponent footnote nzzinteraction\">Barf\u00fcsser Z\u00fcrich, Spitalgasse 3, 8001 Z\u00fcrich<\/p>\n<p> Newsletter <\/p>\n<p>Die besten Artikel aus \u00abNZZ Bellevue\u00bb, einmal pro Woche von der Redaktion f\u00fcr Sie zusammengestellt.<\/p>\n<p> <a href=\"https:\/\/abo.nzz.ch\/benutzerkonto\/newsletter\/nzz-bellevue?KAVZ=0793-0030-01-010\" class=\"button button--black newsletter__button\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n      Kostenlos abonnieren<br \/>\n    <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Bereits um 18 oder 19 Uhr essen gehen? Inspiriert von unsren s\u00fcdlichen Nachbarn, schiebt sich die Zeit des&hellip;\n","protected":false},"author":2,"featured_media":333596,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1834],"tags":[3364,29,3688,30,1209],"class_list":{"0":"post-333595","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-essen","8":"tag-de","9":"tag-deutschland","10":"tag-essen","11":"tag-germany","12":"tag-nordrhein-westfalen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115003982277587892","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/333595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=333595"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/333595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/333596"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=333595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=333595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=333595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}