{"id":336935,"date":"2025-08-11T17:53:11","date_gmt":"2025-08-11T17:53:11","guid":{"rendered":"https:\/\/www.europesays.com\/de\/336935\/"},"modified":"2025-08-11T17:53:11","modified_gmt":"2025-08-11T17:53:11","slug":"fellbacher-schwabenlandtower-viel-skepsis-beim-tower-jetzt-wissen-wir-wer-als-naechstes-insolvenz-anmeldet-startseite","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/336935\/","title":{"rendered":"Fellbacher Schwabenlandtower: Viel Skepsis beim Tower: \u201eJetzt wissen wir, wer als N\u00e4chstes Insolvenz anmeldet\u201c &#8211; Startseite"},"content":{"rendered":"\n<p>Ein Sto\u00dfseufzer der Erleichterung ist jedenfalls bei den wenigsten Social-Media-Kommentaren zu erkennen. \u201eHoffentlich wird diese Schande bald beendet. Schlimm!\u201c, ist zwar in einer Reaktion zu lesen. Doch deutlich \u00f6fter wird statt mit Euphorie mit vorsichtigem Abwarten auf die Botschaft vom neuen Investor reagiert. \u201eDas glaube ich erst, wenn der Tower fertig gebaut und bezogen ist\u201c, schreibt eine Leserin.<\/p>\n<p>Mancher denkt an einen verfr\u00fchten Aprilscherz \u2013 und an die n\u00e4chste Insolvenz <\/p>\n<p>Ohnehin scheinen nicht wenige Menschen \u00fcberzeugt, dass es mit der Fertigstellung des neun Jahre lang vor sich hin gammelnden Wolkenkratzers auch unter der Regie des Immobilienunternehmers Joachim Ebner nichts werden wird. \u201eBis zum 1. April ist es doch noch eine Weile\u201c, wird in einer Netzreaktion auf unsere Berichterstattung eher an einen verfr\u00fchten Scherz als an einen Hoffnungsschimmer f\u00fcr die Vollendung des Pleiten-Hochhauses gedacht. <\/p>\n<p>Und auch in der f\u00fcr meinungsfreudige Ansichten bekannten Kappelberg-Gruppe auf Facebook herrscht vorerst noch Skepsis vor. \u201eDie bauen bestimmt wieder nen Kran auf, um zu zeigen, dass es jetzt aber endlich mal losgeht. Und nach nem halben Jahr wird der in einer Nacht- und Nebelaktion sang- und klanglos wieder abgebaut\u201c, schreibt ein von einer Rettung der Bauruine nicht wirklich \u00fcberzeugter Nutzer. <\/p>\n<p>  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/08\/media.media.4b8161b1-04a4-4ad1-ac48-0f99f35de32e.original1024.media.jpeg\"\/>     Werbebanner des neuen Investors h\u00e4ngen bereits am Bauzaun entlang der Schorndorfer Stra\u00dfe.    Foto: Dirk Herrmann    <\/p>\n<p>Und ein anderersieht den Einstieg in das Pleitenprojekt bereits zum Scheitern verurteilt. \u201eJetzt wissen wir, wer als N\u00e4chstes Insolvenz anmeldet&#8230;\u201c, lautet der bedrohlich klingende Kommentar zur \u00dcbernahme des Wohnturms. \u201eDas wird auf ewig ein Fass ohne Boden sein\u201c, pflichten andere Fellbacher der zur\u00fcckhaltenden Meinung bei. Und einer schreibt: \u201eNa dann \u2013 auf ein Neues!\u201c<\/p>\n<p>Ansonsten wird der Schwabenlandtower in der Bev\u00f6lkerung ebenso geliebt wie gehasst. \u201eBitte schnell abrei\u00dfen. Zerst\u00f6rt das Landschaftsbild\u201c, lautet eine Reaktion auf den Besitzerwechsel, andere Leser scheinen den Wohnturm nicht mehr missen zu wollen. \u201e<a href=\"https:\/\/www.krzbb.de\/thema\/Fellbach\" title=\"Fellbach\" class=\"art_thema\" target=\"_blank\" rel=\"noopener\">Fellbach<\/a> verliert sein Wahrzeichen \u2013 der Tower ist schon vom Stuttgarter Pragsattel aus zu sehen\u201c, mahnt einer. \u201eEin praktisches Hochhaus! Wenn ich im Remstal wandern bin, wei\u00df ich immer genau, wo Fellbach liegt\u201c, wird durchaus auch Spott \u00fcber die jahrelange H\u00e4ngepartie um das Gro\u00dfprojekt geteilt. <\/p>\n<p> Facebook-Kommentar: \u201eDie McTower-Premium-Lounge bringt gutes Geld\u201c <\/p>\n<p>Auch mit Tipps an die Adresse von Joachim Ebner, wie er die Pleite-Ruine gewinnbringend vermarkten k\u00f6nnte, fehlt es nicht. Vom \u201eRestaurant zum Goldenen Falken\u201c ist auf Facebook die Rede, ein anderer Nutzer der Plattform sieht im Tower eine gut bezahlte Werbefl\u00e4che f\u00fcr die unmittelbar neben dem Hochhaus angesiedelte Filiale einer Burgerbrat-Kette. <\/p>\n<p>\u201eEin gro\u00dfes, sich drehendes M aufs Dach, McTower Premium-Lounge ins oberste Stockwerk \u2013 und schon kommt Geld rein\u201c, lautet seine Empfehlung. \u201eAber ich bin immer noch daf\u00fcr, dass man vom F3 eine Seilbahn r\u00fcberbaut und daraus einen Wasserrutschen-Turm macht\u201c, schreibt er weiter. <\/p>\n<p>Ohnehin ist in den Kommentarspalten viel vom \u201eTurmbau zu Babel\u201c und vom \u201eteuersten Vogelhaus der Welt\u201c die Rede. Die im Fr\u00fchjahr zuverl\u00e4ssig in einer Nistbox br\u00fctenden Wanderfalken jedenfalls scheinen vielen Menschen n\u00e4her zu sein als Wohnungsnot und um Millionenbetr\u00e4ge geprellte Investoren. \u201eHat mal jemand an das Falkenp\u00e4rchen gedacht? Die freuen sich \u00fcber ihr teures Loft, das ist ja schon fast wieder Bestandsschutz\u201c, hei\u00dft es<\/p>\n<p>Und: Zumindest in der Tower-Umgebung lebende Menschen haben offensichtlich eine ganz andere Sicht auf den Wohnturm und seine Fertigstellung \u201eHoffentlich wird das Ding nie fertig. Die Parkplatzsituation ist schon beschissen genug, weil Mister Camping seine ganzen Wohnmobile hier parkt. Wenn irgendwann noch wer wei\u00df, wie viele Leute im Turm wohnen und alle irgendwo parken wollen, wird\u2019s richtig \u00fcbel\u201c, hei\u00dft es auf Facebook. <\/p>\n<p>Ein anderer Anwohner nimmt die Nachricht vom Besitzerwechsel zum Anlass f\u00fcr grunds\u00e4tzliche Kritik: \u201eDas Ding h\u00e4tte so nie gebaut werden d\u00fcrfen. Zu wenig Parkpl\u00e4tze da, keine U-Bahn, keine S-Bahn, nur alle 20 bis 30 Minuten ein Stadtbus und ab 21 Uhr gar nix mehr. Der Tower ist das schlimmste Fellbacher Projekt von allen&#8230;.\u201c, schreibt er. <\/p>\n","protected":false},"excerpt":{"rendered":"Ein Sto\u00dfseufzer der Erleichterung ist jedenfalls bei den wenigsten Social-Media-Kommentaren zu erkennen. \u201eHoffentlich wird diese Schande bald beendet.&hellip;\n","protected":false},"author":2,"featured_media":336936,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1830],"tags":[75401,1634,3364,29,6725,30,94761,94760,154,1441],"class_list":{"0":"post-336935","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-stuttgart","8":"tag-bauruine","9":"tag-baden-wuerttemberg","10":"tag-de","11":"tag-deutschland","12":"tag-fellbach","13":"tag-germany","14":"tag-joachim-ebner","15":"tag-slt-107-schwabenlandtower","16":"tag-social-media","17":"tag-stuttgart"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115011413895322065","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/336935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=336935"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/336935\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/336936"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=336935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=336935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=336935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}