{"id":342290,"date":"2025-08-13T19:27:13","date_gmt":"2025-08-13T19:27:13","guid":{"rendered":"https:\/\/www.europesays.com\/de\/342290\/"},"modified":"2025-08-13T19:27:13","modified_gmt":"2025-08-13T19:27:13","slug":"auch-mit-steuererleichterungen-brasilien-will-folgen-von-us-zoellen-mit-hilfspaket-abfedern","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/342290\/","title":{"rendered":"Auch mit Steuererleichterungen: Brasilien will Folgen von US-Z\u00f6llen mit Hilfspaket abfedern"},"content":{"rendered":"<p>                    Auch mit Steuererleichterungen<br \/>\n                Brasilien will Folgen von US-Z\u00f6llen mit Hilfspaket abfedern<\/p>\n<p>\t\t\t\t              13.08.2025, 20:13 Uhr<\/p>\n<p><b>Brasilien hat ein Hilfspaket f\u00fcr Unternehmen vorgestellt, die von den stark erh\u00f6hten US-Z\u00f6llen betroffen sind. Pr\u00e4sident Luiz Inacio Lula da Silva setzt dabei im Streit mit den USA zun\u00e4chst auf Gespr\u00e4che statt Vergeltung. &#8222;Wir werden auf Verhandlungen bestehen, aber unsere Souver\u00e4nit\u00e4t ist unantastbar&#8220;, sagte Lula am Mittwoch in der Hauptstadt Brasilia. &#8222;Wir k\u00fcndigen keine Gegenma\u00dfnahmen an. Wir wollen zun\u00e4chst nichts tun, was eine Verschlechterung unserer Beziehungen rechtfertigen k\u00f6nnte&#8220;, so der linksgerichtete Politiker.<\/b><\/p>\n<p>Kern des Plans ist eine Kreditlinie in H\u00f6he von 30 Milliarden Real (5,55 Milliarden Dollar) \u00fcber den staatlichen Exportgarantiefonds FGE, wie es in einer Mitteilung hie\u00df. Zudem sollen weitere 4,5 Milliarden Real in Fonds zur Unterst\u00fctzung kleinerer Unternehmen flie\u00dfen. Das Programm sieht zudem Steuererleichterungen f\u00fcr Exporteure vor und erm\u00f6glicht staatliche K\u00e4ufe von Waren, die urspr\u00fcnglich f\u00fcr den US-Markt bestimmt waren. Diese sollen an \u00f6ffentliche Schulen und Krankenh\u00e4user umgeleitet werden. Die Ma\u00dfnahmen sind Teil einer von Lula unterzeichneten Verordnung. Diese tritt sofort in Kraft, muss aber innerhalb von vier Monaten vom Kongress gebilligt werden, um g\u00fcltig zu bleiben.<\/p>\n<p>US-Pr\u00e4sident Donald Trump hatte Anfang August die Z\u00f6lle auf mehrere Waren aus Brasilien von zehn auf 50 Prozent angehoben. Davon sind etwa Kaffee, Rindfleisch, Meeresfr\u00fcchte, Textilien, Schuhe und Obst betroffen. Wichtigere G\u00fcter wie Flugzeuge, Orangensaft, \u00d6l und Zellstoff wurden jedoch von den h\u00f6heren Abgaben ausgenommen. Trump begr\u00fcndete die Z\u00f6lle mit einem brasilianischen Gerichtsverfahren gegen seinen Verb\u00fcndeten, den ehemaligen Pr\u00e4sidenten Jair Bolsonaro. Trump hatte das Verfahren als &#8222;Hexenjagd&#8220; bezeichnet. Bolsonaro steht wegen des Vorwurfs vor Gericht, nach der Wahl 2022, die er gegen Lula verloren hatte, einen Umsturz geplant zu haben. <\/p>\n","protected":false},"excerpt":{"rendered":"Auch mit Steuererleichterungen Brasilien will Folgen von US-Z\u00f6llen mit Hilfspaket abfedern 13.08.2025, 20:13 Uhr Brasilien hat ein Hilfspaket&hellip;\n","protected":false},"author":2,"featured_media":342291,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[3977],"tags":[331,332,29512,5697,1503,13,12766,14,15,12,95827,4017,4018,4016,79264,64,4019,4020],"class_list":["post-342290","post","type-post","status-publish","format-standard","has-post-thumbnail","category-usa","tag-aktuelle-nachrichten","tag-aktuelle-news","tag-auch","tag-brasilien","tag-folgen","tag-headlines","tag-hilfspaket","tag-nachrichten","tag-news","tag-schlagzeilen","tag-steuererleichterungen","tag-united-states","tag-united-states-of-america","tag-us","tag-us-zoellen","tag-usa","tag-vereinigte-staaten","tag-vereinigte-staaten-von-amerika"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115023108436924976","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/342290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=342290"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/342290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/342291"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=342290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=342290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=342290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}