{"id":359309,"date":"2025-08-20T12:55:13","date_gmt":"2025-08-20T12:55:13","guid":{"rendered":"https:\/\/www.europesays.com\/de\/359309\/"},"modified":"2025-08-20T12:55:13","modified_gmt":"2025-08-20T12:55:13","slug":"stadt-installiert-sirenen-netz-fuer-mehr-sicherheit","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/359309\/","title":{"rendered":"Stadt installiert Sirenen-Netz f\u00fcr mehr Sicherheit"},"content":{"rendered":"<p>Erste Sirene montiert <\/p>\n<p>Neues Warnsystem als &#8222;Meilenstein f\u00fcr die Sicherheit&#8220;<\/p>\n<p>20.08.2025 &#8211; 14:36 UhrLesedauer: 2 Min.<\/p>\n<p><a href=\"#focus-0\" class=\"transition-colors duration-200 focus-within:text-magenta block text-current relative\" data-sctrack=\"FocusGalleryImage.Reference\"><img fetchpriority=\"high\" data-testid=\"Opener.Image\" style=\"--lqipURL:url('https:\/\/images.t-online.de\/2025\/03\/s8sw3jWUjBye\/0x209:4000x2250\/fit-in\/150x0\/filters:blur(25)\/sirenen-auf-einem-dach-symbolbild-auch-ueber-smartphone-apps-wird-gewarnt.jpg')\"   loading=\"eager\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/08\/sirenen-auf-einem-dach-symbolbild-auch-ueber-smartphone-apps-wird-gewarnt.jpg\" alt=\"Sirenen auf einem Dach (Symbolbild): Auch \u00fcber Smartphone-Apps wird gewarnt.\" title=\"Sirenen auf einem Dach (Symbolbild): Auch \u00fcber Smartphone-Apps wird gewarnt.\" width=\"4000\" height=\"2250\" class=\"bg-[url:var(--lqipURL)] bg-cover bg-center flex h-full w-full max-w-full\" decoding=\"async\"\/><img style=\"--width:32;--height:32\" loading=\"lazy\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/zoom-in.f7dae02f.svg\" alt=\"Vergr\u00f6\u00dfern des Bildes\" title=\"Vergr\u00f6\u00dfern des Bildes\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none absolute bottom-8 right-8 rounded-4 bg-snow p-8\" decoding=\"async\"\/><\/a><\/p>\n<p>Sirenen auf einem Dach (Symbolbild): Auch \u00fcber Smartphone-Apps wird gewarnt. (Quelle: IMAGO\/Christian Ohde)<\/p>\n<p class=\"font-bold text-18 leading-17\">Die Stadt Braunschweig beginnt mit dem Aufbau eines fl\u00e4chendeckenden Sirenennetzes. Am Mittwoch wurde die erste von mehr als 100 geplanten Sirenen auf einem Schuldach montiert.<\/p>\n<p class=\"text-18 leading-17\">Oberb\u00fcrgermeister Thorsten Kornblum und weitere Vertreter der Stadt haben die erste Sirene im Braunschweiger Stadtgebiet in Betrieb genommen. Das neue Warnsystem soll die Bev\u00f6lkerung bei Katastrophen und besonderen Gefahrenlagen schnell und zuverl\u00e4ssig informieren. Die erste Sirene lie\u00df die Stadt auf dem Dach des Lessinggymnasiums Wenden montieren. Kornblum wird in der Mitteilung der Stadt zitiert: &#8222;Die Installation der ersten Sirene markiert einen wichtigen Meilenstein f\u00fcr die Sicherheit der Menschen in unserer Stadt.&#8220;<\/p>\n<p class=\"text-18 leading-17\">Die modernen Sirenen k\u00f6nnen nicht nur klassische Warnt\u00f6ne aussenden, sondern auch bis zu 20 verschiedene Sprachdurchsagen machen. Dies sei besonders wichtig bei Stromausf\u00e4llen oder technischen St\u00f6rungen, wenn digitale Warnmittel ausfallen k\u00f6nnten, erkl\u00e4rte Feuerwehrdezernent Tobias Pollmann.<\/p>\n<p class=\"text-18 leading-17\">Die Stadt verfolgt beim Aufbau des Sirenennetzes einen Drei-Stufen-Plan: Zuerst werden st\u00e4dtische Geb\u00e4ude mit Sirenen ausgestattet, danach folgen Maststandorte und schlie\u00dflich Privatgeb\u00e4ude. Laut Hochbaudezernentin Anna Katharina Hanusch ist eine Installationsrate von einer Sirene pro Tag vorgesehen. Besonderheiten wie Maststandorte, die witterungsabh\u00e4ngige Arbeiten erfordern, w\u00fcrden separat ber\u00fccksichtigt.<\/p>\n<p class=\"text-18 leading-17\">Die Gesamtkosten f\u00fcr das Projekt belaufen sich auf rund 3,4 Millionen Euro. Der Abschluss der Arbeiten ist f\u00fcr Anfang 2026 geplant.<\/p>\n<p class=\"text-18 leading-17\">Bereits zum bundesweiten Warntag am 11. September sollen erste Sirenen zu Demonstrationszwecken in Betrieb genommen werden. Die vollst\u00e4ndige Inbetriebnahme erfolgt jedoch erst nach Installation aller Anlagen und deren Anschluss an die Systeme der Feuerwehr.<\/p>\n<p class=\"text-18 leading-17\">Nach dem Ende des Kalten Krieges waren in <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" href=\"https:\/\/www.t-online.de\/themen\/braunschweig\/\" data-sctrack=\"BodyAnchor\" rel=\"nofollow noopener\" target=\"_blank\">Braunschweig<\/a>, wie in vielen anderen deutschen St\u00e4dten, die Sirenen abgebaut worden. Die ver\u00e4nderte Sicherheitslage seit 2022 und die Zunahme von Extremwetterereignissen durch den <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" href=\"https:\/\/www.t-online.de\/themen\/klimawandel\/\" data-sctrack=\"BodyAnchor\" rel=\"nofollow noopener\" target=\"_blank\">Klimawandel<\/a> haben deutschlandweit zu einem Umdenken im Zivil- und Katastrophenschutz gef\u00fchrt.<\/p>\n","protected":false},"excerpt":{"rendered":"Erste Sirene montiert Neues Warnsystem als &#8222;Meilenstein f\u00fcr die Sicherheit&#8220; 20.08.2025 &#8211; 14:36 UhrLesedauer: 2 Min. Sirenen auf&hellip;\n","protected":false},"author":2,"featured_media":359310,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1850],"tags":[522,6429,3364,29,548,663,3934,30,13,56506,14,15,1411,12,99033,97706,49216],"class_list":["post-359309","post","type-post","status-publish","format-standard","has-post-thumbnail","category-braunschweig","tag-522","tag-braunschweig","tag-de","tag-deutschland","tag-eu","tag-europa","tag-europe","tag-germany","tag-headlines","tag-meilenstein","tag-nachrichten","tag-news","tag-niedersachsen","tag-schlagzeilen","tag-sirenennetz","tag-thorsten-kornblum","tag-warnsystem"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115061203215753735","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/359309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=359309"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/359309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/359310"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=359309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=359309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=359309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}