{"id":399995,"date":"2025-09-05T23:36:22","date_gmt":"2025-09-05T23:36:22","guid":{"rendered":"https:\/\/www.europesays.com\/de\/399995\/"},"modified":"2025-09-05T23:36:22","modified_gmt":"2025-09-05T23:36:22","slug":"mannheim-leinen-los-hundeschwimmen-im-freibad-sandhofen-mrn-news-de","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/399995\/","title":{"rendered":"Mannheim \u2013 Leinen los \u2013 Hundeschwimmen im Freibad Sandhofen! \u2013 \/\/\/ MRN-News.de"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/09\/golden-retriever-7095990_640.jpg\" alt=\"\" width=\"640\" height=\"427\" class=\"alignnone size-full wp-image-601102\"\/><br \/>Mannheim \/ Metropolregion Rhein-Neckar(red\/ak) \u2013 Am Montag, 15. September 2025, d\u00fcrfen Hunde wieder von 14 bis 18 Uhr das nasse Terrain erkunden: Der Fachbereich Sport und Freizeit der Stadt Mannheim bietet auch dieses Jahr wieder die beliebte Veranstaltung an und \u00f6ffnet das Freibad Sandhofen, Kalthorststra\u00dfe 43, 68307 Mannheim, nach Ende der Freibadsaison f\u00fcr den besten Freund des Menschen.<\/p>\n<p>Beim 6. Hundeschwimmtag k\u00f6nnen sich die Vierbeiner in dem Nichtschwimmerbecken austoben und schwimmen.<\/p>\n<p>An diesem Tag besteht im Freibad au\u00dfer im Freilauf-Bereich und Wasser Leinenpflicht. An der Kasse werden die Impfausweise der Hunde auf eine g\u00fcltige Tollwut-Impfung kontrolliert. Eine Hundehalterhaftpflichtversicherung wird ebenfalls vorausgesetzt. Der Eintritt ist frei. An dem Veranstaltungstag ist kein \u201enormaler\u201d Badebetrieb. Die Zugangsregeln f\u00fcr den Hundeschwimmtag sind zu beachten:<br \/>https:\/\/www.mannheim.de\/sites\/default\/files\/2025-05\/Hundeschwimmtag_Zugangsregeln_2025.pdf<\/p>\n<p>Auf dem Programm stehen das Schwimmen im Freibadbecken und das Austoben im Freilaufbereich f\u00fcr den Hund sowie ein gastronomisches Angebot f\u00fcr Frauchen und Herrchen.<\/p>\n<p>Weitere Informationen gibt es beim Fachbereich Sport und Freizeit \u00fcber das Service-Telefon unter der Telefonnummer 0621\/ 293-4004 oder per E-Mail an fb52@mannheim.de.<\/p>\n<p>Quelle: Stadt Mannheim<\/p>\n","protected":false},"excerpt":{"rendered":"Mannheim \/ Metropolregion Rhein-Neckar(red\/ak) \u2013 Am Montag, 15. September 2025, d\u00fcrfen Hunde wieder von 14 bis 18 Uhr&hellip;\n","protected":false},"author":2,"featured_media":399996,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1845],"tags":[20373,5114,1634,18412,3364,29,548,663,3934,70906,10860,10182,30,13,604,3545,755,259,2096,9834,25488,25489,14,14480,15,7789,5206,28951,76985,12,1481,3041,64611,1464,3699,4106],"class_list":{"0":"post-399995","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mannheim","8":"tag-schwimmen","9":"tag-angebot","10":"tag-baden-wuerttemberg","11":"tag-bereich","12":"tag-de","13":"tag-deutschland","14":"tag-eu","15":"tag-europa","16":"tag-europe","17":"tag-fachbereich","18":"tag-freibad","19":"tag-freibadsaison","20":"tag-germany","21":"tag-headlines","22":"tag-hund","23":"tag-hunde","24":"tag-impfung","25":"tag-informationen","26":"tag-mannheim","27":"tag-menschen","28":"tag-metropolregion","29":"tag-metropolregion-rhein-neckar","30":"tag-nachrichten","31":"tag-neckar","32":"tag-news","33":"tag-programm","34":"tag-rhein","35":"tag-rhein-neckar","36":"tag-sandhofen","37":"tag-schlagzeilen","38":"tag-service","39":"tag-stadt","40":"tag-stadt-mannheim","41":"tag-telefon","42":"tag-veranstaltung","43":"tag-wasser"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115154320451151072","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/399995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=399995"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/399995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/399996"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=399995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=399995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=399995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}