{"id":410613,"date":"2025-09-10T02:52:12","date_gmt":"2025-09-10T02:52:12","guid":{"rendered":"https:\/\/www.europesays.com\/de\/410613\/"},"modified":"2025-09-10T02:52:12","modified_gmt":"2025-09-10T02:52:12","slug":"lanz-talk-faeser-im-dauer-widerspruch-um-fluechtlingskrise-und-afd-verbot-politik","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/410613\/","title":{"rendered":"Lanz-Talk: Faeser im Dauer-Widerspruch um Fl\u00fcchtlingskrise und AfD-Verbot | Politik"},"content":{"rendered":"<p><b>Fehler kleinreden, Offensichtliches leugnen, Pirouetten um die Wahrheit drehen und beim Erwischtwerden schnell einen Salto mortale: Ex-Bundesinnenministerin Nancy Faeser (55, SPD) f\u00fchrte bei Markus Lanz (56) in einer einzigen Talkshow die gesamte Palette der nervigsten Politiker-Tricks vor.<\/b><\/p>\n<p>Fl\u00fcchtlingskrise<\/p>\n<p>Faeser \u00fcber die <a href=\"https:\/\/www.bild.de\/politik\/aktuelles\/fluechtlinge\/fluechtlinge-alle-infos-78158144.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Fl\u00fcchtlingskrise<\/a> von 2022: \u201eIch glaube nicht, dass wir zu sp\u00e4t reagiert haben.\u201c  Lanz: \u201eSie haben damals vor dem Bundestag gesagt, wir werden das Zur\u00fcckdr\u00e4ngen der Menschen an den europ\u00e4ischen Au\u00dfengrenzen beenden.\u201c &#8211; Faeser: \u201eNein!\u201c &#8211; Lanz: \u201eDoch!\u201c \u2013 Faeser: \u201eJa, aber wir haben damals \u2026\u201c <\/p>\n<p>Lanz ungeduldig: \u201eJa oder Nein?\u201c <a href=\"https:\/\/www.bild.de\/politik\/leute\/nancy-faeser\/thema-nancy-faeser-alle-infos-80011204.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Faeser<\/a> vorwurfsvoll: \u201eWas wir nicht machen d\u00fcrfen, ist dieser Populismus, zu verallgemeinern, zu sagen: \u201adie Ampel\u2018, oder \u201adie Innenministerin\u2018.\u201c<\/p>\n<p>Mehr zum ThemaAfD-Verbotsverfahren<\/p>\n<p>Lanz \u00fcber m\u00f6gliche <a href=\"https:\/\/www.bild.de\/politik\/inland\/neue-insa-umfrage-afd-verbot-spaltet-deutschland-68bee188fae5f706aa68b853\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">AfD-Verbotsverfahren<\/a>: \u201eWie kann es eigentlich sein, dass ein Gutachten vom Bundesverfassungsschutz genau zu dem Zeitpunkt kommt, an dem Sie Ihren letzten Tag im Amt haben? Der Eindruck, der da entsteht, ist: Das ist politisch motiviert.\u201c \u2013 Faeser treuherzig: \u201eGenau das wollte ich immer vermeiden.\u201c<\/p>\n<p>Auch interessant<\/p>\n<p>Anzeige<\/p>\n<p>Auch interessant<\/p>\n<p>Anzeige<\/p>\n<p>Lanz, sichtlich ungl\u00e4ubig: \u201eSie haben auf den Zeitpunkt keinen Einfluss genommen?\u201c \u2013 Faeser vorsichtig: \u201eNein. Ich habe immer gesagt, das Gutachten kommt, wenn das <a href=\"https:\/\/www.bild.de\/themen\/organisationen\/bundesamt-verfassungsschutz\/politik-nachrichten-news-fotos-videos-21029264.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Bundesamt f\u00fcr Verfassungsschutz<\/a> es erarbeitet hat. Ich habe immer gesagt, wenn es da ist, werde ich nicht verhindern, dass das Bundesamt es ver\u00f6ffentlichen kann. Es geht nicht ums Anordnen, es geht ums Zulassen.\u201c<\/p>\n<p><a href=\"https:\/\/www.bild.de\/unterhaltung\/leute\/markus-lanz\/thema-markus-lanz-alle-infos-81728864.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Lanz<\/a> irritiert: \u201eDie haben gefragt?\u201c &#8211; Faeser: \u201eJa. Es ist da, k\u00f6nnen wir es ver\u00f6ffentlichen? Nat\u00fcrlich hatte ich dann Einfluss darauf, dass wir es dann freigegeben haben.\u201c \u2013 Lanz: \u201eAlso doch!\u201c \u2013 Faeser: \u201eIch habe Ja gesagt: \u201aFreigeben\u2018, aber nicht\u201aAnordnen\u2018. Da ist ein gro\u00dfer Unterschied!\u201c<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"558\" alt=\"Auch WELT-Vize Robin Alexander (50) nimmt die Ex-Bundesinnenministerin in die Mangel\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/09\/de8d22d4102a5be5b9c78c853e010167,2cdbf7f7\"   class=\"landscape\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Auch WELT-Vize Robin Alexander (50) nimmt die Ex-Bundesinnenministerin in die Mangel<\/p>\n<p>Foto: ZDF\/Markus Hertrich<\/p>\n<p>Scharfe Kritik vom WELT-Vize<\/p>\n<p>Robin Alexander (50), Vize bei der WELT (geh\u00f6rt wie BILD zum Axel-Springer-Verlag), \u00fcber den Zeitpunkt der Ver\u00f6ffentlichung: \u201eSo \u00e4hnlich wie mit dem Abschiebeflug nach Afghanistan zwei Tage vor den ostdeutschen Landtagswahlen. Es war nicht gut, dass das Gutachten so politisiert wurde!\u201c \u2013 Faeser hastig: \u201eNein! Eben nicht! Es ist nicht politisiert worden!\u201c &#8211; Lanz: \u201eNormalerweise wird sowas lange gepr\u00fcft.\u201c \u2013 Faeser zuerst: \u201eDas stimmt so nicht.\u201c Dann aber: \u201eDas ist in der Vergangenheit von meinem Vorg\u00e4nger so gemacht worden.\u201c<\/p>\n<p><b>Alexanders Zusammenfassung: \u201eSie sind eine abgew\u00e4hlte Ministerin und bringen es noch raus und nehmen damit Ihrem Nachfolger die M\u00f6glichkeit, damit umzugehen.\u201c \u2013 Faeser unschuldig: \u201eIch glaube, dass es eher f\u00fcr ihn positiv war, dass ich es freigegeben habe.\u201c<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"Fehler kleinreden, Offensichtliches leugnen, Pirouetten um die Wahrheit drehen und beim Erwischtwerden schnell einen Salto mortale: Ex-Bundesinnenministerin Nancy&hellip;\n","protected":false},"author":2,"featured_media":410614,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1773],"tags":[150,3554,29,214,23916,5249,30,31224,7882,36225,471,1780,3638,45,215],"class_list":["post-410613","post","type-post","status-publish","format-standard","has-post-thumbnail","category-serien","tag-alternative-fuer-deutschland","tag-bundesamt-fuer-verfassungsschutz","tag-deutschland","tag-entertainment","tag-faeser-nancy","tag-fluechtlinge","tag-germany","tag-lanz-markus","tag-migrationspolitik","tag-parteiverbot","tag-serien","tag-series","tag-talkshow","tag-texttospeech","tag-unterhaltung"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115177740437524967","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/410613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=410613"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/410613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/410614"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=410613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=410613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=410613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}