{"id":478011,"date":"2025-10-06T18:08:18","date_gmt":"2025-10-06T18:08:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/478011\/"},"modified":"2025-10-06T18:08:18","modified_gmt":"2025-10-06T18:08:18","slug":"hattingen-15-jaehriger-vor-moschee-niedergestochen-mordkommission-regional","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/478011\/","title":{"rendered":"Hattingen: 15-J\u00e4hriger vor Moschee niedergestochen \u2013 Mordkommission | Regional"},"content":{"rendered":"<p>Hattingen (NRW) \u2013 <b>Blutiger Streit vor einer Moschee: Ein 15-J\u00e4hriger soll einem Gleichaltrigen mehrfach in den R\u00fccken gestochen haben!<\/b><\/p>\n<p>Laut Polizei war es am Sonntag gegen 19.50 Uhr in der Martin-Luther-Stra\u00dfe in Hattingen (<a href=\"https:\/\/www.bild.de\/regional\/nordrhein-westfalen\/home-npIP0qL0giWP1ZFIOHn2\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Nordrhein-Westfalen<\/a>) zu einem heftigen Streit zwischen den beiden Jugendlichen gekommen.<\/p>\n<p>Opfer in den R\u00fccken gestochen<\/p>\n<p>Die <a href=\"https:\/\/www.bild.de\/regional\/aktuelles\/polizei\/polizeieinsatz-alle-infos-76681760.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Polizei<\/a>: \u201eEiner der 15-J\u00e4hrigen erlitt mehrere Stichverletzungen.\u201c <\/p>\n<p>Nach letztem Stand der Ermittlungen hielt sich der junge Iraker vor der Moschee auf, als ihn der gleichaltrige Jugendliche mit deutsch-t\u00fcrkischer Nationalit\u00e4t angriff.<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"649\" alt=\"Die Polizei sicherte Spuren rund um den mutma\u00dflichen Tatort, der sich hinter einer Moschee befunden haben soll\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/10\/0b91d779d097dfb0cec421fe4f9a46c6,82054998\"   class=\"dynamic\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Die Polizei sichert an der Moschee Spuren<\/p>\n<p>Foto: Justin Brosch<\/p>\n<p>Der schwer verletzte Jugendliche schleppte sich stark blutend zu einer nahen Tankstelle. Dort sollen Passanten den Notruf gew\u00e4hlt haben. Ein <a href=\"https:\/\/www.bild.de\/themen\/organisationen\/rettungsdienst\/politik-nachrichten-news-fotos-videos-19795274.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Notarzt<\/a> versorgte den Iraker noch vor Ort. Der 15-J\u00e4hrige soll anschlie\u00dfend in eine Spezialklinik nach Bochum gebracht worden sein.<\/p>\n<p>Mehr zum Thema<\/p>\n<p>Gro\u00dffl\u00e4chig wurde \u2013 auch mit einem Diensthund \u2013 nach dem mutma\u00dflichen T\u00e4ter gefahndet. Der tauchte nach BILD-Informationen mit Familienangeh\u00f6rigen rund eineinhalb Stunden sp\u00e4ter in einem <a href=\"https:\/\/www.bild.de\/themen\/organisationen\/krankenhaus\/krankenhaus-nachrichten-news-fotos-videos-42750176.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Krankenhaus<\/a> im knapp 17 Kilometer entfernten Witten auf \u2013 auch er hatte Schnittverletzungen. Der Deutsch-T\u00fcrke wurde dort behandelt, ehe ihn die Polizei vorl\u00e4ufig festnahm.<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"634\" alt=\"Die Fahndung der Polizei nach dem mutma\u00dflichen T\u00e4ter rund um den Tatort verlief zun\u00e4chst ohne Erfolg\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/10\/4c8f592e6dcea60a0c1e357ec17731e3,1b46e761\"   class=\"dynamic\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Die Fahndung der Polizei verlief zun\u00e4chst ohne Erfolg<\/p>\n<p>Foto: Justin Brosch<\/p>\n<p>Angeblich gab es Konflikte zwischen den Familien<\/p>\n<p>Die Polizei geht derzeit von einem versuchten <a href=\"https:\/\/www.bild.de\/news\/aktuelles\/verbrechen\/verbrechen-alle-infos-78141902.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">T\u00f6tungsdelikt<\/a> aus, eine Mordkommission der Hagener Polizei ermittelt. Ob die Tatwaffe sichergestellt wurde, ist nicht bekannt. Angeblich soll es aber bereits in der Vergangenheit zu Konflikten zwischen den Familien der beiden Jugendlichen gekommen sein.<\/p>\n<p>Auf Antrag der Staatsanwaltschaft Essen wird der mutma\u00dfliche Messerstecher noch am Montag einem Haftrichter vorgef\u00fchrt.<\/p>\n<p>In einer fr\u00fcheren Version dieses Artikels schrieb BILD, dass der Angriff hinter einer Moschee stattfand und der Jugendliche lebensgef\u00e4hrlich verletzt sei. Im Laufe des Tages haben Polizei und Staatsanwaltschaft neue Informationen ver\u00f6ffentlicht \u2013 der Beitrag wurde entsprechend aktualisiert.<\/p>\n","protected":false},"excerpt":{"rendered":"Hattingen (NRW) \u2013 Blutiger Streit vor einer Moschee: Ein 15-J\u00e4hriger soll einem Gleichaltrigen mehrfach in den R\u00fccken gestochen&hellip;\n","protected":false},"author":2,"featured_media":478012,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1839],"tags":[44323,7507,3364,29,6212,30,1000,2117,1981,5514,382,17930,1209,121,15376,16652,45,1995],"class_list":["post-478011","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bochum","tag-hattingen","tag-bochum","tag-de","tag-deutschland","tag-ermittlungsverfahren","tag-germany","tag-gewalt","tag-islamische-moschee","tag-messer","tag-messerstecherei","tag-migration","tag-mordversuch","tag-nordrhein-westfalen","tag-polizei","tag-schneider-frank","tag-stanger-ralph","tag-texttospeech","tag-verbrechen"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115328562902795023","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/478011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=478011"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/478011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/478012"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=478011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=478011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=478011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}