{"id":525924,"date":"2025-10-25T13:55:11","date_gmt":"2025-10-25T13:55:11","guid":{"rendered":"https:\/\/www.europesays.com\/de\/525924\/"},"modified":"2025-10-25T13:55:11","modified_gmt":"2025-10-25T13:55:11","slug":"berlin-brandenburg-kranich-sterben-im-teichland-helfer-setzen-einsatz-fort","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/525924\/","title":{"rendered":"Berlin &#038; Brandenburg: Kranich-Sterben im Teichland &#8211; Helfer setzen Einsatz fort"},"content":{"rendered":"<p>                    Berlin &amp; Brandenburg<br \/>\n                Kranich-Sterben im Teichland &#8211; Helfer setzen Einsatz fort<\/p>\n<p>\t\t\t\t              25.10.2025, 14:54 Uhr<\/p>\n<p><strong>Im Linumer Teichland stapeln sich tote Kraniche. Warum der Einsatz gegen die Vogelgrippe noch lange nicht vorbei ist.<\/strong><\/p>\n<p>Fehrbellin\/Linum (dpa\/bb) &#8211; Nach dem massenhaften Kranich-Sterben infolge der Vogelgrippe setzen Helfer ihren Einsatz im Linumer Teichland im Nordwesten Brandenburgs fort. &#8222;Ein Ende ist hier noch nicht in Sicht&#8220;, sagte der B\u00fcrgermeister der Gemeinde Fehrbellin, Mathias Perschall (SPD).\u00a0<\/p>\n<p>Seit rund einer Woche sammeln Helfer Kadaver ein. &#8222;Wir werden jeden Tag rausgehen&#8220;, sagte Perschall. Das Naturschutzgebiet dort gilt als einer der gr\u00f6\u00dften Rastpl\u00e4tze f\u00fcr Kraniche in Europa.\u00a0<\/p>\n<p>Allein am Freitag seien knapp 400 tote Kraniche eingesammelt worden, sagte der B\u00fcrgermeister. Bislang seien es damit insgesamt um die 1.500 Kadaver. Inzwischen unterst\u00fctzen rund 20 Kr\u00e4fte aus dem Landesforstbetrieb die freiwilligen Helfer in Linum, wie Landrat Ralf Reinhardt (SPD) sagte. Die Beseitigung der toten Kraniche wird als k\u00f6rperliche und emotionale Belastung beschrieben.\u00a0<\/p>\n<p>Der B\u00fcrgermeister sagte, es seien inzwischen ausreichend Kr\u00e4fte im Einsatz, die in der Lage seien, \u00fcber mehrere Stunden schwere Arbeit zu leisten. Die Fl\u00e4chen seien schwer zu begehen, teils m\u00fcssten Einsatzkr\u00e4fte durch tiefes Wasser waten.\u00a0<\/p>\n<p>Erkrankte Wildv\u00f6gel, die auf dem Weg in die Winterquartiere im S\u00fcden Rast machen, gelten als \u00dcbertr\u00e4ger der Gefl\u00fcgelpest, umgangssprachlich Vogelgrippe genannt. Die Tierseuche endet f\u00fcr infizierte Tiere oft t\u00f6dlich. In diesem Jahr sind Kraniche besonders stark betroffen und mit dem hochansteckenden Virus vom Typ H5N1 infiziert.<\/p>\n","protected":false},"excerpt":{"rendered":"Berlin &amp; Brandenburg Kranich-Sterben im Teichland &#8211; Helfer setzen Einsatz fort 25.10.2025, 14:54 Uhr Im Linumer Teichland stapeln&hellip;\n","protected":false},"author":2,"featured_media":525925,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1816],"tags":[1960,1958,1959,1957,296,1956,1890,29,588,30,17420,129640,129641],"class_list":{"0":"post-525924","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brandenburg","8":"tag-aktuelle-nachrichten-aus-berlin-und-brandenburg","9":"tag-aktuelle-nachrichten-aus-brandenburg","10":"tag-aktuelle-news-aus-berlin-und-brandenburg","11":"tag-aktuelle-news-aus-brandenburg","12":"tag-berlin","13":"tag-berlin-und-brandenburg","14":"tag-brandenburg","15":"tag-deutschland","16":"tag-einsatz","17":"tag-germany","18":"tag-helfer","19":"tag-kranich-sterben","20":"tag-teichland"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115435151335018681","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/525924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=525924"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/525924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/525925"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=525924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=525924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=525924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}