{"id":560075,"date":"2025-11-08T09:37:16","date_gmt":"2025-11-08T09:37:16","guid":{"rendered":"https:\/\/www.europesays.com\/de\/560075\/"},"modified":"2025-11-08T09:37:16","modified_gmt":"2025-11-08T09:37:16","slug":"der-sport-tag-mit-alba-und-bayern-nba-stellt-plaene-fuer-eigene-liga-in-europa-vor","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/560075\/","title":{"rendered":"Der Sport-Tag: Mit Alba und Bayern? NBA stellt Pl\u00e4ne f\u00fcr eigene Liga in Europa vor"},"content":{"rendered":"<p>                    Der Sport-Tag<br \/>\n                Mit Alba und Bayern? NBA stellt Pl\u00e4ne f\u00fcr eigene Liga in Europa vor<\/p>\n<p>\t\t\t\t              08.11.2025, 10:05 Uhr<\/p>\n<p>Die nordamerikanische Basketballliga NBA m\u00f6chte ab Oktober 2027 eine eigene Liga in Europa an den Start bringen. Dies erkl\u00e4rte der Gesch\u00e4ftsf\u00fchrer von NBA Europe, George Aivazoglou, auf einer Veranstaltung in Mailand. Zudem habe man sich auf zw\u00f6lf Standorte festgelegt. Mit <b>Berlin und M\u00fcnchen sind auch zwei deutsche St\u00e4dte dabei<\/b>. Au\u00dferdem sollen aus Frankreich<b> Lyon und Paris, aus Griechenland Athen, aus Gro\u00dfbritannien London und Manchester, aus Italien Mailand und Rom, aus Spanien Barcelona und Madrid sowie aus der T\u00fcrkei Istanbul<\/b> eine Mannschaft der NBA-Europaliga beheimaten.<\/p>\n<p>NBA-Commissioner Adam Silver hatte zuletzt einen m\u00f6glichen Start der geplanten Liga im Jahr 2027 als ambitioniert bezeichnet, aber nicht ausgeschlossen. Er wolle nicht viel l\u00e4nger als bis 2028 warten. &#8222;Jetzt ist die Gelegenheit, so etwas zu tun&#8220;, sagte er. Um welche Teams es sich dabei konkret handelt und ob aus deutscher Sicht die BBL-Klubs FC Bayern M\u00fcnchen und Alba Berlin dabei sein k\u00f6nnten, lie\u00df Aivazoglou offen.<\/p>\n","protected":false},"excerpt":{"rendered":"Der Sport-Tag Mit Alba und Bayern? NBA stellt Pl\u00e4ne f\u00fcr eigene Liga in Europa vor 08.11.2025, 10:05 Uhr&hellip;\n","protected":false},"author":2,"featured_media":560076,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[3933],"tags":[331,332,13329,772,282,548,663,158,3934,3935,13,13762,19872,14,15918,15,236,12,283],"class_list":["post-560075","post","type-post","status-publish","format-standard","has-post-thumbnail","category-eu","tag-aktuelle-nachrichten","tag-aktuelle-news","tag-alba","tag-bayern","tag-der","tag-eu","tag-europa","tag-europaeische-union","tag-europe","tag-european-union","tag-headlines","tag-liga","tag-mit","tag-nachrichten","tag-nba","tag-news","tag-plaene","tag-schlagzeilen","tag-sport-tag"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115513409152196154","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/560075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=560075"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/560075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/560076"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=560075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=560075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=560075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}