{"id":56324,"date":"2025-04-24T02:55:16","date_gmt":"2025-04-24T02:55:16","guid":{"rendered":"https:\/\/www.europesays.com\/de\/56324\/"},"modified":"2025-04-24T02:55:16","modified_gmt":"2025-04-24T02:55:16","slug":"sabaton-praesentieren-neues-label-und-teasen-neues-album","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/56324\/","title":{"rendered":"Sabaton pr\u00e4sentieren neues Label und teasen neues Album"},"content":{"rendered":"<p data-pm-slice=\"1 1 []\">Nach sechs Alben und fast 15 Jahren Zusammenarbeit ist es jetzt so weit: <a class=\"qbe-widget\" href=\"https:\/\/www.metal-hammer.de\/artists\/sabaton\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sabaton<\/a> haben sich von Nuclear Blast getrennt. Eine Entscheidung, die einige Fans der schwedischen Power Metal-Giganten \u00fcberraschen d\u00fcrfte. Stattdessen machen Sabaton jetzt gemeinsame Sache mit den Amerikanern Better Noise Music, bei denen bereits bekannte, aber eher im Modern Metal beheimatete Bands wie <a class=\"qbe-widget\" href=\"https:\/\/www.metal-hammer.de\/artists\/five-finger-death-punch\/\" target=\"_blank\" rel=\"noopener noreferrer\">Five Finger Death Punch<\/a> und <a class=\"qbe-widget\" href=\"https:\/\/www.metal-hammer.de\/artists\/the-hu\/\" target=\"_blank\" rel=\"noopener noreferrer\">The Hu<\/a> unter Vertrag stehen.<\/p>\n<p>Erster Teaser f\u00fcrs neue Sabaton-Album<\/p>\n<p>\u00a0\u201eWir sind begeistert, dieses neue Kapitel mit Better Noise Music zu beginnen,\u201c kommentiert Sabaton-Bassist und -Manager P\u00e4r Sundstr\u00f6m in der <a href=\"https:\/\/betternoise.com\/news\/better-noise-sign-sabaton-yellowcard-in-this-moment-and-the-rasmus\/\" target=\"_blank\" rel=\"noopener\">offiziellen Pressemitteilung des Labels<\/a>. \u201eNachdem wir uns weltweit verschiedene Plattenlabels angeschaut haben, hat sich Better Noise als die perfekte Wahl ergeben. Als unabh\u00e4ngiges Label haben sie sich traditionell nicht auf unseren Stil des Heavy Metal konzentriert, was diese Zusammenarbeit besonders spannend macht. Wir sind gespannt zu sehen, wie sich diese Partnerschaft entwickelt, und sind zuversichtlich, dass [Better Noise] bereit ist, die Herausforderung anzunehmen, mit einer Band zu arbeiten, die einen einzigartigen Sound in ihr Repertoire bringt.\u201c<\/p>\n<p>Empfehlungen der Redaktion<\/p>\n<p>F\u00fcr Fans sollte aber besonders die erste Passage der Pressemitteilung besonders interessant sein: \u201eSabaton ist die weltweit f\u00fchrende Power Metal-Band und eine der gr\u00f6\u00dften schwedischen Bands, mit allein vier Milliarden Streams auf Spotify. Am 25. April werden sie die Single \u201aTemplars\u2019 und ihr Musikvideo als erste Ver\u00f6ffentlichung ihres Deb\u00fctalbums bei Better Noise Music ver\u00f6ffentlichen.\u201c Hier best\u00e4tigt Better Noise n\u00e4mlich die Vermutungen und Ger\u00fcchte, die schon seit Monaten ihre Runden in den Sabaton-Fangemeinden drehen:<\/p>\n<p>Ein neues Sabaton-Album steht am Horizont. Zwar verr\u00e4t die Pressemitteilung weder einen Albumtitel noch ein Ver\u00f6ffentlichungsdatum, aber als erste offizielle Best\u00e4tigung sollte sie es trotzdem schaffen, die Gem\u00fcter der Fans etwas zu beruhigen. Zumindest mit \u2018Templars\u2019 k\u00f6nnen sich Sabaton-Anh\u00e4nger bereits diesen Freitag (25.4.) einen ersten Eindruck der kommenden Platte verschaffen.<\/p>\n<p>An dieser Stelle findest du Inhalte aus Instagram<\/p>\n<p>Um mit Inhalten aus Sozialen Netzwerken zu interagieren oder diese darzustellen, brauchen wir deine Zustimmung.<\/p>\n<p>\tSoziale Netzwerke aktivieren<\/p>\n<p>\u2014<br \/>Bestens informiert \u00fcber dieses und alle weiteren wichtigen Themen im Metal bleibt ihr au\u00dferdem mit unserem Newsletter. Einmal pro Woche flattert euch \u00fcbersichtlich sortiert ein Update ins Postfach.\u00a0<a href=\"https:\/\/www.metal-hammer.de\/news\/newsletter\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Einfach anmelden<\/strong><\/a>, damit euch auch sicher nichts entgeht.<\/p>\n","protected":false},"excerpt":{"rendered":"Nach sechs Alben und fast 15 Jahren Zusammenarbeit ist es jetzt so weit: Sabaton haben sich von Nuclear&hellip;\n","protected":false},"author":2,"featured_media":56325,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1772],"tags":[26329,29,214,30,1779,810,3070,26330,26331,26332,26333,215],"class_list":{"0":"post-56324","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-musik","8":"tag-better-noise-music","9":"tag-deutschland","10":"tag-entertainment","11":"tag-germany","12":"tag-music","13":"tag-musik","14":"tag-neues-album","15":"tag-paer-sundstroem","16":"tag-power-metal","17":"tag-sabaton","18":"tag-templars","19":"tag-unterhaltung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/114390691310229200","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/56324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=56324"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/56324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/56325"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=56324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=56324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=56324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}