{"id":574289,"date":"2025-11-14T06:32:27","date_gmt":"2025-11-14T06:32:27","guid":{"rendered":"https:\/\/www.europesays.com\/de\/574289\/"},"modified":"2025-11-14T06:32:27","modified_gmt":"2025-11-14T06:32:27","slug":"berlin-wie-sicher-fuehlen-sich-frauen-nachts-auf-dem-heimweg-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/574289\/","title":{"rendered":"Berlin | Wie sicher f\u00fchlen sich Frauen nachts auf dem Heimweg?"},"content":{"rendered":"<p>Berlin (dpa) &#8211; So ziemlich jede Frau d\u00fcrfte dieses Gef\u00fchl kennen. Schnellen Schrittes und mit dem Schl\u00fcssel in der Hand f\u00fchren die letzten Meter bis nach Hause durch eine dunkle Unterf\u00fchrung. F\u00fcr viele M\u00e4dchen und Frauen ist der Heimweg in der Nacht mit Angst verbunden. Durch die \u00abStadtbild\u00bb-Debatte um \u00f6ffentliche Sicherheit und Migration nimmt das Thema jetzt wieder an Fahrt auf.\u00a0<\/p>\n<p>Seit Wochen wird \u00fcber die Aussage von Bundeskanzler Friedrich Merz (CDU) diskutiert. Er sagte: Die Bundesregierung korrigiere fr\u00fchere Vers\u00e4umnisse in der Migrationspolitik und mache Fortschritte, \u00ababer wir haben nat\u00fcrlich immer im Stadtbild noch dieses Problem, und deswegen ist der Bundesinnenminister ja auch dabei, jetzt in sehr gro\u00dfem Umfang auch R\u00fcckf\u00fchrungen zu erm\u00f6glichen und durchzuf\u00fchren\u00bb.<\/p>\n<p>Erst eine Woche sp\u00e4ter wurde er konkreter: Probleme machten jene Migranten, die keinen dauerhaften Aufenthaltsstatus h\u00e4tten, nicht arbeiteten und sich nicht an Regeln hielten. Zwischenzeitlich antwortete er auf die Frage, was er mit seiner \u00c4u\u00dferung zu Problemen im Stadtbild denn gemeint habe: \u00abFragen Sie mal Ihre T\u00f6chter\u00bb.<\/p>\n<p>Studie: Frauen f\u00fchlen sich h\u00e4ufiger unsicher als M\u00e4nner<\/p>\n<p>Die Aussagen sorgten f\u00fcr viel Kritik. In einem offenen Brief stellen jetzt 60 prominente Frauen zehn Forderungen f\u00fcr mehr Sicherheit an Merz, darunter: eine bessere Beleuchtung und \u00dcberwachung \u00f6ffentlicher R\u00e4ume, sichere Wege, besonders an Bahnh\u00f6fen, Haltestellen und in Parks. Doch wie steht es um das Sicherheitsgef\u00fchl von Frauen &#8211; und welche Angebote helfen, es zu verbessern?<\/p>\n<p>Klar ist: Frauen f\u00fchlen sich im \u00f6ffentlichen Raum h\u00e4ufiger unsicher als M\u00e4nner. Das zeigt eine 2022 erstmals ver\u00f6ffentlichte Studie des Bundeskriminalamts (BKA) zu \u00abSicherheit und Kriminalit\u00e4t in Deutschland\u00bb. So f\u00fchlte sich zum Zeitpunkt der Erhebung der Daten nur jede dritte Frau (33,3 Prozent) nachts im \u00f6ffentlichen Personennahverkehr \u00absehr sicher\u00bb oder \u00abeher sicher\u00bb.\u00a0<\/p>\n<p>F\u00fcr die M\u00e4nner lag der Wert bei knapp 60 Prozent. Rund 61 Prozent der Frauen gaben an, sich in der eigenen Wohngegend nachts ohne Begleitung sicher zu f\u00fchlen, von den m\u00e4nnlichen Befragten sagten das rund 83 Prozent.<\/p>\n<p>Auf diese Studie verweist auch Mitarbeiter Daniel von der Telefonhotline Heimwegtelefon. Der Dresdner Verein begleitet deutschlandweit Menschen telefonisch auf ihrem Heimweg bis nach Hause. Dabei wird regelm\u00e4\u00dfig der Standort durchgegeben.\u00a0<\/p>\n<p>Heimwegtelefon: Gef\u00fchl von Unsicherheit hat viele Ursachen<\/p>\n<p>Zun\u00e4chst einmal sei man froh, dass \u00fcberhaupt in Deutschland \u00fcber das Sicherheitsgef\u00fchl gesprochen wird und eine Debatte entsteht, unabh\u00e4ngig von einzelnen politischen Positionen, sagt Daniel.<\/p>\n<p>\u00abWir glauben, dass sich das Sicherheitsgef\u00fchl in \u00f6ffentlichen R\u00e4umen allerdings nicht ausschlie\u00dflich auf eine Pr\u00e4senz von migrantischen Personen zur\u00fcckf\u00fchren l\u00e4sst, sondern dass es ganz vielf\u00e4ltige Ursachen hat. Wir haben das Gef\u00fchl, hier werden gerade verschiedene Punkte in der Debatte miteinander vermischt, die wahrscheinlich nur bedingt miteinander zu tun haben\u00bb.<\/p>\n<p>Unter der bundesweit g\u00fcltigen Nummer 030 1207 4182 sind Ehrenamtliche des 2011 gegr\u00fcndeten Vereins erreichbar. Die meisten Anrufe k\u00e4men von Frauen, sagt Daniel. Die Gr\u00fcnde, weshalb sich Menschen unsicher f\u00fchlen, seien sehr vielseitig, vereinzelt riefen auch migrantische Frauen an, die sich wegen Anfeindungen etwa wegen ihres Kopftuchs in der \u00d6ffentlichkeit unwohl f\u00fchlten.<\/p>\n<p>Problem \u00e4lter als die aktuelle Migrationsdebatte<\/p>\n<p>H\u00e4ufig meldeten sich auch Anrufer, weil sie das Gef\u00fchl h\u00e4tten, von jemandem verfolgt zu werden, wegen einer zuvor erlebten unangenehmen Situation oder fr\u00fcheren Erfahrungen. Und: \u00abViele Menschen sagen: \u201aIch kann dir \u00fcberhaupt nicht sagen, woher das gerade kommt. Das bricht gerade so \u00fcber mich herein.\u2018 Menschen k\u00f6nnen sich auch sehr, sehr unwohl f\u00fchlen, obwohl sich niemand sonst auf der Stra\u00dfe befindet\u00bb, berichtet der Ehrenamtler.\u00a0<\/p>\n<p>Der Verein findet: Man k\u00f6nnte vielleicht auch mal die M\u00fctter fragen, wie sicher sie sich gef\u00fchlt haben, als sie fr\u00fcher die T\u00f6chter waren. \u00abIch h\u00f6re manchmal bei meinen Schichten, dass Frauen sagen: `Ach, da h\u00e4tte ich mich mal gefreut, wenn es das Angebot schon gegeben h\u00e4tte, als ich jung war`. Da reden wir \u00fcber eine Jugend, die teilweise 20 oder 30 Jahre zur\u00fcckliegt\u00bb, sagt Daniel. \u00abInsofern ist dieses Gef\u00fchl von \u201aIch f\u00fchle mich abends, nachts drau\u00dfen nicht wohl\u2018 viel \u00e4lter als die aktuelle Migrationsdebatte\u00bb.\u00a0<\/p>\n<p>Frauen-Nacht-Taxis in mehreren deutschen St\u00e4dten<\/p>\n<p>Neben dem Heimwegtelefon gibt es in vielen St\u00e4dten Deutschlands weitere Projekte, die das Sicherheitsempfinden in der Dunkelheit st\u00e4rken wollen. In Mannheim, Heidelberg (\u00fcbrigens schon seit 1992) oder M\u00fcnchen etwa werden Frauen bei n\u00e4chtlichen Taxifahrten finanziell unterst\u00fctzt.<\/p>\n<p>Zudem kann man das Angebot \u00abHalten auf Wunsch\u00bb der M\u00fcnchner Verkehrsgesellschaft nutzen. Die Busfahrer lassen Fahrg\u00e4ste ab 21 Uhr &#8211; au\u00dferhalb des Mittleren Rings und wenn es die Verkehrssituation zul\u00e4sst &#8211; auf Wunsch zwischen den Haltestellen aussteigen. \u00abDie Nutzung war und ist \u00fcberschaubar und bel\u00e4uft sich auf aktuell weniger als f\u00fcnf Haltew\u00fcnsche in der Woche\u00bb, teilt ein Sprecher mit.<\/p>\n<p>Hohe Nachfrage f\u00fcr Nightwalks<\/p>\n<p>Ein anderes Beispiel: sogenannte Nightwalks im nieders\u00e4chsischen Landkreis Emsland. Die begleiteten Spazierg\u00e4nge durch dunkle Stra\u00dfen sollen Frauen helfen, mit bedrohlichen oder unangenehmen Situationen besser umzugehen.<\/p>\n<p>Laut der Gleichstellungsbeauftragten des Landkreises, Marlies Kohne, waren die Anmeldezahlen f\u00fcr die zun\u00e4chst zw\u00f6lf Termine insgesamt sehr hoch. Einige Kommunen h\u00e4tten Zusatztermine organisiert, die direkt wieder ausgebucht waren.\u00a0<\/p>\n<p>Kohne betont: Das Projekt stehe in keinem Zusammenhang mit der aktuellen \u00abStadtbild\u00bb-Debatte. Vielmehr existierten diese und vergleichbare Angebote schon seit vielen Jahren. Sie sollen M\u00e4dchen und Frauen mental st\u00e4rken, sich selbstbewusst und selbstverst\u00e4ndlich im \u00f6ffentlichen Raum zu bewegen. \u00abM\u00e4dchen und Frauen d\u00fcrfen sich nicht aus der \u00d6ffentlichkeit zur\u00fcckziehen.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"Berlin (dpa) &#8211; So ziemlich jede Frau d\u00fcrfte dieses Gef\u00fchl kennen. Schnellen Schrittes und mit dem Schl\u00fcssel in&hellip;\n","protected":false},"author":2,"featured_media":574290,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[1941,1939,296,1937,29,3236,30,1724,1940,1938,3931],"class_list":["post-574289","post","type-post","status-publish","format-standard","has-post-thumbnail","category-berlin","tag-aktuelle-nachrichten-aus-berlin","tag-aktuelle-news-aus-berlin","tag-berlin","tag-berlin-news","tag-deutschland","tag-frauen","tag-germany","tag-gesellschaft","tag-nachrichten-aus-berlin","tag-news-aus-berlin","tag-sicherheit"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115546655526883050","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/574289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=574289"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/574289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/574290"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=574289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=574289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=574289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}