{"id":588356,"date":"2025-11-20T02:52:15","date_gmt":"2025-11-20T02:52:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/588356\/"},"modified":"2025-11-20T02:52:15","modified_gmt":"2025-11-20T02:52:15","slug":"haben-einen-der-butscha-schlaechter-identifiziert","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/588356\/","title":{"rendered":"Haben einen der Butscha-Schl\u00e4chter identifiziert"},"content":{"rendered":"<p>Newsblog zum Ukraine-Krieg <\/p>\n<p>Ukraine: Haben einen der Butscha-Schl\u00e4chter identifiziert<\/p>\n<p>Aktualisiert am 20.11.2025 &#8211; 03:23 UhrLesedauer: 15 Min.<\/p>\n<p><a href=\"#focus-0\" class=\"transition-colors duration-200 block text-current relative\" data-sctrack=\"FocusGalleryImage.Reference\"><img fetchpriority=\"high\" data-testid=\"Opener.Image\" style=\"--lqipURL:url('https:\/\/images.t-online.de\/2022\/12\/AlumSAVuvaWT\/0x180:4000x2250\/fit-in\/150x0\/filters:blur(25)\/butscha-in-dem-kleinen-vorort-von-kiew-haben-russische-soldaten-brutale-kriegsverbrechen-begangen.jpg')\"   loading=\"eager\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/11\/butscha-in-dem-kleinen-vorort-von-kiew-haben-russische-soldaten-brutale-kriegsverbrechen-begangen.jp.jpeg\" alt=\"Butscha: In dem kleinen Vorort von Kiew haben russische Soldaten brutale Kriegsverbrechen begangen.\" title=\"Butscha: In dem kleinen Vorort von Kiew haben russische Soldaten brutale Kriegsverbrechen begangen.\" width=\"4000\" height=\"2250\" class=\"bg-[url:var(--lqipURL)] bg-cover bg-center flex h-full w-full max-w-full\" decoding=\"async\"\/><img style=\"--width:32;--height:32\" loading=\"lazy\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/zoom-in.f7dae02f.svg\" alt=\"Vergr\u00f6\u00dfern des Bildes\" title=\"Vergr\u00f6\u00dfern des Bildes\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none absolute bottom-8 right-8 rounded-4 bg-snow p-8\" decoding=\"async\"\/><\/a><\/p>\n<p>Butscha: In dem kleinen Vorort von Kiew haben russische Soldaten brutale Kriegsverbrechen begangen. (Quelle: SOPA Images)<\/p>\n<p class=\"font-bold text-18 leading-17\">Die Ukraine nennt einen Verd\u00e4chtigen f\u00fcr die Gr\u00e4uel von Butscha. Polen reagiert mit H\u00e4rte auf den Anschlag auf eine Bahnstrecke. Alle Entwicklungen im Newsblog.<\/p>\n<p class=\"text-18 leading-17\">Die <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" href=\"https:\/\/www.t-online.de\/themen\/ukraine\/\" data-sctrack=\"BodyAnchor\" target=\"_blank\" rel=\"noopener\">Ukraine<\/a> hat erstmals einen russischen Kommandeur als Verd\u00e4chtigen f\u00fcr einige der T\u00f6tungen im Kiewer Vorort Butscha im Jahr 2022 identifiziert. Der Zugf\u00fchrer der 76. Luftlandedivision sei f\u00fcr 17 T\u00f6tungen und vier F\u00e4lle von Misshandlungen verantwortlich, die von Truppen unter seinem Kommando begangen wurden, teilte die internationale Rechtsstiftung Global Rights Compliance am Mittwoch unter Berufung auf ukrainische Ermittlungsunterlagen mit. Dies sei ein entscheidender Schritt zur Aufkl\u00e4rung der Befehlskette hinter den Massenhinrichtungen von Zivilisten, erkl\u00e4rte der stellvertretende ukrainische Generalstaatsanwalt Andrij Leschtschenko.<\/p>\n<p class=\"text-18 leading-17\">Den Ermittlungen zufolge habe der Kommandeur seinen Truppen befohlen, Personen zu jagen und zu t\u00f6ten, die als Unterst\u00fctzer der ukrainischen Streitkr\u00e4fte galten. Nach den T\u00f6tungen habe er angeordnet, einige Leichen zu verbrennen, um die Verbrechen zu verschleiern. Der Mann befinde sich nicht in ukrainischer Gewahrsam. Bei der R\u00fcckeroberung Butschas Ende M\u00e4rz 2022 nach einmonatiger russischer Besatzung hatten ukrainische Truppen Leichen auf den Stra\u00dfen gefunden. Mehr als 450 Tote wurden aus Massengr\u00e4bern geborgen, Hunderte weitere Menschen starben in der Region.<\/p>\n<p class=\"text-18 leading-17\">Eine US-Milit\u00e4rdelegation f\u00fchrt Gespr\u00e4che in <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" href=\"https:\/\/www.t-online.de\/themen\/kiew\/\" data-sctrack=\"BodyAnchor\" target=\"_blank\" rel=\"noopener\">Kiew<\/a> inmitten von Nachrichten \u00fcber einen neuen amerikanisch-russischen Plan f\u00fcr ein Ende des \u00fcber dreieinhalbj\u00e4hrigen Kriegs. Der ukrainische Verteidigungsminister Denys Schmyhal berichtete von einem Treffen mit Daniel Driscoll, dem f\u00fcr das Heer zust\u00e4ndigen Staatssekret\u00e4r im US-Verteidigungsministerium.<\/p>\n<p class=\"text-18 leading-17\">Die Ukraine sei f\u00fcr die <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" href=\"https:\/\/www.t-online.de\/themen\/usa\/\" data-sctrack=\"BodyAnchor\" target=\"_blank\" rel=\"noopener\">USA<\/a> ein verl\u00e4sslicher Partner, sagte Schmyhal der Delegation nach eigenen Angaben. Er habe den G\u00e4sten neue Entwicklungen der ukrainischen Drohnentechnik vorgestellt, wie er auf Telegram schrieb.<\/p>\n<p class=\"text-18 leading-17\">Neben dem Zivilbeamten Driscoll geh\u00f6ren der Delegation nach US-Medienberichten drei Gener\u00e4le und andere Offiziere an. Sie sollen auch mit Pr\u00e4sident <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" href=\"https:\/\/www.t-online.de\/themen\/wolodymyr-selenskyj\/\" data-sctrack=\"BodyAnchor\" target=\"_blank\" rel=\"noopener\">Wolodymyr Selenskyj<\/a> sprechen, der am Mittwochabend von einer mehrt\u00e4gigen Auslandsreise in die Ukraine zur\u00fcckkehrte. Der Besuch der Pentagon-Delegation wird als Taktik der USA gedeutet, das Gespr\u00e4ch mit Kiew auf milit\u00e4rische Fragen zu verlagern. Dort sieht es derzeit nicht gut aus f\u00fcr die ukrainische Armee, sie muss an vielen Stellen vor russischen Dauerangriffen zur\u00fcckweichen.<\/p>\n","protected":false},"excerpt":{"rendered":"Newsblog zum Ukraine-Krieg Ukraine: Haben einen der Butscha-Schl\u00e4chter identifiziert Aktualisiert am 20.11.2025 &#8211; 03:23 UhrLesedauer: 15 Min. Butscha:&hellip;\n","protected":false},"author":2,"featured_media":588357,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1217,326,6079,522,140883,2226,124389,140880,12583,8331,106,37829,775,140882,551,13,15768,5793,1480,451,14,15,3129,3917,3186,307,12,140881,10,8,9,11,317,312,64,1995,25240,14060,320,103,306,107,104],"class_list":{"0":"post-588356","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-welt","8":"tag-1217","9":"tag-326","10":"tag-6079","11":"tag-522","12":"tag-andrij-leschtschenko","13":"tag-bahnstrecke","14":"tag-butscha","15":"tag-daniel-driscoll","16":"tag-denys-schmyhal","17":"tag-dmitri-peskow","18":"tag-donald-trump","19":"tag-donald-tusk","20":"tag-friedrich-merz","21":"tag-graeuel","22":"tag-grossbritannien","23":"tag-headlines","24":"tag-keith-kellogg","25":"tag-kiew","26":"tag-luftwaffe","27":"tag-militaer","28":"tag-nachrichten","29":"tag-news","30":"tag-newsblog","31":"tag-polen","32":"tag-reuters","33":"tag-russland","34":"tag-schlagzeilen","35":"tag-ternopil","36":"tag-top-news","37":"tag-top-meldungen","38":"tag-topmeldungen","39":"tag-topnews","40":"tag-ukraine","41":"tag-ukrainekrieg","42":"tag-usa","43":"tag-verbrechen","44":"tag-verteidigungsministerium-der-vereinigten-staaten","45":"tag-warschau","46":"tag-washington","47":"tag-welt","48":"tag-wladimir-putin","49":"tag-wolodymyr-selenskyj","50":"tag-world"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/588356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=588356"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/588356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/588357"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=588356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=588356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=588356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}