{"id":633720,"date":"2025-12-09T03:48:15","date_gmt":"2025-12-09T03:48:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/633720\/"},"modified":"2025-12-09T03:48:15","modified_gmt":"2025-12-09T03:48:15","slug":"mann-mit-messer-leistet-widerstand-am-hauptbahnhof-leipzig-%c2%b7-leipziger-zeitung","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/633720\/","title":{"rendered":"Mann mit Messer leistet Widerstand am Hauptbahnhof Leipzig \u00b7 Leipziger Zeitung"},"content":{"rendered":"<p>Am 6. Dezember, gegen 22:45 Uhr wurde die Bundespolizei alarmiert: Laut einem reisenden Fu\u00dfball-Fan aus Frankfurt\/M., sollte sich auf einem Bahnsteig des Hauptbahnhofs in Leipzig ein Mann mit einem Messer aufhalten. Vor Ort stellten die Beamten den Mann fest. Als sie ihn durchsuchen wollten, sperrte sich der 32- J\u00e4hrige und musste schlie\u00dflich zu Boden gebracht und gefesselt werden.<\/p>\n<p>In seiner Jackentasche fanden die Beamten neben dem Messer ein Pfefferspray sowie diverse Dokumente, wie einen F\u00fchrerschein, einen Personalausweis und eine Bahncard, welche nicht auf den Mann ausgestellt waren. Der Algerier muss sich nun wegen Versto\u00dfes gegen die Allgemeinverf\u00fcgung und Versto\u00dfes gegen das Waffengesetz sowie wegen Widerstands gegen Vollstreckungsbeamte und Unterschlagung verantworten.<\/p>\n<p><strong>Erg\u00e4nzender Hinweis:<\/strong><\/p>\n<p>Vom 14. November 2025 bis zum 22. Dezember 2025, jeweils Freitag bis Sonntag in der Zeit von 15:00 Uhr bis 06:00 Uhr des Folgetages ist es verboten, gef\u00e4hrliche Gegenst\u00e4nde (Pfeffersprays, Schlaggegenst\u00e4nde usw.) am Leipziger Hauptbahnhof einschlie\u00dflich der Station Leipzig Hauptbahnhof (tief) mitzuf\u00fchren! Im Falle von Zuwiderhandlungen k\u00f6nnen Gegenst\u00e4nde sichergestellt und ein Zwangsgeld festgesetzt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"Am 6. Dezember, gegen 22:45 Uhr wurde die Bundespolizei alarmiert: Laut einem reisenden Fu\u00dfball-Fan aus Frankfurt\/M., sollte sich&hellip;\n","protected":false},"author":2,"featured_media":22790,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1832],"tags":[421,3364,29,30,71,121,859],"class_list":{"0":"post-633720","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-leipzig","8":"tag-bundespolizei","9":"tag-de","10":"tag-deutschland","11":"tag-germany","12":"tag-leipzig","13":"tag-polizei","14":"tag-sachsen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115687568510332107","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/633720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=633720"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/633720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/22790"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=633720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=633720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=633720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}