{"id":663676,"date":"2025-12-22T05:06:24","date_gmt":"2025-12-22T05:06:24","guid":{"rendered":"https:\/\/www.europesays.com\/de\/663676\/"},"modified":"2025-12-22T05:06:24","modified_gmt":"2025-12-22T05:06:24","slug":"neues-schiedsgericht-fuer-ns-raubkunst-das-grosse-hoffen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/663676\/","title":{"rendered":"Neues Schiedsgericht f\u00fcr NS-Raubkunst: Das gro\u00dfe Hoffen"},"content":{"rendered":"<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/kunsthalle-116.webp\" alt=\"Eine junge Frau betrachtet in der Hamburger Kunsthalle das Bild &quot;Junges M\u00e4dchen&quot;.\" title=\"Eine junge Frau betrachtet in der Hamburger Kunsthalle das Bild &quot;Junges M\u00e4dchen&quot;. | NDR, Marc-Oliver Rehrmann\" class=\"responsive\"\/><\/p>\n<p>AUDIO: Neues Schiedsgericht zur NS-Raubkunst: Der Fall Hannover (4 Min)<\/p>\n<p>\n                Stand: 22.12.2025 06:00 Uhr<\/p>\n<p class=\"preface\">Seit Anfang Dezember gibt es ein neues Schiedsgericht zur NS-Raubkunst. Die Hoffnung ist, dass Streitf\u00e4lle zwischen Erben und Museen endlich gekl\u00e4rt werden. Kommt nun neuer Schwung in zwei prominente F\u00e4lle in Norddeutschland?<\/p>\n<p class=\"textauthor\">von Marc-Oliver Rehrmann<\/p>\n<p class=\"\">Die Erben des j\u00fcdischen Fabrikanten und Kunstsammlers Max Levy lassen nicht locker. Die Familie lebt seit der Flucht aus Nazi-Deutschland in Brasilien. Von dort aus fordert sie seit nunmehr 17 Jahren von der Stadt Hannover, ihr ein \u00d6lgem\u00e4lde des impressionistischen Malers Lovis Corinth zur\u00fcckzugeben &#8211; bisher vergeblich. Sein Blumenstillleben &#8222;Bunte Wicken und Rosen, Erbsenbl\u00fcten&#8220; entstand im Jahr 1913. Experten sch\u00e4tzen den aktuellen Wert auf mehrere Hunderttausend Euro. Heute geh\u00f6rt es zur Sammlung des st\u00e4dtischen Sprengel Museums.<\/p>\n<p>    Flucht kurz vor Kriegsbeginn 1939<\/p>\n<p>                    <a href=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/corinth-100.webp\" class=\"zoomimage\" title=\"Bild vergr\u00f6\u00dfern\"><\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/corinth-100.webp\" alt=\"Das Gem\u00e4lde &quot;Bunte Wicken und Rosen, Erbsenbl\u00fcten&quot; von Lovis Corinth\" title=\"Um dieses Stillleben des Malers Lovis Corinth geht es im Raubkunst-Fall von Hannover. | Lovis Corinth, Public domain, via Wikimedia Commons\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>                    <\/a><\/p>\n<p>                    Um dieses Stillleben des Malers Lovis Corinth geht es im Raubkunst-Fall von Hannover.<\/p>\n<p class=\"\">Die Erben von Max Levy sagen: Das Bild geh\u00f6rte uns, es hing bis Ende der 1930er-Jahre in der Familien-Villa in Berlin. Das hat die Tochter von Max Levy in einer eidesstattlichen Versicherung bezeugt. Demnach konnte sie sich gut daran erinnern, wie sie als junges M\u00e4dchen das Blumen-Gem\u00e4lde im Salon h\u00e4ufig betrachtet hat. Als die Familie im Sommer 1939 wegen der Verfolgung durch die Nationalsozialisten Deutschland verlassen musste, konnte sie ihre Kunstsammlung nicht mitnehmen. Das Bild sei daraufhin verloren gegangen. Sp\u00e4ter tauchte das Kunstwerk in der Sammlung des NSDAP-Mitglieds Conrad Doebbeke auf.<\/p>\n<p class=\"\">Es ist bekannt, dass Doebbeke w\u00e4hrend der NS-Herrschaft j\u00fcdischen Familien, die aufgrund der Verfolgung in Not geraten waren, Kunstwerke abkaufte &#8211; in den meisten F\u00e4llen wohl weit unter Wert. Die Stadt Hannover kaufte im Jahr 1949 insgesamt 114 Kunstwerke aus der Doebbecke-Sammlung &#8211; auch das besagte Stillleben von Lovis Corinth.<\/p>\n<p>Gemeint sind Kunstwerke und Kulturg\u00fcter, die Opfer der Nationalsozialisten aufgrund der Verfolgung zwischen 1933 und 1945 verloren. In den meisten F\u00e4llen handelt es sich um j\u00fcdische Familien. Manches beschlagnahmten die Nazis direkt. Manchmal waren Menschen gezwungen, ihr Hab und Gut weit unter Wert zu verkaufen, weil sie Deutschland verlassen mussten oder von den Nationalsozialisten in Konzentrationslager verschleppt wurden. Laut Sch\u00e4tzungen geht es um insgesamt mehr als 600.000 Kunstwerke. Nur ein kleiner Teil wurde bislang zur\u00fcckgegeben.<\/p>\n<p>    Sprengel Museum: &#8222;Das Bild soll der Richtige bekommen&#8220;<\/p>\n<p class=\"\">Ja, bei dem Gem\u00e4lde handele es sich vermutlich um NS-Raubkunst, sagt Reinhard Spieler im Gespr\u00e4ch mit dem NDR. Er ist seit 2014 Direktor des Sprengel Museums. &#8222;Wir sind bereit, das Gem\u00e4lde zur\u00fcckzugeben. Aber wir wollen auch, dass es der Richtige oder die Richtige bekommt.&#8220;<\/p>\n<p class=\"\">Aber wer ist der oder die Richtige? Wer war in den 1930er-Jahren der letzte Eigent\u00fcmer des Gem\u00e4ldes und h\u00e4tte Anspruch auf eine R\u00fcckgabe? Die Stadt Hannover will den Fall nun vor das neue Schiedsgericht bringen. Die Vorbereitungen dazu laufen auf Seiten der Stadt bereits, so Spieler. &#8222;Neu ist jetzt, dass es beim Schiedsgericht eine rechtsverbindliche Entscheidung gibt. Die Beratende Kommission, die es vorher gab, sprach ja nur Empfehlungen aus. Das Schiedsgericht bringt also einfach Sicherheit.&#8220;<\/p>\n<p>    Hat Max Levy das Gem\u00e4lde vor 1933 verkauft?<\/p>\n<p class=\"\">Bislang konnten die Erben sich nicht mit der Stadt Hannover einigen, sie beklagen eine Hinhalte-Taktik. Aber Museumsdirektor Spieler sagt: &#8222;Die Familie Levy kommt unserer Meinung nach nicht f\u00fcr eine R\u00fcckgabe des Gem\u00e4ldes infrage.&#8220;<\/p>\n<p class=\"\">Die Stadt Hannover meint: Es sei nicht erwiesen, dass das Gem\u00e4lde von Lovis Corinth w\u00e4hrend der NS-Herrschaft immer noch im Besitz der Familie Levy war. Dies w\u00fcrde aber nicht zu der Aussage der Tochter passen, dass das Bild auch nach 1933 in der Familienvilla hing. Die Stadt Hannover ignoriert die eidesstattliche Versicherung der Tochter und interpretiert die raren Archivfunde wie folgt: Levy habe das Gem\u00e4lde vermutlich Anfang der 1920er-Jahre besessen und vor der Machtergreifung 1933 wieder verkauft.<\/p>\n<p>    Mehrere j\u00fcdische Namen im Werkverzeichnis<\/p>\n<p class=\"\">Sp\u00e4tere Besitzer k\u00f6nnten demnach der Galerist Justin Thannhauser oder die Kunstsammlerin Toni Lessing gewesen sein. &#8222;Aber das ist nicht ganz klar, es gibt letztlich keine Faktenlage dazu&#8220;, r\u00e4umt Spieler ein. Und doch sagt der Museumsdirektor: &#8222;Wir denken, dass es einer der beiden Namen sein w\u00fcrde, dem man das Gem\u00e4lde zur\u00fcckgeben w\u00fcrde.&#8220; Alle drei Namen &#8211; Thannhauser, Lessing und Levy &#8211; sind im Werkverzechnis aufgef\u00fchrt &#8211; allerdings ohne Jahreszahlen. So bleibt die Reihenfolge der Besitzer strittig.<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/picasso-laurens-werke-ausstellung-100.webp\" alt=\"In einer Ausstellung ist das Gem\u00e4lde &quot;Madame Soler&quot; neben anderen Kunstwerken zu sehen.\" title=\"In einer Ausstellung ist das Gem\u00e4lde &quot;Madame Soler&quot; neben anderen Kunstwerken zu sehen. | picture-alliance \/ dpa\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>Ein Schiedsgericht soll \u00fcber die R\u00fcckgabe von Nazi-Raubkunst entscheiden. W\u00e4hrend die Politik das als gro\u00dfen Fortschritt feiert, haben Kunsthistoriker und Anw\u00e4lte der Erben j\u00fcdischer Opfer gro\u00dfe Zweifel.<\/p>\n<p>    Neuer Schwung durch neues Schiedsgericht?<\/p>\n<p class=\"\">Und so erhitzt auch mehr als 80 Jahre nach Kriegsende die NS-Raubkunst die Gem\u00fcter. Jahrzehntelang war das heikle Thema nicht angegangen worden. Erst im Jahr 1998 tat sich mit den <a href=\"https:\/\/kulturgutverluste.de\/sites\/default\/files\/2023-04\/Washingtoner-Prinzipien.pdf\" title=\"Washingtoner Prinzipien\" class=\"js-link-dialog\" data-type=\"external\" rel=\"nofollow noopener\" target=\"_blank\">&#8222;Washingtoner Prinzipien&#8220;<\/a> etwas Neues: Damals vereinbarten die Bundesrepublik Deutschland und rund 40 weitere Staaten, die urspr\u00fcnglichen Besitzer von Kunstwerken beziehungsweise ihre Erben zu ermutigen, ihre Anspr\u00fcche anzumelden. Eine &#8222;gerechte und faire L\u00f6sung&#8220; sollte gefunden werden.<\/p>\n<p class=\"\">So nahm im Jahr 2003 in Deutschland die <a href=\"https:\/\/www.beratende-kommission.de\/de\" title=\"Beratende Kommission\" class=\"js-link-dialog\" data-type=\"external\" rel=\"nofollow noopener\" target=\"_blank\">&#8222;Beratende Kommission NS-Raubgut&#8220;<\/a> ihre Arbeit auf. Jedoch kam die Kommission mit ihrer Arbeit schleppend voran. Innerhalb von 22 Jahren wurden nur 26 F\u00e4lle abgeschlossen.<\/p>\n<p>    Weimer: &#8222;Aufarbeitung historischen Unrechts&#8220;<\/p>\n<p class=\"\">Kulturstaatsminister Wolfram Weimer (parteilos) h\u00e4lt das neue Schiedsgericht f\u00fcr eine gute L\u00f6sung: Es bringe &#8222;neue Bewegung in die Aufarbeitung historischen Unrechts. Damit setzen wir ein deutliches Zeichen: Der Staat steht zu seiner historischen Verantwortung.&#8220; Auch j\u00fcdische Vertreter waren an der Ausarbeitung des Schiedsgerichtes beteiligt: die Jewish Claims Conference und der Zentralrat der Juden in Deutschland.<\/p>\n<p>Wem geh\u00f6rt ein Kunstwerk, das w\u00e4hrend der Nazizeit geraubt oder unter Zwang verkauft wurde? Seit Ende des Zweiten Weltkriegs ist diese Frage bis heute in vielen F\u00e4llen nicht gekl\u00e4rt. Bei Streitf\u00e4llen zwischen Opfer-Familien und Museen kann nun <a href=\"https:\/\/schiedsgerichtsbarkeit-ns-raubgut.de\/de\" title=\"Schiedsgericht zu NS-Raubkunst\" class=\"js-link-dialog\" data-type=\"external\" rel=\"nofollow noopener\" target=\"_blank\">das neue Schiedsgericht zu NS-Raubkunst<\/a> entscheiden, das die Beratende Kommission abl\u00f6st. Neu ist, dass das Schiedsgericht rechtlich verbindliche Entscheidungen f\u00e4llen kann. Die Beratende Kommission konnte nur Empfehlungen aussprechen. Zudem k\u00f6nnen betroffene Familien das Schiedsgericht auch einseitig anrufen. Das hei\u00dft: Eine Kultureinrichtung, die mutma\u00dflich im Besitz von NS-Raubkunst ist, kann ein Verfahren vor dem Schiedsgericht nicht mehr blockieren. Voraussetzung ist allerdings, dass das Museum oder die Bibliothek ein &#8222;stehendes Angebot&#8220; abgegeben hat, also das Schiedsgericht grunds\u00e4tzlich anerkennt. Der Bund und die L\u00e4nder haben dieses &#8222;stehende Angebot&#8220; f\u00fcr all ihre Kultureinrichtungen abgegeben. <\/p>\n<p>    Sprengel Museum: &#8222;Warum sollten die Erben nicht zustimmen?&#8220;<\/p>\n<p class=\"\">Bringt das Schiedsgericht also bald eine L\u00f6sung im Fall Levy? Der Haken ist: Die Stadt Hannover kann das Schiedsgericht nur anrufen, wenn die Erben zustimmen. Wie Recherchen des NDR ergeben haben, will sich die Familie dazu nicht \u00e4u\u00dfern. Der Museumsdirektor geht aber von einem Einverst\u00e4ndnis aus. &#8222;Was h\u00e4tten die Erben f\u00fcr einen Grund, das Verfahren nicht zuzulassen?&#8220;, fragt Spieler. &#8222;Wir w\u00fcrden sonst von uns aus sagen, die Familie Levy kriegt es auf keinen Fall. Nur mit dem Schiedsgericht h\u00e4tten sie noch eine Chance, das Gem\u00e4lde zu kriegen.&#8220;<\/p>\n<p>    Hamburg: Jahrelanger Streit ums Gem\u00e4lde &#8222;Junges M\u00e4dchen&#8220;<\/p>\n<p>                    <a href=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/kunsthalle-118.webp\" class=\"zoomimage\" title=\"Bild vergr\u00f6\u00dfern\"><\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/kunsthalle-118.webp\" alt=\"Das Bild &quot;Junges M\u00e4dchen&quot; von Paula Modersohn-Becker in der Hamburger Kunsthalle\" title=\"NS-Raubkunst oder nicht? Das Bild &quot;Junges M\u00e4dchen&quot; von Paula Modersohn-Becker h\u00e4ngt in der Hamburger Kunsthalle. | NDR, Marc-Oliver Rehrmann\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>                    <\/a><\/p>\n<p>                    NS-Raubkunst oder nicht? Das Bild &#8222;Junges M\u00e4dchen&#8220; von Paula Modersohn-Becker h\u00e4ngt in der Hamburger Kunsthalle.<\/p>\n<p class=\"\">Auch in Hamburg gibt es seit Jahren ein Tauziehen um ein Gem\u00e4lde, das m\u00f6glicherweise NS-Raubkunst ist. In der Kunsthalle h\u00e4ngt das Bild &#8222;Junges M\u00e4dchen&#8220; von der deutschen Malerin Paula Modersohn-Becker. Das Kunstwerk kam 1958 als Geschenk in die Sammlung des Museums &#8211; und zwar von Else Doebbeke, der Witwe des Kunsth\u00e4ndlers Conrad Doebbeke.<\/p>\n<p class=\"\">Seit 2020 fordert die Familie von Robert Graetz von Brasilien aus die Stadt Hamburg auf, das Gem\u00e4lde herauszugeben. Robert Graetz war j\u00fcdischer Textilunternehmer in Berlin, Kunstsammler und M\u00e4zen. Als die Nationalsozialisten an die Macht kamen, musste er seine Firma schlie\u00dfen. Aus finanzieller Not heraus sah er sich gezwungen, einen Gro\u00dfteil seines Besitzes weit unter Wert zu ver\u00e4u\u00dfern. 1942 wurde er deportiert und kam ums Leben.<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/kunsthalle-114.webp\" alt=\"Die beleuchtete Fassade der Kunsthalle in Hamburg\" title=\"Die beleuchtete Fassade der Kunsthalle in Hamburg | picture alliance \/ imageBROKER, Thomas Lammeyer\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>Knapp 80 Jahre nach Kriegsende gibt es Streit um ein Bild von Paula Modersohn-Becker &#8211; zwischen der Hamburger Kunsthalle und den Nachkommen eines NS-Opfers.<\/p>\n<p>    Ist es \u00fcberhaupt das besagte Kunstwerk?<\/p>\n<p class=\"\">Die Stadt lehnt eine R\u00fcckgabe des Gem\u00e4ldes &#8222;Junges M\u00e4dchen&#8220; ab. Auf Nachfrage des NDR teilt die Kunsthalle mit: &#8222;Aus unserer Sicht liegen keine klaren Belege vor, dass es sich bei dem beanspruchten Werk um das aus der Sammlung Graetz handelt. F\u00fcr das Werk aus der Sammlung Graetz liegen verschiedene Titel vor, keine Ma\u00dfe und keine Technikangaben. Und die Datierung entspricht nicht des Werkes, das sich in der Kunsthalle befindet.&#8220;<\/p>\n<p class=\"\">Um den Streitfall zu l\u00f6sen, befasste sich die Beratende Kommission &#8211; also der Vorl\u00e4ufer des Schiedsgerichtes &#8211; mit den Argumenten beider Seiten. Aus zeitlichen Gr\u00fcnden sprach die Kommission aber keine Empfehlung mehr aus.<\/p>\n<p>    Erst Schiedsgericht, dann R\u00fcckgabe?<\/p>\n<p class=\"\">Die Stadt Hamburg geht nach eigenen Angaben davon aus, dass der Fall vom neuen Schiedsgericht erneut aufgegriffen wird. &#8222;F\u00fcr uns ist entscheidend, dass die Werksidentit\u00e4t zweifelsfrei gekl\u00e4rt wird. Sollte sich herausstellen, dass die Stadt nicht rechtm\u00e4\u00dfig in den Besitz des Gem\u00e4ldes gekommen ist, werden wir dieses selbstverst\u00e4ndlich restituieren&#8220;, teilt die Hamburger Kulturbeh\u00f6rde dem NDR mit. Aber f\u00fcr ein Verfahren vor dem Schiedsgericht fehlt noch die Zustimmung der Erben von Robert Graetz.<\/p>\n<p>    Hannover bedauert lange H\u00e4ngepartie<\/p>\n<p class=\"\">Im Fall Hannover kann der Direktor des Sprengel Museums den Frust auf Seiten der Familie Levy nachvollziehen, dass sich der Streitfall schon seit 17 Jahren hinzieht. &#8222;Das ist auf alle F\u00e4lle sehr misslich und das finde ich auch sehr problematisch.&#8220;<\/p>\n<p class=\"\">Die Tochter des Kunstsammlers Max Levy wird eine m\u00f6gliche Kl\u00e4rung nicht mehr erleben. Sie verstarb im Herbst 2024 im Alter von 96 Jahren in Brasilien. Nun ist es die Enkel-Generation, die das Gem\u00e4lde zur\u00fcckfordert &#8211; und die Hoffnung nicht aufgibt, dass die Stadt Hannover ihr eines Tages doch noch das Gem\u00e4lde von Lovis Corinth \u00fcbergibt.<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/utehaug-100.webp\" alt=\"Zwei Mitarbeiter betrachten eine Druckgrafik\" title=\"Zwei Mitarbeiter betrachten eine Druckgrafik | Sreenshot\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>Die Provenienzforscherin der Hamburger Kunsthalle  sucht in deutschen Museen nach NS-Raubkunst. Sie ist Tr\u00e4gerin des Bundesverdienstkreuzes.<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/screenshot-96046.webp\" alt=\"Ein altes aufgeklapptes Buch in einer Glasvitrine.\" title=\"Ein altes aufgeklapptes Buch in einer Glasvitrine. | Screenshot\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>Die Universit\u00e4t G\u00f6ttingen und Museen haben ihre Best\u00e4nde auf Raubgut gepr\u00fcft. Die Ergebnisse zeigt das G\u00f6ttinger &#8222;Forum Wissen&#8220; bis Mai 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"AUDIO: Neues Schiedsgericht zur NS-Raubkunst: Der Fall Hannover (4 Min) Stand: 22.12.2025 06:00 Uhr Seit Anfang Dezember gibt&hellip;\n","protected":false},"author":2,"featured_media":663677,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1826],"tags":[29,30,692,2075],"class_list":{"0":"post-663676","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hamburg","8":"tag-deutschland","9":"tag-germany","10":"tag-hamburg","11":"tag-kunst"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115761485825515772","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/663676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=663676"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/663676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/663677"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=663676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=663676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=663676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}