{"id":663967,"date":"2025-12-22T08:07:45","date_gmt":"2025-12-22T08:07:45","guid":{"rendered":"https:\/\/www.europesays.com\/de\/663967\/"},"modified":"2025-12-22T08:07:45","modified_gmt":"2025-12-22T08:07:45","slug":"polizei-einsatz-in-berlin-huendin-mit-axt-geschlagen-regional","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/663967\/","title":{"rendered":"Polizei-Einsatz in Berlin: H\u00fcndin mit Axt geschlagen! | Regional"},"content":{"rendered":"<p>Hellersdorf \u2013 <b> Eine einj\u00e4hrige H\u00fcndin wurde am Freitagabend Opfer eines eskalierten Streites unter zwei M\u00e4nnern (32, 41). Pl\u00f6tzlich z\u00fcckte der \u00c4ltere eine Axt. Das Tier geriet zwischen die Fronten und wurde schwer am Kopf verletzt.<\/b><\/p>\n<p>Auch interessant<\/p>\n<p>Anzeige<\/p>\n<p>Auch interessant<\/p>\n<p>Anzeige<\/p>\n<p>Gegen 21.30 Uhr sollen der 41-j\u00e4hrige Steven O., sein Bekannter (32) und dessen gleichaltrige Lebensgef\u00e4hrtin an der Tangerm\u00fcnder Stra\u00dfe in <a href=\"https:\/\/www.bild.de\/regional\/berlin\/berlin-regional\/home-15823246.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Berlin<\/a>-Hellersdorf unterwegs gewesen sein. Offenbar aus nichtigem Anlass gerieten die M\u00e4nner w\u00e4hrenddessen in Streit. <\/p>\n<p>Die Auseinandersetzung eskalierte derart, dass Steven O. schlie\u00dflich eine Axt gezogen und ausgeholt haben soll. Ob zum Angriff oder zur Verteidigung, ist derzeit noch unklar. Ein Schlag traf Pittbull-H\u00fcndin Shiva am Kopf.<\/p>\n<p><b>Das Paar hatte f\u00fcr ein Familienmitglied auf den Vierbeiner aufgepasst. Der Angreifer behauptet sp\u00e4ter, der <\/b><a href=\"https:\/\/www.bild.de\/ratgeber\/haustier\/hund\/thema-hunde-alle-infos-80118564.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\"><b>Hund<\/b><\/a><b> sei auf ihn gehetzt worden. <\/b><\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"558\" alt=\"Dieses Waffenarsenal mit \u00c4xten und Messern wurde in der Wohnung von Steven S. (41) sichergestellt\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/1424572735ea1250c7943bfc84a9c2e5,edeb66ae\"   class=\"landscape\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Dieses Waffenarsenal mit \u00c4xten und Messern wurde in der Wohnung von Steven S. (41) sichergestellt<\/p>\n<p>Foto: Olaf Wagner<\/p>\n<p><b>Nach der Attacke auf Shiva fl\u00fcchtete Steven O. in seine Wohnung an der Tangerm\u00fcnde Stra\u00dfe. <\/b><\/p>\n<p>Alarmierte Polizisten brachten das schwer verletzte Tier in eine Veterin\u00e4rklinik. \u201eDer Hund hat eine blutende Wunde am Kopf erlitten, wurde notoperiert\u201c, sagt eine Polizeisprecherin.<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"1178\" alt=\"Die H\u00fcndin wurde am linken Auge verletzt\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/2c96503220feee00430f6dda2a42f3da,3d72f646\"   class=\"portrait\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Die H\u00fcndin wurde am linken Auge verletzt<\/p>\n<p>Foto: Olaf Wagner<\/p>\n<p>Weil die Ermittler davon ausgehen mussten, dass der Verd\u00e4chtige im Besitz von Waffen war, r\u00fcckte die Polizei am Sonnabendmorgen dann mit Unterst\u00fctzung des <a href=\"https:\/\/www.bz-berlin.de\/thema\/sek\" target=\"_blank\" rel=\"noopener nofollow\" class=\"text-link--external text-link\">SEK<\/a> an der Tangerm\u00fcnder Stra\u00dfe an. Steven S. wurde laut Polizei angetroffen, aber nicht festgenommen. <\/p>\n<p>Die Beamten durchsuchten die Wohnung und entdeckten drei \u00c4xte, darunter die Tatwaffe, sowie mehrere Messer und stellten diese als m\u00f6gliche Beweismittel sicher.<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"558\" alt=\"Einsatzfahrzeuge bei der Wohungsdurchsuchung an der Tangerm\u00fcnder Stra\u00dfe\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/12\/0e1929e743a9bf37fd1cf0a6b03aadb5,4f994fb2\"   class=\"landscape\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Einsatzfahrzeuge bei der Wohnungsdurchsuchung an der Tangerm\u00fcnder Stra\u00dfe<\/p>\n<p>Foto: Olaf Wagner<\/p>\n<p><b>Die weiteren Ermittlungen zu den Hintergr\u00fcnden der Auseinandersetzung \u00fcbernahm das Fachkommissariat der Polizeidirektion 3 (Ost). <\/b><\/p>\n","protected":false},"excerpt":{"rendered":"Hellersdorf \u2013 Eine einj\u00e4hrige H\u00fcndin wurde am Freitagabend Opfer eines eskalierten Streites unter zwei M\u00e4nnern (32, 41). Pl\u00f6tzlich&hellip;\n","protected":false},"author":2,"featured_media":663968,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1825],"tags":[31484,296,29,30,1000,19134,604,1981,121,45,1995],"class_list":["post-663967","post","type-post","status-publish","format-standard","has-post-thumbnail","category-berlin","tag-axt","tag-berlin","tag-deutschland","tag-germany","tag-gewalt","tag-hellersdorf","tag-hund","tag-messer","tag-polizei","tag-texttospeech","tag-verbrechen"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115762197753065344","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/663967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=663967"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/663967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/663968"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=663967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=663967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=663967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}