{"id":696201,"date":"2026-01-05T23:42:10","date_gmt":"2026-01-05T23:42:10","guid":{"rendered":"https:\/\/www.europesays.com\/de\/696201\/"},"modified":"2026-01-05T23:42:10","modified_gmt":"2026-01-05T23:42:10","slug":"lego-smart-play-star-wars-sets-mit-licht-und-sound","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/696201\/","title":{"rendered":"Lego Smart Play: Star-Wars-Sets mit Licht und Sound"},"content":{"rendered":"<ol class=\"a-toc__list\">\n<li class=\"a-toc__item&#10;          &#10;            a-toc__item--counter&#10;          &#10;            a-toc__item--current\">\n<p>              Lego Smart Play: Star-Wars-Sets mit Licht und Sound<\/p>\n<\/li>\n<\/ol>\n<p>Unter dem Motto \u201eLet them play back with you!\u201c hat Lego auf der CES 2026 in Las Vegas seinen Smart Brick vorgestellt, einen Klemmbaustein mit integrierter Elektronik. Er ist Bestandteil der neuen Plattform Lego Smart Play. Smart Bricks erkennen Bewegungen, Lage und Ber\u00fchrung und reagieren darauf mit Licht- und Soundeffekten. Weitere Komponenten wie Smartphone, Bildschirm oder eine App sind nicht n\u00f6tig.<\/p>\n<p>        Weiterlesen nach der Anzeige<\/p>\n<p><strong>Kompakte Technik in klassischem Klemmbaustein<\/strong><\/p>\n<p>Der Smart Brick entspricht \u00e4u\u00dferlich dem seit Jahrzehnten bekannten 2&#215;4-Klemmbaustein von Lego. Er ist aber vollgestopft mit Sensoren, einem Lautsprecher, LEDs und einem eigens f\u00fcr ihn entwickelten, 41 mm kleinen Chip. Mehr als 20 Patente erm\u00f6glichen laut Hersteller die n\u00f6tige Miniaturisierung, damit sich der 2&#215;4-Stein in die Welt g\u00e4ngiger Klemmbausteine einf\u00fcgt. Der Stein ist als Smart Brick gekennzeichnet, damit er nicht unter anderen in der Lego-Kiste untergeht.<\/p>\n<p>Ein propriet\u00e4res \u201eNeighbour Position Measurement System\u201c (NPM) nutzt Kupferspulen, um Entfernung, Richtung und Ausrichtung der Smart Bricks magnetisch zu erfassen. Ein kompakter analoger Synthesizer generiert Sound-Effekte wie Melodien, Tier- oder Motorenger\u00e4usche, ein LED-Array leuchtet dazu in unterschiedlichen Farben.<\/p>\n<p>      <a href=\"https:\/\/www.heise.de\/imgs\/18\/5\/0\/0\/3\/0\/5\/7\/PXL_20260105_181427020-e7c582a03217a188.jpg\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>  <img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"1141\" src=\"data:image\/svg+xml,%3Csvg xmlns='http:\/\/www.w3.org\/2000\/svg' width='696px' height='391px' viewBox='0 0 696 391'%3E%3Crect x='0' y='0' width='696' height='391' fill='%23f2f2f2'%3E%3C\/rect%3E%3C\/svg%3E\" style=\"aspect-ratio: 2024 \/ 1141; object-fit: cover;\" width=\"2024\"\/><\/p>\n<p>      <\/a><\/p>\n<p>Smart bricks k\u00f6nnen leuchten und Ger\u00e4usche von sich geben. Die Smart-Tag-Pl\u00e4ttchen enthalten Code, der von Smart-Minifiguren ausgel\u00f6st werden kann.<\/p>\n<p class=\"a-caption__source\">\n      (Bild:\u00a0heise medien)\n    <\/p>\n<p>Smart-Tags und Smart-Minifiguren<\/p>\n<p>Erg\u00e4nzt wird das System durch 2&#215;2-Smart-Tags und Smart-Minifiguren, die der Smart Brick \u00fcber NPM kontaktlos identifizieren kann. Die Smart-Tags erhalten einen Code, der den Smart-Bricks mitteilt, wie sie sich verhalten sollen. Er kann beispielsweise die Anweisung erhalten, nach einer Smart-Minifigur zu suchen. Ein Smart-Tag kann beispielsweise in einem Feuerwehr-Set den Brand eines Geb\u00e4udes simulieren. \u00dcber die Richtung l\u00e4sst sich ein Rennwagen gegen\u00fcber einem anderen in F\u00fchrungsposition identifizieren, und Gr\u00fcn statt Rot leuchten.<\/p>\n<p>Die Komponenten lassen sich induktiv laden und sind mit bestehenden Lego-Steinen kompatibel. Mehrere Smart Bricks k\u00f6nnen drahtlos miteinander kommunizieren. Daf\u00fcr nutzt Lego das propriet\u00e4re, auf Bluetooth aufsetzende Protokoll BrickNet, das Positions- und Bewegungsdaten austauscht. Eine Steuereinheit ist nicht erforderlich. Lego versichert zudem, Spulen und Akkus f\u00fcr den Einsatz \u00fcber mehrere Jahre konzipiert zu haben.<\/p>\n<p>        Weiterlesen nach der Anzeige<\/p>\n<p>      <a href=\"https:\/\/www.heise.de\/imgs\/18\/5\/0\/0\/3\/0\/5\/7\/PXL_20260105_183421420-61cdaa0e423da712.jpg\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>  <img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"2888\" src=\"data:image\/svg+xml,%3Csvg xmlns='http:\/\/www.w3.org\/2000\/svg' width='696px' height='391px' viewBox='0 0 696 391'%3E%3Crect x='0' y='0' width='696' height='391' fill='%23f2f2f2'%3E%3C\/rect%3E%3C\/svg%3E\" style=\"aspect-ratio: 3895 \/ 2888; object-fit: cover;\" width=\"3895\"\/><\/p>\n<p>      <\/a><\/p>\n<p>Bei der Pr\u00e4sentation holte Lego Dave Filoni auf die B\u00fchne (rechts). Er ist bei Disney Chief Creative Officer von Lucasfilm und f\u00fcr die inhaltliche Ausrichtung und Weiterentwicklung des Star\u2011Wars\u2011Universums verantwortlich.<\/p>\n<p class=\"a-caption__source\">\n      (Bild:\u00a0heise medien)\n    <\/p>\n<p><strong>Start mit drei Star-Wars-Sets<\/strong><\/p>\n<p>Zum Marktstart erscheinen drei Sets aus dem Star-Wars-Programm: Luke Skywalkers X-Wing, Darth Vaders TIE Fighter und ein Thronsaal-Duell-Set mit A-Wing Fighter. Die Sets enthalten jeweils mindestens einen Smart Brick samt Ladeger\u00e4t sowie mindestens eine Smart-Minifigur und ein Smart-Tag.<\/p>\n<p>Die Sets sollen sich ab dem 9. Januar 2026 vorbestellen lassen. Der Verkaufsstart ist f\u00fcr den 1. M\u00e4rz 2026 geplant. Dann stehen sie \u00fcber Lego Stores, Lego.com und ausgew\u00e4hlte Einzelh\u00e4ndler zur Verf\u00fcgung.<\/p>\n<p>      <a href=\"https:\/\/www.heise.de\/imgs\/18\/5\/0\/0\/3\/0\/5\/7\/PXL_20260105_184121180-28e303c003a81a85.jpg\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>  <img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"2299\" src=\"data:image\/svg+xml,%3Csvg xmlns='http:\/\/www.w3.org\/2000\/svg' width='696px' height='391px' viewBox='0 0 696 391'%3E%3Crect x='0' y='0' width='696' height='391' fill='%23f2f2f2'%3E%3C\/rect%3E%3C\/svg%3E\" style=\"aspect-ratio: 3486 \/ 2299; object-fit: cover;\" width=\"3486\"\/><\/p>\n<p>      <\/a><\/p>\n<p>Die Smart Bricks erscheinen zun\u00e4chst in drei Star-Wars-Sets.<\/p>\n<p class=\"a-caption__source\">\n      (Bild:\u00a0heise medien)\n    <\/p>\n<p><strong>Die Smart-Play-Sets im Detail<\/strong><\/p>\n<p>Das 473 Teile umfassende TIE-Fighter-Set inklusive Rebellen-Au\u00dfenposten und imperialer Tankstelle enth\u00e4lt einen smarten Darth Vader sowie eine Rebellenfigur. Aus dem Smart Brick im TIE Fighter ert\u00f6nen die Zwillings-Ionentriebwerke, wenn man die Darth-Vader-Minifigur hineinsetzt. Das Set \u201eLEGO\u00ae Star Wars\u2122 SMART Play\u2122: Darth Vader\u2019s TIE Fighter\u2122\u201c (Setnummer 75421) soll 69,99 Euro kosten.<\/p>\n<p>      <a href=\"https:\/\/www.heise.de\/imgs\/18\/5\/0\/0\/3\/0\/5\/7\/Lego_TIE_Fighter-570e7b86a0f33629.jpeg\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>  <img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"4481\" src=\"data:image\/svg+xml,%3Csvg xmlns='http:\/\/www.w3.org\/2000\/svg' width='696px' height='391px' viewBox='0 0 696 391'%3E%3Crect x='0' y='0' width='696' height='391' fill='%23f2f2f2'%3E%3C\/rect%3E%3C\/svg%3E\" style=\"aspect-ratio: 6722 \/ 4481; object-fit: cover;\" width=\"6722\"\/><\/p>\n<p>      <\/a><\/p>\n<p>LEGO\u00ae Star Wars\u2122 SMART Play\u2122: Darth Vader\u2019s TIE Fighter\u2122<\/p>\n<p class=\"a-caption__source\">\n      (Bild:\u00a0Lego)\n    <\/p>\n<p>Das X-Wing-Set enth\u00e4lt 584 Teile und zwei Smart-Minifiguren: Luke Skywalker in Pilotenuniform und Prinzessin Leia. Auch herk\u00f6mmliche Minifiguren wie Rebellen, Sturmtruppen und R2-D2 sind dabei. \u201eLEGO\u00ae Star Wars\u2122 SMART Play\u2122: Luke\u2019s Red Five X-Wing\u2122\u201c (75423) kommt f\u00fcr 89,99 Euro in den Handel.<\/p>\n<p>      <a href=\"https:\/\/www.heise.de\/imgs\/18\/5\/0\/0\/3\/0\/5\/7\/Lego_X-Win-13499e0726bb5f19.jpeg\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>  <img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"4481\" src=\"data:image\/svg+xml,%3Csvg xmlns='http:\/\/www.w3.org\/2000\/svg' width='696px' height='391px' viewBox='0 0 696 391'%3E%3Crect x='0' y='0' width='696' height='391' fill='%23f2f2f2'%3E%3C\/rect%3E%3C\/svg%3E\" style=\"aspect-ratio: 6722 \/ 4481; object-fit: cover;\" width=\"6722\"\/><\/p>\n<p>      <\/a><\/p>\n<p>LEGO\u00ae Star Wars\u2122 SMART Play\u2122: Luke\u2019s Red Five X-Wing\u2122<\/p>\n<p class=\"a-caption__source\">\n      (Bild:\u00a0Lego)\n    <\/p>\n<p>Mit 962 Teilen ist das Thron-Raum-Set das umfangreichste. Es enth\u00e4lt drei smarte Minifiguren: Darth Vader, den Imperator und Luke Skywalker in schwarzer Jedi-Montur. Laserkanonen am Thronsaal reagieren \u00fcber Smart Bricks mit Ger\u00e4uschen. Weitere Sound-Effekte umfassen Lichtschwertger\u00e4usche im Duell zwischen Vater und Sohn und den Imperialen Marsch, wenn man Palpatine auf seinen Thron setzt. Der vollst\u00e4ndige Name lautet \u201eLEGO\u00ae Star Wars\u2122 SMART Play\u2122: Throne Room Duel &amp; A-Wing\u2122\u201c (75427). Als Preis nannte Lego 159,99 Euro.<\/p>\n<p>      <a href=\"https:\/\/www.heise.de\/imgs\/18\/5\/0\/0\/3\/0\/5\/7\/Lego_Throne_Room-1099b7d9ab9b9173.jpeg\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>  <img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"4481\" src=\"data:image\/svg+xml,%3Csvg xmlns='http:\/\/www.w3.org\/2000\/svg' width='696px' height='391px' viewBox='0 0 696 391'%3E%3Crect x='0' y='0' width='696' height='391' fill='%23f2f2f2'%3E%3C\/rect%3E%3C\/svg%3E\" style=\"aspect-ratio: 6722 \/ 4481; object-fit: cover;\" width=\"6722\"\/><\/p>\n<p>      <\/a><\/p>\n<p>LEGO\u00ae Star Wars\u2122 SMART Play\u2122: Throne Room Duel &amp; A-Wing\u2122<\/p>\n<p class=\"a-caption__source\">\n      (Bild:\u00a0Lego)\n    <\/p>\n<p><strong>Erweiterungen angek\u00fcndigt<\/strong><\/p>\n<p>Lego legt Smart Play als Plattform an und will sie k\u00fcnftig durch weitere Sets und technische Erweiterungen erg\u00e4nzen. Weitere Details will das Unternehmen zu einem sp\u00e4teren Zeitpunkt bekanntgeben.<\/p>\n<p>heise online ist Medienpartner der CES 2026<\/p>\n<p>(<a class=\"redakteurskuerzel__link\" href=\"https:\/\/www.heise.de\/news\/mailto:akr@ct.de\" title=\"Andr\u00e9 Kramer\" rel=\"nofollow noopener\" target=\"_blank\">akr<\/a>)<\/p>\n<p>\n      Dieser Link ist leider nicht mehr g\u00fcltig.\n    <\/p>\n<p>Links zu verschenkten Artikeln werden ung\u00fcltig,<br \/>\n      wenn diese \u00e4lter als 7\u00a0Tage sind oder zu oft aufgerufen wurden.\n    <\/p>\n<p><strong>Sie ben\u00f6tigen ein heise+ Paket, um diesen Artikel zu lesen. Jetzt eine Woche unverbindlich testen \u2013 ohne Verpflichtung!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"Lego Smart Play: Star-Wars-Sets mit Licht und Sound Unter dem Motto \u201eLet them play back with you!\u201c hat&hellip;\n","protected":false},"author":2,"featured_media":696202,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[135],"tags":[11048,29,214,30,30827,190,189,8267,2890,194,191,193,192],"class_list":["post-696201","post","type-post","status-publish","format-standard","has-post-thumbnail","category-wissenschaft-technik","tag-ces","tag-deutschland","tag-entertainment","tag-germany","tag-lego","tag-science","tag-science-technology","tag-spiele","tag-star-wars","tag-technik","tag-technology","tag-wissenschaft","tag-wissenschaft-technik"],"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/696201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=696201"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/696201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/696202"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=696201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=696201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=696201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}