{"id":706038,"date":"2026-01-09T20:27:10","date_gmt":"2026-01-09T20:27:10","guid":{"rendered":"https:\/\/www.europesays.com\/de\/706038\/"},"modified":"2026-01-09T20:27:10","modified_gmt":"2026-01-09T20:27:10","slug":"der-winter-macht-ernst-und-haelt-der-gesellschaft-den-spiegel-vor","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/706038\/","title":{"rendered":"Der Winter macht ernst \u2013 und h\u00e4lt der Gesellschaft den Spiegel vor"},"content":{"rendered":"<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Liebe Leserinnen und Leser,<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">kommen wir einmal zu dem wirklich wichtigen Thema dieser Zeit \u2013 dem Winter. Der macht diesmal seinem Namen alle Ehre und tut das, was ein Winter eben so tut: Er bringt Schnee, Frost und Sturm. Und so unseren sch\u00f6nen geregelten und getakteten Alltag durcheinander. Schnell ist vom Schneechaos die Rede, wenn der Weg zur Arbeit l\u00e4nger dauert oder man zu sp\u00e4t zu Terminen kommt.<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Diejenigen, die sich dem \u201eChaos\u201c alle Jahre wieder entgegenstemmen, tragen orangefarbene, reflektierende Arbeitskleidung der Technischen Betriebe Solingen (TBS). Sie sitzen stundenlang bei K\u00e4lte und Dunkelheit auf Streuwagen und Schneer\u00e4umern. Oder schaufeln und fr\u00e4sen Schnee von B\u00fcrgersteigen und Bushaltestellen. Das oft zu Zeiten, in denen die meisten von uns noch im warmen Bett liegen und erst sp\u00e4ter nach einer hei\u00dfen Tasse Kaffee der rauen wei\u00dfen Wirklichkeit vor der Haust\u00fcr entgegentreten. <\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Die TBS haben ausreichend Streusalz im Depot gebunkert. Aber dort lagert kein zus\u00e4tzliches Personal f\u00fcr solche extremen Situationen. Der Winterdienst muss also mit den vorhandenen Kr\u00e4ften auskommen. Das bedeutet Nachteins\u00e4tze, Extraschichten und Ruhepausen am gesetzlichen Minimum. <a href=\"https:\/\/www.solinger-tageblatt.de\/lokales\/solingen\/alles-stockt-schnee-legt-solinger-verkehr-lahm-busse-mit-starker-verspaetung-FRJIBCMNIVFGVGXVYJRO4WNTAM.html\" target=\"_self\" rel=\"noopener\" title=\"https:\/\/www.solinger-tageblatt.de\/lokales\/solingen\/alles-stockt-schnee-legt-solinger-verkehr-lahm-busse-mit-starker-verspaetung-FRJIBCMNIVFGVGXVYJRO4WNTAM.html\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/www.solinger-tageblatt.de\/lokales\/solingen\/alles-stockt-schnee-legt-solinger-verkehr-lahm-busse-mit-starker-verspaetung-FRJIBCMNIVFGVGXVYJRO4WNTAM.html\">Bisher hat das dank vorausschauender Planung und hohem Einsatz gut funktioniert.<\/a> Trotz erheblicher Schneemassen blieb das Chaos bisher aus. Es gab keine stundenlangen Blockaden durch querstehende Fahrzeuge, die Busse fuhren zwar nicht p\u00fcnktlich, aber sie fuhren.<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Wer nun denkt, die orange-wei\u00dfen Retter w\u00fcrden in einer Woge von Dankbarkeit und Zuneigung baden, irrt. Ja, es gibt sie, die lobende Stimme, das Schulterklopfen, die kleine Anerkennung. Doch in den sogenannten Sozialen Netzwerken \u00fcberwiegt wie \u00fcblich der Chor der Meckerer, N\u00f6rgler und Krakeeler. Schlie\u00dflich ist die eigene Stra\u00dfe noch wei\u00df und vor der eigenen Haust\u00fcr ist keine TBS-Schippe weit und breit zu sehen. <\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Was vielleicht daran liegen k\u00f6nnte, dass der Schnee \u00fcberall gleichzeitig f\u00e4llt, die M\u00e4nner der TBS aber nicht \u00fcberall gleichzeitig r\u00e4umen k\u00f6nnen. Ein Stra\u00dfennetz von mehr als 588 Kilometern (entspricht in etwa der Strecke Solingen-Prag) erfordert Priorisierung \u2013 das m\u00fcsste selbst dem gr\u00f6\u00dften Simpel klar sein.<a href=\"https:\/\/www.solinger-tageblatt.de\/lokales\/solingen\/wintereinbruch-auf-den-strassen-in-solingen-gab-es-nur-wenig-probleme-EPJIDCR7JJCBLGXRVFKDXTPMNU.html\" target=\"_self\" rel=\"noopener\" title=\"https:\/\/www.solinger-tageblatt.de\/lokales\/solingen\/wintereinbruch-auf-den-strassen-in-solingen-gab-es-nur-wenig-probleme-EPJIDCR7JJCBLGXRVFKDXTPMNU.html\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/www.solinger-tageblatt.de\/lokales\/solingen\/wintereinbruch-auf-den-strassen-in-solingen-gab-es-nur-wenig-probleme-EPJIDCR7JJCBLGXRVFKDXTPMNU.html\"> Die Fokussierung auf Hauptverkehrsachsen und Buslinien ist dem TBS bisher gut gelungen,<\/a> auch im Vergleich zu anderen St\u00e4dten. Das war in der Vergangenheit nicht immer so.<\/p>\n<p>Woher kommt diese Unzufriedenheit?<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Warum also diese Unzufriedenheit, die sich manchmal in Unfl\u00e4tigkeiten entl\u00e4dt? Die Antwort ist vielschichtig. Zum einen ist das Netz nicht die Wirklichkeit. In den Internetblasen tummeln sich immer wieder dieselben wenigen Trolle, die ihr Gift verspritzen. Die Mehrheit denkt und f\u00fchlt anders, auch wenn sie sich nicht \u00e4u\u00dfert.<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">In der sch\u00fctzenden Anonymit\u00e4t des Internets l\u00e4sst sich leider nicht herausfinden, wo mehr Zeit investiert wird: vor dem Bildschirm oder mit der Schippe vor dem eigenen Haus. Meckern ist halt leichter als Machen.<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Staat misstraut dem Einzelnen zutiefst<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Zum anderen steigt die Anspruchshaltung gegen\u00fcber dem Staat ins Uferlose. Woran dieser nicht unschuldig ist. Denn er misstraut dem Individuum zutiefst. Daher spinnt die \u00f6ffentliche Hand die B\u00fcrger in ein immer weiter wachsendes Netz aus Regelungen, Vorschriften und Sanktionen ein, in dem Engagement und jede Eigenverantwortung erstickt werden.<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Bei keinem Arzneimittelchen, f\u00fcr das geworben wird, darf der Hinweis fehlen, dass man erst R\u00fccksprache mit einem Arzt oder Apotheker halten soll. \u00c4rztinnen d\u00fcrfen nat\u00fcrlich auch gefragt werden, wie seit einiger Zeit klargestellt wird. Doch das ist wieder ein anderes Thema. Warnhinweise und Werbeverbote f\u00fcr zucker- oder fetthaltige Lebensmittel sind schon lange in Vorbereitung. Dabei gibt es kaum ein pers\u00f6nlicheres Thema als die eigene Ern\u00e4hrung.<\/p>\n<p>Wenn die Welt zur R\u00e4uberh\u00f6hle verkommt<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Wenn der Sch\u00e4fer aus der Sicht seiner Sch\u00e4fchen dann aber versagt \u2013 was angesichts der zunehmenden Regulierungswut des Staates unausweichlich ist \u2013, wird das Wutgeheul entsprechend laut. Zumal sich Anstand und Empathie in unserer Welt immer weiter verabschieden, w\u00e4hrend Egoismus, Dreistigkeit und R\u00fccksichtslosigkeit zunehmen.<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Es wird ja inzwischen vorgelebt, dass sich das ruppige Brechen aller Regeln scheinbar auszahlt. <a href=\"https:\/\/www.solinger-tageblatt.de\/politik\/weltordnung-der-willkuer-das-ist-trumps-donroe-doktrin-JOBJG2AQYFG6REDIITYZYHDNRY.html\" target=\"_self\" rel=\"noopener\" title=\"https:\/\/www.solinger-tageblatt.de\/politik\/weltordnung-der-willkuer-das-ist-trumps-donroe-doktrin-JOBJG2AQYFG6REDIITYZYHDNRY.html\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/www.solinger-tageblatt.de\/politik\/weltordnung-der-willkuer-das-ist-trumps-donroe-doktrin-JOBJG2AQYFG6REDIITYZYHDNRY.html\">Wenn die Weltmacht USA alte gemeinsame Werte schleift<\/a> und sich offen zum alleinigen Recht des St\u00e4rkeren bekennt, braucht man sich nicht zu wundern, wenn die Welt zu einer R\u00e4uberh\u00f6hle verkommt. Mit den entsprechenden Sitten und Umgangsformen.<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Ihr <a href=\"https:\/\/www.solinger-tageblatt.de\/autoren\/stefan-kob\/\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"https:\/\/www.solinger-tageblatt.de\/autoren\/stefan-kob\/\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/www.solinger-tageblatt.de\/autoren\/stefan-kob\/\">Stefan M. Kob<\/a>, Kolumnist<\/p>\n<p>Themen der WocheDar\u00fcber diskutiert Solingen<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Das sollten Sie wissen Jetzt unsere Spiele-Seite besuchen <\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Spielen Sie <a href=\"https:\/\/www.solinger-tageblatt.de\/spiele\/\" rel=\"noopener noreferrer\" title=\"https:\/\/www.solinger-tageblatt.de\/spiele\/\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/www.solinger-tageblatt.de\/spiele\/\" target=\"_blank\">spannende Kreuzwortr\u00e4tsel, knifflige Sudoku sowie weitere Spiele gratis<\/a> bei uns. Jede neue Spiel-Session f\u00f6rdert Ihr logisches Denkverm\u00f6gen und sorgt dabei f\u00fcr Abwechslung.<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Weiterer Service<\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\"><a href=\"https:\/\/www.solinger-tageblatt.de\/podcast\/\" rel=\"noopener noreferrer\" title=\"https:\/\/www.solinger-tageblatt.de\/podcast\/\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/www.solinger-tageblatt.de\/podcast\/\" target=\"_blank\">Podcasts <\/a>| <a href=\"https:\/\/login.st-epaper.de\/\" rel=\"noopener noreferrer\" title=\"https:\/\/login.st-epaper.de\/\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/login.st-epaper.de\/\" target=\"_blank\">ePaper <\/a>| <a href=\"https:\/\/trauer.solinger-tageblatt.de\/\" rel=\"noopener noreferrer\" title=\"https:\/\/trauer.solinger-tageblatt.de\/\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/trauer.solinger-tageblatt.de\/\" target=\"_blank\">Traueranzeigen<\/a> | <a href=\"https:\/\/formulare.solinger-tageblatt.de\/leserbrief\" rel=\"noopener noreferrer\" title=\"https:\/\/formulare.solinger-tageblatt.de\/leserbrief\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/formulare.solinger-tageblatt.de\/leserbrief\" target=\"_blank\">Leserbriefe<\/a> | <a href=\"https:\/\/www2.st-karte.de\/\" rel=\"noopener noreferrer\" title=\"https:\/\/www2.st-karte.de\/\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/www2.st-karte.de\/\" target=\"_blank\">ST-Karte<\/a> | <a href=\"https:\/\/bergische-leserreisen.de\/\" rel=\"noopener noreferrer\" title=\"https:\/\/bergische-leserreisen.de\/\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/bergische-leserreisen.de\/\" target=\"_blank\">Bergische Leserreisen<\/a> | <a href=\"https:\/\/bergisch-bestes.de\/\" rel=\"noopener noreferrer\" title=\"https:\/\/bergisch-bestes.de\/\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/bergisch-bestes.de\/\" target=\"_blank\">Shop \u201eBergisch Bestes\u201c<\/a> <\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Weiterlesen nach der Anzeige<\/p>\n<p>Mehr lesen mit dem + <\/p>\n<p class=\"Textstyled__Text-sc-1cqv9mi-0 cLyiiX\">Einige der im Newsletter verlinkten Artikel sind f\u00fcr alle Leserinnen und Leser frei zug\u00e4nglich, andere bieten wir ausschlie\u00dflich unseren ST+-Abonnentinnen und -Abonnenten an. Sie haben noch kein ST+? Testen Sie jetzt unser Abo und erhalten Sie Zugang zu interessanten Hintergr\u00fcnden, spannenden Reportagen und exklusiven Interviews. <a href=\"https:\/\/www.solinger-tageblatt.de\/abo\/\" rel=\"noopener noreferrer\" title=\"https:\/\/www.solinger-tageblatt.de\/abo\/\" data-vars-event-category=\"intext_link\" data-vars-event-action=\"click\" data-vars-event-label=\"https:\/\/www.solinger-tageblatt.de\/abo\/\" target=\"_blank\">Jetzt Probeabo starten<\/a> <\/p>\n<p class=\"Editorialstyled__Editorial-sc-1bfvh9l-0 cSmjnJ\">ST<\/p>\n","protected":false},"excerpt":{"rendered":"Liebe Leserinnen und Leser, Weiterlesen nach der Anzeige Weiterlesen nach der Anzeige kommen wir einmal zu dem wirklich&hellip;\n","protected":false},"author":2,"featured_media":706039,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1840],"tags":[3364,29,30,1209,4418],"class_list":{"0":"post-706038","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-wuppertal","8":"tag-de","9":"tag-deutschland","10":"tag-germany","11":"tag-nordrhein-westfalen","12":"tag-wuppertal"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115867028252021864","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/706038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=706038"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/706038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/706039"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=706038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=706038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=706038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}