{"id":708151,"date":"2026-01-10T16:45:17","date_gmt":"2026-01-10T16:45:17","guid":{"rendered":"https:\/\/www.europesays.com\/de\/708151\/"},"modified":"2026-01-10T16:45:17","modified_gmt":"2026-01-10T16:45:17","slug":"homeoffice-wegen-schnee-diese-regeln-gelten-fuer-beschaeftigte","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/708151\/","title":{"rendered":"Homeoffice wegen Schnee? Diese Regeln gelten f\u00fcr Besch\u00e4ftigte"},"content":{"rendered":"<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/01\/homeoffice-238.webp.webp\" alt=\"Eine Frau sitzt mit einem Laptop an einem Tisch im Homeoffice.\" title=\"Eine Frau sitzt mit einem Laptop an einem Tisch im Homeoffice. | picture alliance\/dpa | Fabian Strauch\" class=\"responsive\"\/><\/p>\n<p>AUDIO: &#8222;Wegerisiko&#8220;: Arbeitsrecht macht keine Ausnahmen bei Extremwetter (3 Min)<\/p>\n<p>\n                Stand: 10.01.2026 04:40 Uhr<\/p>\n<p class=\"preface\">Sind au\u00dfergew\u00f6hnliche Wetterlagen wie ein Schneesturm angek\u00fcndigt, sind viele Berufspendler betroffen. Besch\u00e4ftigte sollten das Gespr\u00e4ch mit dem Arbeitgeber suchen. Denn das Arbeitsrecht ist hier eindeutig. <\/p>\n<p class=\"textauthor\">von Hauke B\u00fclow<\/p>\n<p class=\"\">Starke Schneef\u00e4lle und Eisgl\u00e4tte sind in Norddeutschland eher die Ausnahme. Kommt es zu extremen winterlichen Verh\u00e4ltnissen, ist das vor allem f\u00fcr Arbeitnehmer auf dem Land eine schwierige Situation. Schneeverwehungen und glatte Stra\u00dfen k\u00f6nnten den Weg zum Job kompliziert machen. Arbeitsrechtlich ist die Lage allerdings eindeutig: Besch\u00e4ftigte sind selbst daf\u00fcr verantwortlich, p\u00fcnktlich zu erscheinen. Juristen sprechen vom sogenannten Wegerisiko. Ob der Bus versp\u00e4tet ist oder die Bahn ganz ausf\u00e4llt, \u00e4ndert daran nichts.<\/p>\n<p>    Ohne Arbeit kein Lohn<\/p>\n<p>                    <a href=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/01\/1768063514_511_schneeverwehungen106.webp.webp\" class=\"zoomimage\" title=\"Bild vergr\u00f6\u00dfern\"><\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/01\/1768063514_511_schneeverwehungen106.webp.webp\" alt=\"Ein festgefahrener Gel\u00e4ndewagen steht verlassen in einer Schneewehe.\" title=\"Arbeitnehmer m\u00fcssen selbst daf\u00fcr sorgen, p\u00fcnktlich zur Arbeit zu kommen. | dpa, Carsten Rehder\/dpa\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>                    <\/a><\/p>\n<p>                    Arbeitnehmer m\u00fcssen selbst daf\u00fcr sorgen, p\u00fcnktlich zur Arbeit zu kommen.<\/p>\n<p class=\"\">Wer zu sp\u00e4t oder gar nicht erscheint, hat f\u00fcr die ausgefallene Zeit auch keinen Anspruch auf Verg\u00fctung. Es gilt das allgemeine Prinzip &#8222;Ohne Arbeit kein Lohn&#8220;, erkl\u00e4rt die <a href=\"https:\/\/www.ndr.de\/nachrichten\/schleswig-holstein\/textlink-305810~splash.html\" title=\"Arbeitsrecht Schnee\" data-url=\"https:\/\/www.verdi.de\/themen\/arbeit\/++co++19889528-d65a-11e6-9a1a-525400940f89\" class=\"js-link-dialog\" data-type=\"external\" target=\"_blank\" rel=\"noopener\">Gewerkschaft ver.di<\/a>. Auf der anderen Seite m\u00fcssen Besch\u00e4ftigte die verlorenen Stunden nicht automatisch nacharbeiten. Eine Pflicht zum Nachholen besteht nur dann, wenn es daf\u00fcr im Unternehmen ein geregeltes Arbeitszeit- oder \u00dcberstundenkonto gibt, so die Gewerkschaft. Dort k\u00f6nnten die Minus-Stunden festgehalten werden.<\/p>\n<p>    Homeoffice nur mit Zustimmung<\/p>\n<p>                    <a href=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/01\/oezren-100.webp.webp\" class=\"zoomimage\" title=\"Bild vergr\u00f6\u00dfern\"><\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/01\/oezren-100.webp.webp\" alt=\"IHK-Sprecher L\u00fcbeck Dr. Can \u00d6zren.\" title=\"Can \u00d6zren, Sprecher der IHK zu L\u00fcbeck: &quot;Wenn jemand aus dem Homeoffice arbeitet, ist es vermutlich besser, als stundenlang im Stau zu stehen und zu sp\u00e4t zu kommen.&quot; | IHK zu L\u00fcbeck\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>                    <\/a><\/p>\n<p>                    Can \u00d6zren, Sprecher der IHK zu L\u00fcbeck: &#8222;Wenn jemand aus dem Homeoffice arbeitet, ist es vermutlich besser, als stundenlang im Stau zu stehen und zu sp\u00e4t zu kommen.&#8220;<\/p>\n<p class=\"\">W\u00e4hrend der &#8222;Corona-Jahre&#8220; haben viele Arbeitgeber Homeoffice-L\u00f6sungen geschaffen. Einen Anspruch darauf gibt es allerdings nicht, erkl\u00e4rt die <a href=\"https:\/\/www.ndr.de\/nachrichten\/schleswig-holstein\/textlink-305816~splash.html\" title=\"Homeoffice IHK\" data-url=\"https:\/\/www.ihk.de\/schleswig-holstein\/recht\/arbeitsrecht\/arbeitsrechtliche-grundlagen-des-homeoffice-6204638\" class=\"js-link-dialog\" data-type=\"external\" target=\"_blank\" rel=\"noopener\">IHK Schleswig-Holstein<\/a>. Mobiles Arbeiten sei immer eine Frage der vertraglichen Grundlage und der Zustimmung des Arbeitgebers. &#8222;Allerdings ist es nat\u00fcrlich sinnvoll, hier mit Augenma\u00df vorzugehen&#8220;, sagte Can \u00d6zren von der IHK zu L\u00fcbeck. Bei Extremwetterbedingungen sollten nach M\u00f6glichkeit flexible Arbeitsorte erm\u00f6glicht werden, um keine Menschen zu gef\u00e4hrden, sagte \u00d6zren NDR Schleswig-Holstein.<\/p>\n<p>    Wenn der Betrieb stillsteht<\/p>\n<p class=\"\">Muss eine Firma witterungsbedingt schlie\u00dfen, zum Beispiel weil Lagerhallen durch den Schnee nicht mehr erreichbar sind, Maschinen einfrieren oder ganze Schichten abgesagt werden, handelt es sich laut der <a href=\"https:\/\/www.ndr.de\/nachrichten\/schleswig-holstein\/textlink-305830~splash.html\" title=\"IG Metall\" data-url=\"https:\/\/www.igmetall.de\/im-betrieb\/arbeits--und-sozialrecht\/zu-spaet-wegen-eis-und-schnee\" class=\"js-link-dialog\" data-type=\"external\" target=\"_blank\" rel=\"noopener\">Gewerkschaft IG Metall<\/a> um das Betriebsrisiko. Das tr\u00e4gt der Arbeitgeber. In solchen Ausnahmef\u00e4llen m\u00fcssen Besch\u00e4ftigte keine Lohnk\u00fcrzung bef\u00fcrchten, obwohl sie nicht arbeiten k\u00f6nnen.<\/p>\n<p>    Kinderbetreuung bei Schul- oder Kita-Ausfall<\/p>\n<p class=\"\">F\u00fcr berufst\u00e4tige Eltern k\u00f6nnen Schneelagen noch ein ganz anderes Problem mit sich bringen: Die Kita oder Schule bleibt kurzfristig geschlossen. Wenn Besch\u00e4ftigte deshalb keine Betreuungsm\u00f6glichkeit f\u00fcr ihr eigenes Kind finden, sind sie berechtigt, der Arbeit fernzubleiben. Nach Paragraf 616 des BGB kann dann zumindest f\u00fcr einige Tage Anspruch auf Weiterzahlung des Lohnes bestehen. Allerdings nur, wenn die Regelung nicht im Arbeitsvertrag, dem Tarifvertrag oder einer Betriebsvereinbarung eingeschr\u00e4nkt oder gar ausgeschlossen ist, so die Gewerkschaften.<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/01\/bahnsteig-112.webp.webp\" alt=\"Ein voller Bahnsteig im Hamburger Hauptbahnhof nachdem der Bahnverkehr nach Wintersturm &quot;Elli&quot; langsam wieder anl\u00e4uft\" title=\"Ein voller Bahnsteig im Hamburger Hauptbahnhof nachdem der Bahnverkehr nach Wintersturm &quot;Elli&quot; langsam wieder anl\u00e4uft | dpa-Bildfunk, Bodo Marks\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>Fernz\u00fcge fahren im Norden vorerst nur zwischen Hamburg und NRW. Auch Regional- und Nahverkehr bleiben eingeschr\u00e4nkt. Die Unwetterwarnungen des DWD sind aufgehoben.<\/p>\n<p>    Konsequenzen bei &#8222;Schneewetter-Schw\u00e4nzen&#8220;<\/p>\n<p class=\"\">Eine K\u00fcndigung brauchen Arbeitnehmer bei extremen Wetterlagen nicht zu f\u00fcrchten. Ob eine Abmahnung wegen Versp\u00e4tungen m\u00f6glich ist, h\u00e4ngt vom Einzelfall ab. Bei pl\u00f6tzlichem Blitzeis oder einer offiziellen Unwetterwarnung w\u00e4re eine Abmahnung in der Regel nicht gerechtfertigt, erkl\u00e4ren IG Metall und ver.di. Wer sich jedoch mehrere Tage hintereinander &#8222;mit dem Schnee rausreden&#8220; will, m\u00fcsse sich darauf einstellen, dass der Arbeitgeber das irgendwann nicht mehr akzeptiere. Grunds\u00e4tzlich gilt: Besch\u00e4ftigte und Unternehmen sollten fr\u00fchzeitig miteinander reden, um pragmatische L\u00f6sungen zu finden.<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/01\/1767864321_826_winter-278.webp.webp\" alt=\"Autos fahren durch verschneite Landschaft in Sieversen in der Samtgemeinde Rosengarten.\" title=\"Autos fahren durch verschneite Landschaft in Sieversen in der Samtgemeinde Rosengarten. | picture alliance\/imageBROKER, Siegfried Kuttig\" class=\"responsive\" loading=\"lazy\"\/><\/p>\n<p>Auch bei Schneesturm und Blitzeis m\u00fcssen Arbeitnehmer p\u00fcnktlich im Betrieb sein, denn sie tragen das Wegerisiko. Absprachen mit dem Arbeitgeber sind aber sinnvoll.<\/p>\n","protected":false},"excerpt":{"rendered":"AUDIO: &#8222;Wegerisiko&#8220;: Arbeitsrecht macht keine Ausnahmen bei Extremwetter (3 Min) Stand: 10.01.2026 04:40 Uhr Sind au\u00dfergew\u00f6hnliche Wetterlagen wie&hellip;\n","protected":false},"author":2,"featured_media":708152,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[620,6442,29,17989,30,42751,13,19234,163241,14,15,4125,1009,12,16406,97394,10,8,9,11,2898,87874],"class_list":{"0":"post-708151","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deutschland","8":"tag-arbeitsmarkt","9":"tag-arbeitsrecht","10":"tag-deutschland","11":"tag-extremwetter","12":"tag-germany","13":"tag-glaette","14":"tag-headlines","15":"tag-homeoffice","16":"tag-lohnanspruch","17":"tag-nachrichten","18":"tag-news","19":"tag-pendler","20":"tag-recht","21":"tag-schlagzeilen","22":"tag-schnee","23":"tag-schneesturm","24":"tag-top-news","25":"tag-top-meldungen","26":"tag-topmeldungen","27":"tag-topnews","28":"tag-verspaetung","29":"tag-winterdienst"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115871818652711388","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/708151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=708151"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/708151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/708152"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=708151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=708151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=708151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}