{"id":721073,"date":"2026-01-15T20:26:10","date_gmt":"2026-01-15T20:26:10","guid":{"rendered":"https:\/\/www.europesays.com\/de\/721073\/"},"modified":"2026-01-15T20:26:10","modified_gmt":"2026-01-15T20:26:10","slug":"alba-ist-das-modell-eines-klubs-wie-wir-ihn-in-der-nba-europe-sehen-wollen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/721073\/","title":{"rendered":"\u201eAlba ist das Modell eines Klubs, wie wir ihn in der NBA Europe sehen wollen\u201c"},"content":{"rendered":"<p class=\"tspCBne tspCBnf\">Alba Berlin hat gute Chancen, beim geplanten Start der NBA Europe im Herbst 2027 dabei zu sein. \u201eIch werde nichts \u00fcber den Stand der Verhandlungen sagen, aber Alba Berlin ist mir sehr gut bekannt\u201c, sagte NBA-Commissioner Adam Silver in einer Pressekonferenz im Rahmen des <a href=\"https:\/\/www.tagesspiegel.de\/sport\/allein-der-geruch-gibt-mir-ptbs-vom-kadertraining-fruher-moritz-und-franz-wagner-sind-zuruck-in-ihrem-hinterhof-15131455.html?icid=in-text-link_15141309\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" target=\"_blank\" rel=\"noopener\">ersten NBA-Spiels in Deutschland am Donnerstag<\/a>. \u201eAlba ist das Modell eines Klubs, wie wir ihn in der NBA Europe sehen wollen.\u201c <\/p>\n<p><a href=\"https:\/\/leute.tagesspiegel.de\/?utm_source=tagesspiegel.de&amp;utm_campaign=newsletter-signup&amp;utm_medium=website&amp;utm_content=link&amp;icid=single-topic_15141309___\" data-gtm-class=\"article-mzt-link\" class=\"tspC1p0\" target=\"_blank\" rel=\"noopener\">Mehr \u00fcber guten Sport aus lokaler Perspektive lesen! In unseren w\u00f6chentlichen Newslettern aus den zw\u00f6lf Berliner Bezirken finden Sie Spannendes zu lokalem Sport, lokaler Politik und Kultur. Hier bestellen.  <\/a><\/p>\n<p class=\"tspCBne\">Silver, der am Mittwoch bei einem Empfang im Roten Rathaus auch mit Alba-Manager Marco Baldi und Pr\u00e4sident Axel Schweitzer gesprochen hat, lobte vor allem die Jugendarbeit des elffachen Deutschen Meisters, <a href=\"https:\/\/www.tagesspiegel.de\/sport\/moritz-macht-einfach-franz-ist-bedachter-auf-den-spuren-der-wagner-bruder-durch-berlin-15095454.html?icid=in-text-link_15141309\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" target=\"_blank\" rel=\"noopener\">aus der auch die Magic-Stars Moritz und Franz Wagner hervorgegangen sin<\/a>d. \u201eIch habe mit Marco \u00fcber Jugendbasketball gesprochen\u201c, sagte Silver und die USA k\u00f6nnten hier viel von Europa lernen.<\/p>\n<p class=\"tspCBne\">Dass die NBA eine europ\u00e4ische Liga aufbauen will, ist schon l\u00e4nger bekannt. Im November sprach George Aivazoglou, Gesch\u00e4ftsf\u00fchrer der NBA f\u00fcr den europ\u00e4ischen Markt, erstmals \u00fcber das Grundger\u00fcst der Pl\u00e4ne. Losgehen soll es im Herbst 2027 mit zw\u00f6lf festen Teilnehmern sowie vier Mannschaften, die sich \u00fcber europ\u00e4ische Wettbewerbe oder nationale Ligen qualifizieren k\u00f6nnen. <\/p>\n<p class=\"tspAAfm\">Empfohlener redaktioneller Inhalt<\/p>\n<p> An dieser Stelle finden Sie einen von unseren Redakteuren ausgew\u00e4hlten, externen Inhalt, der den Artikel f\u00fcr Sie mit zus\u00e4tzlichen Informationen anreichert. Sie k\u00f6nnen sich hier den externen Inhalt mit einem Klick anzeigen lassen oder wieder ausblenden. <\/p>\n<p> Externen Inhalt anzeigen <\/p>\n<p class=\"tspAAfs\"> Ich bin damit einverstanden, dass mir der externe Inhalt angezeigt wird. Damit k\u00f6nnen personenbezogene Daten an Drittplattformen \u00fcbermittelt werden.  Mehr Informationen dazu erhalten Sie in den Datenschutz-Einstellungen. Diese finden Sie ganz unten auf unserer Seite im Footer, sodass Sie Ihre Einstellungen jederzeit verwalten oder widerrufen k\u00f6nnen. <\/p>\n<p class=\"tspCBne\">Die dauerhaften Standorte sollen Berlin, M\u00fcnchen, Barcelona, Madrid, London, Manchester, Lyon, Paris, Mailand, Rom, Athen und Istanbul sein. Welche Klubs in den St\u00e4dten aber Teil der NBA Europe werden sollen, dar\u00fcber hatten sich bisher weder die Liga noch die Vereine ge\u00e4u\u00dfert. <\/p>\n<p class=\"tspCBne\">Laut Aivazoglou beginnt die NBA in dieser Woche die Gespr\u00e4che mit Interessenten. \u201eDazu geh\u00f6ren Investoren und Teams. Einige dieser Teams sind bestehende Basketballteams, andere sind Fu\u00dfballteams, die sehr daran interessiert sind, ein Basketballprogramm als Teil der NBA Europe aufzubauen\u201c, sagte er. <\/p>\n<p class=\"tspCBne\">W\u00e4hrend in St\u00e4dten wie Athen, Madrid oder M\u00fcnchen etablierte Vereine existieren, die aus der Euroleague in die neue Liga wechseln k\u00f6nnten, gibt es in London, Rom und Manchester bisher keinen hochklassigen Basketball. <\/p>\n<p class=\"tspCBne\">Die NBA ist davon \u00fcberzeugt, dass der europ\u00e4ische Basketball sein Potenzial bisher nicht aussch\u00f6pft\u00a0\u2013 insbesondere finanziell. Viele Euroleague-Teams machen jede Saison Verluste in zweistelliger Millionenh\u00f6he, gerade die Einnahmen aus der Fernsehrechtevermarktung sind teilweise l\u00e4cherlich niedrig. <\/p>\n<p class=\"tspCBne\">Die NBA hat 2024 einen TV-Vertrag \u00fcber elf Jahre und 77 Milliarden Dollar abgeschlossen. Das Geld f\u00fcr die Expansion nach Europa fehlt der gr\u00f6\u00dften Basketballliga der Welt nicht. \u201eIch glaube nicht, dass der europ\u00e4ische Basketball das vielf\u00e4ltige und gro\u00dfe globale Publikum erreicht, das er erreichen k\u00f6nnte und das die NBA erreicht. Basketball in Europa macht weniger als 0,5 Prozent der 50 Milliarden US-Dollar schweren Sportindustrie aus\u201c, sagte Aivazoglou. <\/p>\n<p>Mehr zum NBA-Spiel in Berlin<a href=\"https:\/\/www.tagesspiegel.de\/sport\/allein-der-geruch-gibt-mir-ptbs-vom-kadertraining-fruher-moritz-und-franz-wagner-sind-zuruck-in-ihrem-hinterhof-15131455.html?icid=topic-list_15141309___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:null},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/sport\/allein-der-geruch-gibt-mir-ptbs-vom-kadertraining-fruher-moritz-und-franz-wagner-sind-zuruck-in-ihrem-hinterhof-15131455.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;\u201eAllein der Geruch gibt mir PTBS vom Kadertraining fr\u00fcher\u201c&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;Moritz und Franz Wagner sind zur\u00fcck in ihrem \u201eHinterhof\u201c&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15131455&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspC1p0 tspC0py\" target=\"_blank\" rel=\"noopener\">\u201eAllein der Geruch gibt mir PTBS vom Kadertraining fr\u00fcher\u201c Moritz und Franz Wagner sind zur\u00fcck in ihrem \u201eHinterhof\u201c <\/a><a href=\"https:\/\/www.tagesspiegel.de\/sport\/moritz-macht-einfach-franz-ist-bedachter-auf-den-spuren-der-wagner-bruder-durch-berlin-15095454.html?icid=topic-list_15141309___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:true},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/sport\/moritz-macht-einfach-franz-ist-bedachter-auf-den-spuren-der-wagner-bruder-durch-berlin-15095454.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;\u201eMoritz macht einfach, Franz ist bedachter\u201c&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;Auf den Spuren der Wagner-Br\u00fcder durch Berlin&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15095454&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspC1p0 tspC0py\" target=\"_blank\" rel=\"noopener\">\u201eMoritz macht einfach, Franz ist bedachter\u201c Auf den Spuren der Wagner-Br\u00fcder durch Berlin <\/a><a href=\"https:\/\/www.tagesspiegel.de\/sport\/beate-wagner-uber-ihre-sohne-franz-und-moritz-vollkornbrot-mogen-die-beiden-gar-nicht-15138243.html?icid=topic-list_15141309___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:true},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/sport\/beate-wagner-uber-ihre-sohne-franz-und-moritz-vollkornbrot-mogen-die-beiden-gar-nicht-15138243.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;Beate Wagner \u00fcber ihre S\u00f6hne Franz und Moritz&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;\u201eVollkornbrot m\u00f6gen die beiden gar nicht\u201c&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15138243&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspC1p0 tspC0py\" target=\"_blank\" rel=\"noopener\">Beate Wagner \u00fcber ihre S\u00f6hne Franz und Moritz \u201eVollkornbrot m\u00f6gen die beiden gar nicht\u201c <\/a><\/p>\n<p class=\"tspCBne\"><a href=\"https:\/\/www.tagesspiegel.de\/sport\/alba-berlin-hofft-auf-nba-europe-wir-sind-ein-solider-kandidat-14799257.html?icid=in-text-link_15141309\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" target=\"_blank\" rel=\"noopener\">Alba hat sich schon mehrfach klar zur NBA Europe bekannt<\/a>. Nach Jahrzehnten im Kosmos der Euroleague sind die Berliner im Sommer in die Champions League gewechselt. Diese ist qualitativ zwar deutlich schw\u00e4cher, wird aber vom Weltverband Fiba ausgerichtet, der auch in die <a href=\"https:\/\/www.tagesspiegel.de\/sport\/entscheidung-wird-ende-marz-erwartet-nba-arbeitet-intensiv-an-expansion-nach-europa-13273537.html?icid=in-text-link_15141309\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" target=\"_blank\" rel=\"noopener\">Planungen der NBA Europe<\/a> involviert ist. \u201eDie NBA Europe ist kein Hirngespinst mehr. Sie wird kommen und wir wollen dabei sein\u201c, <a href=\"https:\/\/www.tagesspiegel.de\/sport\/alba-berlin-zwischen-saisonstart-und-zukunftsvisionen-die-nba-europe-wird-kommen-und-wir-wollen-dabei-sein-14398178.html?icid=in-text-link_15141309\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" target=\"_blank\" rel=\"noopener\">hatte Albas Manager Marco Baldi im September gesagt<\/a>. (mit dpa)<\/p>\n","protected":false},"excerpt":{"rendered":"Alba Berlin hat gute Chancen, beim geplanten Start der NBA Europe im Herbst 2027 dabei zu sein. \u201eIch&hellip;\n","protected":false},"author":2,"featured_media":721074,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[2471,296,29,527,30,15918,530,2281,64],"class_list":{"0":"post-721073","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-alba-berlin","9":"tag-berlin","10":"tag-deutschland","11":"tag-friedrichshain-kreuzberg","12":"tag-germany","13":"tag-nba","14":"tag-pankow","15":"tag-silvester","16":"tag-usa"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115900998301122502","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/721073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=721073"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/721073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/721074"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=721073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=721073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=721073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}