{"id":730504,"date":"2026-01-19T14:30:17","date_gmt":"2026-01-19T14:30:17","guid":{"rendered":"https:\/\/www.europesays.com\/de\/730504\/"},"modified":"2026-01-19T14:30:17","modified_gmt":"2026-01-19T14:30:17","slug":"nuernberg-heftige-vorwuerfe-gegen-den-schwarzen-spd-ob-kandidaten-bayern","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/730504\/","title":{"rendered":"N\u00fcrnberg: Heftige Vorw\u00fcrfe gegen den schwarzen SPD-OB-Kandidaten &#8211; Bayern"},"content":{"rendered":"<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1ygz9cx\">Im M\u00e4rz 2025 hat <a href=\"https:\/\/www.sueddeutsche.de\/bayern\/nasser-ahmed-ob-kandidat-rassismus-netz-nuernberg-anzeigen-interview-li.3224849\" target=\"_blank\" rel=\"noopener\">Nasser Ahmed in einem Gespr\u00e4ch mit der <\/a><a href=\"https:\/\/www.sueddeutsche.de\/bayern\/nasser-ahmed-ob-kandidat-rassismus-netz-nuernberg-anzeigen-interview-li.3224849\" target=\"_blank\" rel=\"noopener\">S\u00fcddeutschen Zeitung<\/a><a href=\"https:\/\/www.sueddeutsche.de\/bayern\/nasser-ahmed-ob-kandidat-rassismus-netz-nuernberg-anzeigen-interview-li.3224849\" target=\"_blank\" rel=\"noopener\"> geschildert<\/a>, wie er im Alltag mit rassistischen Anfeindungen zu k\u00e4mpfen hat. Unter einem einzigen Post von ihm, so schilderte Ahmed, fanden sich einmal \u201eTausende Hasskommentare\u201c. Diese habe man anschlie\u00dfend in verschiedene Kategorien unterteilt, unter anderem in \u201erassistische Beleidigungen, Volksverhetzung, Gewaltandrohung\u201c. Ahmed, Sohn eritreischer Einwanderer, ist Kandidat der N\u00fcrnberger SPD bei der kommenden OB-Wahl. Sollte er gew\u00e4hlt werden, so w\u00e4re er der erste schwarze Oberb\u00fcrgermeister in Deutschland.<\/p>\n","protected":false},"excerpt":{"rendered":"Im M\u00e4rz 2025 hat Nasser Ahmed in einem Gespr\u00e4ch mit der S\u00fcddeutschen Zeitung geschildert, wie er im Alltag&hellip;\n","protected":false},"author":2,"featured_media":730505,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1837],"tags":[4249,772,83785,3364,29,30,2839,4156,3783,1181,154,149],"class_list":{"0":"post-730504","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nuernberg","8":"tag-rassismus","9":"tag-bayern","10":"tag-bayern-spd","11":"tag-de","12":"tag-deutschland","13":"tag-germany","14":"tag-kommunalpolitik","15":"tag-mittelfranken","16":"tag-nuernberg","17":"tag-politik-bayern","18":"tag-social-media","19":"tag-sueddeutsche-zeitung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115922247693717138","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/730504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=730504"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/730504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/730505"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=730504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=730504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=730504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}