{"id":733545,"date":"2026-01-20T18:27:17","date_gmt":"2026-01-20T18:27:17","guid":{"rendered":"https:\/\/www.europesays.com\/de\/733545\/"},"modified":"2026-01-20T18:27:17","modified_gmt":"2026-01-20T18:27:17","slug":"baum-freut-sich-auf-die-herausforderung-fc-bayern-welche-spieler-sind-fit","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/733545\/","title":{"rendered":"Baum freut sich auf die Herausforderung FC Bayern \u2013 welche Spieler sind fit"},"content":{"rendered":"<p class=\"mb-6 text-xs md:text-m lg:text-l font-serif group-[.font-sans]:font-sans \">\n    Jeffrey Gouweleeuw ist zur\u00fcck auf dem Platz. Zumindest, um individuell Runden zu laufen. Das machte der Niederl\u00e4nder auch am Dienstag wieder, als der FC Augsburg in die neue Trainingswoche startete. Seit Anfang November ist Gouweleeuw verletzt, seit einer Woche ist er zumindest zeitweise wieder mit der Mannschaft auf dem Rasen.\n  <\/p>\n<p class=\"mb-6 text-xs md:text-m lg:text-l font-serif group-[.font-sans]:font-sans \">\n    Vor wenigen Tagen hatte Gouweleeuw seinen Wunsch ge\u00e4u\u00dfert, gerne wieder Ende Februar am Spielbetrieb der Fu\u00dfball-Bundesliga teilzunehmen. Trainer Manuel Baum ist da etwas zur\u00fcckhaltender. Er sprach davon, dass er schon zufrieden w\u00e4re, w\u00fcrde der 34-J\u00e4hrige Ende Februar wieder voll ins Training einsteigen. \u201eDa geht es ums Erwartungsmanagement. Ich erwarte lieber weniger, dann werde ich nicht entt\u00e4uscht\u201c, sagte Baum.\n  <\/p>\n<p class=\"mb-6 text-xs md:text-m lg:text-l font-serif group-[.font-sans]:font-sans \">\n    Kristijan Jakic fehlte am Dienstag auch. <a href=\"https:\/\/www.augsburger-allgemeine.de\/baden-wuerttemberg\/fussball-bundesliga-beim-treppengang-verletzt-augsburgs-kurioser-spielerwechsel-113200449\" target=\"_self\" class=\"underline \" rel=\"nofollow noopener\">Der Kroate hatte sich beim Runtergehen der Treppe nach der Pause am Sonntag an der Wade verletzt<\/a>. \u201eEs ist kein strukturelles Thema\u201c, sagte Baum. Die Untersuchung best\u00e4tigte die erste Vermutung, dass es sich um eine Muskelverh\u00e4rtung handelt.  Am Dienstag hatte Jakic allerdings noch Schmerzen. Am Samstag (15.30 Uhr) sollte er bei der Partie in M\u00fcnchen wieder dabei sein.\n  <\/p>\n<p>            FC Augsburg: Baum mit Keitel-Deb\u00fct sehr zufrieden<\/p>\n<p class=\"mb-6 text-xs md:text-m lg:text-l font-serif group-[.font-sans]:font-sans \">\n    Wom\u00f6glich wird er beim FC Bayern sogar in der Innenverteidigung gebraucht. Noahkai Banks fehlt gesperrt, <a href=\"https:\/\/www.augsburger-allgemeine.de\/sport\/fc-augsburg\/fc-augsburg-yannik-keitel-ich-bin-ein-freund-von-herausforderungen-113207764\" target=\"_self\" class=\"underline \" rel=\"nofollow noopener\">bei Yannik Keitel stellt sich die Frage, wie der Neuzugang aus Stuttgart seinen ersten Startelfeinsatz \u00fcberstanden hat.<\/a> Seit November hatte er keine Partie mehr bestritten. Gegen Freiburg jedenfalls hatte Keitel \u00fcberzeugt. \u201eMit Ball hat er uns Flexibilit\u00e4t gegeben, er war auch gut im Kommunizieren. Ich war sehr zufrieden mit seinem Deb\u00fct\u201c, sagte Baum am Dienstag.\n  <\/p>\n<p class=\"mb-6 text-xs md:text-m lg:text-l font-serif group-[.font-sans]:font-sans \">\n    Die Aufgabe am Samstag wird gewaltig. Baum wei\u00df das. Er sagte aber auch: \u201eVom Grundsatz ist in der Vorbereitung alles darauf ausgelegt, dass wir das Spiel gewinnen wollen.\u201c  Auch die zuletzt hohen Siege der Bayern machen ihm keine Angst. \u201eWie viele Menschen haben denn die M\u00f6glichkeit im Alltag, Herausforderungen zu haben, an denen sie wachsen k\u00f6nnen? Wir haben jede Woche die M\u00f6glichkeit, uns zu messen. Jetzt haben wir eine Megaherausforderung vor uns, an die wir mit Spa\u00df und Freude herangehen\u201c, sagte der FCA-Trainer.\n  <\/p>\n<p class=\"mb-6 text-xs md:text-m lg:text-l font-serif group-[.font-sans]:font-sans \">\n    Die Entwicklung nach dem 0:4 gegen M\u00f6nchengladbach hat ihm und seinem Team Vertrauen gegeben. Andererseits gibt es noch einige Themen zu bearbeiten: Wie schafft es der FCA, F\u00fchrungen \u00fcber die Zeit zu bringen? Wie kann es gelingen, mit dem Ball noch zielstrebiger zu spielen? Antworten braucht es schnellstm\u00f6glich.\n  <\/p>\n<ul data-module-id=\"DragDropModule\" class=\"flex flex-wrap justify-start group-[.no-bookmarks]:hidden\">\n<li class=\"mb-3 mr-3\">\n    Marco Scheinhof<\/p>\n<p>      Icon Haken im Kreis gesetzt<\/p>\n<p>      Icon Plus im Kreis<\/p>\n<\/li>\n<li class=\"mb-3 mr-3\">\n    Manuel Baum<\/p>\n<p>      Icon Haken im Kreis gesetzt<\/p>\n<p>      Icon Plus im Kreis<\/p>\n<\/li>\n<li class=\"mb-3 mr-3\">\n    Jeffrey Gouweleeuw<\/p>\n<p>      Icon Haken im Kreis gesetzt<\/p>\n<p>      Icon Plus im Kreis<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"Jeffrey Gouweleeuw ist zur\u00fcck auf dem Platz. Zumindest, um individuell Runden zu laufen. Das machte der Niederl\u00e4nder auch&hellip;\n","protected":false},"author":2,"featured_media":733546,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1846],"tags":[680,772,3364,29,548,663,3934,483,458,485,30,13,115754,17194,92758,1268,14,15,12,1441,87016,29935],"class_list":{"0":"post-733545","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-augsburg","8":"tag-augsburg","9":"tag-bayern","10":"tag-de","11":"tag-deutschland","12":"tag-eu","13":"tag-europa","14":"tag-europe","15":"tag-fc-augsburg","16":"tag-fc-bayern-muenchen","17":"tag-fussball-bundesliga","18":"tag-germany","19":"tag-headlines","20":"tag-jeffrey-gouweleeuw","21":"tag-kristijan-jakic","22":"tag-manuel-baum","23":"tag-muenchen","24":"tag-nachrichten","25":"tag-news","26":"tag-schlagzeilen","27":"tag-stuttgart","28":"tag-trainingswoche","29":"tag-yannik-keitel"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115928841828077944","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/733545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=733545"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/733545\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/733546"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=733545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=733545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=733545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}